{"id":1449398,"date":"2024-05-10T18:03:51","date_gmt":"2024-05-11T01:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/"},"modified":"2024-05-10T18:03:51","modified_gmt":"2024-05-11T01:03:51","slug":"gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","title":{"rendered":"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional"},"content":{"rendered":"<p>(CNN) &#8212; El gobierno de Biden afirm\u00f3 este viernes que es &#171;razonable considerar&#187; que las fuerzas israel\u00edes utilizaron armas estadounidenses en Gaza de forma &#171;incompatible&#187; con el derecho internacional humanitario, pero no lleg\u00f3 a afirmar oficialmente que Israel viol\u00f3 la ley.<\/p>\n<p>El informe, elaborado por el Departamento de Estado, afirma que se est\u00e1n investigando posibles violaciones, pero se\u00f1ala que Estados Unidos &#171;no dispone de informaci\u00f3n completa para verificar&#187; si las armas estadounidenses &#171;se utilizaron espec\u00edficamente&#187; en presuntas violaciones del derecho internacional humanitario.<\/p>\n<p>\u00daltima hora de la guerra entre Israel y Hamas en vivo: noticias, situaci\u00f3n en Gaza y m\u00e1s<\/p>\n<p>&#171;Dada la naturaleza del conflicto en Gaza, con Hamas tratando de escudarse en poblaciones e infraestructuras civiles y exponerlas a la acci\u00f3n militar israel\u00ed, as\u00ed como la falta de personal del Gobierno estadounidense sobre el terreno en Gaza, es dif\u00edcil evaluar o llegar a conclusiones definitivas sobre incidentes individuales. No obstante, dada la considerable dependencia de Israel de art\u00edculos de defensa de fabricaci\u00f3n estadounidense, es razonable considerar que las fuerzas de seguridad israel\u00edes han utilizado desde el 7 de octubre art\u00edculos de defensa incluidos en la norma NSM-20 en casos incompatibles con sus obligaciones en materia de derecho internacional humanitario o con las mejores pr\u00e1cticas establecidas para mitigar los da\u00f1os a civiles&#187;, se\u00f1ala el informe.<\/p>\n<p>El informe, que abarca desde el estallido de la guerra con Hamas el 7 de octubre hasta finales de abril, no concluye que Israel haya retenido la ayuda humanitaria a Gaza en violaci\u00f3n de la legislaci\u00f3n estadounidense.<\/p>\n<p>Aunque el informe no considera que Israel haya violado ninguno de los t\u00e9rminos del memorando, critica duramente el saldo de la campa\u00f1a militar israel\u00ed. Las conclusiones del informe marcan otro momento de tensi\u00f3n en las relaciones entre Estados Unidos e Israel en la misma semana en que el presidente Joe Biden amenaz\u00f3 con restringir las transferencias de armas si Israel segu\u00eda adelante con una gran ofensiva en Rafah.<\/p>\n<p>Aun as\u00ed, la conclusi\u00f3n final, a saber, que las garant\u00edas ofrecidas por Israel en el marco del memorando de seguridad nacional son &#171;cre\u00edbles y fiables&#187;, suscitar\u00e1 probablemente el escrutinio de algunos legisladores y organizaciones humanitarias y de derechos humanos.<\/p>\n<p>El informe no obliga al gobierno de Israel a tomar ninguna medida, y no implica ning\u00fan cambio de pol\u00edtica. La administraci\u00f3n ha evitado en gran medida restringir la ayuda militar a Israel, pero en un cambio significativo antes de la publicaci\u00f3n del informe, Biden declar\u00f3 p\u00fablicamente en una entrevista con CNN esta semana que si Israel lleva a cabo una gran ofensiva en la ciudad de Gaza, restringir\u00eda la transferencia de ciertas armas ofensivas a Israel.<\/p>\n<p>Por qu\u00e9 el presidente Biden hizo p\u00fablico su ultim\u00e1tum a Israel sobre Rafah<\/p>\n<p>El informe de alto riesgo fue desclasificado y transmitido al Capitolio el viernes por la tarde. La administraci\u00f3n estaba obligada a tomar una determinaci\u00f3n sobre esos dos asuntos en virtud de un memorando de seguridad nacional de febrero, que Biden emiti\u00f3 bajo la presi\u00f3n de los legisladores dem\u00f3cratas. Era la primera vez que el gobierno estadounidense ten\u00eda que hacer una evaluaci\u00f3n sobre la conducta de Israel en los siete meses de guerra con Hamas en Gaza, desencadenada por el brutal ataque del grupo terrorista del 7 de octubre, que ha dejado m\u00e1s de 34.000 muertos y gran parte del enclave costero destruido.<\/p>\n<p>&#171;Eludi\u00f3 todas las preguntas dif\u00edciles&#187;<\/p>\n<p>El senador dem\u00f3crata Chris Van Hollen, impulsor de la creaci\u00f3n del memorando de seguridad nacional, expres\u00f3 su decepci\u00f3n por el informe.<\/p>\n<p>&#171;La administraci\u00f3n eludi\u00f3 todas las preguntas dif\u00edciles sobre la determinaci\u00f3n real&#187;, dijo a los periodistas el viernes por la noche. &#171;Creo que lo que intentan hacer es dejar claro que reconocen lo mala que es la situaci\u00f3n, pero no quieren tener que tomar ninguna medida para responsabilizar al gobierno de Netanyahu de lo que est\u00e1 ocurriendo&#187;.<\/p>\n<p>El dem\u00f3crata de Maryland afirm\u00f3 que &#171;el prop\u00f3sito de este informe no era ofrecer una instant\u00e1nea en el tiempo&#187; y acus\u00f3 a la administraci\u00f3n de aceptar las garant\u00edas de Israel &#171;sin m\u00e1s&#187;, a pesar de que las investigaciones realizadas por grupos de derechos humanos constatan violaciones de la ley.<\/p>\n<p>Sin embargo, un alto funcionario del Departamento de Estado dijo que siempre se pretendi\u00f3 que fuera retrospectivo, y que hay procesos en marcha para evaluar la actividad en curso. No hay ning\u00fan plazo para que se extraigan conclusiones en el marco de esos procesos.<\/p>\n<p>El informe se\u00f1ala que &#171;en cualquier conflicto en el que participen socios extranjeros, a menudo es dif\u00edcil realizar evaluaciones o determinaciones r\u00e1pidas y definitivas sobre si se han utilizado art\u00edculos o servicios de defensa estadounidenses espec\u00edficos de manera no conforme con el derecho internacional&#187;.<\/p>\n<p>&#171;Sin embargo, se ha informado de suficientes incidentes como para suscitar serias preocupaciones&#187;, dec\u00eda.<\/p>\n<p>&#171;Aunque Israel tiene los conocimientos, la experiencia y las herramientas para aplicar las mejores pr\u00e1cticas para mitigar los da\u00f1os a civiles en sus operaciones militares, los resultados sobre el terreno, incluidos los altos niveles de v\u00edctimas civiles, plantean dudas sustanciales sobre si las FDI las est\u00e1n utilizando eficazmente en todos los casos&#187;, dec\u00eda el informe.<\/p>\n<p>Una investigaci\u00f3n de Amnist\u00eda afirma que se utilizaron armas de fabricaci\u00f3n estadounidense en dos ataques a\u00e9reos israel\u00edes en Gaza que mataron a 43 civiles<\/p>\n<p>El informe de gran trascendencia fue remitido al Capitolio el viernes por la tarde. El Gobierno deb\u00eda pronunciarse sobre estas dos cuestiones en virtud de un memorando de seguridad nacional de febrero, que Biden emiti\u00f3 bajo la presi\u00f3n de los legisladores dem\u00f3cratas. Era la primera vez que el gobierno estadounidense ten\u00eda que hacer una evaluaci\u00f3n sobre la conducta de Israel en los siete meses de guerra con Hamas en Gaza, desencadenada por el brutal ataque del grupo terrorista del 7 de octubre, que ha dejado m\u00e1s de 34.000 muertos y gran parte del enclave costero destruido.<\/p>\n<p>Seg\u00fan un alto funcionario del Departamento de Estado, la elaboraci\u00f3n del informe ha sido una herramienta \u00fatil para que el gobierno de Biden se dirija al gobierno de Israel e insista en la obtenci\u00f3n de informaci\u00f3n y en cambios de comportamiento. Ese funcionario dijo que el informe se compartir\u00eda con el gobierno de Israel.<\/p>\n<p>Los funcionarios del gobierno de Biden llevan meses pidiendo a Israel que haga m\u00e1s para reducir el n\u00famero de v\u00edctimas civiles y permitir la entrada de m\u00e1s ayuda en Gaza. En cuanto a la ayuda humanitaria, el informe se\u00f1ala que el gobierno estadounidense &#171;ha estado profundamente preocupado durante el periodo transcurrido desde el 7 de octubre por la acci\u00f3n y la inacci\u00f3n de Israel, que han contribuido significativamente a la falta de una entrega sostenida y predecible de la ayuda necesaria a gran escala, y el nivel general que llega a los civiles palestinos -aunque ha mejorado- sigue siendo insuficiente&#187;.<\/p>\n<p>Sin embargo, afirma que &#171;actualmente no se considera que el gobierno israel\u00ed est\u00e9 prohibiendo o restringiendo de otro modo el transporte o la entrega de ayuda humanitaria estadounidense en el sentido de la secci\u00f3n 620I de la Ley de Ayuda Exterior&#187;, que proh\u00edbe la asistencia a gobiernos que restrinjan intencionadamente la ayuda.<\/p>\n<p>El informe considera que &#171;el impacto de las operaciones militares de Israel sobre los actores humanitarios&#187; es un \u00e1rea espec\u00edfica de preocupaci\u00f3n, citando una serie de incidentes, incluyendo el ataque mortal a un convoy de ayuda de la World Central Kitchen.<\/p>\n<p>Israel atac\u00f3 a los trabajadores humanitarios &#171;sistem\u00e1ticamente, coche por coche&#187;, dice el fundador de WCK, mientras aumenta la furia por el ataque mortal<\/p>\n<p>Tras ese ataque, el mes pasado, Biden advirti\u00f3 al primer ministro israel\u00ed Netanyahu en una llamada telef\u00f3nica que Israel ten\u00eda que hacer m\u00e1s para abordar la situaci\u00f3n humanitaria o se producir\u00eda un cambio en la pol\u00edtica estadounidense. En las \u00faltimas semanas, funcionarios estadounidenses afirmaron que Israel hab\u00eda tomado medidas importantes tras esa conversaci\u00f3n, pero que a\u00fan quedaba mucho por hacer. Sin embargo, tras el lanzamiento de operaciones militares israel\u00edes &#171;limitadas&#187; en Rafah, adonde han huido millones de palestinos, el acceso de la ayuda humanitaria ha vuelto a caer en picado.<\/p>\n<p>Intenso debate<\/p>\n<p>El informe fue objeto de intenso debate durante meses en toda la administraci\u00f3n. Las organizaciones de derechos humanos han considerado que la campa\u00f1a militar israel\u00ed ha violado el derecho humanitario.<\/p>\n<p>A finales del mes pasado, Amnist\u00eda Internacional estim\u00f3 que las armas suministradas por Estados Unidos a Israel se han utilizado &#171;en graves violaciones del derecho internacional humanitario y de los derechos humanos, y de manera incompatible con la legislaci\u00f3n y la pol\u00edtica estadounidenses&#187;.<\/p>\n<p>Un funcionario de Amnist\u00eda Internacional declar\u00f3 el viernes que &#171;este informe parece la versi\u00f3n internacional de &#8216;pensamientos y oraciones&#8217;: admitir que hay un problema pero no hacer nada significativo para evitar que se sigan perdiendo vidas&#187;.<\/p>\n<p>&#171;A pesar de los vagos comentarios del presidente Biden a principios de esta semana, su administraci\u00f3n ha dejado hoy clara su postura: se\u00f1ala con el dedo y act\u00faa con rapidez cuando un actor al que el gobierno estadounidense considera adversario viola el derecho internacional, pero trata al gobierno de Israel como si estuviera por encima de la ley, aun reconociendo la abrumadora evidencia de que las fuerzas israel\u00edes est\u00e1n violando el derecho internacional y matando a civiles palestinos con armas estadounidenses con el dinero de los contribuyentes estadounidenses&#187;, declar\u00f3 Amanda Klasing, directora nacional de Relaciones Gubernamentales e Incidencia Pol\u00edtica de Amnist\u00eda Internacional Estados Unidos.<\/p>\n<p>Van Hollen dijo el viernes que &#171;no es cre\u00edble que el gobierno estadounidense tenga menos informaci\u00f3n que organizaciones como Amnist\u00eda Internacional, Human Rights Watch, Oxfam&#187;.<\/p>\n<p>Un alto funcionario del Departamento de Estado dijo que no pod\u00edan hablar de las normas de las evaluaciones realizadas por esas organizaciones, pero afirm\u00f3 que el proceso del gobierno estadounidense era muy diligente y ten\u00eda en cuenta cualquier medida de rendici\u00f3n de cuentas emprendida por el gobierno israel\u00ed.<\/p>\n<p>El presidente tambi\u00e9n reconoci\u00f3 a CNN que &#171;han muerto civiles como consecuencia&#187; de las bombas suministradas por Estados Unidos. El portavoz del Departamento de Estado, Matthew Miller, afirm\u00f3 el jueves que Biden se refer\u00eda a &#171;la tr\u00e1gica p\u00e9rdida de vidas civiles a lo largo de este conflicto&#187;, y no a una determinaci\u00f3n legal en virtud del derecho internacional humanitario.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El gobierno de Biden afirm\u00f3 este viernes que es &#171;razonable considerar&#187; que las fuerzas israel\u00edes utilizaron armas estadounidenses en Gaza de forma &#171;incompatible&#187; con el derecho internacional humanitario, pero no lleg\u00f3 a afirmar oficialmente que Israel viol\u00f3 la ley. El informe, elaborado por el Departamento de Estado, afirma que se est\u00e1n investigando posibles [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449398","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Biden dice que es &quot;razonable considerar&quot; que Israel utiliz\u00f3 armas estadounidenses de forma &quot;incompatible&quot; con el derecho internacional - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Biden dice que es &quot;razonable considerar&quot; que Israel utiliz\u00f3 armas estadounidenses de forma &quot;incompatible&quot; con el derecho internacional - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El gobierno de Biden afirm\u00f3 este viernes que es &#171;razonable considerar&#187; que las fuerzas israel\u00edes utilizaron armas estadounidenses en Gaza de forma &#171;incompatible&#187; con el derecho internacional humanitario, pero no lleg\u00f3 a afirmar oficialmente que Israel viol\u00f3 la ley. El informe, elaborado por el Departamento de Estado, afirma que se est\u00e1n investigando posibles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-11T01:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional\",\"datePublished\":\"2024-05-11T01:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\"},\"wordCount\":1822,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\",\"name\":\"El Gobierno de Biden dice que es \\\"razonable considerar\\\" que Israel utiliz\u00f3 armas estadounidenses de forma \\\"incompatible\\\" con el derecho internacional - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-11T01:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Biden dice que es \"razonable considerar\" que Israel utiliz\u00f3 armas estadounidenses de forma \"incompatible\" con el derecho internacional - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Biden dice que es \"razonable considerar\" que Israel utiliz\u00f3 armas estadounidenses de forma \"incompatible\" con el derecho internacional - Noticias","og_description":"(CNN) &#8212; El gobierno de Biden afirm\u00f3 este viernes que es &#171;razonable considerar&#187; que las fuerzas israel\u00edes utilizaron armas estadounidenses en Gaza de forma &#171;incompatible&#187; con el derecho internacional humanitario, pero no lleg\u00f3 a afirmar oficialmente que Israel viol\u00f3 la ley. El informe, elaborado por el Departamento de Estado, afirma que se est\u00e1n investigando posibles [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-11T01:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional","datePublished":"2024-05-11T01:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/"},"wordCount":1822,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","name":"El Gobierno de Biden dice que es \"razonable considerar\" que Israel utiliz\u00f3 armas estadounidenses de forma \"incompatible\" con el derecho internacional - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-11T01:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/10\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-11T01:03:51Z","datePublished":"2024-05-11T01:03:51Z","dateModified":"2024-05-11T01:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Biden dice que es &#171;razonable considerar&#187; que Israel utiliz\\u00f3 armas estadounidenses de forma &#171;incompatible&#187; con el derecho internacional\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/10\\\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/10\\\/gobierno-biden-razonable-considerar-israel-armas-estadounidenses-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-11T01:03:51Z\",\"datePublished\":\"2024-05-11T01:03:51Z\",\"dateModified\":\"2024-05-11T01:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457201,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/01\/03\/administracion-biden-venta-armas-israel-trax\/","url_meta":{"origin":1449398,"position":0},"title":"El Departamento de Estado notifica al Congreso la venta de armas a Israel por valor de US$ 8.000 millones","author":"","date":"enero 3, 2025","format":false,"excerpt":"El Departamento de Estado ha notificado informalmente al Congreso su intenci\u00f3n de vender US$ 8.000 millones en armas a Israel, seg\u00fan han informado a la CNN un funcionario estadounidense y otra fuente familiarizada con el asunto.El Departamento de Estado envi\u00f3 a la Comisi\u00f3n de Asuntos Exteriores de la C\u00e1mara de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449426,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/12\/biden-reaccion-capitolio-ultimatum-israel-trax\/","url_meta":{"origin":1449398,"position":1},"title":"Biden enfrenta cr\u00edtica bipartidista en el Capitolio por el ultim\u00e1tum a Israel","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos Joe Biden se enfrenta a cr\u00edticas por parte de legisladores de ambos partidos por su ultim\u00e1tum de que una gran ofensiva israel\u00ed en la ciudad de Rafah dar\u00eda lugar al corte de suministro de algunas armas estadounidenses.La decisi\u00f3n de Biden de hacer p\u00fablico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449248,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/08\/informe-alto-nivel-biden-israel-violo-derecho-internacional-trax\/","url_meta":{"origin":1449398,"position":2},"title":"Un informe de alto nivel se cierne sobre Biden para saber si Israel viol\u00f3 el derecho internacional","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN) -- El Gobierno de Biden se apresura a terminar un informe de alto riesgo que debe presentar al Congreso esta semana sobre si Israel ha violado el derecho internacional humanitario durante su guerra en Gaza, una determinaci\u00f3n que podr\u00eda tener importantes repercusiones y avivar a\u00fan m\u00e1s las divisiones dentro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449669,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/22\/netanyahu-niega-hambre-civiles-gaza-guerra-trax\/","url_meta":{"origin":1449398,"position":3},"title":"Netanyahu niega que est\u00e9 matando de hambre a civiles en Gaza como m\u00e9todo de guerra","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) -- El primer ministro de Israel, Benjamin Netanyahu, neg\u00f3 las acusaciones de que estaba matando de hambre a los palestinos en Gaza como m\u00e9todo de guerra en una entrevista con Jake Tapper de CNN el martes, diciendo que una solicitud de orden de detenci\u00f3n actualmente en revisi\u00f3n en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448675,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/29\/estados-unidos-seguridad-israel-violaciones-derechos-humanos-trax\/","url_meta":{"origin":1449398,"position":4},"title":"Estados Unidos determina que cinco unidades de seguridad israel\u00edes cometieron violaciones de derechos humanos antes de la guerra de Gaza","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- El Departamento de Estado de EE.UU determin\u00f3 que cinco unidades de seguridad de Israel cometieron graves violaciones a los derechos humanos antes del estallido de la guerra con Hamas en Gaza, pero a\u00fan est\u00e1 por decidir si restringir\u00e1 la asistencia militar a una de las unidades seg\u00fan la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459588,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/06\/analisis-eeuu-dialoga-hamas-primera-vez-trax\/","url_meta":{"origin":1449398,"position":5},"title":"Estados Unidos dialoga directamente con Hamas por primera vez. \u00bfQu\u00e9 busca el grupo palestino?","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Durante la mayor parte de los \u00faltimos 17 meses, la idea de un acuerdo pol\u00edtico para la guerra en Gaza, y mucho menos para el conflicto palestino-israel\u00ed, ha parecido muy lejana a la realidad, eclipsada por una devastadora campa\u00f1a militar que ha cobrado decenas de miles de vidas y por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449398"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449398\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}