{"id":1449428,"date":"2024-05-12T23:03:50","date_gmt":"2024-05-13T06:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/"},"modified":"2024-05-12T23:03:50","modified_gmt":"2024-05-13T06:03:50","slug":"joven-llamo-911-crisis-muerto-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","title":{"rendered":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera"},"content":{"rendered":"<p>(CNN) &#8212; \u201cPor favor, no disparen\u201d, rog\u00f3 Notan Eva Costa, una inmigrante banglades\u00ed de 48 a\u00f1os que vive en Queens, a los dos agentes de Polic\u00eda de la ciudad de Nueva York (NYPD) que entraron a su casa despu\u00e9s de que su hijo adolescente llamara al 911.<\/p>\n<p>Tumbada en el suelo, la madre de los dos hijos tendi\u00f3 la mano a los oficiales, con terror y angustia que se pod\u00edan escuchar en su voz.<\/p>\n<p>Era muy tarde. Uno de los polic\u00edas dispar\u00f3 su pistola al menos cuatro veces, e hiri\u00f3 de muerte a Win Rozario, de 19 a\u00f1os. Hab\u00edan pasado menos de dos minutos desde que la Polic\u00eda hab\u00eda entrado en la casa de la familia.<\/p>\n<p>Los agentes \u201cmataron a mi hijo en minutos\u201d, dijo Costa a trav\u00e9s de un int\u00e9rprete en una conferencia de prensa este mi\u00e9rcoles. \u201cAntes de que vinieran, todo estaba en calma. Luego vinieron, crearon caos y lo asesinaron delante de m\u00ed\u201d.<\/p>\n<p>En las semanas posteriores a la muerte de Rozario, el tiroteo atrajo la atenci\u00f3n de defensores de la justicia social y la salud mental, particularmente despu\u00e9s de que la oficina del fiscal general del estado publicara im\u00e1genes de las c\u00e1maras corporales que llevaban los dos agentes que respondieron y anunciara que est\u00e1 investigando el caso.<\/p>\n<p>Los cr\u00edticos dicen que el uso de fuerza letal por parte de la Polic\u00eda fue innecesario y refleja un patr\u00f3n de violencia contra personas con enfermedades mentales. En un comunicado de prensa, la Polic\u00eda de Nueva York dijo que est\u00e1 \u201ccooperando plenamente\u201d con la investigaci\u00f3n y que est\u00e1 llevando a cabo su propia investigaci\u00f3n, y agreg\u00f3: \u201cBuscamos mejorar continuamente la forma en que respondemos a las solicitudes de asistencia y reconocemos que hay mucho trabajo por hacer. Los neoyorquinos no esperan ni merecen menos\u201d.<\/p>\n<p>Polic\u00edas de California matan a tiros a un adolescente con autismo que sosten\u00eda una herramienta de jardiner\u00eda, dice abogado<\/p>\n<p>Los dos agentes est\u00e1n en una \u201casignaci\u00f3n modificada\u201d, lo que significa que todav\u00eda est\u00e1n trabajando pero no portan armas de fuego ni escudos. La familia de Rozario, as\u00ed como organizaciones locales como el Comit\u00e9 de Justicia y Desis Rising Up and Moving, pidieron que los agentes sean despedidos y procesados.<\/p>\n<p>Tambi\u00e9n tienen objetivos que van mucho m\u00e1s all\u00e1 de penalizar a los agentes que mataron a Rozario. Piden a la ciudad de Nueva York que cambie radicalmente su enfoque para responder a los pedidos de las personas en crisis. En lugar de enviar agentes de Polic\u00eda armados para responder a cada llamada al 911, imaginan un mundo en el que personal capacitado en salud mental pueda responder a las personas que atraviesan crisis, para ayudar a reducir situaciones tensas y conectar a los pacientes con la atenci\u00f3n m\u00e9dica.<\/p>\n<p>Ya se implementaron programas de intervenci\u00f3n en crisis de salud mental en ciudades como Eugene, Oregon, y Denver, Colorado, as\u00ed como en 23 condados de Dakota del Sur y otras partes del pa\u00eds. En Nueva York, un programa piloto similar pero limitado llamado \u201cB-Heard\u201d env\u00eda t\u00e9cnicos de emergencias m\u00e9dicas y socorristas capacitados en salud mental a algunas llamadas de emergencia.<\/p>\n<p>Mientras hablaba a trav\u00e9s de un traductor frente a decenas de seguidores que sosten\u00edan im\u00e1genes de Rozario, su madre describi\u00f3 a su hijo como un adolescente \u201ctranquilo y educado\u201d que so\u00f1aba con unirse alg\u00fan d\u00eda al Ej\u00e9rcito \u201cporque quer\u00eda hacer algo por este pa\u00eds\u201d. Le encantaba cocinar para su madre y ayudarla con sus manualidades, record\u00f3.<\/p>\n<p>\u201cEso es lo que nos rob\u00f3 la Polic\u00eda\u201d, dijo, a veces llorando, mientras describ\u00eda a su hijo. \u201cTrat\u00e9 de proteger a mi hijo. Le rogu\u00e9 a la Polic\u00eda que no disparara, pero aun as\u00ed lo mataron\u201d.<\/p>\n<p>\u201cWin Rosario estar\u00eda vivo hoy si NYPD ya hubiera sido retirado de la salud mental\u201d, dijo Loyda Col\u00f3n, directora ejecutiva del Comit\u00e9 de Justicia, en una conferencia de prensa el mi\u00e9rcoles.<\/p>\n<p>2 minutos, 4 disparos y una vida joven arrebatada<\/p>\n<p>Rozario estaba en medio de una aparente crisis de salud mental cuando llam\u00f3 al 911 el 27 de marzo.<\/p>\n<p>&#171;Est\u00e1 teniendo un episodio&#187;, dijo su hermano menor, Utsho, a los dos agentes de Polic\u00eda que llegaron. &#171;Para ser honesto, ni siquiera sabe lo que est\u00e1 haciendo&#187;.<\/p>\n<p>En el apartamento, los agentes encontraron a Rozario parado en la cocina con su madre cerca. Cuando un agente se dirigi\u00f3 a la cocina, Rozario pareci\u00f3 angustiarse y tom\u00f3 un par de tijeras de cocina, que su madre intent\u00f3 quitarle de la mano.<\/p>\n<p>Rozario se acerc\u00f3 nuevamente a los polic\u00edas con las tijeras, lo que gener\u00f3 que un agente le disparara una Taser y el otro sacara su arma. La madre de Rozario lo agarr\u00f3 mientras un agente gritaba \u201csu\u00e9ltalo y retrocede\u201d y pareci\u00f3 disparar una pistola Taser nuevamente al adolescente, quien se desplom\u00f3 en el suelo.<\/p>\n<p>Luego, la madre de Rozario se alej\u00f3 de \u00e9l y se acerc\u00f3 a los oficiales, sosteniendo las tijeras. Camin\u00f3 de regreso hacia Rozario, aparentemente tratando de consolarlo, lo que caus\u00f3 que un agente gritara: &#171;\u00a1D\u00edgale que se quite del camino!&#187;.<\/p>\n<p>\u201cNo disparen\u201d, dijo a los agentes. Un polic\u00eda volvi\u00f3 a disparar una Taser a Rozario, quien agarr\u00f3 las tijeras y nuevamente se dirigi\u00f3 hacia los agentes. Utsho entr\u00f3 y los tres miembros de la familia se abrazaron mientras los oficiales segu\u00edan grit\u00e1ndoles que se apartaran del camino.<\/p>\n<p>La madre y el hermano de Rozario cayeron al suelo. Rozario estaba de pie y sosteniendo las tijeras, aparentemente a varios metros de distancia de los agentes, cuando uno de los polic\u00edas pareci\u00f3 comenzar a dispararle. Cay\u00f3 al suelo tras m\u00faltiples disparos.<\/p>\n<p>Col\u00f3n dijo que las im\u00e1genes muestran que los agentes que respondieron \u201cintensificaron imprudentemente la situaci\u00f3n varias veces\u201d, y pusieron en peligro tambi\u00e9n a la madre y al hermano de Rozario.<\/p>\n<p>La Polic\u00eda dispar\u00f3 a menor de 13 a\u00f1os con autismo despu\u00e9s de que su madre pidiera ayuda para manejar un &#8216;colapso mental&#8217;<\/p>\n<p>\u201cTuvieron m\u00faltiples oportunidades para reducir la tensi\u00f3n, para detener, y no lo hicieron\u201d, dijo Col\u00f3n. Los agentes le gritaron \u201cd\u00e9jalo\u201d varias veces a Rozario, pero no hablaron con \u00e9l durante las im\u00e1genes de la c\u00e1mara corporal.<\/p>\n<p>&#171;No hab\u00eda ning\u00fan peligro hasta que esos agentes llegaron con sus armas&#187;, dijo el abogado de la familia en la conferencia de prensa.<\/p>\n<p>Michael Alcazar, detective retirado de la Polic\u00eda de Nueva York y profesor adjunto del John Jay College of Criminal Justice, dijo a CNN que vio m\u00faltiples formas en que los agentes podr\u00edan haber evitado dispararle a Rozario. Antes de entrar a la vivienda o cuando la madre de Rozario le quit\u00f3 las tijeras, podr\u00edan haberle pedido a su madre y a su hermano que salieran del apartamento, dejando solo a Rozario dentro, y luego llamar a los servicios de emergencia. Esto es consistente con el protocolo de \u201caislar y contener\u201d que la Polic\u00eda de Nueva York recomienda utilizar a los agentes cuando tratan con \u201cpersonas mentalmente enfermas o con trastornos emocionales\u201d.<\/p>\n<p>Adem\u00e1s, los agentes podr\u00edan haber utilizado armas no letales, como porras, para controlar a Rosario y quitarle las tijeras, seg\u00fan Alc\u00e1zar.<\/p>\n<p>Otra mirada para las intervenciones durante las crisis<\/p>\n<p>Rozario no fue el primer neoyorquino que muri\u00f3 a manos de la Polic\u00eda mientras atravesaba una crisis de salud mental. Community Access, una organizaci\u00f3n sin fines de lucro que apoya a personas con problemas de salud mental en Nueva York, dice que al menos 26 neoyorquinos que experimentan crisis de salud mental fueron muertos a tiros por la Polic\u00eda desde 2007.<\/p>\n<p>Las situaciones que involucran a \u201cpersonas emocionalmente perturbadas\u201d son la segunda situaci\u00f3n m\u00e1s com\u00fan en la que los agentes de Polic\u00eda usan la fuerza, seg\u00fan el informe sobre el uso de la fuerza de 2022 de la Polic\u00eda de Nueva York. Los agentes utilizaron la fuerza en 1.740 encuentros con personas con trastornos emocionales en 2022, seg\u00fan el informe. El informe no incluye datos sobre la fuerza letal utilizada contra personas con trastornos emocionales.<\/p>\n<p>La Polic\u00eda de Nueva York le dijo a CNN que responden a aproximadamente 155.000 \u201cllamadas de emergencia que involucran a personas en medio de una crisis de salud emocional o mental\u201d cada a\u00f1o. Menos del 1% de esas llamadas resultan en que la Polic\u00eda utilice alg\u00fan tipo de fuerza y \u200b\u200bmenos a\u00fan que involucran fuerza letal, seg\u00fan la Polic\u00eda de Nueva York.<\/p>\n<p>Aunque son poco comunes, muertes como las de Rozario, Kawaski Trawick, Deborah Danner y Mohamed Bah exhibieron los peligros de utilizar a la Polic\u00eda para responder a personas que atraviesan crisis agudas y sobre c\u00f3mo podr\u00eda ser un sistema alternativo de apoyo.<\/p>\n<p>En Eugene y Springfield, Oreg\u00f3n, por ejemplo, m\u00e9dicos y socorristas especializados en crisis han respondido a llamadas de crisis durante m\u00e1s de 30 a\u00f1os a trav\u00e9s de un programa de intervenci\u00f3n m\u00f3vil llamado CAHOOTS, acr\u00f3nimo de \u201cCrisis Assistance Helping Out On The Streets\u201d. El programa desv\u00eda entre el 3% y el 8% de las llamadas que de otro modo ser\u00edan atendidas por la Polic\u00eda, seg\u00fan el Departamento de Polic\u00eda de Eugene, incluida la atenci\u00f3n a personas &#171;ebrias, enfermas mentales o desorientadas&#187;.<\/p>\n<p>Jeremy Gates, director ejecutivo de la Cl\u00ednica White Bird, que dirige CAHOOTS, dijo a CNN que parte del \u00e9xito del programa radica en la confianza que sus socorristas han construido con los clientes a lo largo de los a\u00f1os.<\/p>\n<p>\u201cLa gente llama y dice: no quiero a la Polic\u00eda, quiero CAHOOTS\u201d, dijo.<\/p>\n<p>Y en Colorado, donde un exdiputado fue declarado culpable de peligro imprudente, otro se declar\u00f3 culpable de dos delitos menores y otros seis agentes enfrentan actualmente cargos por disparar y matar a un hombre que experimentaba una crisis de salud mental, un programa similar llamado Equipo de Apoyo de Respuesta Asistida, conocido como STAR por sus siglas en ingl\u00e9s, opera en Denver.<\/p>\n<p>\u201cRespondemos de una manera emp\u00e1tica y basada en el trauma\u201d, dijo a CNN el especialista del programa STAR, Evan Thompkins, en una entrevista. &#171;Venimos de una manera amable y afectuosa, en la que podemos conocer a las personas en su situaci\u00f3n actual, realmente ponernos a su nivel y brindarles un acercamiento no autoritario&#187;.<\/p>\n<p>Thompkins se\u00f1al\u00f3 que para algunas personas y comunidades, la sola presencia de polic\u00edas uniformados puede hacer que la situaci\u00f3n &#171;escale&#187;. Algunas \u201ccomunidades tienen miedo de la Polic\u00eda y no quieren interactuar con ella\u201d, dijo.<\/p>\n<p>Video de c\u00e1mara corporal muestra a un polic\u00eda dispar\u00e1ndole a un ni\u00f1o con s\u00edndrome de Asperger<\/p>\n<p>Fountain House, una organizaci\u00f3n sin fines de lucro que brinda apoyo a personas que viven con enfermedades mentales graves en Nueva York, tambi\u00e9n destac\u00f3 la muerte de Rozario para pedir una gran expansi\u00f3n de los programas de intervenci\u00f3n de salud mental de la ciudad.<\/p>\n<p>La enfermedad mental es principalmente \u201cun problema de salud p\u00fablica, no un problema de seguridad p\u00fablica\u201d, dijo a CNN Arvind Sooknanan, miembro de la junta directiva de Fountain House. La organizaci\u00f3n present\u00f3 un plan para que Nueva York \u201csaque tantas llamadas de crisis de salud mental como sea posible del sistema 911\u201d e integre la l\u00ednea directa de salud mental 988 existente \u201ccon el sistema de servicios sociales para ayudar a las personas a abordar las causas fundamentales del estr\u00e9s\u201d.<\/p>\n<p>Para Sooknanan, el caso de Rozario lo toca especialmente de cerca: Sooknanan vive con una enfermedad mental grave desde que ten\u00eda 15 a\u00f1os y tambi\u00e9n proviene de un entorno del sur de Asia, como Rozario.<\/p>\n<p>El caso \u201cme carcomi\u00f3 durante las \u00faltimas semanas\u201d, dijo. \u201cTen\u00eda s\u00f3lo 19 a\u00f1os. No hab\u00eda ninguna raz\u00f3n para que muriera\u201d.<\/p>\n<p>\u201cQuiero que otras personas tengan las mismas oportunidades que yo, de seguir adelante con sus vidas, de encontrar significado, de encontrar una comunidad\u201d, dijo Sooknanan, quien tambi\u00e9n est\u00e1 trabajando para ayudar a desarrollar programas de intervenci\u00f3n en crisis en otros estados.<\/p>\n<p>\u00bfEst\u00e1s en riesgo de desarrollar una enfermedad mental?<\/p>\n<p>Ken Zimmerman, director ejecutivo de Fountain House, dijo a CNN que imagina un futuro en el que \u201cel conocimiento y la conciencia de cu\u00e1les son las enfermedades mentales graves est\u00e9 mucho m\u00e1s extendido, y el tipo de estigma y miedo que impulsa tantas cosas disminuya enormemente\u201d.<\/p>\n<p>Adem\u00e1s, enfatiz\u00f3 la importancia de ampliar los recursos y la infraestructura de la ciudad para la atenci\u00f3n de salud mental, un proceso que podr\u00eda llevar a\u00f1os.<\/p>\n<p>Y esos recursos y planificaci\u00f3n deben tener en cuenta la experiencia vivida por las personas que viven con enfermedades mentales graves, dijo.<\/p>\n<p>Para la familia Rozario, la lucha para brindar una alternativa a la respuesta policial para las personas en crisis de salud mental est\u00e1 impulsada por un sue\u00f1o que ninguna otra familia deber\u00eda tener de experimentar la angustia que ellos sintieron.<\/p>\n<p>\u201cNinguna madre deber\u00eda pasar por el dolor que yo estoy pasando\u201d, dijo la madre de Rozario. &#171;Espero que ninguna otra madre pase por esto en el futuro&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; \u201cPor favor, no disparen\u201d, rog\u00f3 Notan Eva Costa, una inmigrante banglades\u00ed de 48 a\u00f1os que vive en Queens, a los dos agentes de Polic\u00eda de la ciudad de Nueva York (NYPD) que entraron a su casa despu\u00e9s de que su hijo adolescente llamara al 911. Tumbada en el suelo, la madre de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449428","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; \u201cPor favor, no disparen\u201d, rog\u00f3 Notan Eva Costa, una inmigrante banglades\u00ed de 48 a\u00f1os que vive en Queens, a los dos agentes de Polic\u00eda de la ciudad de Nueva York (NYPD) que entraron a su casa despu\u00e9s de que su hijo adolescente llamara al 911. Tumbada en el suelo, la madre de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T06:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera\",\"datePublished\":\"2024-05-13T06:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\"},\"wordCount\":2278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\",\"name\":\"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-13T06:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias","og_description":"(CNN) &#8212; \u201cPor favor, no disparen\u201d, rog\u00f3 Notan Eva Costa, una inmigrante banglades\u00ed de 48 a\u00f1os que vive en Queens, a los dos agentes de Polic\u00eda de la ciudad de Nueva York (NYPD) que entraron a su casa despu\u00e9s de que su hijo adolescente llamara al 911. Tumbada en el suelo, la madre de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-13T06:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/"},"author":{"name":"","@id":""},"headline":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera","datePublished":"2024-05-13T06:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/"},"wordCount":2278,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","name":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-13T06:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un joven de 19 a\u00f1os llam\u00f3 al 911 en medio de una crisis y termin\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/12\/joven-llamo-911-crisis-muerto-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-13T06:03:50Z","datePublished":"2024-05-13T06:03:50Z","dateModified":"2024-05-13T06:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un joven de 19 a\\u00f1os llam\\u00f3 al 911 en medio de una crisis y termin\\u00f3 muerto. Para los defensores, es un llamado a actuar de una mejor manera\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/12\\\/joven-llamo-911-crisis-muerto-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/12\\\/joven-llamo-911-crisis-muerto-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-13T06:03:50Z\",\"datePublished\":\"2024-05-13T06:03:50Z\",\"dateModified\":\"2024-05-13T06:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442932,"url":"https:\/\/noticiasya.com\/san-angelo\/2023\/12\/31\/la-policia-busca-a-una-madre-de-colorado-sospechosa-de-matar-a-dos-de-sus-hijos\/","url_meta":{"origin":1449428,"position":0},"title":"La polic\u00eda busca a una madre de Colorado sospechosa de matar a dos de sus hijos","author":"","date":"diciembre 31, 2023","format":false,"excerpt":"(CNN) -- Las autoridades buscan a una madre de Colorado que es sospechosa de matar a dos de sus hijos e intentar matar a un tercero despu\u00e9s de que la polic\u00eda respondi\u00f3 inicialmente a un reporte de robo en su casa.Se emiti\u00f3 una orden de arresto contra Kimberlee Singler por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456029,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/22\/las-vegas-brandon-durham-llamado-policia-trax\/","url_meta":{"origin":1449428,"position":1},"title":"&#171;Env\u00eda a alguien lo antes posible&#187;, dijo hombre de Las Vegas en llamada al 911 antes de que la Polic\u00eda le disparara fatalmente en su casa","author":"","date":"noviembre 22, 2024","format":false,"excerpt":"(CNN) -- Un hombre que fue fatalmente herido por la Polic\u00eda de Las Vegas tras llamar al 911 durante una invasi\u00f3n de su hogar suplic\u00f3 a los oficiales que llegaran \u201clo antes posible\u201d, porque tem\u00eda que un intruso los \u201ciba a matar a todos\u201d.En la grabaci\u00f3n de audio de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466629,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/19\/pareja-mexicana-detenida-ice-hijos-orix\/","url_meta":{"origin":1449428,"position":2},"title":"Una pareja mexicana fue detenida por ICE y su hija de 19 a\u00f1os se enfrent\u00f3 a los agentes migratorios","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Constantina Ram\u00edrez y Mois\u00e9s Enciso, una pareja de mexicanos que viven en Cicero, Illinois desde hace 15 a\u00f1os, fueron detenidos el domingo por agentes del Servicio de Control de Inmigraci\u00f3n y Aduanas de Estados Unidos (ICE, en ingl\u00e9s) en el d\u00eda de cumplea\u00f1os del menor de sus cuatro hijos, un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445079,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","url_meta":{"origin":1449428,"position":3},"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445083,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia-2\/","url_meta":{"origin":1449428,"position":4},"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445085,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia-3\/","url_meta":{"origin":1449428,"position":5},"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449428"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449428\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}