{"id":1449473,"date":"2024-05-14T18:03:52","date_gmt":"2024-05-15T01:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/"},"modified":"2024-05-14T18:03:52","modified_gmt":"2024-05-15T01:03:52","slug":"fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","title":{"rendered":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda de Ecuador pidi\u00f3 a dos asamble\u00edstas, Pamela Aguirre y Lenin Barreto, informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, quien es investigado en el caso Met\u00e1stasis y est\u00e1 pr\u00f3fugo de la Justicia por contar con una orden de prisi\u00f3n preventiva.<\/p>\n<p>La instituci\u00f3n dio a conocer su petici\u00f3n mediante un comunicado difundido este lunes, horas despu\u00e9s de que la fiscal Diana Salazar acudi\u00f3 a comparecer ante la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional.<\/p>\n<p>Durante la cita, el asamble\u00edsta Lenin Barreto, del opositor partido Revoluci\u00f3n Ciudadana, solicit\u00f3 que se permitiera a Aleaga participar en el encuentro v\u00eda videoconferencia. La asamble\u00edsta Pamela Aguirre, presidenta de la Comisi\u00f3n de Fiscalizaci\u00f3n y tambi\u00e9n integrante de Revoluci\u00f3n Ciudadana, accedi\u00f3 a la solicitud. La fiscal se pronunci\u00f3 en contra y anunci\u00f3 que abandonar\u00eda el sal\u00f3n.<\/p>\n<p>OPINI\u00d3N | Ecuador, en guerra\u2026<\/p>\n<p>\u201cNo voy a ser objeto ni me voy a prestar para el show que quieren hacer los pol\u00edticos sobre los casos, so pena de contaminar el caso Met\u00e1stasis, que en las pr\u00f3ximas semanas se realizar\u00e1 la audiencia. All\u00e1 que comparezca\u201d, dijo Salazar.<\/p>\n<p>\u201cNo vine ac\u00e1 para escuchar a un pr\u00f3fugo de la justicia\u201d, insisti\u00f3 la fiscal, antes de salir del recinto legislativo en protesta.<\/p>\n<p>M\u00e1s tarde, la Fiscal\u00eda dijo en su comunicado que pedir\u00eda informaci\u00f3n a Aguirre y Barreto \u201cdebido al posible cometimiento de un delito al conocer informaci\u00f3n sobre una persona requerida por la Justicia y no entregarla a las instituciones pertinentes\u201d.<\/p>\n<p>CNN intenta contactar a ambos asamble\u00edstas para obtener comentarios sobre los se\u00f1alamientos de la Fiscal\u00eda.<\/p>\n<p>Aleaga explic\u00f3 en un video publicado en su cuenta de Instagram que \u00e9l solicit\u00f3 participar en la comparecencia. Agreg\u00f3 que se considera v\u00edctima de una persecuci\u00f3n pol\u00edtica y acusa a Salazar de liderar intimidaciones y amenazas contra los asamble\u00edstas y de cometer fraude procesal.<\/p>\n<p>Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada<\/p>\n<p>El exasamble\u00edsta es uno de los investigados por la Fiscal\u00eda ecuatoriana dentro del caso Met\u00e1stasis, que se dio a conocer en diciembre pasado a ra\u00edz de un megaoperativo en el que fueron detenidos exfuncionarios judiciales y carcelarios, empresarios, abogados e integrantes de bandas criminales.<\/p>\n<p>De acuerdo con la Fiscal\u00eda, las investigaciones del caso Met\u00e1stasis buscan desarticular las redes de complicidad entre pol\u00edticos de alto nivel y grupos del narcotr\u00e1fico.<\/p>\n<p>La fiscal Diana Salazar, quien encabeza la instituci\u00f3n desde 2019, dijo el domingo en un video publicado en su canal de YouTube que, por su trabajo, frecuentemente recibe amenazas de muerte y debe limitar su vida personal.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda de Ecuador pidi\u00f3 a dos asamble\u00edstas, Pamela Aguirre y Lenin Barreto, informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, quien es investigado en el caso Met\u00e1stasis y est\u00e1 pr\u00f3fugo de la Justicia por contar con una orden de prisi\u00f3n preventiva. La instituci\u00f3n dio a conocer su petici\u00f3n mediante un comunicado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449473","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda de Ecuador pidi\u00f3 a dos asamble\u00edstas, Pamela Aguirre y Lenin Barreto, informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, quien es investigado en el caso Met\u00e1stasis y est\u00e1 pr\u00f3fugo de la Justicia por contar con una orden de prisi\u00f3n preventiva. La instituci\u00f3n dio a conocer su petici\u00f3n mediante un comunicado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T01:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis\",\"datePublished\":\"2024-05-15T01:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\"},\"wordCount\":510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\",\"name\":\"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-15T01:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La Fiscal\u00eda de Ecuador pidi\u00f3 a dos asamble\u00edstas, Pamela Aguirre y Lenin Barreto, informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, quien es investigado en el caso Met\u00e1stasis y est\u00e1 pr\u00f3fugo de la Justicia por contar con una orden de prisi\u00f3n preventiva. La instituci\u00f3n dio a conocer su petici\u00f3n mediante un comunicado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-15T01:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/"},"author":{"name":"","@id":""},"headline":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis","datePublished":"2024-05-15T01:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/"},"wordCount":510,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","name":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-15T01:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Fiscal\u00eda de Ecuador pide a asamble\u00edstas informaci\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\u00e1stasis","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/14\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-15T01:03:52Z","datePublished":"2024-05-15T01:03:52Z","dateModified":"2024-05-15T01:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Fiscal\\u00eda de Ecuador pide a asamble\\u00edstas informaci\\u00f3n sobre el paradero del exlegislador Ronny Aleaga, investigado por el caso Met\\u00e1stasis\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/14\\\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/14\\\/fiscalia-ecuador-pide-informacion-paradero-ronny-aleaga-metastasis-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-15T01:03:52Z\",\"datePublished\":\"2024-05-15T01:03:52Z\",\"dateModified\":\"2024-05-15T01:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465614,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/18\/ecuador-cargos-autores-asesinato-fernando-villavicencio-orix\/","url_meta":{"origin":1449473,"position":0},"title":"Fiscal\u00eda de Ecuador formular\u00e1 cargos contra presuntos autores intelectuales del asesinato de Fernando Villavicencio","author":"","date":"agosto 18, 2025","format":false,"excerpt":"La Fiscal\u00eda General de Ecuador inform\u00f3 este lunes que ha solicitado a un juez que convoque al exministro del Interior, Jos\u00e9 Serrano; al condenado por delitos de corrupci\u00f3n Daniel Salcedo, quien est\u00e1 en prisi\u00f3n; al exasamble\u00edsta del corre\u00edsmo Ronny Aleaga y al empresario Xavier Jord\u00e1n a una audiencia de formulaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466157,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/04\/prision-preventiva-presuntos-autores-intelectuales-asesinato-villavicencio-orix\/","url_meta":{"origin":1449473,"position":1},"title":"Ordenan prisi\u00f3n preventiva para dos presuntos autores intelectuales del asesinato de Villavicencio en Ecuador","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"La Fiscal\u00eda de Ecuador formul\u00f3 este mi\u00e9rcoles cargos en contra de cuatro presuntos autores intelectuales del asesinato del excandidato presidencial Fernando Villavicencio, ocurrido el 9 de agosto de 2023 tras un mitin pol\u00edtico en Quito. La audiencia \u2014que se desarroll\u00f3 en una unidad judicial en Quito\u2014 estuvo marcada por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447540,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/29\/testimonios-ecuador-caso-metastasis-orix\/","url_meta":{"origin":1449473,"position":2},"title":"Testimonios explosivos en Ecuador salpican a decenas de personas dentro del caso Met\u00e1stasis por delincuencia organizada","author":"","date":"marzo 29, 2024","format":false,"excerpt":"(CNN) -- El caso Met\u00e1stasis en Ecuador va tomando nuevos giros a medida que avanzan las investigaciones de la Fiscal\u00eda sobre la existencia de una presunta estructura criminal que operaba en distintas instituciones del Estado, especialmente dentro del \u00e1mbito judicial.Un juez de Ecuador dicta prisi\u00f3n preventiva contra 16 procesados por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456086,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/25\/sentencian-prision-exfuncionarios-ecuador-caso-metastasis-orix\/","url_meta":{"origin":1449473,"position":3},"title":"Sentencian a prisi\u00f3n a 2 ex altos funcionarios de Ecuador y a otras 18 personas por el caso Met\u00e1stasis","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Un tribunal de la Corte Nacional de Justicia de Ecuador conden\u00f3 este lunes por cargos de delincuencia organizada a nueve a\u00f1os y cuatro meses de prisi\u00f3n a dos ex altos funcionarios, en calidad de colaboradores dentro del caso Met\u00e1stasis.Los sentenciados son el expresidente del Consejo de la Judicatura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456950,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/25\/desaparicion-menores-guayaquil-orix\/","url_meta":{"origin":1449473,"position":4},"title":"Jueza de Ecuador reconoce &#171;desaparici\u00f3n forzada&#187; de cuatro menores de Guayaquil. Militares permanecen bajo custodia","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"La noche de este martes la jueza Tanya Loor acept\u00f3 un recurso de habeas corpus planteado por los familiares de los cuatro ni\u00f1os desaparecidos tras un operativo militar el 8 de diciembre en el sector de Las Malvinas, en el sur de Guayaquil, y declar\u00f3 como \u201cdesaparici\u00f3n forzada\u201d este caso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468335,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/11\/14\/ecuador-referendum-consulta-propuestas-orix\/","url_meta":{"origin":1449473,"position":5},"title":"\u00bfQu\u00e9 hay detr\u00e1s del refer\u00e9ndum en Ecuador? Estas son las propuestas que est\u00e1n en juego en las urnas este domingo","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Las urnas volver\u00e1n a ser este domingo el escenario de decisi\u00f3n en Ecuador en un momento de alta polarizaci\u00f3n y tensiones sociales. Los ecuatorianos participar\u00e1n en un nuevo refer\u00e9ndum y consulta popular que plantea \u2014entre otras cosas\u2014 la instalaci\u00f3n de bases militares extranjeras, la elaboraci\u00f3n de una nueva Constituci\u00f3n y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449473"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449473\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}