{"id":1449503,"date":"2024-05-15T22:03:49","date_gmt":"2024-05-16T05:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/"},"modified":"2024-05-15T22:03:49","modified_gmt":"2024-05-16T05:03:49","slug":"ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","title":{"rendered":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza"},"content":{"rendered":"<p>(CNN) &#8212; El ministro de Defensa de Israel, Yoav Gallant, le pidi\u00f3 al primer ministro Benjamin Netanyahu que descarte p\u00fablicamente el gobierno de Israel sobre Gaza y que exponga sus planes para la posguerra, advirtiendo de que se opone al dominio israel\u00ed en el enclave palestino.<\/p>\n<p>&#171;El &#8216;d\u00eda despu\u00e9s de Hamas&#8217;, solo se lograr\u00e1 con entidades palestinas que tomen el control de Gaza, acompa\u00f1adas por actores internacionales, estableciendo una alternativa de gobierno al dominio de Hamas&#187;, dijo Gallant durante una conferencia de prensa en la Kirya, el cuartel general militar de Israel este mi\u00e9rcoles.<\/p>\n<p>&#171;Pido al primer ministro Benjamin Netanyahu que tome una decisi\u00f3n y declare que Israel no establecer\u00e1 un control civil sobre\u00a0 Gaza, que Israel no establecer\u00e1 un gobierno militar en Gaza y que se plantear\u00e1 inmediatamente una alternativa de gobierno a Hamas en Gaza&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Las declaraciones de Gallant se producen en un momento en que se plantean serias dudas sobre la estrategia a largo plazo de Israel en Gaza, tanto dentro como fuera de Israel, despu\u00e9s de que el ej\u00e9rcito israel\u00ed enviara tropas de nuevo a zonas del norte de Gaza de las que se hab\u00eda retirado hace meses para combatir a militantes de Hamas que hab\u00edan regresado en medio de un vac\u00edo de poder.<\/p>\n<p>El ej\u00e9rcito de Israel publica video que muestra a hombres armados en las instalaciones de la ONU en Gaza<\/p>\n<p>Los militares israel\u00edes advirtieron en voz baja que la falta de una estrategia a largo plazo para la gobernanza de posguerra har\u00e1 que este patr\u00f3n se repita en toda Gaza. Y altos funcionarios de Estados Unidos lo est\u00e1n haciendo p\u00fablicamente, con el Secretario de Estado Antony Blinken advirtiendo este mi\u00e9rcoles que Israel debe &#171;centrarse en lo que el futuro puede y debe ser&#187; para evitar &#171;la anarqu\u00eda y un vac\u00edo que probablemente ser\u00e1 llenado por el caos.&#187;<\/p>\n<p>Gallant ya ha dicho anteriormente que se opone al control israel\u00ed sobre la Gaza de la posguerra, pero sus declaraciones de este mi\u00e9rcoles fueron las m\u00e1s directas sobre el tema, ya que advirti\u00f3 de las consecuencias de una presencia militar israel\u00ed a largo plazo en Gaza e interpel\u00f3 directamente a Netanyahu.<\/p>\n<p>&#171;No aceptar\u00e9 el establecimiento de un gobierno militar israel\u00ed en Gaza. Israel no debe establecer un gobierno civil en Gaza&#187;, dijo, advirtiendo de que una ocupaci\u00f3n militar del territorio palestino se cobrar\u00eda un alto precio en &#171;derramamiento de sangre y v\u00edctimas, as\u00ed como un alto precio econ\u00f3mico&#187;, advirti\u00f3.<\/p>\n<p>Netanyahu pareci\u00f3 responder a las declaraciones de Gallant m\u00e1s tarde el mi\u00e9rcoles, diciendo en un video publicado en las redes sociales que ni Hamas ni la Autoridad Palestina ser\u00edan entidades aceptables para gobernar Gaza.<\/p>\n<p>&#171;No estoy dispuesto a sustituir Hamast\u00e1n por Fatahst\u00e1n&#187;, dijo, refiri\u00e9ndose a Fatah, el partido pol\u00edtico palestino que domina la Autoridad Palestina.<\/p>\n<p>Netanyahu tambi\u00e9n dijo que una completa destituci\u00f3n de Hamas ser\u00eda su requisito previo para un nuevo gobierno civil en Gaza. &#171;Mientras Hamas siga en su lugar, ninguna otra entidad entrar\u00eda en Gaza para administrar los aspectos civiles, especialmente no la Autoridad Palestina&#187;, dijo.<\/p>\n<p>La desesperada b\u00fasqueda de sobrevivientes entre los escombros provocados por el bombardeo de Israel en Gaza<\/p>\n<p>Las declaraciones de Gallant desataron una tormenta pol\u00edtica en Israel, con varios legisladores de derechas condenando la declaraci\u00f3n de Gallant y algunos incluso instando a Netanyahu a destituirlo de su cargo. Por su parte, el ministro miembro del gabinete de guerra, Benny Gantz, ha respaldado la postura de Gallant, afirmando que &#171;dec\u00eda la verdad&#187;.<\/p>\n<p>El enfrentamiento p\u00fablico entre Gallant y Netanyahu se produce tras los reiterados llamamientos de Estados Unidos para que Israel elabore un plan claro para la Gaza de la posguerra.<\/p>\n<p>&#171;No apoyamos ni apoyaremos una ocupaci\u00f3n israel\u00ed. Por supuesto, tampoco apoyamos el gobierno de Hamas en Gaza&#187;, declar\u00f3 el mi\u00e9rcoles el Secretario de Estado de Estados Unidos, Antony Blinken, en una rueda de prensa en Kyiv (Ucrania), y a\u00f1adi\u00f3: &#171;Tampoco podemos tener anarqu\u00eda y un vac\u00edo que probablemente sea llenado por el caos&#187;.<\/p>\n<p>&#171;Tiene que haber un plan claro y concreto, y esperamos que Israel presente sus ideas&#187;, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El ministro de Defensa de Israel, Yoav Gallant, le pidi\u00f3 al primer ministro Benjamin Netanyahu que descarte p\u00fablicamente el gobierno de Israel sobre Gaza y que exponga sus planes para la posguerra, advirtiendo de que se opone al dominio israel\u00ed en el enclave palestino. &#171;El &#8216;d\u00eda despu\u00e9s de Hamas&#8217;, solo se lograr\u00e1 con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449503","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &quot;dominio militar israel\u00ed&quot; en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &quot;dominio militar israel\u00ed&quot; en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El ministro de Defensa de Israel, Yoav Gallant, le pidi\u00f3 al primer ministro Benjamin Netanyahu que descarte p\u00fablicamente el gobierno de Israel sobre Gaza y que exponga sus planes para la posguerra, advirtiendo de que se opone al dominio israel\u00ed en el enclave palestino. &#171;El &#8216;d\u00eda despu\u00e9s de Hamas&#8217;, solo se lograr\u00e1 con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T05:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza\",\"datePublished\":\"2024-05-16T05:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\"},\"wordCount\":749,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\",\"name\":\"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al \\\"dominio militar israel\u00ed\\\" en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-16T05:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al \"dominio militar israel\u00ed\" en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al \"dominio militar israel\u00ed\" en Gaza - Noticias","og_description":"(CNN) &#8212; El ministro de Defensa de Israel, Yoav Gallant, le pidi\u00f3 al primer ministro Benjamin Netanyahu que descarte p\u00fablicamente el gobierno de Israel sobre Gaza y que exponga sus planes para la posguerra, advirtiendo de que se opone al dominio israel\u00ed en el enclave palestino. &#171;El &#8216;d\u00eda despu\u00e9s de Hamas&#8217;, solo se lograr\u00e1 con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-16T05:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza","datePublished":"2024-05-16T05:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/"},"wordCount":749,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","name":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al \"dominio militar israel\u00ed\" en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-16T05:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El jefe de Defensa israel\u00ed dice que se opondr\u00eda al &#171;dominio militar israel\u00ed&#187; en Gaza","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/15\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-16T05:03:49Z","datePublished":"2024-05-16T05:03:49Z","dateModified":"2024-05-16T05:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El jefe de Defensa israel\\u00ed dice que se opondr\\u00eda al &#171;dominio militar israel\\u00ed&#187; en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/15\\\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/15\\\/ministro-defensa-israeli-se-opondria-dominio-militar-israeli-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-16T05:03:49Z\",\"datePublished\":\"2024-05-16T05:03:49Z\",\"dateModified\":\"2024-05-16T05:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1443985,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/17\/la-retirada-de-algunas-tropas-israelies-de-gaza-genera-nuevas-divisiones-en-el-gobierno-de-netanyahu\/","url_meta":{"origin":1449503,"position":0},"title":"La retirada de algunas tropas israel\u00edes de Gaza genera nuevas divisiones en el Gobierno de Netanyahu","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN) -- Un ministro del gobierno israel\u00ed de extrema derecha critic\u00f3 la decisi\u00f3n de las fuerzas armadas de ese pa\u00eds de retirar una divisi\u00f3n del ej\u00e9rcito de Gaza, dejando al descubierto nuevas divisiones entre los legisladores sobre la ofensiva militar en el enclave palestino.El ministro de Seguridad Nacional, Itamar Ben\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443987,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/17\/la-retirada-de-algunas-tropas-israelies-de-gaza-genera-nuevas-divisiones-en-el-gobierno-de-netanyahu-2\/","url_meta":{"origin":1449503,"position":1},"title":"La retirada de algunas tropas israel\u00edes de Gaza genera nuevas divisiones en el Gobierno de Netanyahu","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN) -- Un ministro del gobierno israel\u00ed de extrema derecha critic\u00f3 la decisi\u00f3n de las fuerzas armadas de ese pa\u00eds de retirar una divisi\u00f3n del ej\u00e9rcito de Gaza, dejando al descubierto nuevas divisiones entre los legisladores sobre la ofensiva militar en el enclave palestino.El ministro de Seguridad Nacional, Itamar Ben\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443988,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/17\/la-retirada-de-algunas-tropas-israelies-de-gaza-genera-nuevas-divisiones-en-el-gobierno-de-netanyahu-3\/","url_meta":{"origin":1449503,"position":2},"title":"La retirada de algunas tropas israel\u00edes de Gaza genera nuevas divisiones en el Gobierno de Netanyahu","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN) -- Un ministro del gobierno israel\u00ed de extrema derecha critic\u00f3 la decisi\u00f3n de las fuerzas armadas de ese pa\u00eds de retirar una divisi\u00f3n del ej\u00e9rcito de Gaza, dejando al descubierto nuevas divisiones entre los legisladores sobre la ofensiva militar en el enclave palestino.El ministro de Seguridad Nacional, Itamar Ben\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467814,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/28\/netanyahu-ataque-gaza-trax\/","url_meta":{"origin":1449503,"position":3},"title":"Hamas dice que retrasar\u00e1 la entrega de rehenes tras orden de Netanyahu de lanzar ataques &#171;inmediatos y contundentes&#187; en Gaza","author":"","date":"octubre 28, 2025","format":false,"excerpt":"El primer ministro Benjamin Netanyahu orden\u00f3 este martes al ej\u00e9rcito israel\u00ed lanzar ataques \u201cinmediatos y contundentes\u201d en Gaza.\u201cAl concluir las consultas de seguridad, el primer ministro Netanyahu instruy\u00f3 a la c\u00fapula militar para que lanzara ataques inmediatos y contundentes en Gaza\u201d, declar\u00f3 la oficina del primer ministro en un breve\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449669,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/22\/netanyahu-niega-hambre-civiles-gaza-guerra-trax\/","url_meta":{"origin":1449503,"position":4},"title":"Netanyahu niega que est\u00e9 matando de hambre a civiles en Gaza como m\u00e9todo de guerra","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) -- El primer ministro de Israel, Benjamin Netanyahu, neg\u00f3 las acusaciones de que estaba matando de hambre a los palestinos en Gaza como m\u00e9todo de guerra en una entrevista con Jake Tapper de CNN el martes, diciendo que una solicitud de orden de detenci\u00f3n actualmente en revisi\u00f3n en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467256,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/10\/eeuu-personal-militar-plan-paz-gaza-trax\/","url_meta":{"origin":1449503,"position":5},"title":"EE.UU. env\u00eda al terreno 200 efectivos de las Fuerzas Armadas para supervisar el plan de Gaza, seg\u00fan un funcionario","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Estados Unidos establecer\u00e1 un centro de coordinaci\u00f3n militar en Israel para apoyar la campa\u00f1a de estabilizaci\u00f3n en Gaza, seg\u00fan un funcionario estadounidense.\u201cEl Comando Central de EE.UU. (CENTCOM) est\u00e1 estableciendo un Centro de Coordinaci\u00f3n Civil-Militar (CMCC) en Israel para apoyar los esfuerzos de estabilizaci\u00f3n en Gaza tras el anuncio del acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449503"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449503\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}