{"id":1449647,"date":"2024-05-21T14:03:40","date_gmt":"2024-05-21T21:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/"},"modified":"2024-05-21T14:03:40","modified_gmt":"2024-05-21T21:03:40","slug":"pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","title":{"rendered":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia"},"content":{"rendered":"<p>(CNN) &#8212; Una pluma de una ave de Nueva Zelandia extinta hace mucho tiempo bati\u00f3 un r\u00e9cord al venderse por 46.521 d\u00f3lares neozelandeses (unos US$ 28.400), seg\u00fan inform\u00f3 la casa de subastas que se encarg\u00f3 de la venta.<\/p>\n<p>La huia fue avistada oficialmente por \u00faltima vez a principios del siglo XX y sus plumas se hab\u00edan vendido anteriormente por hasta 8.400 d\u00f3lares neozelandeses (unos US$ 5.100), seg\u00fan la casa de subastas Webb&#8217;s.<\/p>\n<p>La pluma de huia, que se esperaba que se vendiera por 3.000 d\u00f3lares neozelandeses (US$ 1.830), super\u00f3 el lunes la estimaci\u00f3n y se convirti\u00f3 en la pluma m\u00e1s cara del mundo jam\u00e1s vendida, seg\u00fan la casa de subastas Webb.<\/p>\n<p>&#171;Esta rara pluma de huia es un bello ejemplo de la historia natural de Aotearoa y nos recuerda la fragilidad de nuestro ecosistema&#187;, declar\u00f3 en un comunicado Leah Morris, responsable de artes decorativas de la casa de subastas, con sede en Auckland.<\/p>\n<p>&#171;Popularidad letal&#187;<\/p>\n<p>Perteneciente a la familia de los p\u00e1jaros wattle, el huia era apreciado por mucha gente, lo que ultimadamente result\u00f3 fatal para la especie.<\/p>\n<p>Para los maor\u00edes, las plumas de esta ave eran un s\u00edmbolo de estatus y su caracter\u00edstico plumaje de puntas blancas se utilizaba en tocados ceremoniales. Seg\u00fan el Museo de Nueva Zelandia, solo los jefes pod\u00edan llevar plumas de huia en el pelo o pieles enteras en las orejas.<\/p>\n<p>Seg\u00fan la casa de subastas, las plumas se intercambiaban a menudo por otros bienes valiosos o se regalaban como muestra de amistad y respeto.<\/p>\n<p>Un jefe maor\u00ed lleva una pluma huia en el pelo. (Cr\u00e9dito: Bettmann Archive\/Getty Images)<\/p>\n<p>Los neozelandeses europeos tambi\u00e9n llegaron a ver en el huia un s\u00edmbolo de prestigio. Utilizaban las plumas del animal para accesorios de moda y los huia disecados se montaban como decoraci\u00f3n en las casas adineradas, seg\u00fan el Museo.<\/p>\n<p>Por qu\u00e9 Nueva Zelandia se gast\u00f3 una peque\u00f1a fortuna en matar a un \u00fanico y escurridizo depredador peludo<\/p>\n<p>El Museo explica que los cazadores maor\u00edes y europeos mataron al ave en &#171;grandes cantidades&#187; durante el siglo XIX, vendiendo la piel a coleccionistas y comerciantes de moda.<\/p>\n<p>La &#171;letal popularidad&#187; del huia creci\u00f3 a\u00fan m\u00e1s cuando el duque y la duquesa de York fueron fotografiados con plumas en el sombrero durante un viaje a Nueva Zelandia en 1901.<\/p>\n<p>&#171;La gente se volvi\u00f3 loca y decidi\u00f3 que todo el mundo quer\u00eda una pluma de huia&#187;, explica Morris.<\/p>\n<p>Tres aves huia pintadas por el artista neerland\u00e9s Johannes Keulemans, hacia 1900. (Cr\u00e9dito: Museo de Nueva Zelandia)<\/p>\n<p>A principios del siglo XX, los cient\u00edficos fracasaron en su intento de conservar los huia que quedaban. Seg\u00fan el Museo, un plan gubernamental para enviar las aves a islas lejanas hizo que quienes las recog\u00edan las vendieran como espec\u00edmenes muertos, a\u00f1adiendo que era m\u00e1s &#171;rentable&#187; que mantenerlas vivas.<\/p>\n<p>El reloj de oro que us\u00f3 el pasajero m\u00e1s rico del Titanic se vendi\u00f3 en subasta por la cifra r\u00e9cord de casi US$ 1,5 millones<\/p>\n<p>La casa de subastas se\u00f1al\u00f3 que todos los posibles compradores deb\u00edan presentar un permiso del Ministerio de Cultura y Patrimonio de Nueva Zelandia antes de la venta del lunes.<\/p>\n<p>Como objeto de importancia nacional, la pluma \u00fanicamente pod\u00eda ser adquirida por coleccionistas registrados y no pod\u00eda salir del pa\u00eds sin permiso del Ministerio.<\/p>\n<p>La venta sigue a la de una pareja victoriana de huia taxidermiados que se vendi\u00f3 por 457.704 d\u00f3lares neozelandeses (unos US$ 280.000) en una subasta en el Reino Unido el a\u00f1o pasado, seg\u00fan la casa de subastas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una pluma de una ave de Nueva Zelandia extinta hace mucho tiempo bati\u00f3 un r\u00e9cord al venderse por 46.521 d\u00f3lares neozelandeses (unos US$ 28.400), seg\u00fan inform\u00f3 la casa de subastas que se encarg\u00f3 de la venta. La huia fue avistada oficialmente por \u00faltima vez a principios del siglo XX y sus plumas se [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449647","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una pluma de una ave de Nueva Zelandia extinta hace mucho tiempo bati\u00f3 un r\u00e9cord al venderse por 46.521 d\u00f3lares neozelandeses (unos US$ 28.400), seg\u00fan inform\u00f3 la casa de subastas que se encarg\u00f3 de la venta. La huia fue avistada oficialmente por \u00faltima vez a principios del siglo XX y sus plumas se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T21:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia\",\"datePublished\":\"2024-05-21T21:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\",\"name\":\"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-21T21:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias","og_description":"(CNN) &#8212; Una pluma de una ave de Nueva Zelandia extinta hace mucho tiempo bati\u00f3 un r\u00e9cord al venderse por 46.521 d\u00f3lares neozelandeses (unos US$ 28.400), seg\u00fan inform\u00f3 la casa de subastas que se encarg\u00f3 de la venta. La huia fue avistada oficialmente por \u00faltima vez a principios del siglo XX y sus plumas se [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-21T21:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/"},"author":{"name":"","@id":""},"headline":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia","datePublished":"2024-05-21T21:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","name":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-21T21:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La pluma m\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/05\/21\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-21T21:03:40Z","datePublished":"2024-05-21T21:03:40Z","dateModified":"2024-05-21T21:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La pluma m\\u00e1s cara del mundo se vende en una subasta en Nueva Zelandia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/21\\\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/05\\\/21\\\/pluma-mas-cara-se-vende-subasta-nueva-zelandia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-21T21:03:40Z\",\"datePublished\":\"2024-05-21T21:03:40Z\",\"dateModified\":\"2024-05-21T21:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452402,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/03\/nueva-zelandia-triplica-impuesto-turistas-trax\/","url_meta":{"origin":1449647,"position":0},"title":"Nueva Zelandia triplica su impuesto al turismo","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) -- A partir de ahora ser\u00e1 m\u00e1s caro visitar los lagos, las monta\u00f1as, las rutas en bicicleta y las bodegas de Nueva Zelandia, ya que el pa\u00eds va a aumentar su tasa tur\u00edstica y de conservaci\u00f3n para visitantes internacionales (IVL) de 35 d\u00f3lares neozelandeses (US$ 22) a 100 d\u00f3lares\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466086,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/02\/observologos-caracol-raro-nueva-zelandia-cte-llamado-tierra\/","url_meta":{"origin":1449647,"position":1},"title":"&#171;Observ\u00f3logos&#187; buscan darle a un caracol raro una oportunidad en el amor en Nueva Zelandia","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"Desde un peque\u00f1o jard\u00edn en Nueva Zelandia, aparece un caracol solitario en busca de amor.Ned es el yin del yang de otro molusco, pero encontrarle pareja se ha convertido en un esfuerzo a nivel nacional.La raz\u00f3n es que la concha de Ned se enrolla hacia la izquierda, mientras que casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465633,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/19\/familia-padre-profugo-pide-vuelva-nueva-zelandia-trax\/","url_meta":{"origin":1449647,"position":2},"title":"Familia de un padre que lleva casi cuatro a\u00f1os pr\u00f3fugo en una zona salvaje con sus hijos peque\u00f1os lo urge a volver a casa","author":"","date":"agosto 19, 2025","format":false,"excerpt":"La familia de un padre fugitivo que lleva casi cuatro a\u00f1os escondiendo a sus tres hijos en la densa selva de Nueva Zelandia habl\u00f3 p\u00fablicamente por primera vez desde su desaparici\u00f3n.Thomas Callam Phillips desapareci\u00f3 con sus hijos en diciembre de 2021 y, a pesar de varios avistamientos, peticiones de ayuda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470902,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/05\/valor-medallas-juegos-olimpicos-invierno-2026-trax\/","url_meta":{"origin":1449647,"position":3},"title":"Juegos Ol\u00edmpicos de Invierno 2026: \u00bfpor qu\u00e9 las medallas de este a\u00f1o valen m\u00e1s que nunca?","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Los atletas que suban al podio en los Juegos Ol\u00edmpicos de Invierno en Italia este mes recibir\u00e1n las medallas m\u00e1s caras en la historia de los Juegos, gracias al vertiginoso aumento de los precios de los metales preciosos.Se entregar\u00e1n m\u00e1s de 700 medallas de oro, plata y bronce a los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448477,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/24\/retrato-klimt-desaparecido-casi-siglo-se-vende-us-32-millones-trax\/","url_meta":{"origin":1449647,"position":4},"title":"Un retrato de Klimt desaparecido durante casi un siglo se vende por US$ 32 millones","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) -- Un retrato de Gustav Klimt que no se hab\u00eda visto en casi un siglo se vendi\u00f3 por US$ 32 millones, la cifra m\u00e1s baja de su estimaci\u00f3n previa a la subasta.El \"Retrato de la se\u00f1orita Lieser\", que se cree una de las \u00faltimas obras del pintor austriaco, gener\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459584,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/06\/venden-camisetas-nba-jordan-kobe-bryant-trax\/","url_meta":{"origin":1449647,"position":5},"title":"Se espera que las primeras camisetas de la NBA de Michael Jordan y Kobe Bryant se vendan por US$ 10 millones cada una","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Las camisetas usadas por Michael Jordan y Kobe Bryant en los primeros partidos de la NBA de sus carreras podr\u00edan venderse por millones de d\u00f3lares cuando salgan a subasta esta primavera.Representando los \u201chumildes comienzos\u201d de las leyendas del baloncesto, se espera que se vendan por un total de US$ 20\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1449647"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1449647\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1449647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1449647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1449647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}