{"id":1455117,"date":"2024-10-15T17:03:38","date_gmt":"2024-10-16T00:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/"},"modified":"2024-10-15T17:03:38","modified_gmt":"2024-10-16T00:03:38","slug":"oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","title":{"rendered":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El equipo electoral de la mayor\u00eda de la oposici\u00f3n venezolana, Comando con Venezuela, present\u00f3 este martes ante la Organizaci\u00f3n de los Estados Americanos (OEA) un informe en el que, asegura, se comprueba que los resultados de la elecci\u00f3n presidencial del 28 de julio dan la victoria al candidato Edmundo Gonz\u00e1lez Urrutia.<\/p>\n<p>El documento se dio a conocer d\u00edas despu\u00e9s de que la Sala Constitucional del Tribunal Supremo de Justicia de Venezuela ratific\u00f3 la sentencia de la Sala Electoral que valid\u00f3 la proclamaci\u00f3n del presidente Nicol\u00e1s Maduro como ganador de la contienda, que ha sido cuestionada por gran parte de la comunidad internacional por su falta de transparencia.<\/p>\n<p>\u201cCada una de estas actas demuestran que el triunfo de Edmundo Gonz\u00e1lez Urrutia es irreversible. \u00bfPor qu\u00e9 hay una irreversibilidad de la victoria del candidato Edmundo Gonz\u00e1lez Urrutia? Porque nosotros tenemos el 83,5% de las actas digitalizadas, procesadas y en la p\u00e1gina web&#187;, explic\u00f3 Gustavo Silva, miembro del equipo electoral.<\/p>\n<p>Misi\u00f3n de la ONU denuncia\u00a0cr\u00edmenes de lesa humanidad\u00a0en Venezuela durante el periodo electoral 2024<\/p>\n<p>Seg\u00fan Silva, incluso si el total de los votantes que corresponden al 16,5% de las actas que no tiene la oposici\u00f3n hubiera votado por Maduro completamente, a\u00fan as\u00ed se mantendr\u00eda la victoria de Gonz\u00e1lez porque \u2014de acuerdo con sus cifras\u2014 la diferencia entre el opositor y Maduro es de m\u00e1s de 3,9 millones de votos y los correspondientes a las actas no publicadas s\u00f3lo equivalen a unos 3,1 millones.<\/p>\n<p>El Consejo Nacional Electoral de Venezuela (CNE), controlado por el chavismo, dice que Maduro gan\u00f3 con 51,95% de los votos por 43,18% de Gonz\u00e1lez, aunque hasta ahora no ha publicado resultados desglosados por centro y mesa de votaci\u00f3n. CNN contact\u00f3 este martes al organismo para pedir comentarios sobre el informe del Comando con Venezuela y espera respuesta.<\/p>\n<p>La oposici\u00f3n argumenta que obtuvo el 83,5% de las actas a trav\u00e9s de sus testigos electorales el d\u00eda de las elecciones. CNN no ha conseguido las actas de forma independiente, pero expertos consultados han dicho que sus n\u00fameros cuadran de forma matem\u00e1tica y estad\u00edstica. En contraste, el gobierno de Maduro los ha descalificado.<\/p>\n<p>La presentaci\u00f3n del informe de la oposici\u00f3n fue transmitida en el perfil de Instagram de Comando con Venezuela. En un comunicado publicado posteriormente, la plataforma Vente Venezuela difundi\u00f3 las palabras de Silva, quien pidi\u00f3 a los miembros de la OEA que defendieran el derecho a la democracia.<\/p>\n<p>Edmundo Gonz\u00e1lez Urrutia se reuni\u00f3 con el rector del CNE Juan Delpino<\/p>\n<p>La oposici\u00f3n pide al organismo ejercer presi\u00f3n entre la comunidad internacional para que no se concrete lo que considera un fraude y evitar que Maduro inicie otro mandato el 10 de enero.<\/p>\n<p>\u201cNo permitan que la mentira triunfe sobre la verdad. No vac\u00eden de sentido nuestra lucha, que es la lucha de todos los dem\u00f3cratas de Am\u00e9rica. Honremos m\u00e1s bien ese esp\u00edritu americano, que siempre defendi\u00f3 con la vida el ideal republicano. Honremos la Carta Democr\u00e1tica Interamericana, que reza en su art\u00edculo 1: Los pueblos de Am\u00e9rica tienen derecho a la democracia y sus gobiernos la obligaci\u00f3n de promoverla y defenderla\u201d, dijo Silva este martes.<\/p>\n<p>La OEA previamente ha llamado a Venezuela a publicar todas las actas electorales y ha respaldado se\u00f1alamientos de instancias como el Centro Carter, que recientemente particip\u00f3 en una sesi\u00f3n del organismo regional e insisti\u00f3 en que el pa\u00eds sudamericano no tuvo elecciones libres. Desde el gobierno venezolano, Maduro y otros l\u00edderes del oficialismo han rechazado estos se\u00f1alamientos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El equipo electoral de la mayor\u00eda de la oposici\u00f3n venezolana, Comando con Venezuela, present\u00f3 este martes ante la Organizaci\u00f3n de los Estados Americanos (OEA) un informe en el que, asegura, se comprueba que los resultados de la elecci\u00f3n presidencial del 28 de julio dan la victoria al candidato Edmundo Gonz\u00e1lez Urrutia. El [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1455117","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El equipo electoral de la mayor\u00eda de la oposici\u00f3n venezolana, Comando con Venezuela, present\u00f3 este martes ante la Organizaci\u00f3n de los Estados Americanos (OEA) un informe en el que, asegura, se comprueba que los resultados de la elecci\u00f3n presidencial del 28 de julio dan la victoria al candidato Edmundo Gonz\u00e1lez Urrutia. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-16T00:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales\",\"datePublished\":\"2024-10-16T00:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\"},\"wordCount\":649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\",\"name\":\"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-16T00:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El equipo electoral de la mayor\u00eda de la oposici\u00f3n venezolana, Comando con Venezuela, present\u00f3 este martes ante la Organizaci\u00f3n de los Estados Americanos (OEA) un informe en el que, asegura, se comprueba que los resultados de la elecci\u00f3n presidencial del 28 de julio dan la victoria al candidato Edmundo Gonz\u00e1lez Urrutia. El [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","og_site_name":"Noticias","article_published_time":"2024-10-16T00:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/"},"author":{"name":"","@id":""},"headline":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales","datePublished":"2024-10-16T00:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","url":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","name":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-16T00:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Oposici\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\u00e1lez en las elecciones presidenciales","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/15\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-16T00:03:38Z","datePublished":"2024-10-16T00:03:38Z","dateModified":"2024-10-16T00:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Oposici\\u00f3n venezolana presenta ante la OEA informe que reitera victoria de Edmundo Gonz\\u00e1lez en las elecciones presidenciales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/15\\\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/15\\\/oposicion-venezuela-informe-oea-elecciones-edmundo-gonzalez-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-16T00:03:38Z\",\"datePublished\":\"2024-10-16T00:03:38Z\",\"dateModified\":\"2024-10-16T00:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1454940,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/04\/edmundo-gonzalez-urrutia-salida-venezuela-temporal-orix\/","url_meta":{"origin":1455117,"position":0},"title":"Edmundo Gonz\u00e1lez Urrutia: \u201cMi salida de Venezuela es solo temporal\u201d","author":"","date":"octubre 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El l\u00edder opositor venezolano, Edmundo Gonz\u00e1lez, se\u00f1al\u00f3 este viernes en el marco del Foro La Toja, un espacio de debate pol\u00edtico que se celebra en el noroeste de Espa\u00f1a, que a pesar de haber dejado Venezuela como consecuencia de \u201cpresiones inenarrables y amenazas extremas\u201d, su \u201csalida del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455927,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/19\/estados-unidos-reconoce-edmundo-gonzalez-presidente-electo-venezuela-trax\/","url_meta":{"origin":1455117,"position":1},"title":"EE.UU. reconoce a Edmundo Gonz\u00e1lez como presidente electo de Venezuela","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) --\u00a0Estados Unidos reconoci\u00f3 formalmente al l\u00edder opositor venezolano Edmundo Gonz\u00e1lez como presidente electo del pa\u00eds tras las elecciones presidenciales del 28 de julio, anunci\u00f3 este martes en X el secretario de Estado, Antony Blinken.\"El pueblo venezolano habl\u00f3 rotundamente el 28 de julio e hizo presidente electo a Edmundo Gonz\u00e1lez.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451532,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/31\/autoridades-venezuela-saben-edmundo-gonzalez-representante-eeuu-orix\/","url_meta":{"origin":1455117,"position":2},"title":"Las autoridades de Venezuela saben que Edmundo Gonz\u00e1lez \u201cclaramente\u201d gan\u00f3 la elecci\u00f3n, dice representante de EE.UU.","author":"","date":"julio 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El secretario de Estado adjunto de Estados Unidos para asuntos del hemisferio occidental, Brian Nichols, dijo este mi\u00e9rcoles que las autoridades de Venezuela \u201csaben\u201d que el candidato presidencial de la mayor\u00eda opositora, Edmundo Gonz\u00e1lez Urrutia, \u201cclaramente\u201d gan\u00f3 las elecciones del domingo pasado, en las que \u00e9l y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452457,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/05\/presidente-consejo-ministros-peru-edmundo-gonzalez-venezuela-orix\/","url_meta":{"origin":1455117,"position":3},"title":"Presidente del Consejo de Ministros de Per\u00fa afirma que Edmundo Gonz\u00e1lez no es el presidente electo de Venezuela","author":"","date":"septiembre 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente del Consejo de Ministros de Per\u00fa, Gustavo Adrianz\u00e9n, neg\u00f3 este jueves que su pa\u00eds haya reconocido a Edmundo Gonz\u00e1lez Urrutia como presidente electo de Venezuela y desautoriz\u00f3 lo que hab\u00eda dicho el entonces canciller Javier Gonz\u00e1lez-Olaechea tras las elecciones.En declaraciones al medio local RPP, Adrianz\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457367,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/01\/08\/maduro-edmundo-gonzalez-urrutia-posesion-presidencia-orix\/","url_meta":{"origin":1455117,"position":4},"title":"As\u00ed lleg\u00f3 Venezuela a este punto: tanto Maduro como Gonz\u00e1lez Urrutia apuntan a tomar posesi\u00f3n de la Presidencia","author":"","date":"enero 8, 2025","format":false,"excerpt":"El 10 de enero, seg\u00fan la Constituci\u00f3n de Venezuela, comienza el nuevo per\u00edodo de gobierno, pero la controversia por los resultados de la elecci\u00f3n del 28 de julio se mantiene viva. Tanto Nicol\u00e1s Maduro como Edmundo Gonz\u00e1lez aseguran que prestar\u00e1n juramento este viernes. \u00bfC\u00f3mo lleg\u00f3 Venezuela a este punto?El Poder\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456407,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/09\/edmundo-gonzalez-anuncia-maria-corina-machado-vicepresidenta-orix\/","url_meta":{"origin":1455117,"position":5},"title":"Edmundo Gonz\u00e1lez anuncia que Mar\u00eda Corina Machado ser\u00e1 su vicepresidenta en Venezuela","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Edmundo Gonz\u00e1lez insiste, desde Madrid, en que asumir\u00e1 la Presidencia de Venezuela el 10 de enero. Y no piensa hacerlo solo. En una entrevista concedida al diario espa\u00f1ol El Pa\u00eds este fin de semana anunci\u00f3 que Mar\u00eda Corina Machado ser\u00e1 su vicepresidenta.\u201cLa determinaci\u00f3n es estar en Venezuela para tomar posesi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1455117"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455117\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1455117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1455117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1455117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}