{"id":1455160,"date":"2024-10-16T14:03:40","date_gmt":"2024-10-16T21:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/"},"modified":"2024-10-16T14:03:40","modified_gmt":"2024-10-16T21:03:40","slug":"elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","title":{"rendered":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump"},"content":{"rendered":"<p>(CNN) &#8212; Algunas de las figuras m\u00e1s ricas del mundo, lideradas por la donante conservadora Miriam Adelson y el multimillonario tecnol\u00f3gico Elon Musk, han canalizado decenas de millones de d\u00f3lares a grupos pol\u00edticos en los \u00faltimos meses para impulsar la candidatura de Donald Trump a la Casa Blanca, seg\u00fan muestran nuevos informes presentados el martes ante los reguladores federales.<\/p>\n<p>Musk, la persona m\u00e1s rica del mundo, don\u00f3 casi US$ 75 millones a un s\u00faper PAC pro-Trump que ayud\u00f3 a formar en los \u00faltimos meses, una inyecci\u00f3n masiva de efectivo destinada a ayudar a que los votantes voten en estados clave en disputa. Adelson, una fiel partidaria de Trump y heredera de una fortuna en casinos, dio a\u00fan m\u00e1s, invirtiendo US$ 95 millones en otro grupo externo que respalda al expresidente, seg\u00fan los documentos presentados ante la Comisi\u00f3n Federal Electoral correspondientes a los tres meses que terminaron el 30 de septiembre.<\/p>\n<p>En total, solo tres multimillonarios (Musk, Adelson y el magnate del embalaje del Medio Oeste Richard Uihlein) donaron aproximadamente US$ 220 millones en un per\u00edodo de tres meses a grupos que respaldan la candidatura del republicano.<\/p>\n<p>Sus asombrosas donaciones dejan en evidencia el papel crucial que desempe\u00f1a un pu\u00f1ado de megadonantes multimillonarios en los intentos de Trump por superar a su rival dem\u00f3crata, la vicepresidenta Kamala Harris, a medida que la campa\u00f1a se ha intensificado.<\/p>\n<p>\u00bfQu\u00e9 propone Kamala Harris en materia de inmigraci\u00f3n de cara a las elecciones de EE.UU.?<\/p>\n<p>Harris ha establecido un ritmo vertiginoso: ha recaudado mil millones de d\u00f3lares desde que se convirti\u00f3 en la abanderada dem\u00f3crata a fines de julio, un hito alcanzado m\u00e1s r\u00e1pido que cualquier otro candidato presidencial. Y los documentos presentados el martes muestran que un comit\u00e9 de recaudaci\u00f3n de fondos de alto valor que canaliza dinero a su campa\u00f1a y a comit\u00e9s dem\u00f3cratas alineados, recaud\u00f3 US$ 633 millones durante el tercer trimestre, cuatro veces la cantidad recaudada por el brazo de recaudaci\u00f3n de fondos equivalente de Trump en ese per\u00edodo.<\/p>\n<p>Pero el equipo de Harris ha implorado a sus partidarios que env\u00eden a\u00fan m\u00e1s, debido tanto al respaldo multimillonario a la candidatura de Trump como a la lucha de su campa\u00f1a por llegar a los votantes a\u00fan indecisos en los estados en disputa que esperan que se inclinen por la vicepresidenta en el sprint final hacia el d\u00eda de las elecciones.<\/p>\n<p>Mientras tanto, en la batalla por el control del Congreso, los candidatos dem\u00f3cratas individuales en algunas contiendas clave para el Senado y la C\u00e1mara de Representantes ampliaron su ventaja financiera sobre sus oponentes republicanos. Los donantes republicanos adinerados tambi\u00e9n intentaron cerrar la brecha al impulsar un s\u00faper PAC republicano para apoderarse de la mayor\u00eda en el Senado.<\/p>\n<p>Elon Musk, CEO de Tesla, habla durante un mitin de campa\u00f1a de Donald Trumo en Butler, Pensilvania, el 5 de octubre de 2024. (Brian Snyder\/Reuters\/Archivo)<\/p>\n<p>A continuaci\u00f3n, se presentan algunas conclusiones clave de los documentos presentados:<\/p>\n<p>Los multimillonarios respaldan el regreso de Trump a la Casa Blanca<\/p>\n<p>Musk ha surgido como una fuerza importante en el intento de Trump de regresar a la Casa Blanca. America PAC, el s\u00faper PAC que Musk financia, ha desatado una operaci\u00f3n masiva de tocar puerta a puerta en estados como Pensilvania en nombre de Trump, aunque la estrategia de una campa\u00f1a presidencial que externaliza su operaci\u00f3n de campo en gran medida no se ha probado.<\/p>\n<p>Seg\u00fan los documentos presentados durante el fin de semana, America PAC inform\u00f3 haber gastado casi US$ 96 millones en la carrera presidencial, incluidos poco menos de US$ 57 millones en operaciones de campa\u00f1a y de campo.<\/p>\n<p>El nuevo documento presentado por America PAC detalla siete contribuciones separadas de Musk que totalizaron cerca de US$ 75 millones entre principios de julio y fines de septiembre, lo que marca las primeras contribuciones que Musk ha hecho al grupo. Recibi\u00f3 su financiaci\u00f3n inicial de una red de antiguos socios y asociados comerciales del multimillonario.<\/p>\n<p>Sin embargo, Musk fue su \u00fanico donante durante el tercer trimestre.<\/p>\n<p>Seg\u00fan sus informes de gastos independientes, que cubren algunos gastos posteriores al 30 de septiembre, America PAC ha asumido un papel de apoyo fundamental para la campa\u00f1a de Trump. Adem\u00e1s de la contienda presidencial, el grupo tambi\u00e9n ha gastado millones en varias contiendas muy competitivas para la C\u00e1mara de Representantes, incluidas las contiendas en California y Nueva York, consideradas clave para que los republicanos conserven su control de la c\u00e1mara.<\/p>\n<p>Los informes del martes muestran que otros multimillonarios conservadores tambi\u00e9n han invertido sumas extraordinarias en la campa\u00f1a por la reelecci\u00f3n de Trump.<\/p>\n<p>Los US$ 95 millones de Adelson se destinaron a otro importante super PAC pro-Trump, Preserve America, lo que representa pr\u00e1cticamente todo el dinero que recaud\u00f3 durante el trimestre de julio a septiembre. Adelson y su difunto esposo, Sheldon, estuvieron entre los mayores donantes a candidatos y causas republicanas en la \u00faltima d\u00e9cada, y ella le ha dado al grupo un total de US$ 100 millones en lo que va del a\u00f1o.<\/p>\n<p>Preserve America ha gastado casi todo lo que recaud\u00f3 en el tercer trimestre y ha gastado casi US$ 92 millones en gastos independientes, principalmente en anuncios publicitarios.<\/p>\n<p>Los datos de publicidad muestran que Preserve America todav\u00eda tiene reservados unos US$ 29 millones en tiempo publicitario para el mes de octubre hasta el d\u00eda de las elecciones, incluso para impulsar la campa\u00f1a de Trump en los estados clave de Michigan y Wisconsin.<\/p>\n<p>Una mujer se toma una selfie durante el mitin de campa\u00f1a de Kamala Harris el 13 de septiembre en Pensilvania. Cr\u00e9dito: Aimee Dilger\/SOPA Images\/LightRocket\/Getty Images.<\/p>\n<p>Otro importante super PAC pro-Trump, Restoration PAC, tambi\u00e9n inform\u00f3 de una enorme recaudaci\u00f3n de un \u00fanico donante importante. Uihlein don\u00f3 unos US$ 49 millones al grupo en el tercer trimestre. En total, Uihlein ha donado casi US$ 59 millones este a\u00f1o a Restoration PAC, que actualmente est\u00e1 gastando millones en aire en los estados en disputa de Pensilvania, Wisconsin y Georgia.<\/p>\n<p>Otros partidarios de Trump que contribuyeron con grandes sumas durante el tercer trimestre incluyeron al multimillonario ex ejecutivo de Marvel Ike Perlmutter y su esposa, Laura, que donaron casi US$ 5 millones a finales del mes pasado al super PAC pro-Trump Right for America.<\/p>\n<p>Harris tambi\u00e9n se ha beneficiado de un importante esfuerzo externo financiado por donantes de mucho dinero.<\/p>\n<p>FF PAC, el principal super PAC que respalda la campa\u00f1a de la vicepresidenta, ha comprado un total de US$ 371 millones en tiempo publicitario desde principios de 2023, seg\u00fan datos de AdImpact, incluso para apoyar al presidente Biden antes de que pusiera fin a su campa\u00f1a de reelecci\u00f3n en julio. Es el mayor anunciante externo individual en la carrera presidencial.<\/p>\n<p>FF PAC revelar\u00e1 su actividad de recaudaci\u00f3n de fondos y gastos de septiembre el domingo. Pero hasta finales de agosto, seg\u00fan sus presentaciones m\u00e1s recientes, el grupo hab\u00eda informado de que hab\u00eda recaudado m\u00e1s de US$ 200 millones en este ciclo electoral, incluidos US$ 19 millones recibidos del multimillonario ex alcalde de Nueva York Michael Bloomberg y US$ 10 millones del cofundador de LinkedIn Reid Hoffman.<\/p>\n<p>M\u00e1s cambios de roles<\/p>\n<p>Trump 47, un comit\u00e9 de recaudaci\u00f3n de fondos conjunto que recauda donaciones de alto valor que se destinan a la campa\u00f1a del expresidente y a una serie de comit\u00e9s republicanos, recibi\u00f3 donaciones de seis cifras durante el tercer trimestre de algunos nombres destacados, entre ellos Steve Mnuchin, que se desempe\u00f1\u00f3 como secretario del Tesoro de Trump, y Dana White, amigo de Trump desde hace mucho tiempo y director ejecutivo de Ultimate Fighting Championship. White tuvo un papel destacado como orador en la Convenci\u00f3n Nacional Republicana durante el verano.<\/p>\n<p>El comit\u00e9 Trump 47 recaud\u00f3 US$ 145 millones durante el tercer trimestre y comenz\u00f3 octubre con casi US$ 53 millones restantes en sus cuentas.<\/p>\n<p>Los documentos presentados el martes muestran que Trump 47 pag\u00f3 la factura en los \u00faltimos meses de algunos gastos de campa\u00f1a tradicionales, como alquileres de instalaciones. El comit\u00e9 ayud\u00f3 a financiar al menos US$ 15,8 millones en costos de viajes y eventos, lo que ayud\u00f3 a liberar recursos en la cuenta principal de campa\u00f1a de Trump para gastar en publicidad en su batalla contra una rival mejor financiada. Solo en agosto, los gastos de publicidad representaron m\u00e1s de 3 de cada 4 d\u00f3lares gastados por el principal comit\u00e9 de campa\u00f1a de Trump.<\/p>\n<p>En la noche de este mi\u00e9rcoles, el expresidente tiene previsto presidir un acto de recaudaci\u00f3n de fondos para Trump 47 en su resort Mar-a-Lago en Florida. Los principales donantes del evento contribuyeron o recaudaron el m\u00e1ximo de US$ 924.600 cada uno, seg\u00fan una copia de la invitaci\u00f3n obtenida por CNN.<\/p>\n<p>Los grandes donantes tambi\u00e9n aportan en la lucha por el Congreso<\/p>\n<p>Los principales super PAC que apuntalan a las carreras del Senado informaron enormes totales de recaudaci\u00f3n de fondos en el tercer trimestre, con la estrecha mayor\u00eda de los dem\u00f3cratas en juego.<\/p>\n<p>El Senado Majority PAC, un importante super PAC dem\u00f3crata alineado con el l\u00edder de la mayor\u00eda Chuck Schumer, recaud\u00f3 m\u00e1s de US$ 119 millones durante el tercer trimestre, un r\u00e9cord para el grupo, superando los aproximadamente US$ 116 millones recaudados por su contraparte republicana, el Fondo de Liderazgo del Senado.<\/p>\n<p>El Senado Majority PAC recibi\u00f3 US$ 30 millones de una organizaci\u00f3n de dinero oscuro dem\u00f3crata, Majority Forward, junto con contribuciones de siete cifras de algunos de los principales partidarios ricos del partido, incluido el gobernador de Illinois JB Pritzker (US$ 2,5 millones), el ex CEO de Google Eric Schmidt (US$ 2 millones) y el cofundador de Netflix Reed Hastings (poco menos de US$ 2 millones).<\/p>\n<p>Los recibos del Fondo de Liderazgo del Senado tambi\u00e9n mostraron que algunos de los principales donantes a los candidatos y causas republicanas abrieron sus billeteras. Entre ellos se encontraban el director ejecutivo de Citadel, Ken Griffin (US$ 20 millones, lo que eleva su total anual a US$ 27,5 millones), el codirector ejecutivo de Elliott Management, Paul Singer (US$ 10 millones, lo que eleva su total anual a 20 millones) y el director ejecutivo de Blackstone Group, Stephen Schwarzman (US$ 9 millones).<\/p>\n<p>Adem\u00e1s, Miriam Adelson don\u00f3 al fondo US$ 5 millones en el tercer trimestre, lo que elev\u00f3 su contribuci\u00f3n anual al grupo a US$ 15 millones.<\/p>\n<p>Mientras tanto, el Congressional Leadership Fund (el principal super PAC que apoya a los republicanos de la C\u00e1mara de Representantes) recaud\u00f3 m\u00e1s de US$ 81 millones en el tercer trimestre. Timothy Mellon, el solitario megadonante republicano, don\u00f3 US$ 5 millones al grupo, y Adelson dio US$ 4 millones adicionales. El grupo entr\u00f3 en octubre con casi US$ 153 millones disponibles.<\/p>\n<p>Su hom\u00f3logo dem\u00f3crata, House Majority PAC, presenta sus candidaturas mensualmente y recaud\u00f3 casi US$ 20 millones en julio y uS$ 11,5 millones en agosto, y dijo que recaud\u00f3 US$ 69 millones en septiembre, seg\u00fan The New York Times.<\/p>\n<p>Los dem\u00f3cratas del Senado dan su \u00faltima batalla<\/p>\n<p>Con la casi certeza de que los republicanos ganar\u00e1n el esca\u00f1o del Senado de Virginia Occidental, los dem\u00f3cratas que esperan mantener su mayor\u00eda en la c\u00e1mara no pueden darse el lujo de perder otro esca\u00f1o si Harris termina ganando la presidencia. Su m\u00e1xima prioridad es defender a dos incumbentes vulnerables de estados republicanos: el senador de Montana Jon Tester y el senador de Ohio Sherrod Brown. Los donantes han respondido en consecuencia.<\/p>\n<p>Ning\u00fan candidato al Senado, incumbente o contrincante, recaud\u00f3 m\u00e1s que Tester. El granjero de Montana recaud\u00f3 US$ 32 millones en el tercer trimestre y entr\u00f3 en octubre con m\u00e1s de US$ 7 millones en mano. Su contrincante republicano, el SEAL retirado de la Marina Tim Sheehy, recaud\u00f3 alrededor de US$ 10 millones y ten\u00edaUS$\u00a0 4 millones.<\/p>\n<p>Brown recaud\u00f3 la asombrosa cantidad de US$ 31 millones, un aumento considerable respecto de los 13 millones que recaud\u00f3 en el segundo trimestre, y termin\u00f3 el trimestre con m\u00e1s de 4 millones en el banco. Su oponente republicano, el empresario Bernie Moreno, recaud\u00f3 US$ 6,5 millones y entr\u00f3 en octubre con US$ 3 millones en mano.<\/p>\n<p>Los candidatos dem\u00f3cratas en Michigan, Pensilvania, Arizona y Maryland \u2013todos ellos estados que figuran en la lista de CNN de los principales esca\u00f1os del Senado con m\u00e1s probabilidades de ser reelegidos\u2013 recaudaron fondos en el tercer trimestre por un margen significativo.<\/p>\n<p>En Wisconsin, un estado en disputa, el banquero republicano Eric Hovde, que se enfrenta a la senadora dem\u00f3crata Tammy Baldwin, prest\u00f3 a su campa\u00f1a US$ 7 millones en el tercer trimestre, lo que elev\u00f3 su total de autofinanciaci\u00f3n a 20 millones de d\u00f3lares. Baldwin, por su parte, recaud\u00f3 m\u00e1s de US$ 13 millones en el per\u00edodo de tres meses.<\/p>\n<p>Y en Texas \u2013una rara oportunidad potencial de repunte para los dem\u00f3cratas\u2013 el representante Colin Allred, el candidato dem\u00f3crata, inund\u00f3 al senador republicano Ted Cruz, que lleva dos mandatos, recaudando US$ 30 millones de d\u00f3lares frente a unos US$ 18 millones en el tercer trimestre. Cruz, sin embargo, comenz\u00f3 octubre con una enorme ventaja en efectivo.<\/p>\n<p>Los dem\u00f3cratas de la C\u00e1mara de Representantes tienen ventaja en efectivo en las contiendas clave<\/p>\n<p>En la batalla por la C\u00e1mara de Representantes, donde los republicanos est\u00e1n defendiendo una mayor\u00eda muy estrecha, los candidatos dem\u00f3cratas entraron en la recta final de la campa\u00f1a en una mejor posici\u00f3n financiera.<\/p>\n<p>En 32 distritos que Inside Elections con Nathan L. Gonzales califica como &#171;empatados&#187; o inclinados hacia un partido, los dem\u00f3cratas, en promedio, recaudaron US$ 2,6 millones y ten\u00edan alrededor de US$ 1,8 millones en efectivo a mano al entrar en octubre. El candidato republicano promedio recaud\u00f3 alrededor de US$ 1,1 millones y le quedaban US$ 1,4 millones para gastar en las \u00faltimas semanas de la contienda. (Los promedios no incluyeron a un par de candidatos de California \u2013 el dem\u00f3crata Adam Gray en el Distrito 13 y la representante republicana Michelle Steel en el Distrito 45 \u2013 cuyos informes de recaudaci\u00f3n de fondos no estaban disponibles justo despu\u00e9s de la medianoche del mi\u00e9rcoles.)<\/p>\n<p>Algunos candidatos en las 32 contiendas se destacaron por informar ganancias trimestrales que no se ven habitualmente en las contiendas de la C\u00e1mara de Representantes. En el s\u00e9ptimo distrito de Virginia, el dem\u00f3crata Eugene Vindman (hermano gemelo de un testigo estrella en el primer juicio pol\u00edtico a Trump) recaud\u00f3 la asombrosa suma de US$ 6,5 millones en el tercer trimestre. La candidata a la C\u00e1mara de Representantes que m\u00e1s se acerc\u00f3 a Vindman fue la representante de Alaska Mary Peltola, que recaud\u00f3 unos US$ 4 millones en el mismo per\u00edodo.<\/p>\n<p>Kristen Holmes de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Algunas de las figuras m\u00e1s ricas del mundo, lideradas por la donante conservadora Miriam Adelson y el multimillonario tecnol\u00f3gico Elon Musk, han canalizado decenas de millones de d\u00f3lares a grupos pol\u00edticos en los \u00faltimos meses para impulsar la candidatura de Donald Trump a la Casa Blanca, seg\u00fan muestran nuevos informes presentados el martes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1455160","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Algunas de las figuras m\u00e1s ricas del mundo, lideradas por la donante conservadora Miriam Adelson y el multimillonario tecnol\u00f3gico Elon Musk, han canalizado decenas de millones de d\u00f3lares a grupos pol\u00edticos en los \u00faltimos meses para impulsar la candidatura de Donald Trump a la Casa Blanca, seg\u00fan muestran nuevos informes presentados el martes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-16T21:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump\",\"datePublished\":\"2024-10-16T21:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\"},\"wordCount\":2507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\",\"name\":\"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-16T21:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias","og_description":"(CNN) &#8212; Algunas de las figuras m\u00e1s ricas del mundo, lideradas por la donante conservadora Miriam Adelson y el multimillonario tecnol\u00f3gico Elon Musk, han canalizado decenas de millones de d\u00f3lares a grupos pol\u00edticos en los \u00faltimos meses para impulsar la candidatura de Donald Trump a la Casa Blanca, seg\u00fan muestran nuevos informes presentados el martes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","og_site_name":"Noticias","article_published_time":"2024-10-16T21:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/"},"author":{"name":"","@id":""},"headline":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump","datePublished":"2024-10-16T21:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/"},"wordCount":2507,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","url":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","name":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-16T21:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\u00f1a de Trump","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-16T21:03:40Z","datePublished":"2024-10-16T21:03:40Z","dateModified":"2024-10-16T21:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Elon Musk y otros multimillonarios donaron unos US$ 220 millones a la campa\\u00f1a de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/elon-musk-multimillonarios-donan-us-220-millones-campana-de-trump\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-16T21:03:40Z\",\"datePublished\":\"2024-10-16T21:03:40Z\",\"dateModified\":\"2024-10-16T21:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452909,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/21\/recaudacion-de-fondos-harris-trump-elon-musk-trax\/","url_meta":{"origin":1455160,"position":0},"title":"Elon Musk le da un gran cheque a los republicanos de la C\u00e1mara de Representantes, seg\u00fan nuevos archivos","author":"","date":"septiembre 21, 2024","format":false,"excerpt":"(CNN) --Kamala Harris entr\u00f3 en septiembre -y en las \u00faltimas semanas de la campa\u00f1a presidencial- con bastante m\u00e1s dinero disponible que Donald Trump, seg\u00fan muestran los nuevos datos federales, tras batir un r\u00e9cord de recaudaci\u00f3n de fondos durante su primer mes completo como candidata presidencial dem\u00f3crata.La recaudaci\u00f3n de fondos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456065,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/11\/25\/elon-musk-mas-rico-que-nunca-elecciones-trax\/","url_meta":{"origin":1455160,"position":1},"title":"Elon Musk es m\u00e1s rico que nunca. Ahora su fortuna es de casi US$ 350.000 millones","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"Nueva York (CNN) -- Las secuelas de las elecciones presidenciales estadounidenses de 2024 han sido una bendici\u00f3n para Elon Musk.Ahora puedes seguirnos en\u00a0WhatsApp ChannelLa persona m\u00e1s rica del mundo se hizo a\u00fan m\u00e1s rica el viernes, con el patrimonio neto de Musk alcanzando un r\u00e9cord de US$ 347.800 millones, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456485,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/11\/elon-musk-primera-persona-400-000-millones-trax\/","url_meta":{"origin":1455160,"position":2},"title":"Elon Musk se convierte en la primera persona en alcanzar un patrimonio neto de US$ 400.000 millones","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"La persona m\u00e1s rica del mundo acaba de alcanzar un hito a\u00fan mayor.El patrimonio neto de Elon Musk alcanz\u00f3 los US$ 400.000 millones, seg\u00fan Bloomberg, lo que le convierte en la primera persona en cruzar esa marca.Detr\u00e1s de su salto de casi US$ 20.000 millones en riqueza est\u00e1 un acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459205,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/25\/elon-musk-perdio-52000-millones-hombre-mas-rico-trax\/","url_meta":{"origin":1455160,"position":3},"title":"Elon Musk perdi\u00f3 US$ 52.000 millones de patrimonio neto este a\u00f1o y sigue siendo la persona m\u00e1s rica del mundo","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Elon Musk perdi\u00f3 US$ 52.000 millones en patrimonio neto desde que comenz\u00f3 el a\u00f1o, pero sigue siendo la persona m\u00e1s rica del mundo por un amplio margen, seg\u00fan el \u00cdndice de Multimillonarios de Bloomberg.Las acciones de Tesla de Musk cayeron un 8% antes del cierre del mercado este martes, despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446517,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/03\/04\/jeff-bezos-destrona-elon-musk-nuevamente-persona-mas-rica-mundo-trax\/","url_meta":{"origin":1455160,"position":4},"title":"Jeff Bezos destrona a Elon Musk para volver a ser la persona m\u00e1s rica del mundo","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 Jeff Bezos recuper\u00f3 el t\u00edtulo de la persona m\u00e1s rica del mundo, superando a Elon Musk, seg\u00fan el \u00cdndice de multimillonarios de Bloomberg de este lunes.El patrimonio neto del fundador de Amazon era de 200.000 millones de d\u00f3lares, seguido de Musk con 198.000 millones de d\u00f3lares. Musk perdi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460777,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/04\/03\/elon-musk-tesla-estallando-trax\/","url_meta":{"origin":1455160,"position":5},"title":"Todo le est\u00e1 estallando en las narices a Elon Musk","author":"","date":"abril 3, 2025","format":false,"excerpt":"Bastaba con perder US$ 100.000 millones en tres meses para que Elon Musk cambiara de opini\u00f3n sobre el trabajo gubernamental.Por si te lo perdiste: las \u00faltimas 24 horas han sido un desfile de humillaciones para el hombre m\u00e1s rico del mundo, empezando por haber apostado US$ 20 millones en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1455160"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455160\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1455160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1455160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1455160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}