{"id":1455177,"date":"2024-10-16T17:04:05","date_gmt":"2024-10-17T00:04:05","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/"},"modified":"2024-10-16T17:04:05","modified_gmt":"2024-10-17T00:04:05","slug":"desmantelan-banda-vendia-botellas-vino-falso-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","title":{"rendered":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Seis personas fueron detenidas como parte de una investigaci\u00f3n sobre una red de fraude enol\u00f3gica que supuestamente vend\u00eda vino franc\u00e9s falso por hasta 15.000 euros (US$ 16.300) por botella.<\/p>\n<p>La polic\u00eda italiana registr\u00f3 14 propiedades y confisc\u00f3 grandes cantidades de botellas de vino, etiquetas falsificadas de los mejores vi\u00f1edos franceses y m\u00e1quinas utilizadas para volver a tapar las botellas, seg\u00fan un comunicado de la agencia europea de aplicaci\u00f3n de la ley, Europol, publicado este martes.<\/p>\n<p>La polic\u00eda espa\u00f1ola desarticula una presunta red de falsificaci\u00f3n de obras de Banksy<\/p>\n<p>La polic\u00eda tambi\u00e9n confisc\u00f3 equipos electr\u00f3nicos por valor de 1,4 millones de euros (US$ 1,5 millones) y m\u00e1s de 100.000 euros (US$ 109.000) en efectivo.<\/p>\n<p>\u201cEl vino falso fue fabricado en Italia, luego entregado a un aeropuerto italiano y exportado para su venta a valor de mercado en todo el mundo por comerciantes de vino honestos\u201d, dijo Europol en el comunicado.<\/p>\n<p>Los investigadores incautaron grandes cantidades de vino. Cr\u00e9dito: Europol.<\/p>\n<p>Las t\u00e9cnicas utilizadas por los falsificadores revelaron un v\u00ednculo con una investigaci\u00f3n anterior, que se cerr\u00f3 en 2015, que involucraba a un estafador ruso, seg\u00fan Europol.<\/p>\n<p>Seg\u00fan un comunicado de los fiscales franceses publicado este martes, un hombre ruso de 40 a\u00f1os, que ya hab\u00eda sido condenado por su participaci\u00f3n en un fraude de vino similar bajo una identidad diferente, tambi\u00e9n estuvo implicado en la \u00faltima investigaci\u00f3n.<\/p>\n<p>Detectan aplicaciones de b\u00f3tox falsificado en varios estados de Estados Unidos: esto deben saber los consumidores<\/p>\n<p>Los fiscales dijeron que la red hab\u00eda logrado vender un \u201cgran volumen de grands crus franceses\u201d valorados en m\u00e1s de 2 millones de euros (US$ 2,18 millones).<\/p>\n<p>Un juez de la ciudad francesa de Dijon acus\u00f3 a un ciudadano franc\u00e9s de fraude y blanqueo de dinero, y el ciudadano ruso comparecer\u00e1 ante el mismo juez para acusarlo, seg\u00fan el comunicado.<\/p>\n<p>Esta investigaci\u00f3n fue dirigida por la Gendarmer\u00eda francesa, y tambi\u00e9n participaron los Carabineros de Italia y la Polic\u00eda Federal Suiza.<\/p>\n<p>Stuart George, fundador y director general de Arden Fine Wines, una empresa con sede en Londres especializada en vinos a\u00f1ejos finos y raros, dijo que \u201ces dif\u00edcil encontrar cifras precisas sobre el fraude en vinos finos porque es una actividad que, por su propia naturaleza, est\u00e1 encubierta y es enga\u00f1osa\u201d.<\/p>\n<p>Sin embargo, las fuerzas del mercado impulsaron el inter\u00e9s en el fraude del vino.<\/p>\n<p>\u201cEl aumento de la demanda de vinos finos en el siglo XXI (\u2026) motiv\u00f3 a los estafadores\u201d, le dijo George a CNN. \u201cTodo lo que sea valioso, ya sea un cuadro o una botella de vino, corre el riesgo de ser falsificado\u201d.<\/p>\n<p>Los estafadores pueden aprovecharse de la falta de conocimientos especializados, a\u00f1adi\u00f3.<\/p>\n<p>\u201cB\u00e1sicamente, la mayor\u00eda de la gente no puede distinguir lo aut\u00e9ntico de lo falso\u201d, afirm\u00f3 George. \u201cSi alguien nunca ha visto una botella aut\u00e9ntica de, por ejemplo, Petrus 1990, entonces es imposible saber si se trata de una falsificaci\u00f3n\u201d.<\/p>\n<p>Mejorar las habilidades en la industria es una forma de combatir el fraude en el vino, a\u00f1adi\u00f3.<\/p>\n<p>Una estafa de romance con &#171;deepfake&#187; recaud\u00f3 US$ 46 millones de hombres en toda Asia, seg\u00fan la Polic\u00eda<\/p>\n<p>\u201cSer\u00eda \u00fatil contar con una mejor formaci\u00f3n y un mejor conocimiento del aspecto real de las botellas de buen vino, y especialmente de las botellas viejas de buen vino\u201d, coment\u00f3 George. \u201cAl final, todo se reduce a la integridad y la competencia\u201d.<\/p>\n<p>En octubre de 2020, la polic\u00eda italiana desmantel\u00f3 una red que produc\u00eda vino Sassicaia falsificado, una variedad considerada entre las mejores del mundo, que se vende a cientos de euros la botella, inform\u00f3 Reuters.<\/p>\n<p>El vino tinto Bolgheri Sassicaia proviene de una zona de la costa de la Toscana y se convirti\u00f3 en uno de los vinos finos m\u00e1s conocidos de Italia desde que apareci\u00f3 en el mercado en la d\u00e9cada de 1970.<\/p>\n<p>Los funcionarios de la Guardia di Finanza dijeron que la sofisticada operaci\u00f3n de falsificaci\u00f3n embotellaba vino de calidad inferior procedente de Sicilia en un almac\u00e9n cerca de Mil\u00e1n, con etiquetas meticulosamente reproducidas y cajas que proven\u00edan de Bulgaria.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Seis personas fueron detenidas como parte de una investigaci\u00f3n sobre una red de fraude enol\u00f3gica que supuestamente vend\u00eda vino franc\u00e9s falso por hasta 15.000 euros (US$ 16.300) por botella. La polic\u00eda italiana registr\u00f3 14 propiedades y confisc\u00f3 grandes cantidades de botellas de vino, etiquetas falsificadas de los mejores vi\u00f1edos franceses y m\u00e1quinas utilizadas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1455177","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Seis personas fueron detenidas como parte de una investigaci\u00f3n sobre una red de fraude enol\u00f3gica que supuestamente vend\u00eda vino franc\u00e9s falso por hasta 15.000 euros (US$ 16.300) por botella. La polic\u00eda italiana registr\u00f3 14 propiedades y confisc\u00f3 grandes cantidades de botellas de vino, etiquetas falsificadas de los mejores vi\u00f1edos franceses y m\u00e1quinas utilizadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T00:04:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una\",\"datePublished\":\"2024-10-17T00:04:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\"},\"wordCount\":748,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\",\"name\":\"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-17T00:04:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias","og_description":"(CNN) \u2013\u2013 Seis personas fueron detenidas como parte de una investigaci\u00f3n sobre una red de fraude enol\u00f3gica que supuestamente vend\u00eda vino franc\u00e9s falso por hasta 15.000 euros (US$ 16.300) por botella. La polic\u00eda italiana registr\u00f3 14 propiedades y confisc\u00f3 grandes cantidades de botellas de vino, etiquetas falsificadas de los mejores vi\u00f1edos franceses y m\u00e1quinas utilizadas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","og_site_name":"Noticias","article_published_time":"2024-10-17T00:04:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/"},"author":{"name":"","@id":""},"headline":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una","datePublished":"2024-10-17T00:04:05+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/"},"wordCount":748,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","url":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","name":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-17T00:04:05+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-17T00:04:05Z","datePublished":"2024-10-17T00:04:05Z","dateModified":"2024-10-17T00:04:05Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Polic\\u00eda de Francia e Italia desmantela banda que vend\\u00eda botellas de vino a\\u00f1ejo falso por US$ 16.000 cada una\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/desmantelan-banda-vendia-botellas-vino-falso-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/desmantelan-banda-vendia-botellas-vino-falso-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-17T00:04:05Z\",\"datePublished\":\"2024-10-17T00:04:05Z\",\"dateModified\":\"2024-10-17T00:04:05Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466541,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/17\/costco-rotura-botellas-prosecco-retiro-trax\/","url_meta":{"origin":1455177,"position":0},"title":"Costco advierte sobre la rotura de botellas de prosecco en un aviso de retiro","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"Costco est\u00e1 retirando del mercado su Prosecco Valdobbiadene de Kirkland Signature, argumentando que las botellas de vino sin abrir podr\u00edan \u201cromperse\u201d sin ser tocadas.En una carta publicada en su sitio web, la compa\u00f1\u00eda advirti\u00f3 a los clientes en 12 estados del Medio Oeste y el sur que desecharan inmediatamente las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457679,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/01\/20\/ventas-champan-caen-gente-no-quiere-celebrar-trax\/","url_meta":{"origin":1455177,"position":1},"title":"Las ventas de champ\u00e1n caen a nivel mundial porque la gente no quiere celebrar","author":"","date":"enero 20, 2025","format":false,"excerpt":"Las ventas de champ\u00e1n han perdido su impulso porque la gente de todo el mundo no est\u00e1 de humor para brindar.El n\u00famero total de env\u00edos de champ\u00e1n desde Francia se redujo casi un 10% el a\u00f1o pasado a 271 millones de botellas, lo que marca el segundo a\u00f1o consecutivo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460290,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/22\/malestar-california-aranceles-vino-europeo-trax\/","url_meta":{"origin":1455177,"position":2},"title":"Malestar entre los vinicultores de California por la amenaza de Trump de imponer un arancel del 200% al vino europeo","author":"","date":"marzo 22, 2025","format":false,"excerpt":"La semana pasada, el presidente de EE.UU., Donald Trump, amenaz\u00f3 con imponer un gigantesco arancel del 200% a todo el vino, champ\u00e1n y otros productos alcoh\u00f3licos procedentes de la Uni\u00f3n Europea. \u201cEsto ser\u00e1 genial para los negocios de vino y champ\u00e1n en Estados Unidos\u201d, escribi\u00f3 en redes sociales.Sin embargo, muchos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444889,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/04\/trabajador-de-finanzas-paga-us-25-millones-despues-de-una-videollamada-con-un-director-financiero-falso\/","url_meta":{"origin":1455177,"position":3},"title":"Trabajador de finanzas paga US$ 25 millones despu\u00e9s de una videollamada con un &#8216;director financiero&#8217; falso","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 Un trabajador financiero de una empresa multinacional fue enga\u00f1ado para que pagara US$ 25 millones de d\u00f3lares a estafadores que utilizaban tecnolog\u00eda deepfake para hacerse pasar por el director financiero de la empresa en una videoconferencia, seg\u00fan la polic\u00eda de Hong Kong.En la elaborada estafa, el trabajador fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444892,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/04\/trabajador-de-finanzas-paga-us-25-millones-despues-de-una-videollamada-con-un-director-financiero-falso-2\/","url_meta":{"origin":1455177,"position":4},"title":"Trabajador de finanzas paga US$ 25 millones despu\u00e9s de una videollamada con un &#8216;director financiero&#8217; falso","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 Un trabajador financiero de una empresa multinacional fue enga\u00f1ado para que pagara US$ 25 millones de d\u00f3lares a estafadores que utilizaban tecnolog\u00eda deepfake para hacerse pasar por el director financiero de la empresa en una videoconferencia, seg\u00fan la polic\u00eda de Hong Kong.En la elaborada estafa, el trabajador fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459959,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/15\/aranceles-vinos-europeos-alternativas-trax\/","url_meta":{"origin":1455177,"position":5},"title":"\u00bfTe deprimen los aranceles? C\u00f3mo sustituir los vinos europeos por alternativas estadounidenses","author":"","date":"marzo 15, 2025","format":false,"excerpt":"El whisky escoc\u00e9s y el irland\u00e9s no son los \u00fanicos alcoholes que sufrir\u00e1n las consecuencias de un arancel del 200% sobre los productos fabricados en Europa: tambi\u00e9n lo har\u00e1n tus botellas favoritas de Burdeos y Chianti.El vino, que ya sufri\u00f3 una ca\u00edda del 8% en las ventas estadounidenses el a\u00f1o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1455177"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455177\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1455177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1455177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1455177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}