{"id":1455179,"date":"2024-10-16T18:03:49","date_gmt":"2024-10-17T01:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/"},"modified":"2024-10-16T18:03:49","modified_gmt":"2024-10-17T01:03:49","slug":"astronomos-descubren-galaxia-lejana-similar-via-lactea-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","title":{"rendered":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Investigadores descubrieron una galaxia distante que tiene caracter\u00edsticas sorprendentemente similares a nuestra propia V\u00eda L\u00e1ctea, lo que podr\u00eda cambiar nuestra comprensi\u00f3n de c\u00f3mo se forman las galaxias.<\/p>\n<p>La galaxia, que ha sido nombrada REBELS-25, es mucho m\u00e1s ordenada de lo que la ciencia actual sugiere que deber\u00eda ser para su edad, seg\u00fan una investigaci\u00f3n liderada por astr\u00f3nomos de la Universidad de Leiden en los Pa\u00edses Bajos.<\/p>\n<p>REBELS-25 es mucho m\u00e1s joven que nuestra galaxia, pero ya comparte su rotaci\u00f3n y estructura, en lugar de parecer desordenada y ca\u00f3tica como otras galaxias tempranas, dijeron los investigadores en un comunicado publicado el 7 de octubre.<\/p>\n<p>El proyecto Atacama Large Millimeter\/submillimeter Array (ALMA) en el norte de Chile. (Alberto Pena\/AFP\/Getty Images)<\/p>\n<p>\u201cSeg\u00fan nuestra comprensi\u00f3n de la formaci\u00f3n de galaxias, esperamos que la mayor\u00eda de las galaxias tempranas sean peque\u00f1as y desordenadas\u201d, dijo Jacqueline Hodge, astr\u00f3noma de la Universidad de Leiden y coautora del estudio, en el comunicado.<\/p>\n<p>Nuevas im\u00e1genes telesc\u00f3picas revelan la fantasmal \u201cMano de Dios\u201d en la V\u00eda L\u00e1ctea que atraviesa el cosmos<\/p>\n<p>Las galaxias tempranas tienden a unirse y desarrollar formas m\u00e1s suaves de manera incre\u00edblemente lenta, con nuestra V\u00eda L\u00e1ctea tardando miles de millones de a\u00f1os en desarrollar estructuras ordenadas, dijeron los investigadores.<\/p>\n<p>La luz que llega a la Tierra desde REBELS-25 fue emitida solo 700 millones de a\u00f1os despu\u00e9s de que el universo se formara hace 13.800 millones de a\u00f1os, un tiempo sorprendentemente corto para haberse vuelto tan ordenada, dijeron.<\/p>\n<p>\u201cVer una galaxia con tales similitudes a nuestra propia V\u00eda L\u00e1ctea, que est\u00e1 fuertemente dominada por la rotaci\u00f3n, desaf\u00eda nuestra comprensi\u00f3n de cu\u00e1n r\u00e1pidamente las galaxias en el universo temprano evolucionan hacia las galaxias ordenadas del cosmos actual\u201d, dijo Lucie Rowland, estudiante de doctorado en la Universidad de Leiden y primera autora del estudio, en el comunicado.<\/p>\n<p>La rotaci\u00f3n y estructura de la galaxia fueron observadas utilizando el telescopio Atacama Large Millimeter\/submillimeter Array (ALMA) en el norte de Chile.<\/p>\n<p>El equipo tambi\u00e9n encontr\u00f3 datos que sugieren caracter\u00edsticas a\u00fan m\u00e1s desarrolladas, como brazos espirales, y planean realizar m\u00e1s observaciones para confirmar si de hecho existen.<\/p>\n<p>\u201cEncontrar m\u00e1s evidencia de estructuras m\u00e1s evolucionadas ser\u00eda un descubrimiento emocionante, ya que ser\u00eda la galaxia m\u00e1s distante con tales estructuras observadas hasta la fecha\u201d, dijo Rowland.<\/p>\n<p>Andrew Blain, profesor de astrof\u00edsica en la Universidad de Leicester, que no particip\u00f3 en el estudio, dijo que REBELS-25 es \u201cun poco inusual\u201d, pero \u201cno es una revoluci\u00f3n\u201d.<\/p>\n<p>Revelan nuevos detalles sobre una misteriosa regi\u00f3n de la V\u00eda L\u00e1ctea llamada &#171;;El Ladrillo&#187;<\/p>\n<p>Blain destac\u00f3 el papel de ALMA en encontrar un ejemplo real de un tipo de galaxia que anteriormente solo se hab\u00eda producido en simulaciones.<\/p>\n<p>\u201cSin ALMA no habr\u00eda habido capacidad para identificar un ejemplo, tanto porque los ejemplos individuales habr\u00edan sido demasiado d\u00e9biles para detectar en un tiempo razonable, como porque no se podr\u00eda haber buscado una muestra lo suficientemente grande de candidatos\u201d, dijo a CNN. \u201cALMA tambi\u00e9n revela detalles m\u00e1s finos que los telescopios anteriores\u201d.<\/p>\n<p>Blain dijo que se necesita m\u00e1s investigaci\u00f3n antes de que los cient\u00edficos cambien su comprensi\u00f3n de la formaci\u00f3n de galaxias.<\/p>\n<p>\u201cUna pregunta ser\u00eda si son muy raras, o si cada galaxia pasa por una fase como esta\u201d, dijo. \u201cSi son comunes, entonces los modelos tendr\u00e1n que ajustarse\u201d.<\/p>\n<p>Dave Clements, lector en astrof\u00edsica en el Imperial College de Londres, que no particip\u00f3 en el estudio, dijo que \u201ces bastante sorprendente\u201d encontrar una galaxia como REBELS-25.<\/p>\n<p>\u201cSe piensa que el universo en ese entonces era mucho m\u00e1s ca\u00f3tico, con interacciones y fusiones de galaxias que se esperaba que interrumpieran la estructura relativamente fr\u00e1gil de un disco. Y sin embargo, eso es lo que parece REBELS-25\u201d, dijo a CNN.<\/p>\n<p>\u201c\u00bfEs solo una galaxia muy inusual, que ha llevado una vida inesperadamente tranquila hasta cuando la vemos, o estas observaciones nos est\u00e1n diciendo que las etapas tempranas de la formaci\u00f3n de galaxias no funcionan como pensamos? En este punto no lo sabemos\u201d.<\/p>\n<p>La investigaci\u00f3n, que est\u00e1 disponible como preimpresi\u00f3n (un art\u00edculo cient\u00edfico que no ha pasado por el proceso de revisi\u00f3n por pares), ha sido aceptada para su publicaci\u00f3n en la revista Monthly Notices of the Royal Astronomical Society.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Investigadores descubrieron una galaxia distante que tiene caracter\u00edsticas sorprendentemente similares a nuestra propia V\u00eda L\u00e1ctea, lo que podr\u00eda cambiar nuestra comprensi\u00f3n de c\u00f3mo se forman las galaxias. La galaxia, que ha sido nombrada REBELS-25, es mucho m\u00e1s ordenada de lo que la ciencia actual sugiere que deber\u00eda ser para su edad, seg\u00fan una investigaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1455179","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Investigadores descubrieron una galaxia distante que tiene caracter\u00edsticas sorprendentemente similares a nuestra propia V\u00eda L\u00e1ctea, lo que podr\u00eda cambiar nuestra comprensi\u00f3n de c\u00f3mo se forman las galaxias. La galaxia, que ha sido nombrada REBELS-25, es mucho m\u00e1s ordenada de lo que la ciencia actual sugiere que deber\u00eda ser para su edad, seg\u00fan una investigaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T01:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos\",\"datePublished\":\"2024-10-17T01:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\",\"name\":\"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-17T01:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias","og_description":"(CNN) &#8212;\u00a0Investigadores descubrieron una galaxia distante que tiene caracter\u00edsticas sorprendentemente similares a nuestra propia V\u00eda L\u00e1ctea, lo que podr\u00eda cambiar nuestra comprensi\u00f3n de c\u00f3mo se forman las galaxias. La galaxia, que ha sido nombrada REBELS-25, es mucho m\u00e1s ordenada de lo que la ciencia actual sugiere que deber\u00eda ser para su edad, seg\u00fan una investigaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","og_site_name":"Noticias","article_published_time":"2024-10-17T01:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/"},"author":{"name":"","@id":""},"headline":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos","datePublished":"2024-10-17T01:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","url":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","name":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-17T01:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Astr\u00f3nomos descubren una galaxia lejana similar a la V\u00eda L\u00e1ctea que desaf\u00eda nuestras teor\u00edas sobre la evoluci\u00f3n del cosmos","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/16\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-17T01:03:49Z","datePublished":"2024-10-17T01:03:49Z","dateModified":"2024-10-17T01:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Astr\\u00f3nomos descubren una galaxia lejana similar a la V\\u00eda L\\u00e1ctea que desaf\\u00eda nuestras teor\\u00edas sobre la evoluci\\u00f3n del cosmos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/16\\\/astronomos-descubren-galaxia-lejana-similar-via-lactea-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-17T01:03:49Z\",\"datePublished\":\"2024-10-17T01:03:49Z\",\"dateModified\":\"2024-10-17T01:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448179,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","url_meta":{"origin":1455179,"position":0},"title":"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN) -- Los astr\u00f3nomos descubrieron el agujero negro estelar m\u00e1s masivo conocido en la V\u00eda L\u00e1ctea despu\u00e9s de detectar una oscilaci\u00f3n inusual en el espacio.El llamado \u201cgigante durmiente\u201d, denominado Gaia BH3, tiene una masa casi 33 veces mayor que la de nuestro Sol y est\u00e1 ubicado a 1.926 a\u00f1os luz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463119,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/06\/02\/colision-galaxias-via-lactea-andromeda-trax\/","url_meta":{"origin":1455179,"position":1},"title":"Una teor\u00eda popular sobre el destino de nuestra galaxia podr\u00eda ser err\u00f3nea, afirman  astr\u00f3nomos","author":"","date":"junio 2, 2025","format":false,"excerpt":"Desde 1912, los astr\u00f3nomos han anticipado una colisi\u00f3n entre nuestra galaxia, la V\u00eda L\u00e1ctea, y su vecina m\u00e1s grande, la galaxia de Andr\u00f3meda, prevista para dentro de unos 4.500 millones de a\u00f1os. Sin embargo, nuevas investigaciones sugieren que la probabilidad de este choque gal\u00e1ctico, conocido en ingl\u00e9s como \u201cMilkomeda\u201d, es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456201,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/02\/nueva-imagen-galaxia-sombrero-aspecto-muy-diferente-trax\/","url_meta":{"origin":1455179,"position":2},"title":"Una nueva imagen de una galaxia parecida a un sombrero revela un aspecto muy diferente","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El telescopio espacial James Webb capt\u00f3 una nueva y sorprendente imagen de una galaxia vecina estudiada durante mucho tiempo, la galaxia del Sombrero, revelando una perspectiva que parece bastante diferente del sombrero mexicano de ala ancha que le da nombre.La imagen tomada con el instrumento MIRI (Mid-Infrared Instrument)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471838,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/03\/03\/descubren-galaxia-99-materia-oscura-trax\/","url_meta":{"origin":1455179,"position":3},"title":"El telescopio Hubble de la NASA detecta una posible &#171;galaxia oscura&#187;","author":"","date":"marzo 3, 2026","format":false,"excerpt":"Los astr\u00f3nomos han detectado una galaxia tan tenue que es casi invisible, un descubrimiento que podr\u00eda ayudar a a arrojar luz sobre una de las sustancias m\u00e1s esquivas del universo.Los investigadores encontraron la Candidata a Galaxia Oscura-2, o CDG-2, utilizando el Telescopio Espacial Hubble, y creen que est\u00e1 compuesta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467551,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/20\/misterioso-brillo-materia-oscura-galaxia-via-lactea-trax\/","url_meta":{"origin":1455179,"position":4},"title":"Los cient\u00edficos creen que el misterioso brillo de nuestra galaxia podr\u00eda provenir de materia oscura. \u00bfQu\u00e9 significa eso?","author":"","date":"octubre 20, 2025","format":false,"excerpt":"En el centro de nuestra galaxia hay un misterioso y difuso resplandor emitido por rayos gamma, una poderosa radiaci\u00f3n generalmente emitida por objetos de alta energ\u00eda, como estrellas que giran r\u00e1pidamente o explotan.El telescopio espacial de rayos gamma Fermi de la NASA detect\u00f3 el resplandor poco despu\u00e9s de su lanzamiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453047,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/09\/25\/chorros-enormes-agujeros-negros-universo-lofar-porfirion-trax\/","url_meta":{"origin":1455179,"position":5},"title":"Descubren chorros enormes que salen de un agujero que equivalen a 140 galaxias como la V\u00eda L\u00e1ctea, seg\u00fan los cient\u00edficos","author":"","date":"septiembre 25, 2024","format":false,"excerpt":"(CNN) -- Los astr\u00f3nomos han observado un par de chorros enormes que salen de un agujero negro supermasivo a 7.500 millones de a\u00f1os luz de la Tierra. La megaestructura se extiende por 23 millones de a\u00f1os luz de longitud, lo que convierte a estos chorros de agujero negro en los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1455179"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455179\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1455179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1455179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1455179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}