{"id":1455244,"date":"2024-10-19T00:03:43","date_gmt":"2024-10-19T07:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/"},"modified":"2024-10-19T00:03:43","modified_gmt":"2024-10-19T07:03:43","slug":"italia-penaliza-gestacion-subrogada-extranjero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","title":{"rendered":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos"},"content":{"rendered":"<p>(CNN) &#8212; Los padres italianos que han tomado la decisi\u00f3n, a menudo dif\u00edcil y costosa, de tener hijos por gestaci\u00f3n subrogada en el extranjero se han visto sumidos en un estado de temor tras un repentino cambio en las ya estrictas restricciones del pa\u00eds para criar a esos ni\u00f1os en Italia.<\/p>\n<p>Italia ampli\u00f3 su legislaci\u00f3n sobre maternidad subrogada, ilegal en el pa\u00eds desde 2004, para tipificar ahora como delito el &#171;turismo de maternidad subrogada&#187; en pa\u00edses como Estados Unidos y Canad\u00e1, castigando a los futuros padres que infrinjan la ley con multas de hasta un mill\u00f3n de euros (US$ 1 mill\u00f3n) y penas de c\u00e1rcel de hasta dos a\u00f1os.<\/p>\n<p>Tal y como est\u00e1 redactada, la ley no afecta a los padres cuyos hijos nacidos por gestaci\u00f3n subrogada ya est\u00e1n registrados en el pa\u00eds, pero muchos padres de ni\u00f1os m\u00e1s peque\u00f1os temen que puedan ser objeto de persecuci\u00f3n de todos modos cuando sus hijos alcancen la edad escolar y tengan que inscribirse en el sistema escolar p\u00fablico.<\/p>\n<p>La ley, que entra en vigor inmediatamente, fue aprobada por el Senado italiano por 84 votos a favor y 58 en contra tras un apasionado debate que dur\u00f3 m\u00e1s de siete horas este mi\u00e9rcoles y en el que por momentos pareci\u00f3 que se llegar\u00eda a las manos.<\/p>\n<p>Italia proh\u00edbe la gestaci\u00f3n subrogada en el extranjero<\/p>\n<p>Las personas que se manifestaron frente al Senado durante el largo debate portaban pancartas que dec\u00edan: &#171;Somos familias, no delitos&#187;, y mostraban fotos de sus hijos bajo las palabras \u201clos hijos que nunca pudimos tener\u201d. Mientras tanto, algunos calificaron la propuesta de ley de sentencia &#171;medieval&#187; en entrevistas con medios de comunicaci\u00f3n italianos.<\/p>\n<p>El proyecto de ley fue presentado por el partido gobernante de extrema derecha Hermanos de Italia, de Giorgia Meloni, e impulsado personalmente por la primera ministra, que ha encontrado en el Papa Francisco un aliado en la cuesti\u00f3n de la maternidad subrogada, lo que subraya la continua influencia pol\u00edtica de la Iglesia cat\u00f3lica en Italia, especialmente cuando se trata de cuestiones reproductivas.<\/p>\n<p>Italia fue una de las \u00faltimas naciones de Europa occidental en legalizar las uniones entre personas del mismo sexo, lo que hizo en 2016, pero sigue sin reconocerlas como &#171;matrimonio&#187; bajo la presi\u00f3n de la Iglesia cat\u00f3lica italiana.<\/p>\n<p>Meloni celebr\u00f3 este mi\u00e9rcoles la decisi\u00f3n del Senado, calific\u00e1ndola de &#171;norma de sentido com\u00fan contra la mercantilizaci\u00f3n del cuerpo femenino y de los ni\u00f1os. La vida humana no tiene precio y no es una mercanc\u00eda&#187;.<\/p>\n<p>Personas se manifiestan cerca del Senado de Italia esta semana para oponerse a la nueva legislaci\u00f3n del pa\u00eds. (Cr\u00e9ditos: Simona Granati\/Corbis\/Getty Images).<\/p>\n<p>A principios de este a\u00f1o, Francisco pidi\u00f3 una prohibici\u00f3n mundial de la maternidad subrogada, describiendo la pr\u00e1ctica como &#171;deplorable&#187; e insistiendo en que &#171;un ni\u00f1o es siempre un regalo y nunca la base de un contrato comercial.&#187; El Papa, sin embargo, no ha pedido que se criminalice la pr\u00e1ctica y una sentencia doctrinal del Vaticano de 2023 se\u00f1al\u00f3 que los ni\u00f1os nacidos por gestaci\u00f3n subrogada pueden ser bautizados.<\/p>\n<p>\u00bfEn qu\u00e9 consiste ser una madre subrogada y c\u00f3mo se lleva a cabo la subrogaci\u00f3n gestacional?<\/p>\n<p>La Iglesia cat\u00f3lica se opone a la maternidad subrogada porque es &#171;contraria a la unidad del matrimonio y a la dignidad de la procreaci\u00f3n de la persona humana&#187; y est\u00e1 en contra de la fecundaci\u00f3n in vitro (FIV) porque el proceso implica la eliminaci\u00f3n de embriones innecesarios, que la iglesia cree que es inmoral.<\/p>\n<p>Francisco cambi\u00f3 el enfoque de la Iglesia sobre la acogida de personas LGBTQ, pero mantuvo una l\u00ednea firme de oposici\u00f3n tanto al aborto como a la maternidad subrogada. Ha enmarcado su cr\u00edtica a la maternidad subrogada en su preocupaci\u00f3n por una &#171;cultura de usar y tirar&#187;, en la que los seres humanos se consideran &#171;bienes de consumo&#187; que hay que desechar, y en la maternidad subrogada ve el peligro de que se explote a las mujeres m\u00e1s pobres.<\/p>\n<p>La nueva ley italiana no distingue entre parejas del mismo sexo y heterosexuales, ni entre gestaci\u00f3n subrogada altruista o de pago, pero afectar\u00e1 desproporcionadamente a la comunidad LGBTQ, temen sus defensores.<\/p>\n<p>&#171;La supuesta defensa de la mujer, el cacareado inter\u00e9s por los ni\u00f1os, son solo hojas de parra tras las que se esconde la obsesi\u00f3n hom\u00f3foba de esta mayor\u00eda, no tanto&#187;, public\u00f3 en X Laura Boldrini, pol\u00edtica italiana y expresidenta de la C\u00e1mara Baja del Parlamento italiano, que tambi\u00e9n se sum\u00f3 a la protesta frente al Senado.<\/p>\n<p>&#171;Con ley o sin ella, las familias homoparentales existen y seguir\u00e1n existiendo. Siempre estaremos a su lado en la batalla por la afirmaci\u00f3n de los derechos de los ni\u00f1os y las ni\u00f1as y la autodeterminaci\u00f3n de las mujeres&#187;.<\/p>\n<p>Alessia Crocini, presidenta del grupo de defensa de las Familias Arco Iris, declar\u00f3: &#171;Nosotros, como Rainbow Families, no nos detendremos y continuaremos nuestra batalla en los tribunales y en las calles. Lucharemos cada d\u00eda para afirmar la belleza y la libertad de nuestras familias y de nuestros hijos e hijas&#187;.<\/p>\n<p>El papa Francisco califica de &#171;deplorable&#187; la maternidad subrogada<\/p>\n<p>Italia ya proh\u00edbe a las parejas homosexuales adoptar ni\u00f1os y el a\u00f1o pasado el pa\u00eds empez\u00f3 a eliminar los nombres de las madres lesbianas de algunos registros de nacimiento si no eran el padre biol\u00f3gico. Muchos gobiernos locales ya han modificado los registros de nacimiento para que solo figuren &#171;madre&#187; y &#171;padre&#187;, en lugar de &#171;progenitor 1&#187; y &#171;progenitor 2&#187;, algo ampliamente aceptado en toda la Uni\u00f3n Europea.<\/p>\n<p>Michela Calabro, responsable del brazo pol\u00edtico del grupo de derechos LGBTQ Arcigay, calific\u00f3 la ley de grave negaci\u00f3n de las libertades individuales y la autodeterminaci\u00f3n.<\/p>\n<p>&#171;Introducir un delito, aunque sea universal, no solo limita la posibilidad de elegir, sino que alimenta una visi\u00f3n patriarcal del cuerpo de las mujeres&#187;, dijo en una declaraci\u00f3n en X. &#171;Esta medida pone de manifiesto la incapacidad del Gobierno y del Parlamento para abordar otras cuestiones importantes y urgentes en nuestro pa\u00eds. De hecho, la mayor\u00eda parlamentaria opta una vez m\u00e1s por demostrar su fuerza principalmente con argumentos ideol\u00f3gicos, mientras que en cuestiones pragm\u00e1ticas confirma su total incapacidad.&#187;<\/p>\n<p>Muchos legisladores se opusieron a la nueva legislaci\u00f3n. (Cr\u00e9dito: Mauro Scrobogna\/LaPresse\/Shutterstock).<\/p>\n<p>No est\u00e1 claro c\u00f3mo se aplicar\u00e1 la nueva ley, ni si podr\u00edan exigirse comprobaciones de ADN cuando se diga que los beb\u00e9s han nacido de mujeres italianas en el extranjero.<\/p>\n<p>Los activistas LGBTQ que protestaron ante el Senado este mi\u00e9rcoles afirmaron que las parejas heterosexuales representan el 90% de todos los vientres de alquiler.<\/p>\n<p>Argumentan que esas parejas seguir\u00e1n pudiendo &#171;colar a sus hijos&#187; y eludir la nueva ley, ya que, en Estados Unidos y Canad\u00e1, los nombres de los padres intencionales pueden figurar en los certificados de nacimiento extranjeros de los beb\u00e9s nacidos de madres de alquiler en cumplimiento de las normas estatales. Las parejas homosexuales masculinas lo tendr\u00edan m\u00e1s dif\u00edcil para encontrar un resquicio legal a su regreso a Italia.<\/p>\n<p>La nueva legislaci\u00f3n podr\u00eda suponer un reto pol\u00edtico para Meloni. Goza de un alto \u00edndice de aprobaci\u00f3n, y las \u00faltimas encuestas le otorgan un 29,3% de apoyo (un 3% m\u00e1s que cuando asumi\u00f3 el cargo a finales de 2022).<\/p>\n<p>Pero el amplio alcance de la legislaci\u00f3n ha suscitado numerosas cr\u00edticas, incluidas las de parejas heterosexuales que han salido a protestar junto a las de la comunidad gay. Tambi\u00e9n es una estrecha aliada pol\u00edtica del multimillonario de la tecnolog\u00eda Elon Musk, que ha tenido hijos a trav\u00e9s de vientres de alquiler y que habl\u00f3 en su convenci\u00f3n pol\u00edtica en diciembre, diciendo a sus partidarios que &#171;hagan m\u00e1s italianos&#187; para combatir la menguante tasa de natalidad del pa\u00eds.<\/p>\n<p>El papa y Meloni tambi\u00e9n han encontrado un terreno com\u00fan en este tema, ya que ambos unieron sus fuerzas en una conferencia destinada a abordar el descenso de la natalidad en Italia, mientras que Francisco ha llamado la atenci\u00f3n por su opini\u00f3n de que algunas parejas hoy en d\u00eda prefieren tener mascotas en lugar de hijos.<\/p>\n<p>Pero no todas las pol\u00edticas de Meloni coinciden con las de Francisco. El mismo d\u00eda en que se aprob\u00f3 la controvertida ley, Italia comenz\u00f3 a enviar a Albania a algunos inmigrantes rescatados en el mar, en una medida que va claramente en contra de la doctrina de la Iglesia de que los inmigrantes deben ser acogidos y de la abierta defensa de Francisco sobre este tema.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los padres italianos que han tomado la decisi\u00f3n, a menudo dif\u00edcil y costosa, de tener hijos por gestaci\u00f3n subrogada en el extranjero se han visto sumidos en un estado de temor tras un repentino cambio en las ya estrictas restricciones del pa\u00eds para criar a esos ni\u00f1os en Italia. Italia ampli\u00f3 su legislaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1455244","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &quot;medieval&quot; por los cr\u00edticos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &quot;medieval&quot; por los cr\u00edticos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los padres italianos que han tomado la decisi\u00f3n, a menudo dif\u00edcil y costosa, de tener hijos por gestaci\u00f3n subrogada en el extranjero se han visto sumidos en un estado de temor tras un repentino cambio en las ya estrictas restricciones del pa\u00eds para criar a esos ni\u00f1os en Italia. Italia ampli\u00f3 su legislaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-19T07:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos\",\"datePublished\":\"2024-10-19T07:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\"},\"wordCount\":1524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\",\"name\":\"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de \\\"medieval\\\" por los cr\u00edticos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-19T07:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de \"medieval\" por los cr\u00edticos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de \"medieval\" por los cr\u00edticos - Noticias","og_description":"(CNN) &#8212; Los padres italianos que han tomado la decisi\u00f3n, a menudo dif\u00edcil y costosa, de tener hijos por gestaci\u00f3n subrogada en el extranjero se han visto sumidos en un estado de temor tras un repentino cambio en las ya estrictas restricciones del pa\u00eds para criar a esos ni\u00f1os en Italia. Italia ampli\u00f3 su legislaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","og_site_name":"Noticias","article_published_time":"2024-10-19T07:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/"},"author":{"name":"","@id":""},"headline":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos","datePublished":"2024-10-19T07:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/"},"wordCount":1524,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","url":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","name":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de \"medieval\" por los cr\u00edticos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-19T07:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Italia penaliza la gestaci\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\u00edticos","url":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2024\/10\/19\/italia-penaliza-gestacion-subrogada-extranjero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-19T07:03:43Z","datePublished":"2024-10-19T07:03:43Z","dateModified":"2024-10-19T07:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Italia penaliza la gestaci\\u00f3n subrogada en el extranjero, una medida tachada de &#171;medieval&#187; por los cr\\u00edticos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/19\\\/italia-penaliza-gestacion-subrogada-extranjero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2024\\\/10\\\/19\\\/italia-penaliza-gestacion-subrogada-extranjero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-19T07:03:43Z\",\"datePublished\":\"2024-10-19T07:03:43Z\",\"dateModified\":\"2024-10-19T07:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443409,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/09\/el-papa-francisco-califica-de-deplorable-la-maternidad-subrogada\/","url_meta":{"origin":1455244,"position":0},"title":"El papa Francisco califica de &#171;deplorable&#187; la maternidad subrogada","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El papa Francisco habl\u00f3 sobre la maternidad subrogada, una pr\u00e1ctica a la que calific\u00f3 de \"deplorable\".\"Considero deplorable la pr\u00e1ctica de la llamada maternidad subrogada, que ofende gravemente la dignidad de la mujer y del ni\u00f1o; y se basa en la explotaci\u00f3n de la situaci\u00f3n de necesidad material\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465389,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/11\/cristiano-ronaldo-se-casa-con-georgina-rodriguez-orix\/","url_meta":{"origin":1455244,"position":1},"title":"Cristiano Ronaldo se casa con Georgina Rodr\u00edguez, que mostr\u00f3 el incre\u00edble anillo de compromiso","author":"","date":"agosto 11, 2025","format":false,"excerpt":"\u201cS\u00ed, quiero. En esta y en todas mis vidas\u201d. Con esas dos frases cargadas de emotividad, Georgina Rodr\u00edguez confirm\u00f3 en sus redes sociales que se casar\u00e1 con Cristiano Ronaldo, hoy futbolista del Al-Nassr de la Liga Profesional de Arabia Saudita.El delantero portugu\u00e9s todav\u00eda no public\u00f3 nada al respecto en sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444155,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/01\/20\/el-papa-francisco-dice-que-el-placer-sexual-es-un-don-de-dios-socavado-por-la-pornografia\/","url_meta":{"origin":1455244,"position":2},"title":"El papa Francisco dice que el placer sexual es un &#171;don de Dios&#187; socavado &#171;por la pornograf\u00eda&#187;","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El papa Francisco dijo que el placer sexual es un \"don de Dios\" pero que es \"socavado por la pornograf\u00eda\". El pont\u00edfice se refiri\u00f3 a esto en su catequesis de la audiencia general de este mi\u00e9rcoles, dedicada al \"vicio de la lujuria\".Francisco defini\u00f3 la pornograf\u00eda como \"satisfacci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447842,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/08\/cirugia-cambio-de-sexo-amenaza-dignidad-unica-de-una-persona-dice-el-vaticano-trax\/","url_meta":{"origin":1455244,"position":3},"title":"La cirug\u00eda de cambio de sexo amenaza la &#171;dignidad \u00fanica&#187; de una persona, dice el Vaticano","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN) --\u00a0 El Vaticano emiti\u00f3 una fuerte advertencia contra la \"teor\u00eda de g\u00e9nero\" y dijo que cualquier cirug\u00eda de cambio de sexo corre el riesgo de amenazar \"la dignidad \u00fanica\" de una persona, en un nuevo documento firmado y aprobado por el papa Francisco.Titulada \u201cDignitas Inifinita\u201d (Dignidad Infinita), la declaraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445489,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/02\/16\/grecia-legaliza-el-matrimonio-entre-personas-del-mismo-sexo-por-primera-vez-en-un-pais-cristiano-ortodoxo\/","url_meta":{"origin":1455244,"position":4},"title":"Grecia legaliza el matrimonio entre personas del mismo sexo por primera vez en un pa\u00eds cristiano ortodoxo","author":"","date":"febrero 16, 2024","format":false,"excerpt":"(CNN) -- El parlamento griego aprob\u00f3 el jueves una ley que legaliza el matrimonio entre personas del mismo sexo, en una victoria hist\u00f3rica para los derechos humanos en Grecia y convirti\u00e9ndolo en el primer pa\u00eds de mayor\u00eda cristiana ortodoxa en establecer el matrimonio igualitario para todos.La decisi\u00f3n, apoyada por 176\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459718,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/03\/10\/vientre-subrogado-abadono-bebe-argetina-orix\/","url_meta":{"origin":1455244,"position":5},"title":"Investigan caso de abandono de una beb\u00e9 concebida por subrogaci\u00f3n de vientre en Argentina","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Luc\u00eda (que no es identificada con su nombre real por pedido de la Justicia) ten\u00eda prevista su fecha de parto para los primeros d\u00edas de enero. Ya hab\u00eda hecho los planes: cuando llegara el momento dar\u00eda a luz en una cl\u00ednica de Buenos Aires, a donde ir\u00eda desde la provincia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1455244"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1455244\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1455244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1455244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1455244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}