{"id":1458336,"date":"2025-02-06T06:03:51","date_gmt":"2025-02-06T14:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/"},"modified":"2025-02-06T06:03:51","modified_gmt":"2025-02-06T14:03:51","slug":"especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","title":{"rendered":"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;"},"content":{"rendered":"<p>Daniela Hozbor, integrante del Laboratorio VacSal, investigadora del CONICET y miembro de la Comisi\u00f3n Nacional de Inmunizaciones, se refiri\u00f3 a la decisi\u00f3n del gobierno nacional de salir de la Organizaci\u00f3n Mundial de la Salud (OMS)<\/p>\n<p>En CNN Primer Ma\u00f1ana, afirm\u00f3 que <strong>\u201ces muy preocupante por el rol que cumple la Organizaci\u00f3n Mundial de la Salud, que brega es por el bienestar de todos los habitantes del planeta. Para eso hay que tener informaci\u00f3n, se trabaja mancomunadamente para tener evidencia cient\u00edfica, para establecer estrategias, para decidir los diagn\u00f3sticos, los reactivos que hay que usar, capacitar personal\u201d<\/strong>.<\/p>\n<p>Destac\u00f3 que \u201cpara lo que es salud p\u00fablica y salud de la humanidad necesitamos un organismo rector que no quita soberan\u00eda porque la Organizaci\u00f3n Mundial de la Salud no obliga a ning\u00fan pa\u00eds, sino lo que hace es establecer recomendaciones y cada pa\u00eds puede adoptar o no\u201d.<\/p>\n<p>La investigadora del CONICET cont\u00f3 que \u201c<strong>en Argentina tenemos centros colaboradores de la OMS, por ejemplo, que est\u00e1n vigilando en t\u00e9rminos de epidemiolog\u00eda<\/strong>, c\u00f3mo es la circulaci\u00f3n de determinados virus, por ejemplo, del virus que provoca la gripe, las distintas cepas, qu\u00e9 es lo que est\u00e1 circulando en el hemisferio sur, para que despu\u00e9s toda esa informaci\u00f3n los expertos y los especialistas las miren y decidan c\u00f3mo va a ser la composici\u00f3n de la vacuna contra la gripe para el a\u00f1o siguiente, lo mismo se hace con el hemisferio norte, entonces se a\u00fana informaci\u00f3n, o sea, si dejamos de formar parte no vamos a estar ni con voz ni con o\u00eddos para poder en tiempo real manejar mejor las situaciones\u201d.<\/p>\n<p>Adem\u00e1s, asegur\u00f3 que <strong>\u201cla OMS no es perfecta porque hay humanidad y humanidad no es perfecta, pero hemos visto muy buenos logros, que no son indiscutibles, que hay evidencia, que no es opini\u00f3n, la erradicaci\u00f3n de enfermedades como la viruela, que tambi\u00e9n es provocada por un virus que fue devastadora, y por un trabajo coordinado, mancomunado de programas de inmunizaci\u00f3n, se logr\u00f3 eliminar<\/strong>\u201d.<\/p>\n<p>Daniela Hozbor afirm\u00f3 que \u201c<strong>los impactos son enormes, son econ\u00f3micos tambi\u00e9n, porque la formaci\u00f3n de recursos humanos implica insumo<\/strong>, y de no tenerlo no tendr\u00edamos la posibilidad de dar buenas respuestas a estas situaciones que son complejas. Entonces desconectarnos nos hace perder la posibilidad de acciones buenas, de calidad y oportunas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniela Hozbor, integrante del Laboratorio VacSal, investigadora del CONICET y miembro de la Comisi\u00f3n Nacional de Inmunizaciones, se refiri\u00f3 a la decisi\u00f3n del gobierno nacional de salir de la Organizaci\u00f3n Mundial de la Salud (OMS) En CNN Primer Ma\u00f1ana, afirm\u00f3 que \u201ces muy preocupante por el rol que cumple la Organizaci\u00f3n Mundial de la Salud, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458336","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Especialistas en inmunizaciones afirman que &quot;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especialistas en inmunizaciones afirman que &quot;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Daniela Hozbor, integrante del Laboratorio VacSal, investigadora del CONICET y miembro de la Comisi\u00f3n Nacional de Inmunizaciones, se refiri\u00f3 a la decisi\u00f3n del gobierno nacional de salir de la Organizaci\u00f3n Mundial de la Salud (OMS) En CNN Primer Ma\u00f1ana, afirm\u00f3 que \u201ces muy preocupante por el rol que cumple la Organizaci\u00f3n Mundial de la Salud, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T14:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;\",\"datePublished\":\"2025-02-06T14:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\"},\"wordCount\":448,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\",\"name\":\"Especialistas en inmunizaciones afirman que \\\"los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-06T14:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Especialistas en inmunizaciones afirman que \"los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","og_locale":"es_ES","og_type":"article","og_title":"Especialistas en inmunizaciones afirman que \"los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos\" - Noticias","og_description":"Daniela Hozbor, integrante del Laboratorio VacSal, investigadora del CONICET y miembro de la Comisi\u00f3n Nacional de Inmunizaciones, se refiri\u00f3 a la decisi\u00f3n del gobierno nacional de salir de la Organizaci\u00f3n Mundial de la Salud (OMS) En CNN Primer Ma\u00f1ana, afirm\u00f3 que \u201ces muy preocupante por el rol que cumple la Organizaci\u00f3n Mundial de la Salud, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","og_site_name":"Noticias","article_published_time":"2025-02-06T14:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/"},"author":{"name":"","@id":""},"headline":"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;","datePublished":"2025-02-06T14:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/"},"wordCount":448,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","url":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","name":"Especialistas en inmunizaciones afirman que \"los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-06T14:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\u00e9n econ\u00f3micos&#187;","url":"http:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-06T14:03:51Z","datePublished":"2025-02-06T14:03:51Z","dateModified":"2025-02-06T14:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Especialistas en inmunizaciones afirman que &#171;los impactos de salir de la OMS son enormes y son tambi\\u00e9n econ\\u00f3micos&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/02\\\/06\\\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/02\\\/06\\\/especialistas-en-inmunizaciones-afirman-que-los-impactos-de-salir-de-la-oms-son-enormes-y-son-tambien-economicos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-06T14:03:51Z\",\"datePublished\":\"2025-02-06T14:03:51Z\",\"dateModified\":\"2025-02-06T14:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470400,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","url_meta":{"origin":1458336,"position":0},"title":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud","author":"","date":"enero 22, 2026","format":false,"excerpt":"El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458964,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/20\/carlos-regazzoni-ningun-pais-pudo-resolver-los-problemas-de-salud-sin-un-robusto-sistema-publico\/","url_meta":{"origin":1458336,"position":1},"title":"Carlos Regazzoni: &#171;Ning\u00fan pa\u00eds pudo resolver los problemas de salud sin un robusto sistema p\u00fablico&#187;","author":"","date":"febrero 20, 2025","format":false,"excerpt":"Carlos Regazzoni, m\u00e9dico y exdirector Ejecutivo del PAMI, visit\u00f3 los estudios de CNN Radio y analiz\u00f3 la situaci\u00f3n del pa\u00eds, especialmente en el sector salud.En CNN Primera Ma\u00f1ana, cont\u00f3 que est\u00e1 \u201cretomando la senda de la pol\u00edtica, pero focalizado en la salud, donde la Argentina tiene una situaci\u00f3n muy delicada,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458413,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/07\/milei-argentina-oms-que-significa-orix\/","url_meta":{"origin":1458336,"position":2},"title":"\u00c1NALISIS | Tras los pasos de Trump, Milei busca sacar a Argentina de la OMS: \u00bfqu\u00e9 significa para el pa\u00eds?","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Dos semanas despu\u00e9s de que el presidente Donald Trump anunci\u00f3 que buscar\u00e1 retirar a Estados Unidos de la Organizaci\u00f3n Mundial de la Salud (OMS), su hom\u00f3logo argentino Javier Milei replic\u00f3 para su pa\u00eds esta decisi\u00f3n, con argumentos similares.\u201cLa mala gesti\u00f3n de la organizaci\u00f3n ante la pandemia de covid-19 y otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457689,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","url_meta":{"origin":1458336,"position":3},"title":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;","author":"","date":"enero 21, 2025","format":false,"excerpt":"La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado.\u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458328,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/graciela-ocana-es-una-medida-de-seguidismo-que-no-aportara-nada-a-los-argentinos\/","url_meta":{"origin":1458336,"position":4},"title":"Graciela Oca\u00f1a: &#171;Es una medida de seguidismo que no aportar\u00e1 nada a los argentinos&#187;","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Graciela Oca\u00f1a, legisladora de la ciudad de Buenos Aires por Confianza P\u00fablica y exministra de Salud de la Naci\u00f3n, se refiri\u00f3 a la decisi\u00f3n del gobierno de retirar a Argentina de la Organizaci\u00f3n Mundial de la Salud (OMS).En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cseguramente no ser\u00e1 una mejora en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458273,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/05\/milei-retira-oms-orix\/","url_meta":{"origin":1458336,"position":5},"title":"Javier Milei retira a Argentina de la OMS","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El Gobierno de Argentina anunci\u00f3 este mi\u00e9rcoles que el pa\u00eds se retirar\u00e1 de la Organizaci\u00f3n Mundial de Salud (OMS), seg\u00fan confirm\u00f3 el portavoz de la Presidencia, Manuel Adorni, durante una conferencia de prensa.Adorni remarc\u00f3 que fue un pedido del presidente de Argentina, Javier Milei, al canciller argentino, Gerardo Werthein.Dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1458336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1458336"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1458336\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1458336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1458336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1458336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}