{"id":1458377,"date":"2025-02-06T18:03:45","date_gmt":"2025-02-07T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/"},"modified":"2025-02-06T18:03:45","modified_gmt":"2025-02-07T02:03:45","slug":"rey-carlos-reina-camila-papa-francisco-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","title":{"rendered":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco"},"content":{"rendered":"<p>El rey Carlos y la reina Camila viajar\u00e1n a Italia y al Vaticano en abril para reunirse con el papa Francisco, mientras la Iglesia Cat\u00f3lica celebra un a\u00f1o jubilar especial, que tiene lugar cada cuarto de siglo.<\/p>\n<p>El monarca brit\u00e1nico se unir\u00e1 a las 32 millones de personas que se espera hagan la peregrinaci\u00f3n a la \u201cCiudad Eterna\u201d este a\u00f1o. El A\u00f1o Jubilar Cat\u00f3lico \u2014o A\u00f1o Santo\u2014 fue establecido en el siglo XIV por el papa Bonifacio VIII y es un per\u00edodo de 12 meses enfocado en el perd\u00f3n y la reconciliaci\u00f3n.<\/p>\n<p>Se anima a los peregrinos a pasar por una de las \u201cPuertas Santas\u201d ubicadas en las cuatro principales bas\u00edlicas de Roma, mientras que Francisco ha pedido que este jubileo se centre en la \u201cesperanza\u201d, lo que subray\u00f3 al abrir la primera \u201cPuerta Santa\u201d en una prisi\u00f3n.<\/p>\n<p>\u201cSus Majestades el rey y la reina realizar\u00e1n visitas de Estado a la Santa Sede y a la Rep\u00fablica de Italia a principios de abril de 2025\u201d, dijo este jueves el Palacio de Buckingham. \u201cDurante la visita de Estado de Sus Majestades a la Santa Sede, el rey y la reina se unir\u00e1n a su santidad el papa Francisco para celebrar el A\u00f1o Jubilar 2025\u201d.<\/p>\n<p>Mientras est\u00e9n en el pa\u00eds, Carlos y Camila tambi\u00e9n fortalecer\u00e1n los lazos entre Italia y el Reino Unido, llevando a cabo compromisos en Roma y R\u00e1vena, en la regi\u00f3n norte\u00f1a de Emilia-Roma\u00f1a.<\/p>\n<p>El rey Carlos \u2014quien, como gobernador supremo de la Iglesia de Inglaterra, es conocido por ser profundamente devoto y asiste regularmente a los servicios\u2014 se ha reunido con Francisco en varias ocasiones. De hecho, el pr\u00f3ximo viaje ser\u00e1 su tercer encuentro, aunque el primero desde que Carlos ascendi\u00f3 al trono.<\/p>\n<p>Tambi\u00e9n ser\u00e1 la segunda vez que Francisco se re\u00fana con un monarca brit\u00e1nico, ya que el pont\u00edfice recibi\u00f3 a la reina Isabel II y al duque de Edimburgo en el Vaticano en 2014.<\/p>\n<p>A pesar del turbulento pasado de la Reforma y la ruptura del rey Enrique VIII con Roma hace casi 500 a\u00f1os, las relaciones entre el Vaticano y la monarqu\u00eda brit\u00e1nica hoy se caracterizan por la calidez y el respeto mutuo. El Reino Unido y la Santa Sede mantienen relaciones diplom\u00e1ticas plenas desde 1982.<\/p>\n<p>El rey Carlos y Francisco son ambos defensores apasionados del medio ambiente y promueven la importancia del di\u00e1logo interreligioso, temas que probablemente surgir\u00e1n durante su reuni\u00f3n. El rey tambi\u00e9n ha expresado su apoyo a los cristianos perseguidos en el Medio Oriente a trav\u00e9s de su colaboraci\u00f3n con una organizaci\u00f3n ben\u00e9fica cat\u00f3lica.<\/p>\n<p>Las relaciones tambi\u00e9n se han fortalecido por el inter\u00e9s del rey en la fe religiosa y el respeto por la Iglesia Cat\u00f3lica, mientras que el papa regal\u00f3 reliquias de la Verdadera Cruz, dos astillas de madera de lo que se cree que es la cruz en la que Cristo fue crucificado, para la coronaci\u00f3n de Carlos. Los fragmentos se incorporaron a una nueva cruz procesional que se hizo especialmente para la lujosa ceremonia religiosa en 2023 y luego se regal\u00f3 a la Iglesia en Gales. La coronaci\u00f3n de Carlos fue asistida por dos cardenales, uno de los cuales era un representante personal del papa. Fue la primera vez en casi medio siglo que prelados cat\u00f3licos participaron en una coronaci\u00f3n brit\u00e1nica.<\/p>\n<p>Como pr\u00edncipe de Gales, Carlos visit\u00f3 la Ciudad del Vaticano en cinco ocasiones. Estuvo presente en la Plaza de San Pedro para la ceremonia de canonizaci\u00f3n de 2019 de San John Henry Newman, un influyente te\u00f3logo que se convirti\u00f3 al catolicismo despu\u00e9s de a\u00f1os como sacerdote anglicano. En ese momento, el rey escribi\u00f3 un art\u00edculo elogiando a Newman y agradeci\u00f3 al papa por sus esfuerzos ambientales.<\/p>\n<p>Francisco, quien se re\u00fane regularmente con l\u00edderes mundiales cuando visitan Italia, ver\u00e1 la reuni\u00f3n como una oportunidad para profundizar las relaciones con el rey. En 2017, el papa anim\u00f3 a Carlos a ser un \u201chombre de paz\u201d, a lo que el futuro rey respondi\u00f3: \u201cHar\u00e9 mi mejor esfuerzo\u201d.<\/p>\n<p>Pero no siempre ha sido f\u00e1cil para el rey en lo que respecta al Vaticano.<\/p>\n<p>\ufeffEn 2005, el entonces pr\u00edncipe de Gales tuvo que posponer su boda con Camilla Parker-Bowles porque coincid\u00eda con el funeral del papa Juan Pablo II. El propio pr\u00edncipe asisti\u00f3 al funeral papal pero, durante el servicio, tuvo que estrechar la mano del brutal presidente de Zimbabue, Robert Mugabe, mientras hac\u00eda el signo de la paz.<\/p>\n<p>Aunque a\u00fan no se han revelado las fechas exactas del pr\u00f3ximo viaje de Carlos y Camila a Italia, se especula que la visita podr\u00eda coincidir con su vig\u00e9simo aniversario de bodas el 9 de abril.<\/p>\n<p>Las otras dos visitas de Carlos fueron en 2009 y 1985.<\/p>\n<p>Al final de su reuni\u00f3n, se espera que Francisco y Carlos intercambien regalos. Cuando el papa se reuni\u00f3 con la reina Isabel II, Francisco le dio un regalo para el pr\u00edncipe George (entonces de 8 meses). Era un orbe de lapisl\u00e1zuli, decorado con una cruz de plata del monarca del siglo XI Eduardo el Confesor, y en la base estaba grabado: \u201cPapa Francisco, a Su Alteza Real el pr\u00edncipe George de Cambridge\u201d. La reina, a su vez, regal\u00f3 al papa una cesta de productos de las propiedades reales.<\/p>\n<p>Y en 2017, el papa le dio a Carlos una copia de su enc\u00edclica sobre el cambio clim\u00e1tico, otros escritos papales y una rama de olivo de bronce que simboliza la paz. Carlos, quien tambi\u00e9n fue acompa\u00f1ado en ese viaje por Camila, no lleg\u00f3 con las manos vac\u00edas. Le dio al papa una cesta de productos de Highgrove, y le dijo a Francisco: \u201cPuede ser \u00fatil\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rey Carlos y la reina Camila viajar\u00e1n a Italia y al Vaticano en abril para reunirse con el papa Francisco, mientras la Iglesia Cat\u00f3lica celebra un a\u00f1o jubilar especial, que tiene lugar cada cuarto de siglo. El monarca brit\u00e1nico se unir\u00e1 a las 32 millones de personas que se espera hagan la peregrinaci\u00f3n a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458377","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias\" \/>\n<meta property=\"og:description\" content=\"El rey Carlos y la reina Camila viajar\u00e1n a Italia y al Vaticano en abril para reunirse con el papa Francisco, mientras la Iglesia Cat\u00f3lica celebra un a\u00f1o jubilar especial, que tiene lugar cada cuarto de siglo. El monarca brit\u00e1nico se unir\u00e1 a las 32 millones de personas que se espera hagan la peregrinaci\u00f3n a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-07T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco\",\"datePublished\":\"2025-02-07T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\"},\"wordCount\":1017,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\",\"name\":\"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-07T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias","og_description":"El rey Carlos y la reina Camila viajar\u00e1n a Italia y al Vaticano en abril para reunirse con el papa Francisco, mientras la Iglesia Cat\u00f3lica celebra un a\u00f1o jubilar especial, que tiene lugar cada cuarto de siglo. El monarca brit\u00e1nico se unir\u00e1 a las 32 millones de personas que se espera hagan la peregrinaci\u00f3n a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-07T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/"},"author":{"name":"","@id":""},"headline":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco","datePublished":"2025-02-07T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/"},"wordCount":1017,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","name":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-07T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco","url":"http:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-07T02:03:45Z","datePublished":"2025-02-07T02:03:45Z","dateModified":"2025-02-07T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El rey Carlos y la reina Camila visitar\\u00e1n al papa Francisco\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/02\\\/06\\\/rey-carlos-reina-camila-papa-francisco-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/02\\\/06\\\/rey-carlos-reina-camila-papa-francisco-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-07T02:03:45Z\",\"datePublished\":\"2025-02-07T02:03:45Z\",\"dateModified\":\"2025-02-07T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467666,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/23\/rey-carlos-papa-leon-vaticano-principe-andres-trax\/","url_meta":{"origin":1458377,"position":0},"title":"El rey Carlos III se re\u00fane con Le\u00f3n XIV en el Vaticano mientras el esc\u00e1ndalo del pr\u00edncipe Andr\u00e9s se cierne sobre Reino Unido","author":"","date":"octubre 23, 2025","format":false,"excerpt":"La visita de estado del rey Carlos III al Vaticano comenz\u00f3 este jueves. El rey se convertir\u00e1 en el primer monarca brit\u00e1nico en rezar con un papa en 500 a\u00f1os, despu\u00e9s de una semana dif\u00edcil con las continuas consecuencias del esc\u00e1ndalo del pr\u00edncipe Andr\u00e9s.El rey Carlos III y la reina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461136,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/04\/13\/papa-francisco-aparece-domingo-ramos-recuperacion-trax\/","url_meta":{"origin":1458377,"position":1},"title":"El papa Francisco aparece brevemente despu\u00e9s de los servicios del Domingo de Ramos mientras contin\u00faa su recuperaci\u00f3n","author":"","date":"abril 13, 2025","format":false,"excerpt":"El papa Francisco salud\u00f3 a la multitud reunida en la Plaza de San Pedro el Domingo de Ramos, dese\u00e1ndoles un \u201cbuen Domingo de Ramos y una buena Semana Santa\u201d, mientras contin\u00faa su recuperaci\u00f3n de una neumon\u00eda doble.El pont\u00edfice de 88 a\u00f1os salud\u00f3 a los cardenales y l\u00edderes c\u00edvicos que asist\u00edan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450379,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/15\/trooping-colour-desfile-por-que-rey-carlos-iii-dos-cumpleanos-trax\/","url_meta":{"origin":1458377,"position":2},"title":"\u00bfPor qu\u00e9 el rey Carlos III celebra dos cumplea\u00f1os? El origen del desfile Trooping the Colour","author":"","date":"junio 15, 2024","format":false,"excerpt":"(CNN) -- El papel de rey del Reino Unido conlleva una larga lista de ventajas, pero quiz\u00e1 una de las m\u00e1s envidiables sea la posibilidad de celebrar tu cumplea\u00f1os no una, sino dos veces al a\u00f1o.El rey Carlos cumple el 14 de noviembre, pero este fin de semana vuelve a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456949,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/12\/25\/papa-francisco-navidad-ucrania-gaza-trax\/","url_meta":{"origin":1458377,"position":3},"title":"El papa Francisco pide una &#171;paz duradera&#187; en Ucrania en su mensaje de Navidad","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"El papa Francisco llam\u00f3 a una \u201cnegociaci\u00f3n\u201d para poner fin a la guerra en Ucrania en un mensaje del d\u00eda de Navidad en el que apel\u00f3 a deponer las armas en los conflictos mundiales y a la reconciliaci\u00f3n entre enemigos.Las declaraciones del pont\u00edfice, de 88 a\u00f1os, se produjeron horas despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448557,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/04\/26\/rey-carlos-funciones-publicas-trax\/","url_meta":{"origin":1458377,"position":4},"title":"El rey Carlos III volver\u00e1 a sus funciones p\u00fablicas la pr\u00f3xima semana","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN) -- El rey Carlos III del Reino Unido reanudar\u00e1 sus funciones p\u00fablicas la pr\u00f3xima semana tras \"un per\u00edodo de tratamiento y recuperaci\u00f3n\", anunci\u00f3 este viernes el Palacio de Buckingham, dos meses despu\u00e9s de revelar que el monarca estaba siendo tratado por c\u00e1ncer.Carlos, de 75 a\u00f1os acompa\u00f1ar\u00e1 a su esposa,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469571,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/12\/25\/rey-carlos-mensaje-navidad-trax\/","url_meta":{"origin":1458377,"position":5},"title":"El rey Carlos insta al coraje y la reconciliaci\u00f3n en su mensaje de Navidad","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"El rey Carlos III del Reino Unido utiliz\u00f3 su mensaje navide\u00f1o para reflexionar sobre la vida como un viaje compartido y llam\u00f3 a las personas a adoptar valores como el coraje, la reconciliaci\u00f3n y la unidad en un mundo dividido e incierto.El monarca brit\u00e1nico afirm\u00f3 que \u201cperegrinaci\u00f3n es una palabra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1458377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1458377"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1458377\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1458377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1458377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1458377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}