{"id":1467316,"date":"2025-10-12T14:03:40","date_gmt":"2025-10-12T21:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/"},"modified":"2025-10-12T14:03:40","modified_gmt":"2025-10-12T21:03:40","slug":"hamas-control-gaza-colaboradores-alto-el-fuego-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","title":{"rendered":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego"},"content":{"rendered":"<p>Hamas est\u00e1 reafirmando el control de partes de Gaza que no est\u00e1n ocupadas por fuerzas israel\u00edes mientras se consolida el cese del fuego, en medio de la continua incertidumbre sobre la seguridad en el territorio si el grupo es desarmado.<\/p>\n<p>Las fuerzas de seguridad interna de Hamas fueron vistas en las calles de la Ciudad de Gaza el s\u00e1bado, y en los \u00faltimos d\u00edas ha habido m\u00faltiples informes de enfrentamientos entre el grupo y clanes que se le oponen.<\/p>\n<p>\u201cVarios colaboradores e informantes fueron capturados y arrestados en la Ciudad de Gaza, despu\u00e9s de que se probara que estaban involucrados en el espionaje para el enemigo\u201d, as\u00ed como \u201cparticipando en el asesinato de varios miembros de la resistencia\u201d, dijo este domingo el Frente Interno Palestino, un canal de Telegram afiliado a Hamas.<\/p>\n<p>\u201cLos servicios de seguridad y la resistencia est\u00e1n llevando a cabo una campa\u00f1a de campo a gran escala en todas las \u00e1reas de Gaza, de norte a sur, para localizar y arrestar a colaboradores e informantes\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Un video distribuido por canales de Telegram afiliados a Hamas el s\u00e1bado mostr\u00f3 a un presunto colaborador al que se golpeaba en un lugar desconocido.<\/p>\n<p>Otros videos difundidos en redes sociales muestran a miembros de Hamas armados y enmascarados caminando por un mercado callejero en la Ciudad de Gaza, y el Ministerio del Interior controlado por Hamas comparti\u00f3 im\u00e1genes de oficiales con rifles y gorras de b\u00e9isbol que dec\u00edan \u201cpolic\u00eda\u201d en la Ciudad de Gaza, interactuando con los residentes.<\/p>\n<p>Hamas ha mantenido durante mucho tiempo un f\u00e9rreo control sobre Gaza que continu\u00f3 incluso durante la guerra. CNN ha informado sobre ejecuciones y mutilaciones realizadas por Hamas a presuntos saqueadores, una se\u00f1al del poder del grupo a pesar de haber sido debilitado por Israel.<\/p>\n<p>El Ministerio del Interior controlado por Hamas ha declarado una amnist\u00eda de una semana que comenzar\u00e1 el lunes para los miembros de bandas criminales \u201cque no est\u00e9n involucrados en derramamiento de sangre o asesinatos\u201d.<\/p>\n<p>Pero el control de Hamas sobre Gaza ha sido desafiado por varios clanes en los \u00faltimos meses, especialmente en el sur. Algunos de esos grupos han recibido protecci\u00f3n de las fuerzas israel\u00edes.<\/p>\n<p>Canales de redes sociales afiliados a Hamas informaron de enfrentamientos en el \u00e1rea de Sabra de la Ciudad de Gaza entre una familia prominente y las fuerzas de seguridad, durante los cuales muri\u00f3 Muhammad Imad Aql, hijo de un alto comandante militar de Hamas.<\/p>\n<p>Las fuerzas de Hamas rodearon el barrio de la familia Dughmush el viernes por la noche. Fuentes dijeron a CNN que varios miembros de la familia hab\u00edan fallecido y que un gran n\u00famero de hombres armados y enmascarados hab\u00edan sido desplegados alrededor del hospital jordano en la Ciudad de Gaza.<\/p>\n<p>El domingo se inform\u00f3 a CNN que los enfrentamientos continuaban en la zona.<\/p>\n<p>En el sur de Gaza, un grupo opositor de Hamas conocido como las Fuerzas Populares se ha negado a deponer las armas.<\/p>\n<p>El grupo ha estado involucrado en la escolta de env\u00edos de ayuda y ha desafiado p\u00fablicamente a Hamas, que a su vez ha dicho que enfrentar\u00e1 a lo que llam\u00f3 \u201cuna banda criminal\u201d.<\/p>\n<p>Uno de sus comandantes, Hussam al-Astal, public\u00f3 en Facebook el s\u00e1bado: \u201cA todas las ratas de Hamas, sus t\u00faneles est\u00e1n destruidos, sus derechos ya no existen. Arrepi\u00e9ntanse antes de que sea demasiado tarde: no hay Hamas a partir de hoy\u201d.<\/p>\n<p>\u201cEstamos tratando de ser una alternativa a Hamas\u201d, dijo al-Astal a la cadena israel\u00ed Canal 12. \u201cEllos se comprometen a la guerra psicol\u00f3gica\u2026 y usar\u00e1n todo su poder para demostrar que no hay otra opci\u00f3n en el enclave m\u00e1s que ellos\u201d.<\/p>\n<p>Sin embargo, se cree que los miembros de las Fuerzas Populares se han reubicado detr\u00e1s de lo que se conoce como la \u201cl\u00ednea amarilla\u201d dentro del sur de Gaza, donde las fuerzas israel\u00edes a\u00fan est\u00e1n presentes.<\/p>\n<p>No est\u00e1 claro c\u00f3mo funcionar\u00e1n la seguridad y la polic\u00eda en Gaza en las pr\u00f3ximas semanas y meses.<\/p>\n<p>Israel ha exigido durante mucho tiempo que Hamas se desarme, pero el grupo se ha resistido a esto.<\/p>\n<p>El plan de paz de 20 puntos del presidente estadounidense Donald Trump, publicado la semana pasada, dice que \u201clos miembros de Hamas que se comprometan a la coexistencia pac\u00edfica y a entregar sus armas recibir\u00e1n amnist\u00eda\u201d.<\/p>\n<p>Tambi\u00e9n dice que habr\u00e1 un proceso de desmilitarizaci\u00f3n de Gaza \u201cbajo la supervisi\u00f3n de monitores independientes, que incluir\u00e1 colocar las armas permanentemente fuera de uso a trav\u00e9s de un proceso acordado de desarme\u201d.<\/p>\n<p>En lugar de Hamas, seg\u00fan el plan de Trump, una Fuerza Internacional de Estabilizaci\u00f3n (ISF, por sus siglas en ingl\u00e9s) se desplegar\u00e1 inmediatamente en Gaza y \u201centrenar\u00e1 y proporcionar\u00e1 apoyo a fuerzas policiales palestinas seleccionadas\u201d.<\/p>\n<p>Pero detalles cr\u00edticos sobre la fuerza de seguridad y un mecanismo internacional de supervisi\u00f3n planeado a\u00fan deben ser definidos m\u00e1s all\u00e1 de los puntos generales del plan inicial.<\/p>\n<p>En la compleja realidad de la situaci\u00f3n actual en Gaza, establecer una fuerza as\u00ed podr\u00eda tomar meses o m\u00e1s, especialmente en medio de una crisis humanitaria y da\u00f1os masivos a edificios y otra infraestructura.<\/p>\n<p>\u201cEl despliegue (de la ISF) en los n\u00fameros requeridos tendr\u00e1 que ocurrir a lo largo de alg\u00fan tiempo y ser\u00e1 un gran desaf\u00edo log\u00edstico\u201d, se\u00f1al\u00f3 el centro de estudios Chatham House, con sede en Londres.<\/p>\n<p>\u201cLos problemas de coordinaci\u00f3n, direcci\u00f3n y control de una empresa multinacional no probada de la escala requerida tambi\u00e9n ser\u00e1n formidables\u201d, se\u00f1al\u00f3 la semana pasada.<\/p>\n<p>Las bajas entre la fuerza policial de Gaza durante el conflicto de dos a\u00f1os han contribuido al deterioro de la seguridad, con el saqueo de ayuda convirti\u00e9ndose en algo com\u00fan.<\/p>\n<p>Se espera que Jordania y Egipto asuman el papel principal en el entrenamiento y supervisi\u00f3n de la nueva fuerza policial. Pero no est\u00e1 claro cu\u00e1ndo esa fuerza comenzar\u00e1 a patrullar las calles de Gaza, ni si las fuerzas de seguridad interna de Hamas desaparecer\u00e1n cuando eso ocurra.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hamas est\u00e1 reafirmando el control de partes de Gaza que no est\u00e1n ocupadas por fuerzas israel\u00edes mientras se consolida el cese del fuego, en medio de la continua incertidumbre sobre la seguridad en el territorio si el grupo es desarmado. Las fuerzas de seguridad interna de Hamas fueron vistas en las calles de la Ciudad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467316","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hamas est\u00e1 reafirmando el control de partes de Gaza que no est\u00e1n ocupadas por fuerzas israel\u00edes mientras se consolida el cese del fuego, en medio de la continua incertidumbre sobre la seguridad en el territorio si el grupo es desarmado. Las fuerzas de seguridad interna de Hamas fueron vistas en las calles de la Ciudad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-12T21:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego\",\"datePublished\":\"2025-10-12T21:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\"},\"wordCount\":1085,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\",\"name\":\"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-12T21:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias","og_description":"Hamas est\u00e1 reafirmando el control de partes de Gaza que no est\u00e1n ocupadas por fuerzas israel\u00edes mientras se consolida el cese del fuego, en medio de la continua incertidumbre sobre la seguridad en el territorio si el grupo es desarmado. Las fuerzas de seguridad interna de Hamas fueron vistas en las calles de la Ciudad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-12T21:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/"},"author":{"name":"","@id":""},"headline":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego","datePublished":"2025-10-12T21:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/"},"wordCount":1085,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","name":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-12T21:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego","url":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-12T21:03:40Z","datePublished":"2025-10-12T21:03:40Z","dateModified":"2025-10-12T21:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hamas afirma su control en partes de Gaza y apunta a presuntos colaboradores mientras se consolida el cese del fuego\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/12\\\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/12\\\/hamas-control-gaza-colaboradores-alto-el-fuego-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-12T21:03:40Z\",\"datePublished\":\"2025-10-12T21:03:40Z\",\"dateModified\":\"2025-10-12T21:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458585,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/11\/cese-fuego-hamas-rehenes-sabado-netanyahu-trax\/","url_meta":{"origin":1467316,"position":0},"title":"El cese del fuego &#171;terminar\u00e1&#187; si Hamas no regresa a los rehenes para el s\u00e1bado, afirma Netanyahu","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Han transcurrido apenas tres semanas de un fr\u00e1gil cese del fuego y tanto Israel como Hamas est\u00e1n intensificando las acusaciones de que la otra parte ha violado el acuerdo.Hasta ahora, 16 de los 33 rehenes cuya liberaci\u00f3n estaba prevista en la fase actual del acuerdo han sido liberados por Hamas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467370,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/14\/combatientes-ejecutan-hombres-gaza-hamas-trax\/","url_meta":{"origin":1467316,"position":1},"title":"Video muestra a combatientes enmascarados ejecutando a hombres en Gaza mientras Hamas se enfrenta con grupos rivales","author":"","date":"octubre 14, 2025","format":false,"excerpt":"Ocurrieron enfrentamientos violentos entre Hamas y grupos rivales en varias zonas de Gaza, incluido un incidente que culmin\u00f3 en una aparente ejecuci\u00f3n p\u00fablica, mientras aumentan las preocupaciones sobre la situaci\u00f3n de seguridad tras la retirada de Israel de partes del territorio.Los informes de violencia se han difundido ampliamente en redes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464480,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/07\/13\/ninos-mueren-agua-gaza-estancan-negociaciones-alto-fuego-trax\/","url_meta":{"origin":1467316,"position":2},"title":"Reportan muerte de varios ni\u00f1os que recolectaban agua en Gaza, mientras se estancan negociaciones para un alto el fuego","author":"","date":"julio 13, 2025","format":false,"excerpt":"Las negociaciones por un nuevo alto al fuego en Gaza se estancan en Doha, mientras en el terreno decenas de personas mueren a diario por la ofensiva israel\u00ed, que busca afianzar su control sobre gran parte del territorio.En uno de los \u00faltimos ataques a\u00e9reos, varios ni\u00f1os murieron en un punto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461335,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/04\/17\/hamas-rechaza-oferta-alto-el-fuego-escalada-gaza-trax\/","url_meta":{"origin":1467316,"position":3},"title":"Hamas rechaza la oferta de cese del fuego mientras los legisladores israel\u00edes de extrema derecha piden una escalada en Gaza","author":"","date":"abril 17, 2025","format":false,"excerpt":"Hamas rechaz\u00f3 la oferta israel\u00ed de cese del fuego presentada a principios de esta semana, seg\u00fan un alto funcionario de Hamas, pidiendo en su lugar una propuesta \u201cintegral\u201d para poner fin a la guerra.El funcionario declar\u00f3 a CNN: \u201cRechazamos la oferta en su totalidad y en detalle\u201d.El rechazo llev\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459178,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/02\/25\/analisis-mientras-el-reloj-avanza-hacia-el-final-del-alto-el-fuego-en-gaza-israel-se-prepara-para-mas-guerra\/","url_meta":{"origin":1467316,"position":4},"title":"AN\u00c1LISIS | Mientras el reloj avanza hacia el final del cese del fuego en Gaza, Israel se prepara para m\u00e1s guerra","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Hace un mes, israel\u00edes y palestinos sent\u00edan lo m\u00e1s raro: optimismo.Tras meses de conversaciones estancadas, por fin hab\u00eda un cese del fuego en Gaza. Parec\u00eda haber un camino real hacia el final de la guerra.Pero la situaci\u00f3n ha cambiado dr\u00e1sticamente desde entonces.La tregua de 42 d\u00edas entre Israel y Hamas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468532,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/11\/20\/israel-mata-28-palestinos-gaza-hamas-trax\/","url_meta":{"origin":1467316,"position":5},"title":"Ataques israel\u00edes en Gaza dejan al menos 32 palestinos muertos, mientras Hamas advierte de una &#171;peligrosa escalada&#187;","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Los ataques israel\u00edes en Gaza han causado la muerte de al menos 32 palestinos en la \u00faltima escalada de violencia desde que entr\u00f3 en vigor el alto el fuego entre Israel y Hamas.El Ministerio de Salud palestino inform\u00f3 que entre los muertos en los ataques, que continuaron desde el mi\u00e9rcoles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1467316"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467316\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1467316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1467316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1467316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}