{"id":1467323,"date":"2025-10-12T19:03:39","date_gmt":"2025-10-13T02:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/"},"modified":"2025-10-12T19:03:39","modified_gmt":"2025-10-13T02:03:39","slug":"mundial-sub-20-cruces-semifinales-colombia-argentina-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","title":{"rendered":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final"},"content":{"rendered":"<p>Apenas cuatro selecciones mantienen vivo el sue\u00f1o de levantar el trofeo del Mundial Sub-20 que se est\u00e1 disputando en Chile, y dos de ellas representan a Sudam\u00e9rica.<\/p>\n<p>Colombia lleg\u00f3 a las semifinales despu\u00e9s de ganar una batalla ante una gran potencia como es Espa\u00f1a. El combinado cafetero, que hab\u00eda dejado algunas dudas en el duelo de octavos de final ante Sud\u00e1frica, despej\u00f3 cualquier aire de incertidumbre con una actuaci\u00f3n contundente, demostrando madurez para asimilar los dos goles casi consecutivos que marcaron los ib\u00e9ricos como para, con tranquilidad, buscar la remontada.<\/p>\n<p>Si Colombia est\u00e1 entre las mejores cuatro selecciones es por la tarde-noche consagratoria de su centrodelantero Neyser Villareal, quien marc\u00f3 los tres tantos de su equipo para, adem\u00e1s, subirse a lo m\u00e1s alto de la tabla de goleadores del torneo, con cinco. Incre\u00edblemente, no podr\u00e1 estar en el pr\u00f3ximo partido por haber llegado al l\u00edmite de amonestaciones. Una baja muy sensible para el elenco cafetero.<\/p>\n<p>Colombia tendr\u00e1 enfrente a la otra representante de Sudam\u00e9rica: Argentina. La albiceleste es una de las grandes candidatas al t\u00edtulo. Ya hab\u00eda sorteado sin problemas la fase de grupos, pero lo que sigui\u00f3 fue a\u00fan mejor: goleada 4 a 0 a Nigeria en octavos y un 2-0 inapelable en cuartos ante M\u00e9xico, un rival que promet\u00eda mucho, pero que acab\u00f3 minimizado por una Argentina que marc\u00f3 el primer gol r\u00e1pido y luego manej\u00f3 los hilos del partido sin problemas.<\/p>\n<p>La selecci\u00f3n dirigida por Diego Placente tiene un amplio abanico de jugadores que pueden ser titulares, sin que la estructura b\u00e1sica del equipo se resienta. Por eso, ante M\u00e9xico no solo no sufri\u00f3 la lesi\u00f3n de Montoro, sino que su reemplazante, Prestianni, fue la figura del encuentro.<\/p>\n<p>La defensa es otro punto a su favor: lleva ya tres presentaciones con la valla invicta.<\/p>\n<p>Cuando parec\u00eda que la selecci\u00f3n estadounidense era firme candidata para llegar a la final del Mundial Sub-20, apareci\u00f3 Marruecos. Los norteamericanos llegaban con el mote de favoritos despu\u00e9s de golear a Nueva Caledonia (9-1), Francia (3-0) y, en octavos de final, Italia (3-0), pero otra vez chocaron con un rival africano. En fase de grupos fue Sud\u00e1frica y en cuartos Marruecos, que la derrot\u00f3 por 3 a 1 para llegar a semifinales.<\/p>\n<p>Los Leones del Atlas apostaron por un juego directo, entregando campo y pelota a los estadounidenses, que, a diferencia de partidos anteriores, esta vez tuvieron una tarde de terror en defensa. Marruecos aprovech\u00f3 cada una de esas fallas y ahora sue\u00f1a con dar el gran golpe. Pergaminos no le faltan: ya la gan\u00f3 a Espa\u00f1a y a Brasil en este torneo.<\/p>\n<p>El seleccionado galo reaccion\u00f3 a tiempo en el torneo y poco queda de aquel que fue goleado por Estados Unidos en la fase de grupos. En los duelos directos se ha visto lo mejor de este seleccionado europeo, que primero elimin\u00f3 a Corea del Sur en octavos y ahora a Noruega en cuartos, este \u00faltimo siendo uno de los pocos invictos que quedaban en la competencia.<\/p>\n<p>El triunfo ante los noruegos por 2 a 1 fue sufrido por el descuento final, pero la realidad es que los franceses tuvieron el dominio durante casi todo el partido, con mayor posesi\u00f3n del bal\u00f3n y tambi\u00e9n el doble de tiros al arco. Francia est\u00e1 de vuelta y ahora va por m\u00e1s.<\/p>\n<p>Los dos enfrentamientos se dar\u00e1n el mi\u00e9rcoles.<\/p>\n<p><strong>Marruecos vs. Francia<\/strong><\/p>\n<ul>\n<li>4:00 p.m. de Miami.<\/li>\n<li>5:00 p.m. de Buenos Aires.<\/li>\n<li>3:00 p.m. de Bogot\u00e1.<\/li>\n<li>2:00 p.m. de Ciudad de M\u00e9xico.<\/li>\n<li>10:00 p.m. de Madrid.<\/li>\n<\/ul>\n<p><strong>Colombia vs. Argentina<\/strong><\/p>\n<ul>\n<li>7:00 p.m. de Miami.<\/li>\n<li>8:00 p.m. de Buenos Aires.<\/li>\n<li>6:00 p.m. de Bogot\u00e1.<\/li>\n<li>5:00 p.m. de Ciudad de M\u00e9xico.<\/li>\n<li>1:00 a.m. de Madrid (ya jueves).<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas cuatro selecciones mantienen vivo el sue\u00f1o de levantar el trofeo del Mundial Sub-20 que se est\u00e1 disputando en Chile, y dos de ellas representan a Sudam\u00e9rica. Colombia lleg\u00f3 a las semifinales despu\u00e9s de ganar una batalla ante una gran potencia como es Espa\u00f1a. El combinado cafetero, que hab\u00eda dejado algunas dudas en el duelo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467323","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias\" \/>\n<meta property=\"og:description\" content=\"Apenas cuatro selecciones mantienen vivo el sue\u00f1o de levantar el trofeo del Mundial Sub-20 que se est\u00e1 disputando en Chile, y dos de ellas representan a Sudam\u00e9rica. Colombia lleg\u00f3 a las semifinales despu\u00e9s de ganar una batalla ante una gran potencia como es Espa\u00f1a. El combinado cafetero, que hab\u00eda dejado algunas dudas en el duelo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T02:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final\",\"datePublished\":\"2025-10-13T02:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\"},\"wordCount\":670,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\",\"name\":\"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-13T02:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias","og_description":"Apenas cuatro selecciones mantienen vivo el sue\u00f1o de levantar el trofeo del Mundial Sub-20 que se est\u00e1 disputando en Chile, y dos de ellas representan a Sudam\u00e9rica. Colombia lleg\u00f3 a las semifinales despu\u00e9s de ganar una batalla ante una gran potencia como es Espa\u00f1a. El combinado cafetero, que hab\u00eda dejado algunas dudas en el duelo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-13T02:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/"},"author":{"name":"","@id":""},"headline":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final","datePublished":"2025-10-13T02:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/"},"wordCount":670,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","name":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-13T02:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mundial Sub-20: as\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final","url":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/12\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-13T02:03:39Z","datePublished":"2025-10-13T02:03:39Z","dateModified":"2025-10-13T02:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mundial Sub-20: as\\u00ed quedaron las semifinales, con Colombia y Argentina buscando la final\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/12\\\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/12\\\/mundial-sub-20-cruces-semifinales-colombia-argentina-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-13T02:03:39Z\",\"datePublished\":\"2025-10-13T02:03:39Z\",\"dateModified\":\"2025-10-13T02:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468581,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/11\/21\/mundial-sub-17-cuartos-semifinales-orix\/","url_meta":{"origin":1467323,"position":0},"title":"Mundial Sub-17: Austria e Italia firman la primera llave de semifinales; as\u00ed avanzan los cuartos de final","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"La recta final del Mundial Sub-17 est\u00e1 en marcha y las semifinales en el objetivo inmediato de las selecciones, que aspiran al t\u00edtulo de un torneo que cada vez llama m\u00e1s la atenci\u00f3n de los amantes del deporte rey.Solo un participante del continente americano qued\u00f3 en competencia, Brasil, mientras otros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466270,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/08\/venezuela-bolivia-como-clasifican-mundial-2026-orix\/","url_meta":{"origin":1467323,"position":1},"title":"Sue\u00f1o Mundial: \u00bfqu\u00e9 necesitan Venezuela y Bolivia para llegar a la Copa del Mundo de 2026?","author":"","date":"septiembre 8, 2025","format":false,"excerpt":"Las selecciones de Venezuela y Bolivia llegaban a la pen\u00faltima jornada de las Eliminatorias sudamericanas con la calculadora en la mano y un par de escenarios posibles, pero las goleadas que sufrieron jugando como visitantes (0-3 ante Argentina y Colombia, respectivamente) acortaron notablemente su margen de maniobra.Este martes, cuando salgan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466341,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/10\/bolivia-repechaje-mundial-2026-rivales-fechas-orix\/","url_meta":{"origin":1467323,"position":2},"title":"Bolivia en el repechaje al Mundial 2026: cu\u00e1ndo sabr\u00e1 sus rivales, c\u00f3mo se elegir\u00e1n y fechas clave","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Las Eliminatorias Sudamericanas para el Mundial de 2026 dejaron una gran sorpresa en la \u00faltima jornada: Bolivia venci\u00f3 a Brasil en los 4.100 metros de altura de El Alto y, como Venezuela fue goleada en casa ante Colombia, se meti\u00f3 en el repechaje intercontinental, que reci\u00e9n se disputar\u00e1 en marzo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465436,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/12\/repechaje-mundial-2026-orix\/","url_meta":{"origin":1467323,"position":3},"title":"As\u00ed se jugar\u00e1 el novedoso repechaje para el Mundial 2026","author":"","date":"agosto 12, 2025","format":false,"excerpt":"Con el aumento de 32 a 48 participantes para el Mundial de F\u00fatbol de 2026, la FIFA tambi\u00e9n tuvo que encontrar una alternativa para los repechajes clasificatorios, que ahora ser\u00e1n m\u00e1s parecidos a un \u201cmini mundial\u201d.La \u201crepesca internacional\u201d, nombre con el que la FIFA bautiz\u00f3 para esta edici\u00f3n al repechaje,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466238,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/09\/07\/mundial-2026-venezuela-bolivia-claves-repechaje-orix\/","url_meta":{"origin":1467323,"position":4},"title":"Mundial 2026: las claves de Venezuela y Bolivia para so\u00f1ar con el repechaje","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"Hay nerviosismo en Venezuela y Bolivia. Y como pocas veces visto, no tiene nada que ver con la crisis pol\u00edtica, econ\u00f3mica y social que puedan estar viviendo estos dos pa\u00edses sudamericanos. Es que este martes las dos selecciones nacionales de f\u00fatbol tienen una cita con la historia.Las Eliminatorias Sudamericanas llegar\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467369,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/14\/mundial-sub-20-argentina-colombia-semifinales-previa-orix\/","url_meta":{"origin":1467323,"position":5},"title":"Mundial Sub-20: Argentina vs. Colombia, por las semifinales: previa, alineaciones, horarios y c\u00f3mo ver por TV e internet","author":"","date":"octubre 14, 2025","format":false,"excerpt":"El Mundial Sub-20 tendr\u00e1 un finalista sudamericano. Argentina y Colombia se ver\u00e1n las caras este mi\u00e9rcoles en el Estadio Nacional Julio Mart\u00ednez Pradanos ubicado en Santiago de Chile. Albicelestes y cafeteros llegan a este duelo definitorio con niveles al alza, pero solo uno podr\u00e1 mantener vivo el sue\u00f1o de dar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1467323"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467323\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1467323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1467323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1467323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}