{"id":1467346,"date":"2025-10-13T21:03:46","date_gmt":"2025-10-14T04:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/"},"modified":"2025-10-13T21:03:46","modified_gmt":"2025-10-14T04:03:46","slug":"spacex-prueba-vuelo-megacohete-starship-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","title":{"rendered":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje"},"content":{"rendered":"<p>SpaceX lanz\u00f3 su nave m\u00e1s potente y durante una hora ejecut\u00f3 una serie de tareas con el prototipo Versi\u00f3n 2 de Starship.<\/p>\n<p>El lanzamiento de este lunes sigui\u00f3 al de <a href=\"https:\/\/www.cnn.com\/science\/live-news\/spacex-starship-flight-10-launch-08-26-25\">agosto<\/a>, que tambi\u00e9n transcurri\u00f3 sin inconvenientes mayores, en comparaci\u00f3n con los tres fallos de vuelo de las misiones previas.<\/p>\n<p>SpaceX busca completar el veh\u00edculo que le permita a la NASA un nuevo alunizaje, estipulado para 2017, en medio de una renovada carrera espacial con China.<\/p>\n<p>Se espera que la misi\u00f3n de prueba de este octubre sea la \u00faltima para la iteraci\u00f3n actual de los prototipos de Starship. La compa\u00f1\u00eda ha dicho que presentar\u00e1 una Versi\u00f3n 3 ampliada para el pr\u00f3ximo vuelo.<\/p>\n<p>Estos son algunos hitos de la m\u00e1s reciente prueba de vuelo de Starship, el gigantesco cohete que mide 121 metros de altura y genera 16,7 millones de libras de fuerza en el despegue.<\/p>\n<p>A diferencia de la espectacularidad de otras misiones anteriores, en la que el propulsor regresaba a la torre de lanzamiento, SpaceX no esperaba aterrizar ni recuperar de manera segura el Super Heavy.<\/p>\n<p>La raz\u00f3n, seg\u00fan la compa\u00f1\u00eda, es que someter\u00e1 el cohete a pruebas de resistencia con maniobras complejas para que los ingenieros puedan usar datos \u00fatiles en las versiones futuras del veh\u00edculo de manera m\u00e1s eficiente.<\/p>\n<p>El Super Heavy ameriz\u00f3 en las aguas del Golfo, justo al este de las instalaciones de lanzamiento de SpaceX, y pareci\u00f3 funcionar bien, o, al menos, no cay\u00f3 de forma aparatosa ni explot\u00f3.<\/p>\n<p>\u201cHasta ahora, todo bien por hoy; eso fue incre\u00edble\u201d, dijo Jake Berkowitz, ingeniero principal de propulsi\u00f3n de los motores de cohetes Starship de SpaceX.<\/p>\n<p>Una gran aleta en el costado del veh\u00edculo \u2014una compuerta llamada \u201cpuerta de carga\u201d\u2014 se abri\u00f3 y comenz\u00f3 a expulsar sat\u00e9lites falsos, marcando la segunda vez que SpaceX realiza una prueba de este tipo.<\/p>\n<p>A diferencia de otros cohetes, que despliegan sat\u00e9lites desde una punta c\u00f3nica, Starship tiene una puerta lateral que debe abrirse para permitir que los sat\u00e9lites se eyecten al espacio.<\/p>\n<p>Los sat\u00e9lites simulados est\u00e1n destinados a representar la versi\u00f3n m\u00e1s reciente de los sat\u00e9lites Starlink de SpaceX, que transmiten internet.<\/p>\n<p>Durante la transmisi\u00f3n en vivo de la misi\u00f3n, uno de los presentadores se\u00f1al\u00f3 que, cuando Starship est\u00e9 en funcionamiento, transportar\u00e1 lotes de unos 60 sat\u00e9lites Starlink a la \u00f3rbita en cada viaje.<\/p>\n<p>A pesar de que el Falcon 9 (el actual veh\u00edculo en el que se hace esta labor) es m\u00e1s peque\u00f1o y barato que Starship, seg\u00fan SpaceX, Starship ser\u00e1 m\u00e1s eficiente y ofrecer\u00e1 un precio m\u00e1s bajo por kilogramo para transportar carga a la \u00f3rbita.<\/p>\n<p>La Starship \u2014tambi\u00e9n conocida como la \u201cnave\u201d\u2014 ameriz\u00f3 en el oc\u00e9ano \u00cdndico. Esto marca la segunda vez que SpaceX logra alcanzar un hito de este tipo con la Versi\u00f3n 2, la serie de prototipos de Starship que la empresa present\u00f3 a principios de este a\u00f1o.<\/p>\n<p>Las Starship Versi\u00f3n 2 fallaron a mitad de vuelo en tres misiones en 2025. Solo con la misi\u00f3n de prueba en agosto la nave logr\u00f3 un aterrizaje limpio.<\/p>\n<p>Descubrir c\u00f3mo hacer que Starship regrese de manera segura a trav\u00e9s de la atm\u00f3sfera terrestre, intacta y sin perder contacto, es un gran logro: SpaceX espera alg\u00fan d\u00eda poder aterrizar la nave de forma segura para que pueda volar nuevamente.<\/p>\n<p>El vuelo de prueba de hoy marc\u00f3 el final de una breve pero impresionante historia de redenci\u00f3n para esta versi\u00f3n de Starship, apodada Versi\u00f3n 2 o V2.<\/p>\n<p>\u201cSe logr\u00f3 cada uno de los principales objetivos de la prueba de vuelo, proporcionando datos valiosos mientras preparamos la pr\u00f3xima generaci\u00f3n de Starship y Super Heavy\u201d, indica un <a href=\"https:\/\/www.spacex.com\/launches\/starship-flight-11\">resumen<\/a> de la misi\u00f3n del lunes en el sitio web de SpaceX.<\/p>\n<p>Despu\u00e9s de explotar tres veces en pleno vuelo a principios de este a\u00f1o, Starship alcanz\u00f3 hoy sus metas clave, incluyendo el despliegue de sat\u00e9lites de prueba y el reencendido de su motor en el espacio, repitiendo haza\u00f1as logradas por primera vez durante la primera prueba completamente exitosa de la V2 en agosto.<\/p>\n<p>SpaceX a\u00fan tiene un largo camino por recorrer antes de que el veh\u00edculo est\u00e9 listo para lanzar sat\u00e9lites reales, y mucho menos para llevar astronautas de la NASA a la Luna.<\/p>\n<p>Antes de que Starship pueda llegar all\u00ed, la empresa necesita llevar a cabo vuelos de prueba igualmente exitosos, pero quiz\u00e1s m\u00e1s desafiantes, de la Versi\u00f3n 3 de Starship, una versi\u00f3n ampliada del veh\u00edculo.<\/p>\n<p>\u201cAhora el enfoque se centra en la pr\u00f3xima generaci\u00f3n de Starship y Super Heavy, con varios veh\u00edculos actualmente en construcci\u00f3n y prepar\u00e1ndose para pruebas\u201d, dice el comunicado en el sitio web de SpaceX. \u201cEsta pr\u00f3xima iteraci\u00f3n se utilizar\u00e1 para los primeros vuelos orbitales de Starship, misiones operativas de carga \u00fatil, transferencia de propelente y m\u00e1s, mientras avanzamos hacia un veh\u00edculo completamente reutilizable y de r\u00e1pida rotaci\u00f3n, con servicio a la \u00f3rbita terrestre, la Luna, Marte y m\u00e1s all\u00e1\u201d.<\/p>\n<p>La transferencia de propelente es una pieza clave del rompecabezas para SpaceX.<br \/>Debido a su enorme tama\u00f1o y dise\u00f1o, la Starship debe ser recargada de combustible mientras est\u00e1 en \u00f3rbita terrestre para poder llegar a la Luna.<\/p>\n<p>Pero tal haza\u00f1a nunca se ha realizado antes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SpaceX lanz\u00f3 su nave m\u00e1s potente y durante una hora ejecut\u00f3 una serie de tareas con el prototipo Versi\u00f3n 2 de Starship. El lanzamiento de este lunes sigui\u00f3 al de agosto, que tambi\u00e9n transcurri\u00f3 sin inconvenientes mayores, en comparaci\u00f3n con los tres fallos de vuelo de las misiones previas. SpaceX busca completar el veh\u00edculo que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467346","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias\" \/>\n<meta property=\"og:description\" content=\"SpaceX lanz\u00f3 su nave m\u00e1s potente y durante una hora ejecut\u00f3 una serie de tareas con el prototipo Versi\u00f3n 2 de Starship. El lanzamiento de este lunes sigui\u00f3 al de agosto, que tambi\u00e9n transcurri\u00f3 sin inconvenientes mayores, en comparaci\u00f3n con los tres fallos de vuelo de las misiones previas. SpaceX busca completar el veh\u00edculo que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T04:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje\",\"datePublished\":\"2025-10-14T04:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\"},\"wordCount\":945,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\",\"name\":\"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-14T04:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias","og_description":"SpaceX lanz\u00f3 su nave m\u00e1s potente y durante una hora ejecut\u00f3 una serie de tareas con el prototipo Versi\u00f3n 2 de Starship. El lanzamiento de este lunes sigui\u00f3 al de agosto, que tambi\u00e9n transcurri\u00f3 sin inconvenientes mayores, en comparaci\u00f3n con los tres fallos de vuelo de las misiones previas. SpaceX busca completar el veh\u00edculo que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-14T04:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/"},"author":{"name":"","@id":""},"headline":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje","datePublished":"2025-10-14T04:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/"},"wordCount":945,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","name":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-14T04:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje","url":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2025\/10\/13\/spacex-prueba-vuelo-megacohete-starship-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-14T04:03:46Z","datePublished":"2025-10-14T04:03:46Z","dateModified":"2025-10-14T04:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El megacohete Starship de SpaceX alcanza hitos clave antes de un impresionante amerizaje\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/13\\\/spacex-prueba-vuelo-megacohete-starship-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2025\\\/10\\\/13\\\/spacex-prueba-vuelo-megacohete-starship-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-14T04:03:46Z\",\"datePublished\":\"2025-10-14T04:03:46Z\",\"dateModified\":\"2025-10-14T04:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450039,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","url_meta":{"origin":1467346,"position":0},"title":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN) -- SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba de su enorme cohete lunar.Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se abre a las 8 a.m. ET.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450059,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/06\/05\/starship-spacex-lanzamiento-junio-cuando-como-ver-trax\/","url_meta":{"origin":1467346,"position":1},"title":"Cuarto lanzamiento del Starship de SpaceX: qu\u00e9 busca, cu\u00e1ndo es y c\u00f3mo ver en vivo","author":"","date":"junio 5, 2024","format":false,"excerpt":"(CNN) -- SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba del Starship, su enorme cohete lunar.\u00bfCu\u00e1ndo es y a qu\u00e9 hora?Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462896,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/05\/28\/spacex-starship-que-fallo-trax\/","url_meta":{"origin":1467346,"position":2},"title":"Esto es lo que sali\u00f3 bien (y lo que sali\u00f3 mal) en el vuelo de prueba de SpaceX","author":"","date":"mayo 28, 2025","format":false,"excerpt":"La nave Starship de SpaceX super\u00f3 algunos hitos importantes. Sin embargo, no logr\u00f3 alcanzar algunos objetivos clave de la prueba. Aqu\u00ed un breve resumen de lo sucedido:El despegue fue un \u00e9xito. El cohete propulsor Super Heavy, que ya hab\u00eda volado en una misi\u00f3n anterior, encendi\u00f3 con \u00e9xito sus 33 motores.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465796,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/23\/spacex-prueba-starship-expertos-preocupados-trax\/","url_meta":{"origin":1467346,"position":3},"title":"Una &#171;apuesta existencial&#187;: SpaceX se prepara para la pr\u00f3xima prueba de Starship, pero algunos expertos est\u00e1n preocupados","author":"","date":"agosto 23, 2025","format":false,"excerpt":"El sistema de cohetes m\u00e1s poderoso jam\u00e1s construido se encamina hacia su pr\u00f3xima prueba, utilizando una versi\u00f3n del veh\u00edculo que ha estado en el centro de una serie de errores y fallas explosivas.SpaceX anunci\u00f3 que planea lanzar su megacohete Starship en un vuelo de prueba de una hora a partir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465888,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/26\/spacex-lanza-cohete-starship-decima-prueba-trax\/","url_meta":{"origin":1467346,"position":4},"title":"SpaceX lanza el cohete Starship en su d\u00e9cima prueba de vuelo tras meses de contratiempos","author":"","date":"agosto 26, 2025","format":false,"excerpt":"SpaceX lanz\u00f3 este martes el d\u00e9cimo vuelo de prueba de su nave espacial Starship y el propulsor Super Heavy. Este fue el tercer intento de lanzamiento de la misi\u00f3n, despu\u00e9s de que el despegue del domingo fuera frustrado por problemas en los sistemas en tierra y el intento del lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465822,"url":"https:\/\/noticiasya.com\/san-angelo\/2025\/08\/24\/spacex-cancela-intento-lanzamiento-starship-trax\/","url_meta":{"origin":1467346,"position":5},"title":"SpaceX cancel\u00f3 el intento de lanzamiento del megacohete Starship","author":"","date":"agosto 24, 2025","format":false,"excerpt":"SpaceX ten\u00eda como objetivo lanzar un d\u00e9cimo vuelo de prueba de una nave Starship y el propulsor Super Heavy alrededor de las 7:30 p.m. (hora de Miami) el domingo.Sin embargo, la compa\u00f1\u00eda pospuso el intento de lanzamiento debido a \u201cun problema con los sistemas terrestres\u201d, lo que indica que hubo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1467346"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1467346\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1467346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1467346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1467346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}