{"id":1470732,"date":"2026-02-01T13:03:51","date_gmt":"2026-02-01T21:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/"},"modified":"2026-02-01T13:03:51","modified_gmt":"2026-02-01T21:03:51","slug":"maria-corina-machado-presidencia-venezuela-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","title":{"rendered":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;"},"content":{"rendered":"<p>Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas.<\/p>\n<p>\u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el domingo en el programa \u201cFace the Nation\u201d de CBS.<\/p>\n<p>Machado a\u00fan no ha regresado a Venezuela tras la audaz operaci\u00f3n militar de Estados Unidos del mes pasado para remover al presidente depuesto Nicol\u00e1s Maduro.<\/p>\n<p>\u201cNo me permitieron postularme en la \u00faltima elecci\u00f3n, como ya mencionamos, porque Maduro ten\u00eda miedo de enfrentarse a m\u00ed, y pens\u00f3 que Edmundo no representaba una amenaza, porque nadie sab\u00eda qui\u00e9n era\u201d, dijo, al referirse a la campa\u00f1a electoral de 2024 de Edmundo Gonz\u00e1lez Urrutia contra Maduro.<\/p>\n<p>\u201cY en menos de tres meses logramos que todo el pa\u00eds lo apoyara, porque esto \u2014esto es un tema de libertad\u201d.<\/p>\n<p>En noviembre de 2024, Estados Unidos reconoci\u00f3 a Gonz\u00e1lez como \u201cpresidente electo\u201d del pa\u00eds sudamericano.<\/p>\n<p>Machado es una de las dos figuras que disputan el liderazgo de una Venezuela posterior a Maduro. Trump ha optado por trabajar con la hist\u00f3rica figura del r\u00e9gimen Delcy Rodr\u00edguez, quien ahora se desempe\u00f1a como presidenta interina.<\/p>\n<p>L\u00edderes de la oposici\u00f3n se mostraron decepcionados por la decisi\u00f3n de Trump de no respaldar a Machado, quien a comienzos de enero dijo que ser\u00eda \u201cmuy dif\u00edcil para ella ser la l\u00edder\u201d y que no ten\u00eda \u201cel respeto dentro del pa\u00eds\u201d.<\/p>\n<p>Aun as\u00ed, Machado cree que Trump la respalda y afirma que se concentra en lo que el presidente de Estados Unidos le ha dicho fuera del ojo p\u00fablico.<\/p>\n<p>\u201cMe voy a concentrar en lo que me dijo en una conversaci\u00f3n privada, mir\u00e1ndonos a los ojos, y yo \u2014yo realmente creo que \u00e9l entiende la naturaleza de este r\u00e9gimen. Todos saben que Delcy Rodr\u00edguez es una comunista en la que no se puede confiar. Ni siquiera, ya sabes, la gente que la rodea ahora mismo\u201d, dijo Machado.<\/p>\n<p>Agreg\u00f3 que Rodr\u00edguez \u201cest\u00e1 haciendo lo que est\u00e1 haciendo porque Estados Unidos est\u00e1 ejerciendo la presi\u00f3n suficiente para que entiendan que no tiene otra opci\u00f3n\u201d.<\/p>\n<p>Machado a\u00f1adi\u00f3 que, sin esa presi\u00f3n, Rodr\u00edguez dar\u00eda marcha atr\u00e1s. \u201cSi esa presi\u00f3n se retirara, ella se dar\u00eda la vuelta y volver\u00eda a donde\u2026 su lealtad est\u00e1 con esos reg\u00edmenes\u201d, dijo, al sugerir que Rodr\u00edguez retomar\u00eda el trabajo con \u201clos enemigos de Estados Unidos\u201d, Gobiernos estrechamente alineados con el r\u00e9gimen de Maduro, como Rusia, Ir\u00e1n, China y Cuba.<\/p>\n<p>\u201cAs\u00ed que aqu\u00ed nadie es ingenuo\u201d, dijo Machado, al a\u00f1adir que cree que Rodr\u00edguez en realidad est\u00e1 ayudando a hacer \u201cparte del trabajo sucio de desmantelar su propio r\u00e9gimen y su entorno\u201d.<\/p>\n<p>El 15 de enero, Machado entreg\u00f3 a Trump su Premio Nobel de la Paz durante una visita a la Casa Blanca.<\/p>\n<p>Consultada por CBS sobre el motivo, dijo: \u201cCreo que esto es una cuesti\u00f3n de justicia y de lo que est\u00e1 en el inter\u00e9s superior de nuestro pa\u00eds. Nosotros, el pueblo venezolano, estamos verdaderamente agradecidos por lo que ha hecho y confiamos en lo que har\u00e1 en los d\u00edas, semanas y meses por venir\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas. \u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el domingo en el programa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470732","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &quot;cuando llegue el momento&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &quot;cuando llegue el momento&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas. \u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el domingo en el programa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T21:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;\",\"datePublished\":\"2026-02-01T21:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\",\"name\":\"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela \\\"cuando llegue el momento\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-01T21:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela \"cuando llegue el momento\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela \"cuando llegue el momento\" - Noticias","og_description":"Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas. \u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el domingo en el programa [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-01T21:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/"},"author":{"name":"","@id":""},"headline":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;","datePublished":"2026-02-01T21:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","name":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela \"cuando llegue el momento\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-01T21:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;","url":"http:\/\/noticiasya.com\/san-angelo\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-angelo\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-01T21:03:51Z","datePublished":"2026-02-01T21:03:51Z","dateModified":"2026-02-01T21:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mar\\u00eda Corina Machado dice que ser\\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2026\\\/02\\\/01\\\/maria-corina-machado-presidencia-venezuela-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-angelo\\\/2026\\\/02\\\/01\\\/maria-corina-machado-presidencia-venezuela-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-01T21:03:51Z\",\"datePublished\":\"2026-02-01T21:03:51Z\",\"dateModified\":\"2026-02-01T21:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470149,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/16\/machado-conferencia-prensa-eeuu-venezuela-trump-orix\/","url_meta":{"origin":1470732,"position":0},"title":"Machado dice que a Trump &#171;realmente le importa la vida y el bienestar de los venezolanos&#187;","author":"","date":"enero 16, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado ofrece este viernes una conferencia de prensa desde Washington, donde ayer se reuni\u00f3 con el presidente de Estados Unidos, Donald Trump.A Trump \u201crealmente le importa la vida y el bienestar de los venezolanos\u201d, asegur\u00f3 Machado, \u201c\u00e9l me lo dijo\u201d.\u201cEstamos absolutamente agradecidos con Trump.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470155,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/16\/machado-conferencia-prensa-eeuu-trump-orix\/","url_meta":{"origin":1470732,"position":1},"title":"Machado dice que a Trump &#171;realmente le importa la vida y el bienestar de los venezolanos&#187;","author":"","date":"enero 16, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado ofrece este viernes una conferencia de prensa desde Washington, donde ayer se reuni\u00f3 con el presidente de Estados Unidos, Donald Trump.A Trump \u201crealmente le importa la vida y el bienestar de los venezolanos\u201d, asegur\u00f3 Machado, \u201c\u00e9l me lo dijo\u201d.\u201cEstamos absolutamente agradecidos con Trump.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471230,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/02\/14\/maria-corina-machado-eeuu-derrocamiento-maduro-trax\/","url_meta":{"origin":1470732,"position":2},"title":"Mar\u00eda Corina Machado elogia el papel de EE.UU. en el derrocamiento de Maduro","author":"","date":"febrero 14, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo que Estados Unidos arriesg\u00f3 la vida de sus ciudadanos para derrocar la dictadura de Nicol\u00e1s Maduro en Venezuela, por lo cual dedic\u00f3 su Premio Nobel de la Paz al presidente de EE.UU., Donald Trump.En su intervenci\u00f3n este s\u00e1bado en la Conferencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451349,"url":"https:\/\/noticiasya.com\/san-angelo\/2024\/07\/22\/maria-corina-machado-venezuela-elecciones-conclusiones-entrevista-conclu-orix\/","url_meta":{"origin":1470732,"position":3},"title":"Mar\u00eda Corina Machado en Conclusiones: Maduro ha hecho de su campa\u00f1a la violencia, es lo \u00fanico que le queda","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Mar\u00eda Corina Machado asegur\u00f3 en Conclusiones de CNN con Fernando del Rinc\u00f3n que Nicol\u00e1s Maduro ha hecho de su campa\u00f1a la violencia debido a que es lo \u00fanico que le queda, pues el r\u00e9gimen se ha desgastado tanto que \"ya est\u00e1 derrotado\".La semana pasada, el presidente Nicol\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470127,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/01\/15\/claves-maria-corina-machado-delcy-rodriguez-trump-orix\/","url_meta":{"origin":1470732,"position":4},"title":"Claves del d\u00eda en que Mar\u00eda Corina Machado y Delcy Rodr\u00edguez compitieron por la atenci\u00f3n de Trump y el futuro de Venezuela","author":"","date":"enero 15, 2026","format":false,"excerpt":"Venezuela vivi\u00f3 este jueves, otra vez, una jornada intensa y potencialmente hist\u00f3rica. A menos de dos semanas del derrocamiento del presidente Nicol\u00e1s Maduro en un ataque militar de EE.UU., su flamante reemplazo, Delcy Rodr\u00edguez, ofreci\u00f3 su primer discurso del estado de la naci\u00f3n ante la Asamblea Nacional y mientras intenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473326,"url":"https:\/\/noticiasya.com\/san-angelo\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","url_meta":{"origin":1470732,"position":5},"title":"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos","author":"","date":"abril 20, 2026","format":false,"excerpt":"La l\u00edder opositora Mar\u00eda Corina Machado asegur\u00f3 este domingo que \u201ces importante\u201d que Venezuela celebre elecciones democr\u00e1ticas lo antes posible para que \u201clos venezolanos no se desesperen y toda la energ\u00eda se canalice de una manera c\u00edvica\u201d.En una entrevista con EFE en Madrid, la premio nobel de la paz dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-angelo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1470732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/comments?post=1470732"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/posts\/1470732\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/media?parent=1470732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/categories?post=1470732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-angelo\/wp-json\/wp\/v2\/tags?post=1470732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}