{"id":1423462,"date":"2022-08-31T11:20:26","date_gmt":"2022-08-31T18:20:26","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1423462"},"modified":"2022-08-31T11:20:26","modified_gmt":"2022-08-31T18:20:26","slug":"conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","title":{"rendered":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis"},"content":{"rendered":"<p> <span style=\"font-weight: 400\">Tan solo en el 2021, en el condado de San Diego se registraron 1,303 muertes a causa de las drogas, es por ello que las v\u00edctimas ser\u00e1n conmemoradas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400\">Madres, padres, hermanos, hermanas, amigos y colegas son las v\u00edctimas en estas muertes, que cada vez van m\u00e1s en aumento.\u00a0<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Seg\u00fan datos de los Centros para el Control y Prevenci\u00f3n de Enfermedades, de las m\u00e1s de 9,300 sobredosis de drogas reportadas en 2020, m\u00e1s de las tres cuartas partes se atribuyeron a los opioides.\u00a0<\/span><\/p>\n<p>Un factor clave en el aumento de las muertes por sobredosis a nivel nacional y local es el fentanilo ilegal en las calles, que es un opioide sint\u00e9tico 50-100 veces m\u00e1s fuerte que la morfina.<\/p>\n<p><a href=\"https:\/\/noticiasya.com\/2022\/08\/25\/preocupa-la-distribucion-de-fentanilo-en-tijuana-tanto-como-en-san-diego\/\" target=\"_blank\" rel=\"noopener\">LEE: Preocupa la distribuci\u00f3n de fentanilo en Tijuana, tanto como en San Diego<\/a><\/p>\n<p><span style=\"font-weight: 400\">Muchas personas que consumen activamente creen que est\u00e1n comprando p\u00edldoras de opioides de calidad farmac\u00e9utica, hero\u00edna u otras drogas callejeras y no se dan cuenta de que est\u00e1n obteniendo fentanilo il\u00edcito, que a menudo resulta en muertes por sobredosis.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cEl preocupante aumento de las muertes por sobredosis relacionadas con el fentanilo en los \u00faltimos a\u00f1os se ha convertido en una crisis. Esto est\u00e1 afectando a casi todos los c\u00f3digos postales y cobrando vidas m\u00e1s j\u00f3venes en el condado de San Diego\u201d, destac\u00f3 la fiscal de distrito del condado de San Diego, Summer Stephan.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400\">El condado de San Diego record\u00f3 a las v\u00edctimas de sobredosis este mi\u00e9rcoles, 31 de agosto, colocando 1,303 banderas moradas en el c\u00e9sped del Centro de Administraci\u00f3n del Condado.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400\">Durante el evento, tambi\u00e9n se dieron cita personal de la sala de emergencias, profesionales de la salud del comportamiento y trastornos por uso de sustancias, as\u00ed como familiares de las v\u00edctimas y sobrevivientes de sobredosis.<\/span><\/p>\n<p><a href=\"https:\/\/noticiasya.com\/2022\/06\/28\/crisis-de-salud-publica-por-venta-de-fentanilo-en-san-diego-autoridades-toman-accion\/\" target=\"_blank\" rel=\"noopener\">lee: Crisis de salud p\u00fablica por venta de fentanilo en San Diego, autoridades toman acci\u00f3n<\/a><\/p>\n<p><span style=\"font-weight: 400\">Adem\u00e1s, el personal de emergencia de UCSD Medical Center y Falck Ambulance ofrecieron demostraciones de c\u00f3mo administrar naloxona, un medicamento que salva vidas y que puede revertir una sobredosis de opioides.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El condado de San Diego planea instalar una docena de m\u00e1quinas expendedoras de naloxona y distribuir m\u00e1s de 30 mil kits de naloxona para fines de 2023 en la lucha contra las sobredosis.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madres, padres, hermanos, hermanas, amigos y colegas son las v\u00edctimas en estas muertes, que cada vez van m\u00e1s en aumento. <\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[36,298,312],"tags":[257,299],"class_list":["post-1423462","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-instagram","category-salud","tag-narcotrafico","tag-san-diego","market-san-diego"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias\" \/>\n<meta property=\"og:description\" content=\"Madres, padres, hermanos, hermanas, amigos y colegas son las v\u00edctimas en estas muertes, que cada vez van m\u00e1s en aumento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T18:20:26+00:00\" \/>\n<meta name=\"author\" content=\"agomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"agomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\"},\"author\":{\"name\":\"agomez\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4bfeadc06f87892bd3c7d0ecf4b92ea5\"},\"headline\":\"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis\",\"datePublished\":\"2022-08-31T18:20:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"keywords\":[\"Narcotr\u00e1fico\",\"San Diego\"],\"articleSection\":[\"Comunidad\",\"Instagram\",\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\",\"url\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\",\"name\":\"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2022-08-31T18:20:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4bfeadc06f87892bd3c7d0ecf4b92ea5\",\"name\":\"agomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bf93b384a664c88a2ecc8f7be3062df2009608f856c7f84ca8b4275bd945bdb2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bf93b384a664c88a2ecc8f7be3062df2009608f856c7f84ca8b4275bd945bdb2?s=96&d=mm&r=g\",\"caption\":\"agomez\"},\"url\":\"https:\/\/noticiasya.com\/san-diego\/author\/agomez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","og_locale":"es_ES","og_type":"article","og_title":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias","og_description":"Madres, padres, hermanos, hermanas, amigos y colegas son las v\u00edctimas en estas muertes, que cada vez van m\u00e1s en aumento.","og_url":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","og_site_name":"Noticias","article_published_time":"2022-08-31T18:20:26+00:00","author":"agomez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"agomez","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/"},"author":{"name":"agomez","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4bfeadc06f87892bd3c7d0ecf4b92ea5"},"headline":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis","datePublished":"2022-08-31T18:20:26+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/"},"wordCount":422,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"keywords":["Narcotr\u00e1fico","San Diego"],"articleSection":["Comunidad","Instagram","Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","url":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","name":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2022-08-31T18:20:26+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4bfeadc06f87892bd3c7d0ecf4b92ea5","name":"agomez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bf93b384a664c88a2ecc8f7be3062df2009608f856c7f84ca8b4275bd945bdb2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf93b384a664c88a2ecc8f7be3062df2009608f856c7f84ca8b4275bd945bdb2?s=96&d=mm&r=g","caption":"agomez"},"url":"https:\/\/noticiasya.com\/san-diego\/author\/agomez"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conmemoran a v\u00edctimas de drogas en el D\u00eda Internacional de Concientizaci\u00f3n sobre la Sobredosis","url":"http:\/\/noticiasya.com\/san-diego\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2022\/08\/31\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Comunidad","author":[{"@type":"Person","name":"agomez"}],"creator":["agomez"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["narcotr\u00e1fico","san diego"],"dateCreated":"2022-08-31T18:20:26Z","datePublished":"2022-08-31T18:20:26Z","dateModified":"2022-08-31T18:20:26Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conmemoran a v\\u00edctimas de drogas en el D\\u00eda Internacional de Concientizaci\\u00f3n sobre la Sobredosis\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2022\\\/08\\\/31\\\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2022\\\/08\\\/31\\\/conmemoran-a-victimas-de-drogas-en-el-dia-internacional-de-concientizacion-sobre-la-sobredosis\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Comunidad\",\"author\":[{\"@type\":\"Person\",\"name\":\"agomez\"}],\"creator\":[\"agomez\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"narcotr\\u00e1fico\",\"san diego\"],\"dateCreated\":\"2022-08-31T18:20:26Z\",\"datePublished\":\"2022-08-31T18:20:26Z\",\"dateModified\":\"2022-08-31T18:20:26Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462345,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/14\/muertes-sobredosis-drogas-caida-estados-unidos-trax\/","url_meta":{"origin":1423462,"position":0},"title":"Las muertes por sobredosis de drogas experimentaron una ca\u00edda en EE.UU., pero los recortes podr\u00edan amenazar esta tendencia","author":"agomez","date":"mayo 14, 2025","format":false,"excerpt":"Las muertes por sobredosis de drogas en Estados Unidos experimentaron una ca\u00edda sin precedentes en 2024, y quedaron al nivel m\u00e1s bajo en cinco a\u00f1os, seg\u00fan una nueva estimaci\u00f3n del Gobierno federal publicada este mi\u00e9rcoles.Durante la pandemia de covid-19, las muertes por sobredosis de drogas alcanzaron niveles r\u00e9cord. Los nuevos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1433370,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/10\/20\/aumento-de-muertes-por-fentanilo-preocupa-a-las-autoridades-del-condado-de-nueces\/","url_meta":{"origin":1423462,"position":1},"title":"Aumento de muertes por fentanilo preocupa a las autoridades del Condado de Nueces","author":"agomez","date":"octubre 20, 2022","format":false,"excerpt":"En el \u00faltimo a\u00f1o el fentanilo fue la primera causa de muerte entre los estadounidenses de 18 a 45 a\u00f1os de edad.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470590,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/29\/esperanza-vida-tasa-mortalidad-muerte-trax\/","url_meta":{"origin":1423462,"position":2},"title":"La esperanza de vida en EE.UU alcanz\u00f3 r\u00e9cord en 2024 a medida que disminuyeron las muertes por sobredosis y covid-19","author":"agomez","date":"enero 29, 2026","format":false,"excerpt":"Las personas en los Estados Unidos pueden esperar vivir m\u00e1s que nunca, ya que las tasas de mortalidad volvieron a los niveles previos a la pandemia en 2024.La esperanza de vida en Estados Unidos hab\u00eda estado aumentando durante d\u00e9cadas antes de caer casi un a\u00f1o y medio entre 2019 y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1420765,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/08\/18\/policias-y-bomberos-de-chula-vista-tendran-aplicacion-para-rastrear-sobredosis-por-fentanilo\/","url_meta":{"origin":1423462,"position":3},"title":"Polic\u00edas y bomberos de Chula Vista tendr\u00e1n aplicaci\u00f3n para rastrear sobredosis por fentanilo","author":"agomez","date":"agosto 18, 2022","format":"video","excerpt":"La idea de las autoridades es apoyarse de esta tecnolog\u00eda para disminuir las muertes por el consumo de fentanilo.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458580,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/11\/impacto-del-fentanilo-en-ee-uu-graficos-y-mapas-trax\/","url_meta":{"origin":1423462,"position":4},"title":"El impacto del fentanilo en EE.UU. en gr\u00e1ficos y mapas","author":"agomez","date":"febrero 11, 2025","format":false,"excerpt":"El fentanilo es un opioide sint\u00e9tico potente que puede ser hasta 100 veces m\u00e1s fuerte que la morfina.Puede recetarse en entornos m\u00e9dicos formales para aliviar el dolor intenso y tratar el dolor severo cuando los analg\u00e9sicos de acci\u00f3n prolongada no son suficientes. Por ejemplo, las inyecciones pueden utilizarse durante o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1409496,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/06\/28\/crisis-de-salud-publica-por-venta-de-fentanilo-en-san-diego-autoridades-toman-accion\/","url_meta":{"origin":1423462,"position":5},"title":"Crisis de salud p\u00fablica por venta de fentanilo en San Diego, autoridades toman acci\u00f3n","author":"agomez","date":"junio 28, 2022","format":false,"excerpt":"El condado tiene servicios de tratamiento para pacientes hospitalizados y ambulatorios disponibles.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1423462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1423462"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1423462\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1423462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1423462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1423462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}