{"id":1436399,"date":"2023-01-04T18:51:07","date_gmt":"2023-01-05T02:51:07","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1436399"},"modified":"2024-03-11T15:15:25","modified_gmt":"2024-03-11T22:15:25","slug":"residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","title":{"rendered":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes con la tradicional rosca\" frameborder=\"0\" width=\"500\" height=\"283\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x8gx6pg&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe><\/p>\n<p>Muchos residentes de San Diego se preparan para continuar con las festividades del D\u00eda de Reyes, una celebraci\u00f3n que da la bienvenida a los Reyes Magos.<\/p>\n<p style=\"font-weight: 400\">Los hermanos Delgado son los responsables de la elaboraci\u00f3n de la rosca de reyes, una tradici\u00f3n familiar que mantienen desde hace m\u00e1s de 40 a\u00f1os, gracias a su padre, un panadero originario de Guadalajara.<\/p>\n<p style=\"font-weight: 400\">As\u00ed como la tradici\u00f3n de quienes preparan la rosca, est\u00e1 la tradici\u00f3n de quienes la compran, como la se\u00f1ora Marines, que por m\u00e1s de 30 a\u00f1os ha sido cliente de la panader\u00eda Panchitas, ubicada en el vecindario de Golden Hills, para continuar con la tradici\u00f3n inculcada por sus padres.<\/p>\n<p style=\"font-weight: 400\">\u201dToda mi vida, mis padres lo hac\u00edan y segu\u00ed yo con la tradici\u00f3n, muy bonito tener la tradici\u00f3n del nacimiento.\u201d Comparti\u00f3 Marines Martin, cliente de Panchitas Bakery.<\/p>\n<p style=\"font-weight: 400\">Adem\u00e1s de la tradicional rosca de reyes, los hermanos Delgado tambi\u00e9n preparan una rosca rellena de queso crema y otra rellena de frutas. todas muy solicitadas tanto en san diego como Tijuana, incluso otros estados del pa\u00eds, no solo este 6 de enero, sino durante todo el mes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1436401 size-large\" src=\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\" alt=\"\" width=\"1024\" height=\"576\" \/><\/p>\n<p style=\"font-weight: 400\">Desde el coraz\u00f3n de la panader\u00eda Panchitas Bakery es donde salen miles de roscas para deleitar el paladar de los residentes de San Diego, con el fin de celebrar la tradici\u00f3n del d\u00eda de reyes, una tradici\u00f3n que muchos festejan, pero pocos saben el verdadero significado.<\/p>\n<p style=\"font-weight: 400\">\u201cEl monito este representa el ni\u00f1o dios que estaba escondi\u00e9ndose de poncio Pilato que quer\u00eda matar a todos los ni\u00f1os de esa \u00e9poca y nosotros como mexicanos se form\u00f3 una tradici\u00f3n que data de mucho tiempo atr\u00e1s, \u201ccoment\u00f3 Juan Manuel Delgado, Panadero de Panchitas Bakery,<\/p>\n<p style=\"font-weight: 400\">La rosca de reyes tambi\u00e9n se caracteriza por su forma ovalada, s\u00edmbolo del amor eterno de dios, que no tiene ni principio ni fin. Las frutas secas que adornan la rosca, simbolizan las joyas incrustadas en las coronas de los reyes magos; Melchor, Gaspar y Baltazar.<\/p>\n<p style=\"font-weight: 400\">\u201cSeg\u00fan las personas que quieren que les salga, los que van a pagar tamales, los que van a poner el champurrado, son los que se dividen varios monitos para eso.\u201d Dijo Carlos Delgado, Panadero de Panchitas Bakery.<\/p>\n<p style=\"font-weight: 400\">En M\u00e9xico se tiene la tradici\u00f3n de quien encuentra la figura del ni\u00f1o Jes\u00fas, debe cuidarlo hasta el dos de febrero, que se celebra el \u201cd\u00eda de la candelaria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el coraz\u00f3n de la panader\u00eda Panchitas es donde salen miles de roscas para deleitar el paladar de los residentes de San Diego para celebrar la tradici\u00f3n del D\u00eda de Reyes. <\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[36,298],"tags":[301,299],"class_list":["post-1436399","post","type-post","status-publish","format-video","hentry","category-comunidad","category-instagram","tag-celebracion","tag-san-diego","post_format-post-format-video","market-san-diego"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Desde el coraz\u00f3n de la panader\u00eda Panchitas es donde salen miles de roscas para deleitar el paladar de los residentes de San Diego para celebrar la tradici\u00f3n del D\u00eda de Reyes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T02:51:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T22:15:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes\",\"datePublished\":\"2023-01-05T02:51:07+00:00\",\"dateModified\":\"2024-03-11T22:15:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\",\"keywords\":[\"Celebraci\u00f3n\",\"San Diego\"],\"articleSection\":[\"Comunidad\",\"Instagram\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\",\"url\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\",\"name\":\"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\",\"datePublished\":\"2023-01-05T02:51:07+00:00\",\"dateModified\":\"2024-03-11T22:15:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/san-diego\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","og_locale":"es_ES","og_type":"article","og_title":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias","og_description":"Desde el coraz\u00f3n de la panader\u00eda Panchitas es donde salen miles de roscas para deleitar el paladar de los residentes de San Diego para celebrar la tradici\u00f3n del D\u00eda de Reyes.","og_url":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","og_site_name":"Noticias","article_published_time":"2023-01-05T02:51:07+00:00","article_modified_time":"2024-03-11T22:15:25+00:00","og_image":[{"url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/"},"author":{"name":"","@id":""},"headline":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes","datePublished":"2023-01-05T02:51:07+00:00","dateModified":"2024-03-11T22:15:25+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/"},"wordCount":444,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024","keywords":["Celebraci\u00f3n","San Diego"],"articleSection":["Comunidad","Instagram"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","url":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","name":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024","datePublished":"2023-01-05T02:51:07+00:00","dateModified":"2024-03-11T22:15:25+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#primaryimage","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/3\/2023\/01\/IMG_3941.MOV.00_00_02_08.Still001.jpg?w=1024"},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/san-diego\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Residentes de San Diego se preparan para celebrar el D\u00eda de Reyes","url":"http:\/\/noticiasya.com\/san-diego\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2023\/01\/04\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Comunidad","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["celebraci\u00f3n","san diego"],"dateCreated":"2023-01-05T02:51:07Z","datePublished":"2023-01-05T02:51:07Z","dateModified":"2024-03-11T22:15:25Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Residentes de San Diego se preparan para celebrar el D\\u00eda de Reyes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2023\\\/01\\\/04\\\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2023\\\/01\\\/04\\\/residentes-de-san-diego-se-preparan-para-celebrar-el-dia-de-reyes\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Comunidad\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"celebraci\\u00f3n\",\"san diego\"],\"dateCreated\":\"2023-01-05T02:51:07Z\",\"datePublished\":\"2023-01-05T02:51:07Z\",\"dateModified\":\"2024-03-11T22:15:25Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467998,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/tradiciones-dia-de-muertos-mixquic-trax\/","url_meta":{"origin":1436399,"position":0},"title":"En Mixquic, el D\u00eda de Muertos florece entre incienso, p\u00e9talos y tradici\u00f3n familiar","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"La ruta desde la tierra de los muertos hasta San Andr\u00e9s Mixquic, un peque\u00f1o pueblo a las afueras de la Ciudad de M\u00e9xico, est\u00e1 marcada de flores de cempas\u00fachil. \u00c1ngel Jim\u00e9nez del \u00c1guila, quien muri\u00f3 en 2010, solo necesita seguir el rastro de p\u00e9talos de flores, el aroma del copal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450333,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/06\/13\/dia-padre-colombia-2024-cuando-fecha-orix\/","url_meta":{"origin":1436399,"position":1},"title":"\u00bfCu\u00e1ndo se celebra el D\u00eda del Padre en Colombia en 2024 y por qu\u00e9?","author":"","date":"junio 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En la mayor\u00eda de los pa\u00edses de Latinoam\u00e9rica el D\u00eda del Padre se celebra el tercer domingo de junio cada a\u00f1o. Este a\u00f1o, siguiendo la tradici\u00f3n, el d\u00eda del padre es el domingo 16 de junio y as\u00ed se celebra en Colombia.Gu\u00eda de regalos para el D\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460425,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/03\/26\/tatuaje-real-madrid-venezolano-deportado-trax\/","url_meta":{"origin":1436399,"position":2},"title":"Tiene un tatuaje del Real Madrid. Su abogado cree que por eso lo deportaron","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Las dos cosas m\u00e1s importantes en la vida de Jerce Reyes, seg\u00fan quienes mejor lo conocen, son la familia y el f\u00fatbol.Los tatuajes del exfutbolista profesional son un testimonio de esas pasiones: un bal\u00f3n de f\u00fatbol y otros s\u00edmbolos en su brazo izquierdo, as\u00ed como los nombres de sus dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450379,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/06\/15\/trooping-colour-desfile-por-que-rey-carlos-iii-dos-cumpleanos-trax\/","url_meta":{"origin":1436399,"position":3},"title":"\u00bfPor qu\u00e9 el rey Carlos III celebra dos cumplea\u00f1os? El origen del desfile Trooping the Colour","author":"","date":"junio 15, 2024","format":false,"excerpt":"(CNN) -- El papel de rey del Reino Unido conlleva una larga lista de ventajas, pero quiz\u00e1 una de las m\u00e1s envidiables sea la posibilidad de celebrar tu cumplea\u00f1os no una, sino dos veces al a\u00f1o.El rey Carlos cumple el 14 de noviembre, pero este fin de semana vuelve a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1414033,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/07\/19\/a-casi-40-anos-recuerdan-a-las-victimas-de-la-masacre-en-mcdonald-s-de-san-ysidro\/","url_meta":{"origin":1436399,"position":4},"title":"A casi 40 a\u00f1os, recuerdan a las v\u00edctimas de la masacre en McDonald &#8216;s de San Ysidro","author":"agomez","date":"julio 19, 2022","format":"video","excerpt":"Este lunes 18 de julio se cumple el aniversario 38 de la terrible masacre ocurrida en el McDonald 's de San Ysidro.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1436055,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/12\/06\/arrancan-los-preparativos-por-el-dia-de-la-virgen-de-guadalupe-en-san-diego\/","url_meta":{"origin":1436399,"position":5},"title":"Arrancan los preparativos por el D\u00eda de la Virgen de Guadalupe en San Diego","author":"agomez","date":"diciembre 6, 2022","format":"video","excerpt":"Una televidente devota de la morenita, abri\u00f3 las puertas de su hogar a noticias Univision San Diego, para mostrar su fervor por esta tradici\u00f3n religiosa.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1436399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1436399"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1436399\/revisions"}],"predecessor-version":[{"id":1446844,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1436399\/revisions\/1446844"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1436399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1436399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1436399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}