{"id":1436646,"date":"2023-01-31T15:02:18","date_gmt":"2023-01-31T23:02:18","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1436646"},"modified":"2023-01-31T15:02:18","modified_gmt":"2023-01-31T23:02:18","slug":"los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","title":{"rendered":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD"},"content":{"rendered":"<p>Las fechas que RBD est\u00e1 ofreciendo por todo lo largo y ancho del continente se est\u00e1n convirtiendo en los conciertos m\u00e1s esperados y es que mucha gente creci\u00f3 con su m\u00fasica y con la telenovela de Rebelde, por lo que la nostalgia es el principal motivo por el que los boletos de cada venue se est\u00e1n agotando.<\/p>\n<p>Tanto en M\u00e9xico como en Estados Unidos los tickets se est\u00e1n terminando al instante de que salen a la venta, ya sean bots o fans que llevaban horas pegados a la computadora, miles y miles de personas se est\u00e1n quedando fuera de sus conciertos y si no abren fechas pronto seguramente no podr\u00e1n asistir.<\/p>\n<p>Con esto en mente y como la internet no perdona, ya hay cientos de memes que representan a los fans que por una u otra cosa no han podido adquirir sus entradas y lamentablemente est\u00e1n sufriendo por todos los rincones.<\/p>\n<p>Por eso te traemos los m\u00e1s divertidos y un recuento de los da\u00f1os que han atravesado los RBD Army.<\/p>\n<p>\u00bfEst\u00e1s listo para las risas?<\/p>\n<p><a href=\"https:\/\/twitter.com\/Chicago_Gi\/status\/1619425038024986625\" rel=\"nofollow\">https:\/\/twitter.com\/Chicago_Gi\/status\/1619425038024986625<\/a><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Esperando que me depositen la quincena que ya me gast\u00e9 en boletos de RBD. <a href=\"https:\/\/t.co\/8AQt35EDOM\">pic.twitter.com\/8AQt35EDOM<\/a><\/p>\n<p>&mdash; sam just sam (@SamSCid) <a href=\"https:\/\/twitter.com\/SamSCid\/status\/1620554884553801728?ref_src=twsrc%5Etfw\">January 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Yo viendo que la fila virtual no avanzo y me qued\u00e9 sin boletos para RBD<a href=\"https:\/\/twitter.com\/hashtag\/Ticketmaster?src=hash&amp;ref_src=twsrc%5Etfw\">#Ticketmaster<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RBDTour2023?src=hash&amp;ref_src=twsrc%5Etfw\">#RBDTour2023<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/rbd?src=hash&amp;ref_src=twsrc%5Etfw\">#rbd<\/a> <a href=\"https:\/\/t.co\/GjftnboFMt\">pic.twitter.com\/GjftnboFMt<\/a><\/p>\n<p>&mdash; Nai (@Odmvj) <a href=\"https:\/\/twitter.com\/Odmvj\/status\/1620521278728962048?ref_src=twsrc%5Etfw\">January 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">my wallet after buying my RBD ticket <a href=\"https:\/\/t.co\/2P194tD4YW\">pic.twitter.com\/2P194tD4YW<\/a><\/p>\n<p>&mdash; \u2671 (@avrilziez) <a href=\"https:\/\/twitter.com\/avrilziez\/status\/1618727714697125895?ref_src=twsrc%5Etfw\">January 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Yo escuchando a RBD afuera del Foro Sol <a href=\"https:\/\/twitter.com\/hashtag\/SoyRebeldeTour?src=hash&amp;ref_src=twsrc%5Etfw\">#SoyRebeldeTour<\/a> <a href=\"https:\/\/t.co\/FqHZyKc27R\">pic.twitter.com\/FqHZyKc27R<\/a><\/p>\n<p>&mdash; \u25e1\u0308 (@CinSolis) <a href=\"https:\/\/twitter.com\/CinSolis\/status\/1618699252812910592?ref_src=twsrc%5Etfw\">January 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">No alcance boletos para RBD, salganse todos de twitter, quiero estar sola.<a href=\"https:\/\/twitter.com\/hashtag\/SoyRebeldeTour?src=hash&amp;ref_src=twsrc%5Etfw\">#SoyRebeldeTour<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RBDISBACK?src=hash&amp;ref_src=twsrc%5Etfw\">#RBDISBACK<\/a> <a href=\"https:\/\/t.co\/gogzTwpEyr\">pic.twitter.com\/gogzTwpEyr<\/a><\/p>\n<p>&mdash; ELI (@elinf3_) <a href=\"https:\/\/twitter.com\/elinf3_\/status\/1618725081450156032?ref_src=twsrc%5Etfw\">January 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Why is getting RBD tickets harder than Coachella passes? \ud83d\ude29\ud83d\ude2b<\/p>\n<p>&mdash; Genesis Rodriguez (@hey_geny) <a href=\"https:\/\/twitter.com\/hey_geny\/status\/1618741982205194240?ref_src=twsrc%5Etfw\">January 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">ME AND MY COUSINS GOT THE RBD TICKETS YALL \ud83d\ude2d\ud83d\ude2d\ud83d\ude2d\ud83d\ude2d\ud83d\ude2d <a href=\"https:\/\/t.co\/j7q4QXGgD7\">https:\/\/t.co\/j7q4QXGgD7<\/a><\/p>\n<p>&mdash; jaz (@camisdaya) <a href=\"https:\/\/twitter.com\/camisdaya\/status\/1618721966470606849?ref_src=twsrc%5Etfw\">January 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fechas que RBD est\u00e1 ofreciendo por todo lo largo y ancho del continente se est\u00e1n convirtiendo en los conciertos m\u00e1s esperados y es que mucha gente creci\u00f3 con su m\u00fasica y con la telenovela de Rebelde, por lo que la nostalgia es el principal motivo por el que los boletos de cada venue se [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1436889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51],"tags":[80,81,82,83,84,85,86,87],"class_list":["post-1436646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-anahi","tag-christian-chavez","tag-christopher-uckermann","tag-dulce-maria","tag-maite-perroni","tag-rbd","tag-rebelde","tag-soy-rebelde-tour","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las fechas que RBD est\u00e1 ofreciendo por todo lo largo y ancho del continente se est\u00e1n convirtiendo en los conciertos m\u00e1s esperados y es que mucha gente creci\u00f3 con su m\u00fasica y con la telenovela de Rebelde, por lo que la nostalgia es el principal motivo por el que los boletos de cada venue se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-31T23:02:18+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD\",\"datePublished\":\"2023-01-31T23:02:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Anah\u00ed\",\"Christian Ch\u00e1vez\",\"Christopher Uckermann\",\"Dulce Mar\u00eda\",\"Maite Perroni\",\"Rbd\",\"Rebelde\",\"Soy Rebelde Tour\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\",\"url\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\",\"name\":\"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-01-31T23:02:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/san-diego\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","og_locale":"es_ES","og_type":"article","og_title":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias","og_description":"Las fechas que RBD est\u00e1 ofreciendo por todo lo largo y ancho del continente se est\u00e1n convirtiendo en los conciertos m\u00e1s esperados y es que mucha gente creci\u00f3 con su m\u00fasica y con la telenovela de Rebelde, por lo que la nostalgia es el principal motivo por el que los boletos de cada venue se [&hellip;]","og_url":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","og_site_name":"Noticias","article_published_time":"2023-01-31T23:02:18+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD","datePublished":"2023-01-31T23:02:18+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/"},"wordCount":408,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage"},"thumbnailUrl":"","keywords":["Anah\u00ed","Christian Ch\u00e1vez","Christopher Uckermann","Dulce Mar\u00eda","Maite Perroni","Rbd","Rebelde","Soy Rebelde Tour"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","url":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","name":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-01-31T23:02:18+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/los-angeles\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/san-diego\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los memes m\u00e1s divertidos tras el sold out de los boletos de RBD","url":"http:\/\/noticiasya.com\/san-diego\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2023\/01\/31\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["anah\u00ed","christian ch\u00e1vez","christopher uckermann","dulce mar\u00eda","maite perroni","rbd","rebelde","soy rebelde tour"],"dateCreated":"2023-01-31T23:02:18Z","datePublished":"2023-01-31T23:02:18Z","dateModified":"2023-01-31T23:02:18Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los memes m\\u00e1s divertidos tras el sold out de los boletos de RBD\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2023\\\/01\\\/31\\\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2023\\\/01\\\/31\\\/los-memes-mas-divertidos-tras-el-sold-out-de-los-boletos-de-rbd\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"anah\\u00ed\",\"christian ch\\u00e1vez\",\"christopher uckermann\",\"dulce mar\\u00eda\",\"maite perroni\",\"rbd\",\"rebelde\",\"soy rebelde tour\"],\"dateCreated\":\"2023-01-31T23:02:18Z\",\"datePublished\":\"2023-01-31T23:02:18Z\",\"dateModified\":\"2023-01-31T23:02:18Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1437000,"url":"https:\/\/noticiasya.com\/san-diego\/2023\/02\/09\/thalia-podria-unirse-a-la-gira-de-rbd-esto-es-lo-que-sabemos\/","url_meta":{"origin":1436646,"position":0},"title":"\u00bfThal\u00eda podr\u00eda unirse a la gira de RBD? Esto es lo que sabemos","author":"Eduardo Salinas","date":"febrero 9, 2023","format":false,"excerpt":"Hace unos d\u00edas, tanto Twitter como Facebook se llenaron de comentarios y especulaciones acerca de la posible participaci\u00f3n de Thal\u00eda en los shows de RBD, luego de que Anah\u00ed y la int\u00e9rprete de 'Piel Morena' compartieran la conversaci\u00f3n de FaceTime que tuvieron hace poco. Aunque no hay nada confirmado por\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453219,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/09\/30\/conciertos-oasis-mexico-estados-unidos-2025-boletos-fechas-ciudades-sorteo-orix\/","url_meta":{"origin":1436646,"position":1},"title":"Conciertos de Oasis en M\u00e9xico y Estados Unidos en 2025: boletos, fechas, ciudades y sorteo","author":"Eduardo Salinas","date":"septiembre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Despu\u00e9s de algunas semanas de agotar los boletos de la gira del reencuentro de Oasis en Reino Unido e Irlanda, finalmente la banda originaria de Manchester, Inglaterra, regresar\u00e1 a Norteam\u00e9rica como parte de su gira mundial que incluye a M\u00e9xico, Estados Unidos y Canad\u00e1. Los boletos podr\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460789,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/04\/03\/shakira-gira-enrtevista-conciertos-orix\/","url_meta":{"origin":1436646,"position":2},"title":"El torbellino de Shakira en su gira mundial: la &#171;locura de los estadios&#187; y los artistas invitados que tendr\u00e1 en sus shows","author":"","date":"abril 3, 2025","format":false,"excerpt":"Shakira no se queda quieta, es un torbellino. Y no solo en el escenario. Su incansable energ\u00eda se puede observar incluso antes del show, lejos de la mirada del p\u00fablico.\u201cEstoy muy emocionada que finalmente iniciar\u00e9 mi primer tour de estadios en Estados Unidos\u201d, dijo Shakira a CNN en Espa\u00f1ol, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470983,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/07\/bad-bunny-fuerza-economica-mas-alla-puerto-rico-orix\/","url_meta":{"origin":1436646,"position":3},"title":"De Medell\u00edn a Ciudad de M\u00e9xico, Bad Bunny es una fuerza econ\u00f3mica m\u00e1s all\u00e1 de Puerto Rico","author":"","date":"febrero 7, 2026","format":false,"excerpt":"Como artista, Bad Bunny tiene un poder actual innegable: acaba de ganar tres premios Grammy (uno de ellos por \u00c1lbum del A\u00f1o, la primera vez que un disco en espa\u00f1ol obtiene la categor\u00eda m\u00e1s prestigiosa de estos galardones); suma 107 millones de seguidores en Spotify y fue el artista m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472783,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/01\/shakira-estados-unidos-gira-fechas-ciudades-orix\/","url_meta":{"origin":1436646,"position":4},"title":"Shakira regresa a Estados Unidos con su gira: fechas y ciudades que visitar\u00e1","author":"","date":"abril 1, 2026","format":false,"excerpt":"Los fans de Shakira podr\u00e1n \u201caullar\u201d nuevamente junto a ella en Estados Unidos. La cantante colombiana confirm\u00f3 que este a\u00f1o realizar\u00e1 una segunda vuelta de conciertos con su gira \u201cLas mujeres ya no lloran\u201d por el pa\u00eds.A trav\u00e9s de sus redes sociales, la superestrella latina comparti\u00f3 su emoci\u00f3n por volver\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461999,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/05\/gira-bad-bunny-debi-tirar-mas-fotos-boletos-fechas-ciudades-conciertos-orix\/","url_meta":{"origin":1436646,"position":5},"title":"La gira de Bad Bunny en su Deb\u00ed Tirar M\u00e1s Fotos World Tour: boletos, fechas, ciudades y pa\u00edses de los conciertos","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Bad Bunny anunci\u00f3 24 fechas en distintos pa\u00edses para la gira mundial de su m\u00e1s reciente disco \u201cDeB\u00cd TiRAR M\u00e1S FOToS\u201d. Visitar\u00e1 pa\u00edses de Latinoam\u00e9rica, Ocean\u00eda, Asia y Europa, pero a\u00fan no confirma conciertos en Estados Unidos.En enero de este a\u00f1o, el cantante anunci\u00f3 una residencia de 30 conciertos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1436646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1436646"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1436646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1436646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1436646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1436646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}