{"id":1448499,"date":"2024-04-25T01:03:41","date_gmt":"2024-04-25T08:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/"},"modified":"2024-04-25T01:03:41","modified_gmt":"2024-04-25T08:03:41","slug":"ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","title":{"rendered":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3"},"content":{"rendered":"<p>(CNN) &#8212; La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de la empresa en general.<\/p>\n<p>Ford, como la mayor\u00eda de los fabricantes de autom\u00f3viles, anunci\u00f3 planes para pasar de los veh\u00edculos tradicionales propulsados \u200b\u200bpor gasolina a los veh\u00edculos el\u00e9ctricos en los pr\u00f3ximos a\u00f1os. Pero es el \u00fanico fabricante de autom\u00f3viles tradicional que desglosa los resultados de sus ventas minoristas de veh\u00edculos el\u00e9ctricos. Y los resultados que inform\u00f3 este mi\u00e9rcoles muestran otra se\u00f1al de las presiones sobre las ganancias en el negocio de veh\u00edculos el\u00e9ctricos de Ford y otros fabricantes de autom\u00f3viles.<\/p>\n<p>La unidad de veh\u00edculos el\u00e9ctricos, que Ford llama Modelo e, vendi\u00f3 10.000 veh\u00edculos en el trimestre, un 20% menos que la cantidad que vendi\u00f3 un a\u00f1o antes. Y sus ingresos se desplomaron un 84% a unos US$ 100 millones de d\u00f3lares, lo que Ford atribuy\u00f3 principalmente a los recortes de precios de los veh\u00edculos el\u00e9ctricos en toda la industria. Esto result\u00f3 en una p\u00e9rdida de US$ 1.300 millones de d\u00f3lares antes de intereses e impuestos (EBIT) y en la enorme p\u00e9rdida por veh\u00edculo en la unidad del Modelo e.<\/p>\n<p>Una guerra de precios entre los veh\u00edculos el\u00e9ctricos durante aproximadamente un a\u00f1o y medio dificult\u00f3 mucho la rentabilidad, dijo el director financiero de Ford, John Lawler. Dijo que si bien Ford elimin\u00f3 alrededor de US$ 5000 en el costo de cada Mustang Mach-E, &#171;los ingresos est\u00e1n cayendo m\u00e1s r\u00e1pido de lo que podemos eliminar el costo&#187;.<\/p>\n<p>En 2023, el Ford Model e inform\u00f3 una p\u00e9rdida EBIT para todo el a\u00f1o de US$ 4.700 millones en ventas de 116.000 veh\u00edculos el\u00e9ctricos, o un promedio de US$ 40.525 por veh\u00edculo, poco m\u00e1s de un tercio de la p\u00e9rdida del primer trimestre.<\/p>\n<p>El Model e no maneja todas las ventas de veh\u00edculos el\u00e9ctricos de la compa\u00f1\u00eda. Algunos tambi\u00e9n se venden en su unidad Ford Pro, que se encarga de las ventas de flotas a empresas y compradores gubernamentales. Y Ford dijo que ten\u00eda fuertes demandas para las ventas de veh\u00edculos el\u00e9ctricos en esa unidad, incluido un pedido de 9.250 furgonetas E-Transit del Servicio Postal de EE. UU., que se entregar\u00e1n hasta finales de este a\u00f1o, y un pedido de m\u00e1s de 1.000 de sus camionetas pickup F-150 Lightning y sus SUV Mustang Mach-E de Ecolab, una empresa global de sostenibilidad.<\/p>\n<p>A pesar de las p\u00e9rdidas de veh\u00edculos el\u00e9ctricos, el director ejecutivo de Ford, Jim Farley, dijo en una llamada con inversores que la compa\u00f1\u00eda est\u00e1 realizando cambios en su negocio de veh\u00edculos el\u00e9ctricos y que la pr\u00f3xima generaci\u00f3n de veh\u00edculos el\u00e9ctricos planificada por la compa\u00f1\u00eda le permitir\u00e1 ser rentable en ese negocio en un futuro cercano.<\/p>\n<p>Ford Pro, que vende principalmente veh\u00edculos tradicionales de combusti\u00f3n interna, fue el principal impulsor de ganancias para Ford en el trimestre, registrando un EBIT de $3 mil millones de d\u00f3lares, o m\u00e1s del doble de lo que gan\u00f3 hace un a\u00f1o, mientras los ingresos de la unidad aumentaron un 36% a $18 mil millones de d\u00f3lares. El n\u00famero de veh\u00edculos vendidos por Ford Pro aument\u00f3 un 21% hasta 409.000.<\/p>\n<p>Pero Ford Blue, que maneja las ventas de autom\u00f3viles a gasolina a los consumidores, inform\u00f3 que las ventas cayeron un 11% a 626.000, y los ingresos cayeron un 13% a US$ 21.000 millones. Esto result\u00f3 en que el EBIT en esas ventas tradicionales cayera en casi dos tercios a US$ 905 millones.<\/p>\n<p>Juntos, Ford Blue y Ford Pro produjeron aproximadamente el mismo nivel de ganancias que el a\u00f1o anterior, pero el aumento de las p\u00e9rdidas en la unidad del Modelo e signific\u00f3 que los ingresos netos generales de Ford cayeron un 20% a US$ 1.300 millones de d\u00f3lares, mientras que sus ganancias ajustadas por acci\u00f3n cayeron a 49 centavos, un 21% menos que el a\u00f1o anterior, pero ligeramente mejor que las previsiones de los analistas de 44 centavos por acci\u00f3n.<\/p>\n<p>El rival de Ford, General Motors, inform\u00f3 a principios de esta semana que sigue en camino de que su negocio de veh\u00edculos el\u00e9ctricos en Am\u00e9rica del Norte se vuelva rentable en la segunda mitad de este a\u00f1o, mientras que Stellantis, que fabrica autom\u00f3viles y camionetas en Am\u00e9rica del Norte bajo el nombre de Jeep, Ram, Dodge y Chrysler , dijeron que su negocio europeo de veh\u00edculos el\u00e9ctricos ya era rentable el a\u00f1o pasado.<\/p>\n<p>Este martes, Tesla, el mayor fabricante de veh\u00edculos el\u00e9ctricos del mundo, inform\u00f3 que sus ganancias ajustadas se desplomaron un 48% en el primer trimestre mientras que los ingresos cayeron un 9%, despu\u00e9s de informar la primera ca\u00edda interanual en las ventas desde la pandemia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de la empresa en general. Ford, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448499","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de la empresa en general. Ford, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T08:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3\",\"datePublished\":\"2024-04-25T08:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\"},\"wordCount\":879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\",\"name\":\"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-25T08:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias","og_description":"(CNN) &#8212; La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de la empresa en general. Ford, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-25T08:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/"},"author":{"name":"","@id":""},"headline":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3","datePublished":"2024-04-25T08:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/"},"wordCount":879,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","name":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-25T08:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3","url":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-25T08:03:41Z","datePublished":"2024-04-25T08:03:41Z","dateModified":"2024-04-25T08:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ford informa de una p\\u00e9rdida masiva por cada veh\\u00edculo el\\u00e9ctrico que vendi\\u00f3\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/25\\\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/25\\\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-25T08:03:41Z\",\"datePublished\":\"2024-04-25T08:03:41Z\",\"dateModified\":\"2024-04-25T08:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467064,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/02\/ventas-tesla-record-riqueza-musk-trax\/","url_meta":{"origin":1448499,"position":0},"title":"Las ventas de Tesla alcanzaron un r\u00e9cord en el tercer trimestre y aumentaron la riqueza de Musk","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Las ventas de Tesla se dispararon a un nivel r\u00e9cord en el tercer trimestre, ya que los compradores estadounidenses se apresuraron a adquirir sus autos antes de que expirara, el 30 de septiembre, un cr\u00e9dito fiscal federal de US$ 7.500.La compa\u00f1\u00eda vendi\u00f3 un r\u00e9cord de 497.099 veh\u00edculos en todo el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447663,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/02\/ventas-tesla-caen-esperado-trax\/","url_meta":{"origin":1448499,"position":1},"title":"Las ventas de Tesla caen mucho m\u00e1s de lo esperado","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) -- Tesla registr\u00f3 su primera ca\u00edda anual en ventas desde la pandemia mientras enfrenta una mayor competencia de veh\u00edculos el\u00e9ctricos por parte de los fabricantes de autom\u00f3viles chinos y occidentales, lo que gener\u00f3 una disminuci\u00f3n en la demanda de la marca.La compa\u00f1\u00eda de autom\u00f3viles el\u00e9ctricos, cuyo CEO es Elon\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451042,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/07\/11\/plan-potenciar-vehiculos-electricos-estados-unidos-trax\/","url_meta":{"origin":1448499,"position":2},"title":"Gobierno de Joe Biden anuncia un plan de US$ 1.700 millones para potenciar los veh\u00edculos el\u00e9ctricos en Estados Unidos","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN) -- La Casa Blanca dijo el jueves que entregar\u00eda US$ 1.700 millones para ayudar a convertir instalaciones de fabricaci\u00f3n y ensamblaje de autom\u00f3viles cerradas o en riesgo para fabricar veh\u00edculos el\u00e9ctricos e h\u00edbridos.La financiaci\u00f3n se da cuando el crecimiento de las ventas de veh\u00edculos el\u00e9ctricos nuevos se ha desacelerado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473729,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/05\/02\/vehiculos-electricos-chinos-listos-dominar-siglo-trax\/","url_meta":{"origin":1448499,"position":3},"title":"\u00bfCrisis del petr\u00f3leo? Los veh\u00edculos el\u00e9ctricos chinos est\u00e1n listos para dominar el siglo XXI","author":"","date":"mayo 2, 2026","format":false,"excerpt":"Un elegante SUV ofrece masajes mec\u00e1nicos para los pies, una lujosa minivan cuenta con asientos giratorios para facilitar el acceso a la tercera fila, y una sorprendente cantidad de modelos ofrecen karaoke a bordo con altavoces profesionales.Otros incorporan faros que proyectan pel\u00edculas en una pared, convirtiendo cualquier lugar en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457957,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/tesla-acciones-musk-trax\/","url_meta":{"origin":1448499,"position":4},"title":"Tesla acaba de tener su peor a\u00f1o en ventas, pero las acciones han tenido una gran racha","author":"","date":"enero 28, 2025","format":false,"excerpt":"Tesla probablemente reportar\u00e1 m\u00e1rgenes de ganancia m\u00e1s estrechos en sus resultados trimestrales y anuales este mi\u00e9rcoles, como resultado de su primera ca\u00edda en las ventas anuales en su historia en 2024 y una guerra de precios en el sector de veh\u00edculos el\u00e9ctricos debido a la creciente competencia. Pero los grandes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447827,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/07\/pasando-tesla-elon-musk-trax\/","url_meta":{"origin":1448499,"position":5},"title":"\u00bfQu\u00e9 ocurre con Tesla y el d\u00e9bil desempe\u00f1o en el \u00faltimo trimestre?","author":"","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- Tesla registr\u00f3 su primera ca\u00edda anual en las ventas desde la pandemia el trimestre pasado, un declive que fue peor de lo esperado. La compa\u00f1\u00eda culp\u00f3 a la d\u00e9bil econom\u00eda china, al incendio provocado en su f\u00e1brica alemana y a las limitaciones de suministro debido a la escalada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1448499"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448499\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1448499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1448499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1448499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}