{"id":1448543,"date":"2024-04-26T06:03:39","date_gmt":"2024-04-26T13:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/"},"modified":"2024-04-26T06:03:39","modified_gmt":"2024-04-26T13:03:39","slug":"metro-buenos-aires-500-aumentos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","title":{"rendered":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 Este jueves se llev\u00f3 a cabo la audiencia p\u00fablica previa a la aplicaci\u00f3n de inusuales alzas en las tarifas del metro de Buenos Aires, que en apenas un mes superar\u00e1n el 500% y se sumar\u00e1n a los aumentos en los servicios de trenes metropolitanos.<\/p>\n<p>Esta instancia de participaci\u00f3n ciudadana es el \u00faltimo paso para implementar los nuevos valores para el Subte de la Ciudad de Buenos Aires. El esquema tarifario propuesto por el Gobierno porte\u00f1o contempla aumentos superiores a 500%, que se aplicar\u00e1n en tres etapas distribuidas en menos de un mes, en medio de un alto nivel inflacionario.<\/p>\n<p>En la audiencia virtual \u2015una instancia de consulta no vinculante efectuada por ley, sin efectos m\u00e1s all\u00e1 de ser consultiva\u2015 participaron representantes de distintos sectores de la sociedad civil, que expusieron su postura respecto a la propuesta.<\/p>\n<p>Pasada esta etapa, la administraci\u00f3n del jefe de Gobierno, Jorge Macri, tiene cinco d\u00edas h\u00e1biles para oficializar la medida. De todas maneras, desde la Secretar\u00eda de Transporte de la Ciudad precisaron a CNN que esperan comenzar a implementarla alrededor del 10 de mayo.<\/p>\n<p>A partir de ese d\u00eda, los pasajeros pasar\u00e1n a pagar hasta 574 pesos (US$ 0,50 al valor paralelo) por el boleto; es decir, casi 360% de aumento. Apenas 15 d\u00edas despu\u00e9s, ver\u00e1n una nueva actualizaci\u00f3n, en esta oportunidad de 16,2% sobre la nueva tarifa, llev\u00e1ndola hasta 667 pesos (US$ 0,60).<\/p>\n<p>En el metro de Buenos Aires, al menos 84 trabajadores afectados por el asbesto y tres muertos por c\u00e1ncer<\/p>\n<p>Pasados otros 15 d\u00edas, ya en junio, los usuarios ver\u00e1n el \u00faltimo cambio en el valor del transporte, al menos por ahora: subir\u00e1 a 757 pesos (US$ 0,70), un 13,9% m\u00e1s en relaci\u00f3n con el \u00faltimo aumento, y 505,6% respecto al importe actual, de 125 pesos (US$ 0,10).<\/p>\n<p>Los importes pueden variar, ya que el metro mantiene un sistema de tarifa gradual, que comprende descuentos de entre 20% y 40%, seg\u00fan la cantidad de viajes que el usuario realice por mes.<\/p>\n<p>La l\u00ednea del Premetro (tranv\u00eda de superficie que conecta a las l\u00edneas del subterr\u00e1neo) seguir\u00e1 el mismo esquema que el Subte, con un primer salto de 357% que llevar\u00e1 el pasaje a 200,9 pesos (US$ 0,19). Luego subir\u00e1 a 233,45 pesos (US$ 0,22), llegando finalmente a 264,95 pesos (US$ 0,25).<\/p>\n<p>\u201cDel an\u00e1lisis efectuado por SBASE (Subterr\u00e1neos de Buenos Aires Sociedad del Estado), surge una desactualizaci\u00f3n de la tarifa al usuario, generada por los reiterados aumentos en los costos involucrados en el servicio, lo que repercuti\u00f3 en la ecuaci\u00f3n econ\u00f3mico-financiera de la actividad\u201d, indica el gobierno de la Ciudad en su decreto.<\/p>\n<p>El \u00cdndice de Precios al Consumidor acumula 51,6% en lo que va de 2024, de acuerdo con los \u00faltimos datos oficiales.<\/p>\n<p>Descuentos<\/p>\n<p>En ambos casos se mantendr\u00e1n valores especiales para los abonos social, estudiantil y maestro. Adem\u00e1s, los boletos para jubilados, pensionados, personas con discapacidad y trasplantadas seguir\u00e1n siendo gratis.<\/p>\n<p>El metro preservar\u00e1 tambi\u00e9n la tarifa gradual, que comprende descuentos de entre 20% y 40%, seg\u00fan la cantidad de viajes que el usuario realice por mes. Del mismo modo, continuar\u00e1 funcionando la Red SUBE, otro sistema de beneficios de 50% a 75% para las personas cuyos viajes combinen distintos transportes, mediante la tarjeta SUBE, empleada para pagar el transporte p\u00fablico en Buenos Aires y otras partes de Argentina.<\/p>\n<p>\u00bfC\u00f3mo explicar la inflaci\u00f3n argentina a China?<\/p>\n<p>Quienes no tengan su tarjeta registrada ser\u00e1n penalizados con cuotas diferenciales, que ascienden a 859,07 pesos (US$ 0,80) en el subterr\u00e1neo, y a 300,67 pesos (US$ 0,28) en el Premetro.<\/p>\n<p>Originalmente, este esquema tarifario estaba planteado para abril, con actualizaciones mensuales hasta junio. Sin embargo, la audiencia p\u00fablica online, prevista para el 15 de marzo, se vio postergada por inconvenientes t\u00e9cnicos. Por eso, la aplicaci\u00f3n se demor\u00f3 y los plazos se acortaron, golpeando as\u00ed al bolsillo de los pasajeros de una forma m\u00e1s repentina.<\/p>\n<p>Los trenes, tambi\u00e9n m\u00e1s caros<\/p>\n<p>El gobierno nacional no se qued\u00f3 atr\u00e1s. Este lunes, anunci\u00f3 aumentos en el costo del viaje de los ferrocarriles de la Ciudad de Buenos Aires.<\/p>\n<p>Los pasajes de tren en el \u00c1rea Metropolitana de Buenos Aires (AMBA) ser\u00e1n 53% m\u00e1s caros a partir de mayo. Adem\u00e1s, quienes no tengan registrada su tarjeta SUBE pagar\u00e1n el doble de la tarifa regular, mientras que los beneficiarios de tarifa social abonar\u00e1n 55% menos.<\/p>\n<p>Espec\u00edficamente, las l\u00edneas alcanzadas son Sarmiento, Roca, Mitre, San Mart\u00edn, Belgrano Sur, Belgrano Norte, Urquiza y Tren de la Costa.<\/p>\n<p>La Secretar\u00eda de Transporte nacional tambi\u00e9n anunci\u00f3 nuevos precios sugeridos para trenes de larga distancia, as\u00ed como tambi\u00e9n defini\u00f3 incrementos en los boletos de media distancia y ferrocarriles regionales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 Este jueves se llev\u00f3 a cabo la audiencia p\u00fablica previa a la aplicaci\u00f3n de inusuales alzas en las tarifas del metro de Buenos Aires, que en apenas un mes superar\u00e1n el 500% y se sumar\u00e1n a los aumentos en los servicios de trenes metropolitanos. Esta instancia de participaci\u00f3n ciudadana es el \u00faltimo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448543","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 Este jueves se llev\u00f3 a cabo la audiencia p\u00fablica previa a la aplicaci\u00f3n de inusuales alzas en las tarifas del metro de Buenos Aires, que en apenas un mes superar\u00e1n el 500% y se sumar\u00e1n a los aumentos en los servicios de trenes metropolitanos. Esta instancia de participaci\u00f3n ciudadana es el \u00faltimo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T13:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes\",\"datePublished\":\"2024-04-26T13:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\",\"name\":\"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T13:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 Este jueves se llev\u00f3 a cabo la audiencia p\u00fablica previa a la aplicaci\u00f3n de inusuales alzas en las tarifas del metro de Buenos Aires, que en apenas un mes superar\u00e1n el 500% y se sumar\u00e1n a los aumentos en los servicios de trenes metropolitanos. Esta instancia de participaci\u00f3n ciudadana es el \u00faltimo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-26T13:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/"},"author":{"name":"","@id":""},"headline":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes","datePublished":"2024-04-26T13:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","name":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T13:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El metro de Buenos Aires sube m\u00e1s de 500% en un mes y se suma a los aumentos en los trenes","url":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/26\/metro-buenos-aires-500-aumentos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T13:03:39Z","datePublished":"2024-04-26T13:03:39Z","dateModified":"2024-04-26T13:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El metro de Buenos Aires sube m\\u00e1s de 500% en un mes y se suma a los aumentos en los trenes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/26\\\/metro-buenos-aires-500-aumentos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/26\\\/metro-buenos-aires-500-aumentos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T13:03:39Z\",\"datePublished\":\"2024-04-26T13:03:39Z\",\"dateModified\":\"2024-04-26T13:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445462,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/02\/15\/mas-aumentos-al-transporte-en-buenos-aires-cuanto-costara-el-subte-y-los-peajes-a-partir-de-abril\/","url_meta":{"origin":1448543,"position":0},"title":"M\u00e1s aumentos al transporte en Buenos Aires: \u00bfcu\u00e1nto costar\u00e1 el subte y los peajes a partir de abril?","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- El transporte subterr\u00e1neo (subte) y los peajes se sumar\u00e1n a los rubros que podr\u00edan aumentar fuertemente en los pr\u00f3ximos meses en la capital de Argentina.El subte se elevar\u00eda en abril de 125 pesos (US$ 0,11 a la cotizaci\u00f3n paralela) a 574 pesos (US$ 0,5), un aumento de casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443173,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/04\/estos-son-los-aumentos-de-precios-de-enero-en-argentina\/","url_meta":{"origin":1448543,"position":1},"title":"Estos son los aumentos de precios de enero en Argentina","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Con el comienzo del nuevo a\u00f1o y la vigencia de las medidas dispuestas por parte del Gobierno de Argentina, enero empieza con aumentos en diferentes rubros, que alimentar\u00e1n la inflaci\u00f3n mensual en el pa\u00eds.Algunas de las subidas ya estaban previstas antes de la entrada en vigor del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444764,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/02\/01\/inflacion-sin-freno-en-argentina-los-aumentos-de-precios-en-febrero\/","url_meta":{"origin":1448543,"position":2},"title":"Inflaci\u00f3n sin freno en Argentina: los aumentos de precios en febrero","author":"","date":"febrero 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Febrero comienza y trae nuevos aumentos de precios en Argentina. Para el segundo mes del a\u00f1o se esperan incrementos en rubros como el transporte p\u00fablico, combustibles y energ\u00eda.El \u00faltimo dato disponible de inflaci\u00f3n alcanz\u00f3 el 25,5% en diciembre, y esa es la tendencia que se espera. \u00bfCu\u00e1les\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449379,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/05\/10\/heridos-colision-trenes-buenos-aires-orix\/","url_meta":{"origin":1448543,"position":3},"title":"Autoridades reportan 16 heridos en colisi\u00f3n de trenes en Buenos Aires","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Autoridades ferroviarias informaron de una colisi\u00f3n entre una formaci\u00f3n vac\u00eda y un tren en el barrio Palermo de la ciudad de Buenos Aires, seg\u00fan public\u00f3 Trenes Argentinos este viernes en su cuenta oficial en X, antes Twitter. La l\u00ednea San Mart\u00edn se encuentra interrumpida.El \u00faltimo reporte del\u00a0Sistema\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443596,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/12\/inflacion-en-argentina-que-productos-y-servicios-subieron-mas-los-precios-en-la-transicion-entre-fernandez-y-milei\/","url_meta":{"origin":1448543,"position":4},"title":"Inflaci\u00f3n en Argentina: \u00bfQu\u00e9 productos y servicios subieron m\u00e1s los precios en la transici\u00f3n entre Fern\u00e1ndez y Milei?","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este jueves, el Instituto de Estad\u00edstica y Censos de Argentina (Indec) dio a conocer el n\u00famero de inflaci\u00f3n de diciembre (25,5%), que deja al pa\u00eds al borde de tener el \u00edndice anual m\u00e1s alto del mundo con un 211,4% de aumento sostenido en los precios de bienes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459948,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/03\/14\/gorodisch-el-numero-de-inflacion-es-malo\/","url_meta":{"origin":1448543,"position":5},"title":"Gorodisch: &#171;El n\u00famero de inflaci\u00f3n es malo&#187;","author":"","date":"marzo 14, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Mariano Gorodisch, economista, habl\u00f3 este viernes con CNN Radio sobre el dato de inflaci\u00f3n del mes de febrero, donde la divisi\u00f3n que registr\u00f3 la mayor incidencia en todas las regiones fue Alimentos y bebidas no alcoh\u00f3licas (3,2%), por los aumentos en carnes y derivados.El INDEC inform\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1448543"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448543\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1448543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1448543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1448543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}