{"id":1448614,"date":"2024-04-27T10:03:43","date_gmt":"2024-04-27T17:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/"},"modified":"2024-04-27T10:03:43","modified_gmt":"2024-04-27T17:03:43","slug":"harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","title":{"rendered":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea"},"content":{"rendered":"<p>(CNN) &#8212; Harvey Weinstein, el poderoso productor de Hollywood cuya ca\u00edda fue un s\u00edmbolo del movimiento #MeToo, ha sido trasladado del Centro Correccional Mohawk en Rome, Nueva York, al pabell\u00f3n de prisi\u00f3n del Hospital Bellevue (BHPW), seg\u00fan registros en l\u00ednea y su abogado.<\/p>\n<p>&#171;Est\u00e1 en Bellevue por razones m\u00e9dicas&#187;, dijo este s\u00e1bado a CNN el abogado de Weinstein, Arthur L. Aidala.<\/p>\n<p>Aidala le dijo a CNN que a\u00fan se espera que Weinstein comparezca ante la Corte Suprema de Manhattan el pr\u00f3ximo mi\u00e9rcoles despu\u00e9s de que el Tribunal de Apelaciones de Nueva York anulara una condena por delitos sexuales en su contra el jueves, inform\u00f3 CNN anteriormente.<\/p>\n<p>BHPW, que trabaja con la infame c\u00e1rcel de Rikers Island de Nueva York, &#171;alberga a hombres que requieren tratamiento m\u00e9dico o psiqui\u00e1trico&#187;, seg\u00fan el Departamento Correccional de la ciudad de Nueva York.<\/p>\n<p>Testigo estrella del juicio a Harvey Weinstein dice que se plantear\u00eda volver a testificiar: &#171;Esto no se trata solo de m\u00ed&#187;<\/p>\n<p>La comparecencia del pr\u00f3ximo mi\u00e9rcoles est\u00e1 prevista para el 1 de mayo, a las 14:15 horas, ante el juez Curtis Farber, seg\u00fan un portavoz de la Fiscal\u00eda del Distrito de Manhattan.<\/p>\n<p>Denunciantes de Harvey Weinstein quieren un nuevo juicio<\/p>\n<p>Cuando el productor de Hollywood Harvey Weinstein fue declarado culpable de dos delitos sexuales en febrero de 2020, la condena fue aclamada como un momento hist\u00f3rico en el movimiento #MeToo.<\/p>\n<p>Ahora, m\u00e1s de cuatro a\u00f1os despu\u00e9s, el fallo de la Corte de Apelaciones de Nueva York que anula esa condena sacude a las comunidades de sobrevivientes de agresiones sexuales, en particular a las m\u00e1s de 100 mujeres que han acusado a Weinstein de agresi\u00f3n y acoso.<\/p>\n<p>&#171;Esto de hoy es un acto de traici\u00f3n institucional&#187;, dijo la actriz y activista Ashley Judd, que fue una de las primeras mujeres en acusar p\u00fablicamente a Weinstein de acoso sexual, en un acto de la ONU por la seguridad en el lugar de trabajo. &#171;Nuestras instituciones traicionan a las sobrevivientes de la violencia sexual masculina&#187;.<\/p>\n<p>Las denunciantes que hablaron con CNN el jueves coincidieron con la frustraci\u00f3n de Judd por la decisi\u00f3n del tribunal de apelaciones. Algunas expresaron su gratitud por el hecho de que Weinstein fuera condenado y sentenciado a una larga pena de prisi\u00f3n en un tribunal de Los \u00c1ngeles por cargos similares.<\/p>\n<p>&#171;Este es un d\u00eda muy triste para innumerables mujeres que sufrieron a manos de un depredador en serie&#187;, dijo Jennifer Siebel Newsom, la esposa del gobernador de California, Gavin Newsom, quien acus\u00f3 a Weinstein de violaci\u00f3n y testific\u00f3 en el juicio de Los \u00c1ngeles.<\/p>\n<p>&#171;Harvey Weinstein es un depredador y violador en serie&#187;, afirm\u00f3. &#171;La valent\u00eda de las mujeres que se presentaron asegura que, independientemente de lo que ocurra en Nueva York, Weinstein morir\u00e1 en prisi\u00f3n&#187;.<\/p>\n<p>Weinstein, de 72 a\u00f1os, ha mantenido su inocencia y ha negado cualquier actividad sexual no consentida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Harvey Weinstein, el poderoso productor de Hollywood cuya ca\u00edda fue un s\u00edmbolo del movimiento #MeToo, ha sido trasladado del Centro Correccional Mohawk en Rome, Nueva York, al pabell\u00f3n de prisi\u00f3n del Hospital Bellevue (BHPW), seg\u00fan registros en l\u00ednea y su abogado. &#171;Est\u00e1 en Bellevue por razones m\u00e9dicas&#187;, dijo este s\u00e1bado a CNN el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448614","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Harvey Weinstein, el poderoso productor de Hollywood cuya ca\u00edda fue un s\u00edmbolo del movimiento #MeToo, ha sido trasladado del Centro Correccional Mohawk en Rome, Nueva York, al pabell\u00f3n de prisi\u00f3n del Hospital Bellevue (BHPW), seg\u00fan registros en l\u00ednea y su abogado. &#171;Est\u00e1 en Bellevue por razones m\u00e9dicas&#187;, dijo este s\u00e1bado a CNN el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T17:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea\",\"datePublished\":\"2024-04-27T17:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\",\"name\":\"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-27T17:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias","og_description":"(CNN) &#8212; Harvey Weinstein, el poderoso productor de Hollywood cuya ca\u00edda fue un s\u00edmbolo del movimiento #MeToo, ha sido trasladado del Centro Correccional Mohawk en Rome, Nueva York, al pabell\u00f3n de prisi\u00f3n del Hospital Bellevue (BHPW), seg\u00fan registros en l\u00ednea y su abogado. &#171;Est\u00e1 en Bellevue por razones m\u00e9dicas&#187;, dijo este s\u00e1bado a CNN el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-27T17:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/"},"author":{"name":"","@id":""},"headline":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea","datePublished":"2024-04-27T17:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","name":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-27T17:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea","url":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-27T17:03:43Z","datePublished":"2024-04-27T17:03:43Z","dateModified":"2024-04-27T17:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Harvey Weinstein fue trasladado al pabell\\u00f3n de prisi\\u00f3n del Bellevue Hospital por razones m\\u00e9dicas, seg\\u00fan su abogado y registros en l\\u00ednea\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/27\\\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/04\\\/27\\\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-27T17:03:43Z\",\"datePublished\":\"2024-04-27T17:03:43Z\",\"dateModified\":\"2024-04-27T17:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452558,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/09\/09\/hospitalizan-emergencia-harvey-weinstein-cirugia-corazon-trax\/","url_meta":{"origin":1448614,"position":0},"title":"Hospitalizan de emergencia a Harvey Weinstein para una cirug\u00eda del coraz\u00f3n","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN) -- Harvey Weinstein fue \"trasladado de emergencia\" al Hospital Bellevue de Nueva York el domingo por la noche \"debido a varias afecciones m\u00e9dicas\", seg\u00fan los representantes del desacreditado exproductor de cine.\"Podemos confirmar que el se\u00f1or Weinstein fue sometido a un procedimiento y cirug\u00eda en su coraz\u00f3n hoy\", dijeron el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455286,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/10\/21\/a-harvey-weinstein-le-diagnosticaron-cancer-segun-fuentes-trax\/","url_meta":{"origin":1448614,"position":1},"title":"A Harvey Weinstein le diagnosticaron c\u00e1ncer, seg\u00fan fuentes","author":"","date":"octubre 21, 2024","format":false,"excerpt":"(CNN) --\u00a0 A Harvey Weinstein le diagnosticaron c\u00e1ncer de huesos, dijo a CNN una fuente cercana al productor encarcelado.El diagn\u00f3stico espec\u00edfico de Weinstein es leucemia mieloide cr\u00f3nica, una forma de c\u00e1ncer de la m\u00e9dula \u00f3sea, dice la fuente, y agrega que est\u00e1 recibiendo tratamiento en Rikers Island en Nueva York.Juda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449323,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/05\/08\/legisladores-nueva-york-malos-actos-previos-procesos-agresion-sexual-trax\/","url_meta":{"origin":1448614,"position":2},"title":"Legisladores neoyorquinos proponen permitir que malos actos previos sean admisibles en los procesos","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN) -- Citando la reciente anulaci\u00f3n de la condena por delitos sexuales de Harvey Weinstein en Nueva York, los miembros de la Asamblea del Estado de Nueva York est\u00e1n presentando esta semana un proyecto de ley que modificar\u00eda la norma de procedimiento penal del estado para permitir que las pruebas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449679,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","url_meta":{"origin":1448614,"position":3},"title":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) --\u00a0Ambra Battilana Gutierrez dice que durante a\u00f1os supo que la estaban silenciando.Corr\u00eda el a\u00f1o 2015 cuando la modelo italiana dice haber sido agredida por el entonces magnate del cine Harvey Weinstein durante una reuni\u00f3n de casting. Inmediatamente acudi\u00f3 a la polic\u00eda para denunciar lo sucedido, dando por hecho que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448519,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/25\/denunciantes-harvey-weinstein-nuevo-juicio-anulacion-condena-trax\/","url_meta":{"origin":1448614,"position":4},"title":"Denunciantes de Harvey Weinstein quieren un nuevo juicio tras anulaci\u00f3n de condena por violaci\u00f3n y agresi\u00f3n","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Cuando el productor de Hollywood Harvey Weinstein fue declarado culpable de dos delitos sexuales en febrero de 2020, la condena fue aclamada como un momento hist\u00f3rico en el movimiento #MeToo.Ahora, m\u00e1s de cuatro a\u00f1os despu\u00e9s, el fallo de la Corte de Apelaciones de Nueva York que anula esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443256,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/06\/en-la-tercera-tanda-de-documentos-del-caso-epstein-figura-una-llamada-de-harvey-weinstein-mas-hombres-famosos-y-detalles-inquietantes\/","url_meta":{"origin":1448614,"position":5},"title":"En la tercera tanda de documentos del caso Epstein figura una llamada de Harvey Weinstein, m\u00e1s hombres famosos y detalles inquietantes","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) -- La tercera ronda de documentos de una demanda relacionada con Jeffrey Epstein, el pederasta convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual, se hizo p\u00fablica este viernes.La publicaci\u00f3n de este viernes ten\u00eda m\u00e1s de mil p\u00e1ginas, y llega\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1448614"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448614\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1448614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1448614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1448614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}