{"id":1448743,"date":"2024-05-01T12:03:56","date_gmt":"2024-05-01T19:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/"},"modified":"2024-05-01T12:03:56","modified_gmt":"2024-05-01T19:03:56","slug":"cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","title":{"rendered":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cuba anunci\u00f3 este martes la suspensi\u00f3n de los vuelos de la aerol\u00ednea Cubana de Aviaci\u00f3n entre la isla y Argentina debido a que la petrolera Yacimientos Petrol\u00edferos Fiscales (YPF), controlada por el gobierno argentino, notific\u00f3 su \u201cnegativa a continuar suministrando combustible a sus aeronaves&#187; en lo que calific\u00f3 como una &#171;aplicaci\u00f3n del bloqueo de Estados Unidos contra Cuba\u201d, en relaci\u00f3n con el embargo comercial instaurado en 1962 contra el Gobierno cubano.<\/p>\n<p>En un comunicado difundido en su p\u00e1gina oficial, el Ministerio de Relaciones Exteriores de Cuba dijo que YPF comunic\u00f3 su decisi\u00f3n a la compa\u00f1\u00eda cubana en marzo de 2024 y calific\u00f3 la medida de \u201carbitraria\u201d, seg\u00fan se\u00f1ala el escrito.<\/p>\n<p>\u201cLa empresa Cubana de Aviaci\u00f3n busc\u00f3 innumerables alternativas para mantener las operaciones que ya estaban planificadas y autorizadas por la Administraci\u00f3n Nacional de la Aviaci\u00f3n Civil argentina y no afectar a los pasajeros\u201d, sostiene el comunicado.<\/p>\n<p>El Ministerio de Relaciones Exteriores del pa\u00eds agrega que la jefa de la Unidad de Cubana de Aviaci\u00f3n en Buenos Aires \u201cse reuni\u00f3 con directivos de alto rango del \u00e1rea de transporte y de la aviaci\u00f3n civil de Argentina para hallar una soluci\u00f3n de conjunto. Sin embargo, no recibi\u00f3 una respuesta satisfactoria que asegurara la venta de combustible\u201d.<\/p>\n<p>Los vuelos regulares de Cubana de Aviaci\u00f3n entre la isla y Argentina se hab\u00edan mantenido durante 39 a\u00f1os, de acuerdo con la Canciller\u00eda de Cuba.<\/p>\n<p>El escrito expresa cr\u00edticas al Gobierno de Argentina \u2014quien controla la petrolera\u2014 por considerar la decisi\u00f3n \u201ccontradictoria\u201d a las ideas de la libertad que defiende su presidente, Javier Milei.<\/p>\n<p>\u201cEs contradictorio que se pregone la libertad a toda costa, mientras se limita la libertad de una empresa que cumple rigurosamente las disposiciones normativas de Argentina y de la Organizaci\u00f3n de la Aviaci\u00f3n Civil Internacional\u201d, sostiene el comunicado difundido por el Gobierno cubano.<\/p>\n<p>En una entrevista con CNN semanas atr\u00e1s, el mandatario de Argentina dej\u00f3 en claro el deteriorado v\u00ednculo bilateral con el gobierno de Cuba, entre otros pa\u00edses. CNN pidi\u00f3 ahora una reacci\u00f3n ante las cr\u00edticas y hasta este mi\u00e9rcoles no se hab\u00eda recibido respuesta.<\/p>\n<p>CNN le consult\u00f3 a YPF por este comunicado de la Canciller\u00eda de Cuba y aseguraron que no hay respuesta oficial.<\/p>\n<p>Sin embargo, una fuente de YPF aclar\u00f3 que la compa\u00f1\u00eda petrolera cotiza en la Bolsa de Nueva York y que eso le impide comerciar con empresas listadas en temas como los embargos, que lo mismo pasa con Venezuela y Rusia. Adem\u00e1s, agreg\u00f3 que cuando las operaciones alcanzaron a la moneda local, se notific\u00f3 en tiempo y forma a Cubana de Aviaci\u00f3n.<\/p>\n<p>Federico Jofre colabor\u00f3 con este reporte.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cuba anunci\u00f3 este martes la suspensi\u00f3n de los vuelos de la aerol\u00ednea Cubana de Aviaci\u00f3n entre la isla y Argentina debido a que la petrolera Yacimientos Petrol\u00edferos Fiscales (YPF), controlada por el gobierno argentino, notific\u00f3 su \u201cnegativa a continuar suministrando combustible a sus aeronaves&#187; en lo que calific\u00f3 como una &#171;aplicaci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448743","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Cuba anunci\u00f3 este martes la suspensi\u00f3n de los vuelos de la aerol\u00ednea Cubana de Aviaci\u00f3n entre la isla y Argentina debido a que la petrolera Yacimientos Petrol\u00edferos Fiscales (YPF), controlada por el gobierno argentino, notific\u00f3 su \u201cnegativa a continuar suministrando combustible a sus aeronaves&#187; en lo que calific\u00f3 como una &#171;aplicaci\u00f3n del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T19:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible\",\"datePublished\":\"2024-05-01T19:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\"},\"wordCount\":500,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\",\"name\":\"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-01T19:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Cuba anunci\u00f3 este martes la suspensi\u00f3n de los vuelos de la aerol\u00ednea Cubana de Aviaci\u00f3n entre la isla y Argentina debido a que la petrolera Yacimientos Petrol\u00edferos Fiscales (YPF), controlada por el gobierno argentino, notific\u00f3 su \u201cnegativa a continuar suministrando combustible a sus aeronaves&#187; en lo que calific\u00f3 como una &#171;aplicaci\u00f3n del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-01T19:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/"},"author":{"name":"","@id":""},"headline":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible","datePublished":"2024-05-01T19:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","name":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-01T19:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cubana de Aviaci\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible","url":"http:\/\/noticiasya.com\/san-diego\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2024\/05\/01\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-01T19:03:56Z","datePublished":"2024-05-01T19:03:56Z","dateModified":"2024-05-01T19:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cubana de Aviaci\\u00f3n suspende vuelos a Argentina por negativa de YPF a venderle combustible\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/05\\\/01\\\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2024\\\/05\\\/01\\\/cubana-de-aviacion-suspende-vuelos-a-argentina-ypf-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-01T19:03:56Z\",\"datePublished\":\"2024-05-01T19:03:56Z\",\"dateModified\":\"2024-05-01T19:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471078,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/10\/cuba-vuelos-dudas-escasez-combustible-orix\/","url_meta":{"origin":1448743,"position":0},"title":"&#171;No nos garantizan el regreso&#187;: dudas y expectativa en Espa\u00f1a tras los ajustes en vuelos a Cuba por la falta de combustible","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Las maletas traquetean de un lado hacia a otro. Los pasaportes de diferentes colores asoman en los bolsillos y bolsas de las diferentes personas a la espera de ser usados para embarcar en sus respectivos vuelos.La estampa de la terminal 1 del aeropuerto Adolfo Su\u00e1rez Madrid-Barajas de este martes por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471140,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/12\/canada-alerta-viaje-cuba-orix\/","url_meta":{"origin":1448743,"position":1},"title":"Canad\u00e1 urge a sus ciudadanos a salir de Cuba y recomienda evitar viajes a la isla","author":"","date":"febrero 12, 2026","format":false,"excerpt":"El Gobierno de Canad\u00e1 emiti\u00f3 este mi\u00e9rcoles una alerta en la que recomienda a sus ciudadanos evitar viajes no esenciales a Cuba e insta a quienes est\u00e9n en la isla a salir del pa\u00eds debido al agravamiento de la escasez de combustible.\u201cSe insta a los canadienses a que salgan del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472900,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/06\/milei-victoria-ypf-rol-trump-consecuencias-orix\/","url_meta":{"origin":1448743,"position":2},"title":"Milei consigui\u00f3 una victoria para Argentina en la Justicia de EE.UU.: \u00bfotra vez recibi\u00f3 la ayuda clave de Trump?","author":"","date":"abril 6, 2026","format":false,"excerpt":"Desde los inicios de su Gobierno, Javier Milei presume de su cercan\u00eda a su par estadounidense, Donald Trump. Este v\u00ednculo lo acompa\u00f1\u00f3 en las elecciones de medio t\u00e9rmino de 2025. Ahora, el presidente de Argentina se jacta de haber conseguido, presumiblemente por esta relaci\u00f3n, otra victoria: el reciente fallo en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471039,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/09\/air-canada-suspende-vuelos-cuba-escasez-combustible-trax\/","url_meta":{"origin":1448743,"position":3},"title":"Air Canada suspende sus vuelos a Cuba en medio de la escasez de combustible","author":"","date":"febrero 9, 2026","format":false,"excerpt":"Air Canada, la aerol\u00ednea m\u00e1s grande de Canad\u00e1, anunci\u00f3 la suspensi\u00f3n de sus vuelos a Cuba debido a la falta de combustible de aviaci\u00f3n en la isla, en un contexto marcado por los esfuerzos de Estados Unidos para cortar los suministros de petr\u00f3leo al pa\u00eds.La compa\u00f1\u00eda inform\u00f3 que interrumpi\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471060,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/10\/china-dispuesta-ayudar-cuba-escasez-combustibles-orix\/","url_meta":{"origin":1448743,"position":4},"title":"China se declara dispuesta a ayudar a Cuba ante sus problemas de escasez de combustibles","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El Ministerio de Relaciones Exteriores de China dijo este martes que el pa\u00eds est\u00e1 dispuesto a apoyar \u201cfirmemente\u201d a Cuba frente a los problemas que padece por escasez de combustibles.El Ministerio hizo esta declaraci\u00f3n \u2014recogida por la agencia Reuters\u2014 tras darse a conocer esta semana la suspensi\u00f3n de vuelos a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473342,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/20\/delegacion-estadounidense-visita-cuba-trax\/","url_meta":{"origin":1448743,"position":5},"title":"Delegaci\u00f3n estadounidense visita Cuba mientras Trump aumenta la presi\u00f3n sobre la isla","author":"","date":"abril 20, 2026","format":false,"excerpt":"Una delegaci\u00f3n estadounidense de alto nivel se reuni\u00f3 con funcionarios del Gobierno de Cuba mientras el Gobierno de Trump intensifica sus esfuerzos para presionar a La Habana a llegar a un acuerdo, al tiempo que contin\u00faa ejerciendo su asfixia econ\u00f3mica sobre la isla.Fue una de las visitas de m\u00e1s alto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1448743"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1448743\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1448743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1448743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1448743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}