{"id":1457893,"date":"2025-01-26T04:03:45","date_gmt":"2025-01-26T12:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/"},"modified":"2025-01-26T04:03:45","modified_gmt":"2025-01-26T12:03:45","slug":"acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","title":{"rendered":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial"},"content":{"rendered":"<p>Los fiscales de Corea del Sur acusaron al presidente destituido Yoon Suk Yeol de cargos de insurrecci\u00f3n por su declaraci\u00f3n de la ley marcial, una medida que sumi\u00f3 al pa\u00eds en la agitaci\u00f3n pol\u00edtica.<\/p>\n<p>Yoon, quien ha negado haber actuado mal, ha estado detenido desde que fue arrestado a principios de este mes. El mandatario fue despojado de sus poderes presidenciales a finales del a\u00f1o pasado por su ef\u00edmera declaraci\u00f3n de la ley marcial, que fue revocada en cuesti\u00f3n de horas por el Parlamento surcoreano.<\/p>\n<p>Podr\u00eda enfrentarse a cadena perpetua o a la pena de muerte si es declarado culpable, aunque Corea del Sur no ha ejecutado a nadie en d\u00e9cadas.<\/p>\n<p><em>Esta es una historia en desarrollo y se actualizar\u00e1.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los fiscales de Corea del Sur acusaron al presidente destituido Yoon Suk Yeol de cargos de insurrecci\u00f3n por su declaraci\u00f3n de la ley marcial, una medida que sumi\u00f3 al pa\u00eds en la agitaci\u00f3n pol\u00edtica. Yoon, quien ha negado haber actuado mal, ha estado detenido desde que fue arrestado a principios de este mes. El mandatario [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457893","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los fiscales de Corea del Sur acusaron al presidente destituido Yoon Suk Yeol de cargos de insurrecci\u00f3n por su declaraci\u00f3n de la ley marcial, una medida que sumi\u00f3 al pa\u00eds en la agitaci\u00f3n pol\u00edtica. Yoon, quien ha negado haber actuado mal, ha estado detenido desde que fue arrestado a principios de este mes. El mandatario [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-26T12:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial\",\"datePublished\":\"2025-01-26T12:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\",\"name\":\"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-26T12:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias","og_description":"Los fiscales de Corea del Sur acusaron al presidente destituido Yoon Suk Yeol de cargos de insurrecci\u00f3n por su declaraci\u00f3n de la ley marcial, una medida que sumi\u00f3 al pa\u00eds en la agitaci\u00f3n pol\u00edtica. Yoon, quien ha negado haber actuado mal, ha estado detenido desde que fue arrestado a principios de este mes. El mandatario [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-26T12:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/"},"author":{"name":"","@id":""},"headline":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial","datePublished":"2025-01-26T12:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","name":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-26T12:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-26T12:03:45Z","datePublished":"2025-01-26T12:03:45Z","dateModified":"2025-01-26T12:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusan de insurrecci\\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/26\\\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/26\\\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-26T12:03:45Z\",\"datePublished\":\"2025-01-26T12:03:45Z\",\"dateModified\":\"2025-01-26T12:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471418,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/19\/expresidente-corea-sur-condenado-cadena-perpetua-trax\/","url_meta":{"origin":1457893,"position":0},"title":"El expresidente de Corea del Sur Yoon Suk Yeol fue condenado a cadena perpetua por liderar una insurrecci\u00f3n","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El expresidente de Corea del Sur Yoon Suk Yeol fue sentenciado este jueves a cadena por un tribunal que lo declar\u00f3 culpable de liderar una insurrecci\u00f3n durante su ef\u00edmera imposici\u00f3n de la ley marcial, que sumi\u00f3 al pa\u00eds en el caos pol\u00edtico y amenaz\u00f3 con desmantelar d\u00e9cadas de democracia.El veredicto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456397,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","url_meta":{"origin":1457893,"position":1},"title":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Las autoridades de Corea del Sur impusieron una prohibici\u00f3n de viajar al extranjero al presidente del pa\u00eds, Yoon Suk Yeol, mientras los fiscales eval\u00faan posibles cargos de insurrecci\u00f3n por su fallido intento de imponer la ley marcial, la semana pasada.Aunque Yoon super\u00f3 el s\u00e1bado una votaci\u00f3n de destituci\u00f3n en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456453,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/12\/10\/exministro-defensa-corea-sur-intento-suicidio-allanan-oficina-presidencial-trax\/","url_meta":{"origin":1457893,"position":2},"title":"Exministro de Defensa de Corea del Sur intenta suicidarse mientras allanan la oficina presidencial tras la ley marcial","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El exministro de Defensa de Corea del Sur, Kim Yong-hyun, intent\u00f3 suicidarse mientras estaba detenido, dijo este mi\u00e9rcoles el jefe del servicio penitenciario del pa\u00eds, mientras contin\u00faa creciendo la crisis pol\u00edtica provocada por la breve declaraci\u00f3n de la ley marcial por parte del presidente.Por otra parte, la Polic\u00eda de Corea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460811,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/04\/03\/destituyen-presidente-corea-del-sur-yoon-suk-yeol-trax\/","url_meta":{"origin":1457893,"position":3},"title":"Destituyen al presidente de Corea del Sur cuatro meses despu\u00e9s de haber declarado la ley marcial","author":"","date":"abril 3, 2025","format":false,"excerpt":"El tribunal m\u00e1s alto de Corea del Sur destituy\u00f3 al presidente Yoon Suk Yeol, poniendo fin a meses de incertidumbre y disputas legales despu\u00e9s de que declarara brevemente la ley marcial en diciembre y sumiera a la naci\u00f3n en una agitaci\u00f3n pol\u00edtica.La decisi\u00f3n del tribunal el viernes marca la destituci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456236,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/12\/03\/que-ha-pasado-corea-sur-ley-marcial-orix\/","url_meta":{"origin":1457893,"position":4},"title":"Esto es lo que ha pasado en Corea del Sur tras la declaraci\u00f3n de ley marcial por el presidente","author":"","date":"diciembre 3, 2024","format":false,"excerpt":"(CNN) -- Corea del Sur vivi\u00f3 horas de incertidumbre pol\u00edtica debido a que el presidente Yoon Suk Yeol declar\u00f3 en la noche del martes la ley marcial, lo que permit\u00eda prohibir actividades pol\u00edticas y parlamentarias y arrestar a personas sin orden judicial, entre otras medidas.Tras las diversas reacciones y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457519,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/14\/autoridades-corea-del-sur-segundo-intento-arresto-interrogar-presidente-yoon-trax\/","url_meta":{"origin":1457893,"position":5},"title":"Las autoridades de Corea del Sur intentan por segunda vez detener al presidente para interrogarlo, informa Yonhap","author":"","date":"enero 14, 2025","format":false,"excerpt":"Las autoridades surcoreanas que investigan al presidente Yoon Suk Yeol llegaron a su residencia oficial en un segundo intento de detener al asediado l\u00edder para interrogarlo sobre su breve declaraci\u00f3n de ley marcial el mes pasado, seg\u00fan la agencia de noticias Yonhap de Corea del Sur.Seg\u00fan Yonhap, veh\u00edculos de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457893"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457893\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}