{"id":1457914,"date":"2025-01-27T04:03:51","date_gmt":"2025-01-27T12:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/"},"modified":"2025-01-27T04:03:51","modified_gmt":"2025-01-27T12:03:51","slug":"5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas"},"content":{"rendered":"<p>Las medidas que tom\u00f3 Trump contra Colombia. ICE aumenta detenciones de inmigrantes indocumentados. Capturan a presuntos miembros del Tren de Aragua en Colorado. <em>Esto es lo que debes saber para comenzar el d\u00eda.<\/em><strong> Primero la verdad.<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.cnn.com\/newsletters\/5-cosas\">Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/a><\/li>\n<li><a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/5-cosas\">\ud83c\udf99 Escucha las 5 cosas de CNN<\/a><\/li>\n<\/ul>\n<p>Colombia <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNy9lZXV1L2NvbG9tYmlhLWRlcG9ydGFkb3MtYXZpb25lcy1taWxpdGFyZXMtdHJhcy1hbWVuYXphcy1hcmFuY2VsYXJpYXMtdHJ1bXAtdHJheA\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3\/gZ5dpWQ\/s5ode471eed\">se ha alejado del borde de una da\u00f1ina guerra comercial con Estados Unidos<\/a>, alcanzando un acuerdo para aceptar que los migrantes deportados sean devueltos en aviones militares, despu\u00e9s de una serie de amenazas del presidente Donald Trump que incluyeron fuertes aranceles.<\/p>\n<p>La presidenta pro tempore de la CELAC y mandataria de Honduras, <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi91bHRpbWEtaG9yYS1kZS1sYXMtbWVkaWRhcy1kZS1lZS11dS1zb2JyZS1pbm1pZ3JhY2lvbi1kZXBvcnRhY2lvbmVzLWFyYW5jZWxlcy1hLWNvbG9tYmlhLXktbWFzLw\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3I2xpdmVibG9nLTZjMzkyM2M5LTIyMjUtNGJkOS05MWYyLTQyMTc3NDdiMGUwYQ\/gZ5dpWQ\/s2hd41f49ef\">Xiomara Castro, convoc\u00f3 de manera urgente a una reuni\u00f3n de presidentes y jefes de Estado <\/a>del organismo para este jueves 30 de enero en Tegucigalpa. La cita, que se llevar\u00e1 a cabo de forma h\u00edbrida, abordar\u00e1 temas clave como migraci\u00f3n, medio ambiente y la unidad de Am\u00e9rica Latina y el Caribe.<\/p>\n<p>La <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi91bHRpbWEtaG9yYS1kZS1sYXMtbWVkaWRhcy1kZS1lZS11dS1zb2JyZS1pbm1pZ3JhY2lvbi1kZXBvcnRhY2lvbmVzLWFyYW5jZWxlcy1hLWNvbG9tYmlhLXktbWFzLw\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3I2xpdmVibG9nLWQyMjQzN2FlLTk2ZGEtNDk5OS04NzE5LWIwMzA5ZDQ5ODkxZQ\/gZ5dpWQ\/s3m093b8b5d\">administraci\u00f3n de Donald Trump orden\u00f3 al Servicio de Control de Inmigraci\u00f3n y Aduanas cumplir<\/a> con una cuota diaria de 75 arrestos de inmigrantes indocumentados, seg\u00fan varias fuentes.<\/p>\n<p>Este domingo, menos de una semana despu\u00e9s de la toma de posesi\u00f3n de Donald Trump, se reportaron m\u00faltiples operativos migratorios en todo EE.UU. como parte de la ofensiva del mandatario contra los inmigrantes indocumentados. Adem\u00e1s de las \u201coperaciones dirigidas mejoradas\u201d del Servicio de Control de Inmigraci\u00f3n y Aduanas, (ICE, por sus siglas en ingl\u00e9s) en Chicago, se efectuaron operativos en Atlanta, Puerto Rico, Colorado, Los \u00c1ngeles y Austin, Texas. El ICE report\u00f3 956 arrestos y 554 detenciones durante la jornada.<\/p>\n<p>Casi <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/26\/ultima-hora-de-las-medidas-de-ee-uu-sobre-inmigracion-deportaciones-aranceles-a-colombia-y-mas\/#liveblog-f4a8eead-c08f-49a7-b526-1befbcee7c4e\">50 personas indocumentadas fueron detenidas en Colorado<\/a> durante una redada contra el narcotr\u00e1fico y pandilleros, ejecutada por la DEA. La operaci\u00f3n, realizada en un \u201cclub nocturno improvisado\u201d en el condado de Adams, result\u00f3 en la incautaci\u00f3n de drogas, armas y dinero en efectivo. La DEA inform\u00f3 que muchas de las personas detenidas tienen v\u00ednculos con el Tren de Aragua.<\/p>\n<p><strong>Casi 50 a\u00f1os despu\u00e9s, pruebas de ADN llevan a un arresto por asesinato en Honolulu<\/strong><\/p>\n<p><a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi9lZXV1L2FzZXNpbmF0by1hZG9sZXNjZW50ZS1ob25vbHVsdS1hZG4tYXJyZXN0by10cmF4\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3\/gZ5dpWQ\/s9h36169165\">Dawn Momohara, de 16 a\u00f1os<\/a>, fue hallada muerta en Honolulu el 21 de marzo de 1977. Pruebas de ADN permitieron hallar al culpable, Gideon Castro.<\/p>\n<p><strong>Fechas l\u00edmite para la declaraci\u00f3n de impuestos ante el IRS en 2025<\/strong><\/p>\n<p>La<a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi9lZXV1L2RlY2xhcmFjaW9uLWltcHVlc3Rvcy1pcnMtMjAyNS1lZS11dS1vcml4\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3Izp-OnRleHQ9TGElMjB0ZW1wb3JhZGElMjBkZSUyMGltcHVlc3RvcyUyMGRlLHNlciVDMyVBMSUyMGVsJTIwMTUlMjBkZSUyMGFicmlsLg\/gZ5dpWQ\/s4qdad842b0\"> temporada de impuestos de 2025 comienza el 27 de enero<\/a> y la fecha l\u00edmite para presentar la declaraci\u00f3n es el 15 de abril, aunque el plazo se extiende si cae en fin de semana o feriado.<\/p>\n<p><strong>Hist\u00f3rica exposici\u00f3n de moda en el Louvre<\/strong><\/p>\n<p>La exposici\u00f3n <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi9jdWx0dXJhL3ByaW1lcmEtZXhwb3NpY2lvbi1tb2RhLWxvdXZyZS12ZXJzYWNlLWRpb3ItdHJheA\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3\/gZ5dpWQ\/s7ib83a01f8\">\u201cLouvre Couture, Art and Fashion: Statement Pieces\u201d<\/a>, que estar\u00e1 abierta hasta el 21 de julio, presenta a 45 dise\u00f1adores ic\u00f3nicos como Chanel, Balenciaga, Versace y Yves Saint Laurent, en una demostraci\u00f3n del di\u00e1logo entre el arte y la moda desde los a\u00f1os 60 hasta la actualidad.<\/p>\n<p><strong>30 a\u00f1os de la patada de Eric Cantona a un aficionado <\/strong><\/p>\n<p>El <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi9kZXBvcnRlcy92aWRlby9lcmljLWNhbnRvbmEtcGF0YWRhLWZhbmF0aWNvLW1hbmNoZXN0ZXItdW5pdGVkLWZ1dGJvbC1jbm4tZGVwb3J0ZXMtdHY\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3\/gZ5dpWQ\/s6l632ad4b4\">exdelantero del Manchester United Eric Cantona<\/a> fue expulsado por patear a un aficionado del Crystal Palace que lo insult\u00f3.<\/p>\n<p><strong>80.000<\/strong><\/p>\n<p>El fabricante de autom\u00f3viles <a href=\"https:\/\/e.newsletters.cnn.com\/click?EYW5nZWxhbWFudWVsYXJleWVzQGdtYWlsLmNvbQ\/CeyJtaWQiOiIxNzM3OTc2MTQ1NTY1NzI5MzczZDU2YjllIiwiY3QiOiJjbm4tNDhhMzE2ZGFiMjczNmE1NWQxYzQxYzFmY2RhMjU1N2YtMSIsInJkIjoiZ21haWwuY29tIn0\/VaHR0cHM6Ly9jbm5lc3Bhbm9sLmNubi5jb20vMjAyNS8wMS8yNi9lY29ub21pYS9raWEtcmV2aXNpb24tODAtMDAwLWF1dG9zLWVlLXV1LXByb2JsZW1hcy1ib2xzYXMtYWlyZS1jYWJsZWFkby1hcA\/SWkhfQ05OX2lfTmV3c19OREJBTjAxMjcyMDI1YzE1MzcwODhiMQ\/LY24x\/qP3V0bV90ZXJtPTE3Mzc5NzYxNDU1NjU3MjkzNzNkNTZiOWUmdXRtX3NvdXJjZT1jbm5fNStjb3NhcysyNytkZStlbmVybyZ1dG1fbWVkaXVtPWVtYWlsJmJ0X2VlPXc3N04ySzlzVCUyRmREaklCJTJGcDRsMCUyRkNldVFjdERZWm9QWFhSWlNoVElsWUE4OTcyNnJsVUFzN3N2aEE0aFpnMyUyQiZidF90cz0xNzM3OTc2MTQ1NTY3\/gZ5dpWQ\/sbp4fb0a770\">Kia America llam\u00f3 a revisi\u00f3n m\u00e1s de 80.000 veh\u00edculos<\/a> debido a que el cableado del piso debajo del asiento del pasajero delantero puede da\u00f1arse e impedir que las bolsas de aire y los cinturones de seguridad se desplieguen correctamente.<\/p>\n<p><strong>\u201cNos esposaron all\u00ed el mi\u00e9rcoles por la noche y llegamos a Brasil y todav\u00eda ten\u00edamos las esposas puestas. Les dijimos que est\u00e1bamos en territorio brasile\u00f1o y que nos quitaran las esposas, pero no quer\u00edan\u201d.<\/strong><\/p>\n<p>Lo dijo un <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/26\/latinoamerica\/brasil-migrantes-repatriados-ee-uu-viola-terminos-acuerdo-trax\">migrante brasile\u00f1o deportado<\/a> quien denunci\u00f3 un \u201chumillante\u201d vuelo del Servicio de Control de Inmigraci\u00f3n y Aduanas. A esa acusaci\u00f3n se uni\u00f3 el Gobierno de Brasil se\u00f1alando que en la deportaci\u00f3n los ciudadanos fueron esposados de pies y manos.<\/p>\n<p><strong>CNN accedi\u00f3 en exclusiva al traslado de los pandas gigantes desde China a EE.UU.<\/strong><\/p>\n<p>Dos pandas gigantes, Bao Li y Qing Bao, abandonaron la base de investigaci\u00f3n en Dujiangyan, una ciudad del suroeste de China, para regresar al Zool\u00f3gico Nacional de Washington. Desde el 2023, la sala de pandas del zool\u00f3gico, que sol\u00eda atraer a millones de visitantes, ha estado vac\u00eda. Ahora, tras completar una remodelaci\u00f3n, est\u00e1 d\u00e1ndole la bienvenida a sus nuevos inquilinos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las medidas que tom\u00f3 Trump contra Colombia. ICE aumenta detenciones de inmigrantes indocumentados. Capturan a presuntos miembros del Tren de Aragua en Colorado. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN Colombia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457914","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las medidas que tom\u00f3 Trump contra Colombia. ICE aumenta detenciones de inmigrantes indocumentados. Capturan a presuntos miembros del Tren de Aragua en Colorado. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN Colombia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T12:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas\",\"datePublished\":\"2025-01-27T12:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\"},\"wordCount\":767,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\",\"name\":\"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-27T12:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias","og_description":"Las medidas que tom\u00f3 Trump contra Colombia. ICE aumenta detenciones de inmigrantes indocumentados. Capturan a presuntos miembros del Tren de Aragua en Colorado. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad. Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo \ud83c\udf99 Escucha las 5 cosas de CNN Colombia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-27T12:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas","datePublished":"2025-01-27T12:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/"},"wordCount":767,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","name":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-27T12:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-27T12:03:51Z","datePublished":"2025-01-27T12:03:51Z","dateModified":"2025-01-27T12:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 27 de enero: migrantes, crisis entre Colombia y EE.UU., redadas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/27\\\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/27\\\/5-cosas-27-enero-migrantes-crisis-colombia-y-eeuu-redadas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-27T12:03:51Z\",\"datePublished\":\"2025-01-27T12:03:51Z\",\"dateModified\":\"2025-01-27T12:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464214,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/04\/5-cosas-4-julio-orix\/","url_meta":{"origin":1457914,"position":0},"title":"Las 5 cosas que debes saber este 4 de julio: Megaproyecto de ley de Trump, ICE y Julio C\u00e9sar Ch\u00e1vez Jr.","author":"","date":"julio 4, 2025","format":false,"excerpt":"ICE detiene al boxeador mexicano Julio C\u00e9sar Ch\u00e1vez Jr. Lo que debes saber sobre los registros biom\u00e9tricos contemplados en pol\u00e9mica reforma mexicana. \u00bfQu\u00e9 pas\u00f3 con el inmigrante cubano que falleci\u00f3 bajo custodia de ICE? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457949,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/5-cosas-28-enero-trump-gaza-deepseek-aranceles-chelsea-orix\/","url_meta":{"origin":1457914,"position":1},"title":"Las 5 cosas que debes saber este 28 de enero: Trump, Gaza, DeepSeek, aranceles, fichaje del Chelsea y m\u00e1s","author":"","date":"enero 28, 2025","format":false,"excerpt":"Los aranceles explicados. \u00bfQu\u00e9 es DeepSeek? El cambio clim\u00e1tico est\u00e1 alterando los sistemas alimentarios de Am\u00e9rica Latina, seg\u00fan un informe de la ONU. El Chelsea bate el r\u00e9cord mundial de fichajes de una jugadora de f\u00fatbol. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451210,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/07\/17\/colombia-34-medallas-historia-juegos-olimpicos-orix\/","url_meta":{"origin":1457914,"position":2},"title":"Cu\u00e1ntas medallas ha ganado Colombia en su historia en los Juegos Ol\u00edmpicos y cu\u00e1l fue su mejor participaci\u00f3n","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Colombia, desde su debut en los Juegos Ol\u00edmpicos de Los \u00c1ngeles en 1932, ha acumulado un total de 34 medallas: 5 de oro, 13 de plata y 16 de bronce, seg\u00fan datos del Comit\u00e9 Ol\u00edmpico Internacional.Las primeras medallas no llegaron hasta los Juegos Ol\u00edmpicos de M\u00fanich en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457990,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/5-cosas-29-enero-deportados-colombia-deepseek-soldados-norcoreanos-boom-supersonic-orix\/","url_meta":{"origin":1457914,"position":3},"title":"Las 5 cosas que debes saber este 29 de enero: deportados a Colombia, DeepSeek, soldados norcoreanos y Boom Supersonic","author":"","date":"enero 29, 2025","format":false,"excerpt":"Tras la llegada de dos vuelos con colombianos deportados, se espera que EE.UU. reactive esta semana la emisi\u00f3n de visas en su embajada en Bogot\u00e1. DeepSeek hace estallar la narrativa del dinero de la IA. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470366,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/22\/5-cosas-22-enero-orix\/","url_meta":{"origin":1457914,"position":4},"title":"Las 5 cosas que debes saber este 22 de enero","author":"","date":"enero 22, 2026","format":false,"excerpt":"Directriz permite a agentes de ICE entrar en hogares sin orden judicial, seg\u00fan memorando. Venezuela informa que recibi\u00f3 US$ 300 millones por la venta de crudo tras el acuerdo con EE.UU. Ecuador anuncia una \u201ctasa de seguridad\u201d del 30 % a las importaciones de Colombia. Esto es lo que debes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463357,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/06\/09\/5-cosas-los-angeles-colombia-barbara-orix\/","url_meta":{"origin":1457914,"position":5},"title":"Las 5 cosas que debes saber este 9 de junio: protestas y choques en Los \u00c1ngeles, atentado en Colombia y tormenta Barbara","author":"","date":"junio 9, 2025","format":false,"excerpt":"Ataque contra Uribe Turbay revive lo peor de la violencia pol\u00edtica colombiana. Portugal gana la Nations League en penaltis: Cristiano Ronaldo anot\u00f3 en una final ag\u00f3nica. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457914"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457914\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}