{"id":1457923,"date":"2025-01-27T10:03:40","date_gmt":"2025-01-27T18:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/"},"modified":"2025-01-27T10:03:40","modified_gmt":"2025-01-27T18:03:40","slug":"agentes-federales-grabados-detenciones-migracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","title":{"rendered":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones"},"content":{"rendered":"<p>A las <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/26\/eeuu\/trump-ofensiva-control-arresto-inmigracion\">operaciones de b\u00fasqueda de inmigrantes<\/a> del fin de semana llevadas a cabo por el Gobierno de Trump, que incluyeron casi 1.000 arrestos y que han asustado a muchas comunidades de inmigrantes, le sigui\u00f3 otra ofensiva: un aluvi\u00f3n de videos y fotos del gobierno federal que muestran a agentes con equipo t\u00e1ctico y chalecos con las leyendas \u201cPolic\u00eda ICE\u201d y \u201cSeguridad Nacional\u201d llev\u00e1ndose a sospechosos esposados.<\/p>\n<p>El aspecto de los arrestos, hecho para la televisi\u00f3n, no es una coincidencia.<\/p>\n<p>Al menos dos agencias que asisten a los funcionarios de inmigraci\u00f3n de Estados Unidos en las b\u00fasquedas han dicho al personal que se asegure de que su vestimenta muestre claramente su respectiva agencia en caso de que sean filmados por miembros de los medios de comunicaci\u00f3n, seg\u00fan fuentes familiarizadas con las operaciones que han sido citadas por CNN.<\/p>\n<p>Si bien es una pr\u00e1ctica de seguridad com\u00fan que los agentes que llevan a cabo arrestos lleven insignias que los identifiquen claramente como miembros de las fuerzas del orden, incluso los agentes en el per\u00edmetro de las operaciones llevadas a cabo en todo el pa\u00eds han recibido instrucciones espec\u00edficas de sus superiores para que lleven chaquetas de redada en previsi\u00f3n de la atenci\u00f3n de los medios de comunicaci\u00f3n, seg\u00fan las fuentes.<\/p>\n<p>El domingo, las agencias federales publicaron numerosas fotos en las redes sociales de agentes con equipo t\u00e1ctico que llevaban a cabo supuestos arrestos de inmigrantes.<\/p>\n<p>El expresentador de programas de entrevistas de televisi\u00f3n Dr. Phil McGraw anunci\u00f3 <a href=\"https:\/\/x.com\/DrPhil\">en las redes sociales<\/a> que estaba participando en una operaci\u00f3n con un equipo de Inmigraci\u00f3n y Control de Aduanas en Chicago cuando comenzaron las operaciones. McGraw public\u00f3 un video en el que se le ve entrevistando al nuevo \u201czar de la frontera\u201d de la Administraci\u00f3n Trump, Tom Homan, en lo que se describi\u00f3 como un Centro de Mando de ICE.<\/p>\n<p>Invitar a una celebridad a las operaciones de Chicago fue frustrante para el fiscal general de Illinois, Kwame Raoul, quien le dijo a Jim Acosta de CNN que su oficina no hab\u00eda recibido ninguna notificaci\u00f3n sobre los arrestos a pesar de haber colaborado con las fuerzas del orden federales en el pasado.<\/p>\n<p>\u201cCreo que se ha hecho por el espect\u00e1culo, y creo que se ha hecho para molestar a la comunidad y ganar puntos pol\u00edticos con aquellos que quieren dividir\u201d, dijo Raoul.<\/p>\n<p>El senador dem\u00f3crata estadounidense Dick Durbin, de Illinois, dijo en una <a href=\"https:\/\/x.com\/SenatorDurbin\/status\/1883687299696972174\">publicaci\u00f3n en X<\/a> que sus oficinas del Congreso ayudar\u00edan a cualquiera que hubiera sido arrestado indebidamente. \u201cTodos estamos de acuerdo en que debemos expulsar a las personas peligrosas que est\u00e1n aqu\u00ed de forma ilegal\u201d, escribi\u00f3 Durbin. \u201cPero las acciones que est\u00e1 tomando la administraci\u00f3n Trump van m\u00e1s all\u00e1 de esos objetivos\u201d.<\/p>\n<p>Adem\u00e1s de Chicago, tambi\u00e9n se han denunciado acciones de inmigraci\u00f3n en California, Texas, Georgia, Colorado, Puerto Rico y las Islas V\u00edrgenes de Estados Unidos, seg\u00fan el Departamento de Seguridad Nacional y la Agencia Antidrogas.<\/p>\n<p>\u201cEstamos dando prioridad a los extranjeros delincuentes\u201d, dijo Homan a CNN el domingo, pero a\u00f1adi\u00f3: \u201cLlegar\u00e1 un momento en el que tendremos que abrir la veda a los fugitivos\u201d.<\/p>\n<p>Una mujer de los suburbios de Chicago dijo que su padre, originario de M\u00e9xico, llevaba casi 30 a\u00f1os viviendo en Estados Unidos cuando fue arrestado el domingo despu\u00e9s de que unos agentes llamaran a su puerta.<\/p>\n<p>\u201cAbrieron la puerta porque pensaron que tal vez uno de (sus hijos) estaba en problemas o que nos hab\u00eda pasado algo\u201d, <a href=\"https:\/\/abc7chicago.com\/post\/mass-deportation-acting-deputy-attorney-general-emil-bove-chicago-observe-immigration-enforcement-ops-doj-tells-abc\/15838277\/\">dijo Yelitza Marquina a WLS<\/a>, afiliada de CNN. \u201cNunca pens\u00f3 que eran de ICE\u201d.<\/p>\n<p>Un hombre indocumentado fue detenido por ICE mientras asist\u00eda a la iglesia el domingo en Tucker, Georgia, dijo su pastor a CNN.<\/p>\n<p>Luis Ortiz estaba en medio de su serm\u00f3n cuando vio al hombre siendo escoltado por otros feligreses. Le dijeron que los agentes de ICE no entraron en el edificio, pero preguntaron por el hombre.<\/p>\n<p>Los inmigrantes adultos han dejado de acudir al trabajo y los ni\u00f1os no van a la escuela por miedo a ser detenidos en cualquier momento, dijo a CNN una organizaci\u00f3n sin fines de lucro con sede en Chicago que ayuda a los inmigrantes. La organizaci\u00f3n ben\u00e9fica pidi\u00f3 no ser identificada por temor a represalias.<\/p>\n<p>En el \u00e1rea de Atlanta, el Distrito Escolar del Condado de DeKalb envi\u00f3 una nota a las familias de las escuelas advirti\u00e9ndoles que el distrito no permitir\u00e1 voluntariamente la entrada de agentes de inmigraci\u00f3n en sus escuelas.<\/p>\n<p>\u201cAl igual que con cualquier visitante no autorizado, est\u00e1 prohibida la entrada m\u00e1s all\u00e1 de la oficina principal y el acceso a los estudiantes o a su informaci\u00f3n sin una orden judicial o circunstancias apremiantes\u201d, escribi\u00f3 el superintendente Devon Horton.<\/p>\n<p>El ICE continuar\u00e1 con las \u201coperaciones mejoradas\u201d en todo el sureste entre dos y tres veces por semana, seg\u00fan una fuente con conocimiento de las operaciones. En ellas participar\u00e1n el FBI, la Administraci\u00f3n para el Control de Drogas y la Oficina de Alcohol, Tabaco, Armas de Fuego y Explosivos, y se dar\u00e1 <a href=\"https:\/\/www.cbp.gov\/newsroom\/stats\/cbp-enforcement-statistics\/title-8-and-title-42-statistics\">autoridad a las agencias para detener a los inmigrantes<\/a>.<\/p>\n<p>El ICE est\u00e1 lanzando una amplia red, pero su objetivo principal es el <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/18\/tren-de-aragua-expansion-america-orix\">Tren de Aragua<\/a>, una banda criminal transnacional que se origin\u00f3 en una prisi\u00f3n venezolana, seg\u00fan la fuente.<\/p>\n<p>A los equipos de todo el pa\u00eds se les han asignado varias cuotas para el n\u00famero de b\u00fasquedas de inmigrantes de \u201calto perfil\u201d que deben llevar a cabo cada mes, dijo una fuente, con el objetivo de superar el n\u00famero de arrestos administrativos realizados por el Servicio de Inmigraci\u00f3n y Control de Aduanas el a\u00f1o pasado.<\/p>\n<p>Las Operaciones de Cumplimiento y Deportaci\u00f3n del ICE llevaron a cabo 113.431 detenciones administrativas en el a\u00f1o fiscal que finaliz\u00f3 en octubre de 2024, seg\u00fan <a href=\"https:\/\/www.ice.gov\/doclib\/eoy\/iceAnnualReportFY2024.pdf\">un informe de la agencia<\/a>. Eso supone unas 310 detenciones al d\u00eda.<\/p>\n<p>Homan neg\u00f3 haber impuesto una cuota de detenciones a los agentes del ICE.<\/p>\n<p>\u201cMi objetivo es detener al mayor n\u00famero posible de amenazas a la seguridad p\u00fablica y nacional y pasar a otras prioridades\u201d, declar\u00f3 a CNN.<\/p>\n<p>Alrededor de 11 millones de inmigrantes indocumentados viven en Estados Unidos, seg\u00fan indican las <a href=\"https:\/\/www.pewresearch.org\/short-reads\/2024\/07\/22\/what-we-know-about-unauthorized-immigrants-living-in-the-us\/\">\u00faltimas estimaciones<\/a> del Centro de Investigaci\u00f3n Pew.<\/p>\n<p>Las agencias federales de aplicaci\u00f3n de la ley han recibido instrucciones de dar prioridad a la deportaci\u00f3n de una amplia franja de sospechosos de delitos que est\u00e1n siendo investigados y que pueden estar \u201cfuera de estatus\u201d, seg\u00fan ha declarado a CNN una fuente policial familiarizada con las \u00faltimas operaciones. Alguien que est\u00e1 fuera de estatus puede haber entrado legalmente en Estados Unidos, pero ha violado los t\u00e9rminos de su visado u otros requisitos de inmigraci\u00f3n.<\/p>\n<p>Si un sospechoso investigado por agencias como el FBI, la ATF o la DEA se encuentra en el pa\u00eds de forma ilegal y no es probable que se presente en un futuro pr\u00f3ximo una acusaci\u00f3n por delitos penales no relacionados con la inmigraci\u00f3n investigados por dichas agencias, la fuente dijo que se ha ordenado a los investigadores que consideren \u201csimplemente expulsarlos\u201d.<\/p>\n<p>La nueva postura es notable porque los delitos investigados por las agencias federales de aplicaci\u00f3n de la ley pueden tardar semanas o incluso varios meses en ser probados y procesados. Sin embargo, bajo la nueva orientaci\u00f3n de los funcionarios del Gobierno de Trump, se ha dicho a las agencias que opten por la deportaci\u00f3n de los sospechosos indocumentados si no se vislumbra una acusaci\u00f3n penal.<\/p>\n<p>Antes de asumir el cargo, los funcionarios de transici\u00f3n de Trump preguntaban a las fuerzas del orden cu\u00e1ntas de sus investigaciones involucraban a ciudadanos no estadounidenses, dijo la fuente.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las operaciones de b\u00fasqueda de inmigrantes del fin de semana llevadas a cabo por el Gobierno de Trump, que incluyeron casi 1.000 arrestos y que han asustado a muchas comunidades de inmigrantes, le sigui\u00f3 otra ofensiva: un aluvi\u00f3n de videos y fotos del gobierno federal que muestran a agentes con equipo t\u00e1ctico y chalecos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457923","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"A las operaciones de b\u00fasqueda de inmigrantes del fin de semana llevadas a cabo por el Gobierno de Trump, que incluyeron casi 1.000 arrestos y que han asustado a muchas comunidades de inmigrantes, le sigui\u00f3 otra ofensiva: un aluvi\u00f3n de videos y fotos del gobierno federal que muestran a agentes con equipo t\u00e1ctico y chalecos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T18:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones\",\"datePublished\":\"2025-01-27T18:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\"},\"wordCount\":1360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\",\"name\":\"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-27T18:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias","og_description":"A las operaciones de b\u00fasqueda de inmigrantes del fin de semana llevadas a cabo por el Gobierno de Trump, que incluyeron casi 1.000 arrestos y que han asustado a muchas comunidades de inmigrantes, le sigui\u00f3 otra ofensiva: un aluvi\u00f3n de videos y fotos del gobierno federal que muestran a agentes con equipo t\u00e1ctico y chalecos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-27T18:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/"},"author":{"name":"","@id":""},"headline":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones","datePublished":"2025-01-27T18:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/"},"wordCount":1360,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","name":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-27T18:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los agentes federales en operaciones de inmigraci\u00f3n deben estar preparados para ser grabados tras cientos de detenciones","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/agentes-federales-grabados-detenciones-migracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-27T18:03:40Z","datePublished":"2025-01-27T18:03:40Z","dateModified":"2025-01-27T18:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los agentes federales en operaciones de inmigraci\\u00f3n deben estar preparados para ser grabados tras cientos de detenciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/27\\\/agentes-federales-grabados-detenciones-migracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/27\\\/agentes-federales-grabados-detenciones-migracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-27T18:03:40Z\",\"datePublished\":\"2025-01-27T18:03:40Z\",\"dateModified\":\"2025-01-27T18:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463425,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/06\/11\/protestas-ice-agencia-arrestos-inmigracion-trump-trax\/","url_meta":{"origin":1457923,"position":0},"title":"Protestas contra ICE ocurren mientras la agencia se esfuerza por cumplir con las metas de arrestos de inmigraci\u00f3n de Trump","author":"","date":"junio 11, 2025","format":false,"excerpt":"Las protestas que se desarrollan en todo el pa\u00eds contra la agenda de inmigraci\u00f3n del presidente Donald Trump coinciden con el esfuerzo del ICE por cumplir con los objetivos de detenciones establecidos por la Casa Blanca.Desde que Trump asumi\u00f3 el cargo, ICE, que anteriormente operaba con un conjunto de pautas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462981,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/29\/casa-blanca-arrestos-migratorios-presion-agencias-trax\/","url_meta":{"origin":1457923,"position":1},"title":"La presi\u00f3n de la Casa Blanca para aumentar los arrestos migratorios sobrecarga a las agencias del orden p\u00fablico","author":"","date":"mayo 29, 2025","format":false,"excerpt":"La administraci\u00f3n de Trump aumentar\u00e1 el personal y los recursos federales para cumplir con el deseo de la Casa Blanca de triplicar el n\u00famero de arrestos diarios por inmigraci\u00f3n, lo que indica un renovado impulso para ir mucho m\u00e1s all\u00e1 de los esfuerzos de administraciones anteriores.La Casa Blanca ejerce una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457899,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/26\/trump-ofensiva-control-arresto-inmigracion\/","url_meta":{"origin":1457923,"position":2},"title":"El Gobierno de Trump lanza una operaci\u00f3n en Chicago para facilitar el arresto de inmigrantes","author":"","date":"enero 26, 2025","format":false,"excerpt":"El Gobierno de Trump lanz\u00f3 una ofensiva de control de inmigraci\u00f3n en Chicago este domingo que permite que varias agencias federales a las que se les hab\u00edan otorgado autorizaciones adicionales puedan arrestar a inmigrantes indocumentados en Estados Unidos, seg\u00fan m\u00faltiples fuentes.Es parte de un esfuerzo m\u00e1s amplio para agregar personal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464598,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/16\/demandan-gobierno-trump-arrestos-ice-tribunales-inmigracion-trax\/","url_meta":{"origin":1457923,"position":3},"title":"Demandan al Gobierno de Trump por los arrestos de ICE en tribunales de inmigraci\u00f3n","author":"","date":"julio 16, 2025","format":false,"excerpt":"Grupos de derechos civiles demandaron a la administraci\u00f3n de Trump el mi\u00e9rcoles en un intento por detener la pol\u00edtica gubernamental de permitir que los agentes de ICE arresten a inmigrantes indocumentados que se presentan a audiencias de inmigraci\u00f3n en los tribunales.La demanda colectiva, presentada en un tribunal federal en Washington\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464475,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/13\/tension-aumenta-california-redadas-migratorias-trax\/","url_meta":{"origin":1457923,"position":4},"title":"La tensi\u00f3n aumenta en el sur de California por las redadas contra inmigrates","author":"","date":"julio 13, 2025","format":false,"excerpt":"Despu\u00e9s de semanas de redadas ca\u00f3ticas de inmigraci\u00f3n en p\u00fablico y en lugares de trabajo en todo el sur de California, un juez ha otorgado una orden de restricci\u00f3n temporal en una demanda, requiriendo que las autoridades federales encuentren una \u201csospecha razonable\u201d para realizar arrestos de inmigraci\u00f3n en el distrito\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459260,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/26\/mas-20-000-inmigrantes-indocumentados-arrestados-primer-mes-de-trump-dhs-trax\/","url_meta":{"origin":1457923,"position":5},"title":"Arrestan a m\u00e1s de 20.000 inmigrantes indocumentados durante el primer mes de Trump en la presidencia, seg\u00fan el DHS","author":"","date":"febrero 26, 2025","format":false,"excerpt":"M\u00e1s de 20.000 inmigrantes indocumentados fueron arrestados durante el primer mes de Donald Trump como presidente, seg\u00fan el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s).El Gobierno de Trump lanz\u00f3 una ofensiva contra la inmigraci\u00f3n en los momentos posteriores a su toma de posesi\u00f3n y public\u00f3 los totales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457923"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457923\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}