{"id":1457944,"date":"2025-01-28T03:03:42","date_gmt":"2025-01-28T11:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/"},"modified":"2025-01-28T03:03:42","modified_gmt":"2025-01-28T11:03:42","slug":"analisis-agenda-represiva-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","title":{"rendered":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan"},"content":{"rendered":"<p>Mucho m\u00e1s all\u00e1 del clamor en Washington de acciones ejecutivas y demandas, y de los comunicados de prensa en duelo entre aliados y adversarios de Donald Trump, la llegada del r\u00e9gimen de inmigraci\u00f3n del nuevo presidente ya est\u00e1 cambiando la vida sobre el terreno para millones de personas: inmigrantes indocumentados, sus hijos, su familia, amigos y vecinos, profesores y directores, gobiernos locales y fuerzas del orden.<\/p>\n<p>En los d\u00edas previos a la segunda toma de posesi\u00f3n de Trump la semana pasada, las familias ansiosas que buscaban consejo en el grupo de derechos de los inmigrantes m\u00e1s prominente de Los \u00c1ngeles ten\u00edan una pregunta por encima de todo.<\/p>\n<p>\u201cDe lo que m\u00e1s quieren hablar es de la separaci\u00f3n familiar\u201d, me dijo Ang\u00e9lica Salas, directora ejecutiva de la Coalici\u00f3n por los Derechos Humanos de los Inmigrantes (CHIRLA, por sus siglas en ingl\u00e9s), sobre los miles de inmigrantes indocumentados que se han puesto en contacto con su oficina desde la elecci\u00f3n de Trump. \u201cLas personas est\u00e1n realmente preocupadas por qui\u00e9n va a cuidar de sus hijos\u201d si son detenidos o deportados.<\/p>\n<p>Hubo decenas de otras preguntas dolorosamente pr\u00e1cticas cuando cientos de personas se reunieron el martes pasado por la noche, al final del primer d\u00eda completo de Trump en su segundo mandato, para un foro de \u201cconoce tus derechos\u201d que CHIRLA patrocin\u00f3 en la oficina de United Teachers Los Angeles, el sindicato de maestros de Los \u00c1ngeles. Un hombre quer\u00eda saber cu\u00e1les eran sus obligaciones como propietario si los agentes federales de Inmigraci\u00f3n y Aduanas se presentaban en su negocio exigiendo hablar con sus trabajadores. Otra mujer quer\u00eda saber si el grupo dispon\u00eda de material que pudiera facilitar para informar a las personas ciegas y sordas con las que trabaja sobre sus derechos en caso de ser detenidas por el ICE. Otra persona pregunt\u00f3 si pod\u00edan seguir facilitando con seguridad su nacionalidad a los hospitales cuando se la pidieran en un certificado de nacimiento.<\/p>\n<p>Las preocupaciones planteadas en la reuni\u00f3n no se refer\u00edan a grandes cuestiones de pol\u00edtica nacional, sino a realidades \u00edntimas de la vida cotidiana.<em> \u00bfPuedo enviar a mis hijos a la escuela? \u00bfPuedo ir al m\u00e9dico? \u00bfCu\u00e1les son mis derechos si el ICE me para por la calle?<\/em><\/p>\n<p>Cuando Salas habl\u00f3 a la gran multitud el pasado martes por la noche, su mensaje principal fue que las personas preocupadas por la promesa de deportaci\u00f3n masiva de Trump necesitaban mantenerse fuertes tanto en su determinaci\u00f3n de proteger sus derechos individuales como en su compromiso de unirse colectivamente para protestar contra sus pol\u00edticas. \u201cNo pueden vencernos con el miedo\u201d, insisti\u00f3. \u201cNo pueden impedir que protejamos nuestros derechos humanos\u201d.<\/p>\n<p>La multitud de miembros de la comunidad, sindicatos locales y grupos de derechos civiles que se reuni\u00f3 el martes pasado por la noche era en\u00e9rgica, los c\u00e1nticos de \u201cs\u00ed se puede\u201d siempre vigorosos, la emoci\u00f3n apasionada en una vigilia con velas a la que asistieron decenas de personas al atardecer frente a una iglesia al otro lado de la calle. Y, sin embargo, no hab\u00eda duda de la ansiedad y la aprensi\u00f3n que bull\u00edan en todo ello.<\/p>\n<p>\u201cTrabajo para la escuela local y muchos de nuestros padres sienten mucho miedo\u201d, me dijo Erica Granados al comenzar el acto. Cuando la velada tocaba a su fin, Myrla Baldonado, que trabaja con un grupo que defiende a las trabajadoras dom\u00e9sticas, me cont\u00f3 que esa ma\u00f1ana hab\u00eda visto a tres j\u00f3venes latinas salir corriendo de una estaci\u00f3n de metro gritando: \u201cYa vienen, ya vienen\u201d. Result\u00f3 ser una falsa alarma, dijo, pero lo m\u00e1s revelador fue que nadie tuvo que preguntar a las mujeres qui\u00e9nes eran \u201cellos\u201d.<\/p>\n<p>Salas vive en uno de los barrios amenazados por los incendios forestales que arrasaron Los \u00c1ngeles a principios de mes. Mientras hac\u00eda la maleta e intentaba reunir objetos de valor por si ten\u00eda que evacuar, le sorprendieron las similitudes entre los consejos que o\u00eda en televisi\u00f3n a los funcionarios de emergencias locales y las orientaciones que ella da a los inmigrantes indocumentados en su oficina. \u201cLo est\u00e1s pensando como si fuera un plan para una cat\u00e1strofe\u201d, me dijo. Al igual que los incendios o un terremoto, dijo, \u201chasta cierto punto es bastante aleatorio\u201d a qui\u00e9n detienen en una redada.<\/p>\n<p>\u201cSe lo decimos a la gente de forma muy pr\u00e1ctica: ahorren algo de dinero para que la persona que sea deportada pueda tener algunos recursos\u201d, me dijo Salas. \u201cPreparen una bolsita o puedan enviarles tanto dinero como ropa, sobre todo si los detienen solo con un pijama\u201d.<\/p>\n<p>Su grupo inculca a los inmigrantes indocumentados y a sus familias, incluidos los que tienen estatus legal, la importancia de hacer los tr\u00e1mites legales b\u00e1sicos. \u201cHemos estado haciendo innumerables consultas con personas para que al menos\u2026 podamos tener parte de su informaci\u00f3n b\u00e1sica: su nombre, su fecha de nacimiento\u201d, dijo. Sin esa informaci\u00f3n b\u00e1sica, puede ser tan dif\u00edcil localizar a los detenidos, dijo Salas, que existe el riesgo de que las personas puedan ser expulsadas de EE.UU. antes de que sus familias siquiera determinen d\u00f3nde est\u00e1n retenidas. \u201cEspecialmente si viven en regiones fronterizas, la deportaci\u00f3n es muy r\u00e1pida\u201d, dijo.<\/p>\n<p>Salas anima sobre todo a los padres con hijos menores a rellenar lo que se llama \u201cDeclaraci\u00f3n jurada de autorizaci\u00f3n del cuidador\u201d. Con ese documento, un padre autoriza a otra persona \u2013un amigo, un pariente, incluso un hermano mayor\u2013 a cuidar de sus hijos si son expulsados del pa\u00eds. La autoridad otorgada por los padres mediante el documento, me dijo Salas, \u201ces suficiente para poder mantener a un ni\u00f1o matriculado en la escuela o autorizar cualquier atenci\u00f3n m\u00e9dica si el ni\u00f1o se pone enfermo y tiene que ir al m\u00e9dico\u201d.<\/p>\n<p>La cuesti\u00f3n de cu\u00e1nto contar a los ni\u00f1os sobre estas contingencias es dif\u00edcil. Los padres \u201csuelen hablar con los ni\u00f1os mayores y les dicen cosas muy pr\u00e1cticas: Aqu\u00ed dejo algo de dinero, si me recogen a este es a quien tienes que llamar, aqu\u00ed es donde guardamos algo de dinero\u201d, me dijo Salas. \u201cSiempre recuerdo la historia de nuestro alcalde aqu\u00ed en Pasadena, cuyos padres eran indocumentados; sus padres le dijeron que su dinero estaba en el tarro del caf\u00e9, que fuera all\u00ed si les pasaba algo\u201d.<\/p>\n<p>Solo explicar estos preparativos puede ser traum\u00e1tico para los ni\u00f1os m\u00e1s peque\u00f1os, dijo Salas. Ella lo sabe por experiencia personal: su madre, que era indocumentada, fue deportada cuando Salas ten\u00eda 11 a\u00f1os. Aunque su madre finalmente regres\u00f3 a California en virtud de una demanda colectiva que permiti\u00f3 a su familia obtener un estatus legal, \u201cesto es algo que se queda contigo para el resto de tu vida\u201d, dijo Salas. \u201cY es absolutamente traum\u00e1tico. Incluso tener al padre detenido es traum\u00e1tico\u201d.<\/p>\n<p>CHIRLA ha ayudado a miles de inmigrantes indocumentados a llenar declaraciones juradas de cuidadores a lo largo de los a\u00f1os, con el ritmo notablemente acelerado desde que Trump gan\u00f3 las elecciones. El grupo est\u00e1 trabajando con el sindicato de maestros y el Distrito Escolar Unificado de Los \u00c1ngeles para capacitar a los maestros para detectar a los ni\u00f1os que se sienten estresados por lo que pueda sucederles a sus padres (incluso si los propios ni\u00f1os son ciudadanos estadounidenses). En el foro del martes pasado, Karla Griego, miembro de la junta del LAUSD, dijo que el distrito escolar estaba llevando a cabo varios d\u00edas de capacitaci\u00f3n esta semana para los directores de las escuelas sobre lo que ICE puede y no puede exigir en los terrenos de la escuela, con los directores luego dirigidos a instruir a todos sus maestros y personal. \u201cTodo el mundo va a recibir formaci\u00f3n\u201d, dijo. (Esa promesa parec\u00eda especialmente relevante para la audiencia, dado que la administraci\u00f3n Trump ha rescindido la orientaci\u00f3n de larga data que proh\u00edbe las operaciones de aplicaci\u00f3n de inmigraci\u00f3n en lugares sensibles, incluidos hospitales y escuelas).<\/p>\n<p>A pesar de todo este alcance, Granados, cuyo trabajo implica fomentar un clima de aprendizaje positivo, dice que cree que la mayor\u00eda de los padres indocumentados con los que trabaja en las cercanas Escuelas Comunitarias Robert F. Kennedy (ubicadas en el sitio del Hotel Ambassador, donde RFK fue asesinado en 1968) no tienen idea de que necesitan una declaraci\u00f3n jurada de cuidador. Pensaba llevar copias de la reuni\u00f3n para colocarlas en la sala de recursos para padres de la escuela. \u201cMuchos de nuestros padres tienen un gran esp\u00edritu de lucha\u201d, dijo, \u201cpero realmente se trata de prepararse para un posible trauma\u201d.<\/p>\n<p>Todo el trabajo que CHIRLA est\u00e1 haciendo con los inmigrantes indocumentados equivale a apilar sacos de arena contra una tormenta que se avecina. Ella y otros grupos de derechos de los inmigrantes en todo el pa\u00eds han estado poniendo sistem\u00e1ticamente otros preparativos en su lugar mientras Trump y su equipo lanzaban su programa de deportaci\u00f3n masiva con una <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/21\/eeuu\/trump-ice-migracion-arrestar-iglesias-escuelas-lugares-sensibles-trax\">serie de acciones de aplicaci\u00f3n intensificadas<\/a> durante el fin de semana desde Chicago y Atlanta hasta Austin y Los \u00c1ngeles.<\/p>\n<p>El Gobierno de Trump presenta esta intensificaci\u00f3n de las medidas coercitivas como el correctivo atrasado a las pol\u00edticas del expresidente Joe Biden que, seg\u00fan argumentan, cedieron el control de la frontera e inundaron de forma insostenible las ciudades con inmigrantes indocumentados. En una entrevista con CNN, el \u201czar fronterizo\u201d de la Casa Blanca, Tom Homan, calific\u00f3 de \u201cbuen d\u00eda\u201d y de \u201ccambio de juego\u201d las medidas policiales adoptadas el domingo en Chicago.<\/p>\n<p>\u201cTuvimos a todas las fuerzas del orden del Gobierno hoy para centrarse en la seguridad p\u00fablica y las amenazas a la seguridad nacional en Chicago\u201d, dijo Homan, que mantuvo que fue una \u201coperaci\u00f3n criminal\u201d.<\/p>\n<p>La ofensiva del domingo es probablemente solo un anticipo de la presi\u00f3n sostenida que se ejercer\u00e1 sobre las comunidades de inmigrantes: Las oficinas de campo del ICE han recibido la orden de cumplir un cupo de 75 detenciones diarias, seg\u00fan inform\u00f3 el domingo CNN, lo que allana el camino para superar el n\u00famero de detenciones diarias del a\u00f1o pasado.<\/p>\n<p>La respuesta de los defensores de los inmigrantes, huelga decirlo, no puede compararse en magnitud. Las organizaciones que trabajan en las comunidades de inmigrantes han establecido un n\u00famero de tel\u00e9fono gratuito nacional para que la gente llame en cualquier momento en que crea que se est\u00e1 produciendo una aplicaci\u00f3n del ICE. Grupos de varios estados est\u00e1n formando equipos de respuesta r\u00e1pida que incluyen abogados, organizadores comunitarios y vide\u00f3grafos, para acudir r\u00e1pidamente al lugar si se confirman tales operaciones.<\/p>\n<p>Chicago, donde <a href=\"https:\/\/www.cnn.com\/2025\/01\/26\/politics\/chicago-immigration-trump-ice\/index.html\">la administraci\u00f3n centr\u00f3 el domingo una gran b\u00fasqueda<\/a> en la que participaron cinco agencias gubernamentales, es uno de los lugares donde ese trabajo ha sido m\u00e1s urgente. \u201cEn realidad, se trata de una red integral de cualquier cosa que las familias puedan necesitar en ese momento\u201d, dijo Lawrence Benito, director ejecutivo de la Coalici\u00f3n de Illinois por los Derechos de los Inmigrantes y Refugiados. \u201cNuestros equipos tambi\u00e9n est\u00e1n preparados para documentar y plantear la pregunta al pueblo estadounidense sobre la brutalidad de lo que pueden parecer estas pol\u00edticas de aplicaci\u00f3n de la ley y si esto es lo que la gente realmente quiere que ocurra\u201d. El domingo, mientras las fuerzas de seguridad federales se concentraban en Chicago, los equipos de respuesta r\u00e1pida del grupo \u201cestuvieron trabajando pr\u00e1cticamente todo el d\u00eda\u201d, me dijo Brandon Lee, director de Comunicaciones de la coalici\u00f3n.<\/p>\n<p>Los grupos de defensa de los inmigrantes tambi\u00e9n est\u00e1n presionando a los funcionarios locales de las ciudades y estados azules para que no presten a la administraci\u00f3n m\u00e1s cooperaci\u00f3n que la absolutamente requerida por la ley federal, incluso mientras Homan y el Departamento de Justicia <a href=\"https:\/\/www.governing.com\/politics\/trump-admin-will-target-sanctuary-cities-his-border-czar-says\">amenazan en voz alta con procesar a quienes se resistan a sus esfuerzos<\/a>. \u201cEstamos dispuestos a responder al momento de nuestros miembros y nuestras comunidades, pero la responsabilidad tambi\u00e9n recae en los funcionarios estatales y locales\u201d, dijo Greisa Mart\u00ednez Rosas, directora ejecutiva de United We Dream Action, en una llamada con periodistas la semana pasada. \u201cTienen responsabilidades que proteger. Tienen responsabilidades de proteger nuestras escuelas, nuestras iglesias, nuestros hospitales\u201d.<\/p>\n<p>David Leopold, expresidente de la Asociaci\u00f3n Estadounidense de Abogados de Inmigraci\u00f3n, me dijo que las amenazas de Homan de procesar a funcionarios locales bajo una ley federal que proh\u00edbe \u201calbergar\u201d a un inmigrante indocumentado no est\u00e1n respaldadas por la ley. \u201cNo hay nada en la ley que respalde lo que dice Homan\u201d, insiste Leopold. Pero, a\u00f1ade, tambi\u00e9n hay l\u00edmites severos sobre cu\u00e1nto pueden impedir en la pr\u00e1ctica los funcionarios locales las operaciones del ICE.<\/p>\n<p>Los gobiernos locales pueden optar por no cooperar con el ICE de diversas maneras, sobre todo neg\u00e1ndose a proporcionarles informaci\u00f3n o asistencia de su propio personal, pero incluso en los estados y ciudades que se consideran santuarios, los funcionarios no tienen autoridad para bloquear las operaciones federales de inmigraci\u00f3n legalmente autorizadas, se\u00f1ala. \u201cIncluso en las ciudades santuario, entre comillas, la ley de inmigraci\u00f3n puede aplicarse y se aplica\u201d, me dijo Leopold. \u201cNo hay ning\u00fan lugar en Estados Unidos donde un no ciudadano buscado por el ICE pueda ser inmune a la aplicaci\u00f3n de la ley por parte del ICE\u201d.<\/p>\n<p>Ese es el l\u00edmite desalentador en todos los esfuerzos de los defensores de los inmigrantes indocumentados, y sus aliados de la ciudad azul y el estado, para prepararse para lo que Trump est\u00e1 planeando. \u201cPor lo que podemos controlar, vamos por buen camino\u201d, me dijo Benito. \u201cHemos estado haciendo todo lo correcto en t\u00e9rminos de capacitaci\u00f3n de personas para que conozcan sus derechos, creando equipos de respuesta r\u00e1pida, en continu protecci\u00f3n de las ordenanzas locales de bienvenida. Lo que no sabemos con esta pr\u00f3xima administraci\u00f3n, que ahora tiene m\u00e1s experiencia, es el nivel al que llegar\u00e1n\u201d.<\/p>\n<p>Las acciones iniciales de Trump \u2013incluyendo un intento de poner fin a la ciudadan\u00eda por derecho de nacimiento a trav\u00e9s de un decreto (que ya ha sido <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/23\/eeuu\/juez-bloquea-decreto-trump-ciudadania-nacimiento-trax\">prohibido por un tribunal federal<\/a>), <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/21\/eeuu\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\">el despliegue de m\u00e1s tropas militares en servicio activo en la frontera sur<\/a>, l<a href=\"https:\/\/www.cbsnews.com\/news\/trump-immigration-ice-arrests-sensitive-locations\/\">a revocaci\u00f3n de la orientaci\u00f3n que proh\u00edbe la aplicaci\u00f3n de la ley de inmigraci\u00f3n en lugares sensibles como escuelas y hospitales<\/a>, y <a href=\"https:\/\/apnews.com\/article\/justice-department-immigration-enforcement-f0e3fc616da9746796378d1cd6385b1b\">la directiva a los fiscales estadounidenses de investigar a los funcionarios locales que obstruyan sus planes<\/a>\u2013 sugieren que planea llevar su agenda de inmigraci\u00f3n de l\u00ednea dura a un nivel muy alto de confrontaci\u00f3n.<\/p>\n<p>\u201cEste pa\u00eds fue forjado por personas que han estado dispuestas a resistir\u201d, dijo Salas a su audiencia en Los \u00c1ngeles la semana pasada. En los pr\u00f3ximos meses, quienes est\u00e9n decididos a resistir la mano dura de Trump contra la inmigraci\u00f3n pueden sentirse, como el ic\u00f3nico manifestante chino en la plaza de Tiananmen hace una generaci\u00f3n, como si se estuvieran enfrentando a una l\u00ednea de tanques rodando sin remordimientos en su direcci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mucho m\u00e1s all\u00e1 del clamor en Washington de acciones ejecutivas y demandas, y de los comunicados de prensa en duelo entre aliados y adversarios de Donald Trump, la llegada del r\u00e9gimen de inmigraci\u00f3n del nuevo presidente ya est\u00e1 cambiando la vida sobre el terreno para millones de personas: inmigrantes indocumentados, sus hijos, su familia, amigos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457944","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mucho m\u00e1s all\u00e1 del clamor en Washington de acciones ejecutivas y demandas, y de los comunicados de prensa en duelo entre aliados y adversarios de Donald Trump, la llegada del r\u00e9gimen de inmigraci\u00f3n del nuevo presidente ya est\u00e1 cambiando la vida sobre el terreno para millones de personas: inmigrantes indocumentados, sus hijos, su familia, amigos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T11:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan\",\"datePublished\":\"2025-01-28T11:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\"},\"wordCount\":2620,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\",\"name\":\"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-28T11:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias","og_description":"Mucho m\u00e1s all\u00e1 del clamor en Washington de acciones ejecutivas y demandas, y de los comunicados de prensa en duelo entre aliados y adversarios de Donald Trump, la llegada del r\u00e9gimen de inmigraci\u00f3n del nuevo presidente ya est\u00e1 cambiando la vida sobre el terreno para millones de personas: inmigrantes indocumentados, sus hijos, su familia, amigos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-28T11:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan","datePublished":"2025-01-28T11:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/"},"wordCount":2620,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","name":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-28T11:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\u00e9n se movilizan","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/analisis-agenda-represiva-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-28T11:03:42Z","datePublished":"2025-01-28T11:03:42Z","dateModified":"2025-01-28T11:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Mientras Trump lanza su ofensiva represiva, los defensores de los inmigrantes tambi\\u00e9n se movilizan\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/28\\\/analisis-agenda-represiva-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/28\\\/analisis-agenda-represiva-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-28T11:03:42Z\",\"datePublished\":\"2025-01-28T11:03:42Z\",\"dateModified\":\"2025-01-28T11:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442492,"url":"https:\/\/noticiasya.com\/san-diego\/2023\/12\/22\/analisis-trump-y-biden-estan-empatados-entre-los-votantes-inmigrantes-por-que\/","url_meta":{"origin":1457944,"position":0},"title":"AN\u00c1LISIS | Trump y Biden est\u00e1n empatados entre los votantes inmigrantes. \u00bfPor qu\u00e9?","author":"","date":"diciembre 22, 2023","format":false,"excerpt":"(CNN) -- Las duras declaraciones de Donald Trump sobre los inmigrantes que entran ilegalmente en Estados Unidos han desencadenado una dura respuesta de los dem\u00f3cratas, y la campa\u00f1a de Joe Biden ha acusado al expresidente de imitar a Adolf Hitler.Incluso algunos republicanos se han distanciado de las declaraciones de Trump,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459260,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/26\/mas-20-000-inmigrantes-indocumentados-arrestados-primer-mes-de-trump-dhs-trax\/","url_meta":{"origin":1457944,"position":1},"title":"Arrestan a m\u00e1s de 20.000 inmigrantes indocumentados durante el primer mes de Trump en la presidencia, seg\u00fan el DHS","author":"","date":"febrero 26, 2025","format":false,"excerpt":"M\u00e1s de 20.000 inmigrantes indocumentados fueron arrestados durante el primer mes de Donald Trump como presidente, seg\u00fan el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s).El Gobierno de Trump lanz\u00f3 una ofensiva contra la inmigraci\u00f3n en los momentos posteriores a su toma de posesi\u00f3n y public\u00f3 los totales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467787,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/27\/gobierno-trump-medio-millon-deportaciones-inmigrantes-trax\/","url_meta":{"origin":1457944,"position":2},"title":"El Gobierno de Trump dice que ha deportado a m\u00e1s de 500.000 inmigrantes indocumentados desde enero","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El Departamento de Seguridad Nacional de EE.UU. (DHS, por sus siglas en ingl\u00e9s) inform\u00f3 el lunes que ha deportado a m\u00e1s de medio mill\u00f3n de inmigrantes indocumentados de Estados Unidos desde el inicio del segundo mandato del presidente Trump.Las cifras incluyen deportaciones realizadas por varias agencias, incluidas personas que fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461822,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/01\/inmigrantes-indocumentados-seguro-social-prestaciones-trax\/","url_meta":{"origin":1457944,"position":3},"title":"Los inmigrantes indocumentados aportan m\u00e1s al Seguro Social de lo que reciben en prestaciones","author":"","date":"mayo 1, 2025","format":false,"excerpt":"La iniciativa del presidente Donald Trump para deportar inmigrantes y bloquear la llegada de nuevos inmigrantes podr\u00eda socavar las finanzas del Seguro Social en un momento en que el programa ya se encuentra en una situaci\u00f3n financiera precaria, seg\u00fan los expertos.Adem\u00e1s de la presi\u00f3n del Servicio de Inmigraci\u00f3n y Control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463599,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/06\/16\/menos-10-inmigrantes-detenidos-condenas-penales-graves-trax\/","url_meta":{"origin":1457944,"position":4},"title":"Menos del 10 % de los inmigrantes detenidos por el ICE desde octubre ten\u00edan condenas penales severas, seg\u00fan datos internos","author":"","date":"junio 16, 2025","format":false,"excerpt":"A medida que el Gobierno de Trump ha intensificado las redadas en Los \u00c1ngeles y otras partes del pa\u00eds, altos funcionarios han destacado la captura de inmigrantes condenados por delitos como asesinato, agresi\u00f3n y violaci\u00f3n, calific\u00e1ndolos de criminales \u201cb\u00e1rbaros\u201d que \u201csembraron el terror\u201d en comunidades estadounidenses.Pero documentos internos del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465730,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/21\/inmigrantes-indocumentados-ee-uu-record-2023-trax\/","url_meta":{"origin":1457944,"position":5},"title":"La poblaci\u00f3n de inmigrantes indocumentados en EE.UU. alcanz\u00f3 un r\u00e9cord en 2023","author":"","date":"agosto 21, 2025","format":false,"excerpt":"La poblaci\u00f3n de inmigrantes indocumentados en Estados Unidos lleg\u00f3 a un r\u00e9cord de 14 millones en 2023, un aumento del 19 % con respecto al a\u00f1o anterior, seg\u00fan nuevas estimaciones del Centro de Investigaciones Pew.El aumento fue impulsado por inmigrantes a quienes se les otorg\u00f3 protecci\u00f3n contra la deportaci\u00f3n bajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457944"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457944\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}