{"id":1457964,"date":"2025-01-28T11:03:52","date_gmt":"2025-01-28T19:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/"},"modified":"2025-01-28T11:03:52","modified_gmt":"2025-01-28T19:03:52","slug":"boom-supersonic-primer-vuelo-supersonico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","title":{"rendered":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico"},"content":{"rendered":"<p>El regreso de los viajes supers\u00f3nicos ha sido notablemente lento para una nave m\u00e1s r\u00e1pida que la velocidad del sonido, pero el 28 de enero se logr\u00f3 un hito importante.<\/p>\n<p><a href=\"https:\/\/boomsupersonic.com\/\">Boom Supersonic<\/a>, la empresa estadounidense que est\u00e1 construyendo el que promete ser el avi\u00f3n de pasajeros m\u00e1s r\u00e1pido del mundo, rompi\u00f3 la barrera del sonido por primera vez con un vuelo de prueba en Mojave, California.<\/p>\n<p>El vuelo supers\u00f3nico del avi\u00f3n de demostraci\u00f3n XB-1 de la empresa es la primera vez que un avi\u00f3n desarrollado de forma independiente rompe la barrera del sonido.<\/p>\n<p>El XB-1, que ha completado 12 vuelos de prueba con \u00e9xito desde que despeg\u00f3 por primera vez en marzo de 2024, es el precursor del desarrollo del avi\u00f3n supers\u00f3nico comercial de Boom, Overture.<\/p>\n<p>Cuando el XB-1 despeg\u00f3 del puerto a\u00e9reo y espacial de Mojave en su vuelo m\u00e1s reciente, se encontraba en el mismo espacio a\u00e9reo hist\u00f3rico donde el legendario piloto Chuck Yeager rompi\u00f3 la barrera del sonido por primera vez en 1947.<\/p>\n<p>El avi\u00f3n, pilotado por el piloto de pruebas jefe de Boom, Tristan \u201cGeppetto\u201d Brandenburg, aceler\u00f3 a Mach 1,1 por primera vez (alrededor 1.358 kil\u00f3metros por hora), un 10 % m\u00e1s r\u00e1pido que la velocidad del sonido, aproximadamente 12 minutos despu\u00e9s del inicio del vuelo de prueba a unos 35.000 pies.<\/p>\n<p>La velocidad m\u00e1s r\u00e1pida que ha alcanzado el XB-1 antes de este vuelo era de Mach 0,95, justo por debajo del umbral supers\u00f3nico de Mach 1, que alcanz\u00f3 durante el vuelo de prueba el 10 de enero.<\/p>\n<p>Una <a href=\"https:\/\/boomsupersonic.com\/xb-1\">transmisi\u00f3n<\/a> en vivo document\u00f3 el momento hist\u00f3rico del primer avi\u00f3n supers\u00f3nico civil construido en Estados Unidos y el primer avi\u00f3n supers\u00f3nico desarrollado de forma independiente del mundo.<\/p>\n<p>En la sala de control, 25 ingenieros revisaron los datos en vivo durante la misi\u00f3n.<\/p>\n<p>El esperado avi\u00f3n ya cuenta con 130 pedidos y reservas de American Airlines, United Airlines y Japan Airlines.<\/p>\n<p>Han pasado casi 55 a\u00f1os desde que el prototipo 002 del Concorde vol\u00f3 por primera vez a Mach 1 el 25 de marzo de 1970, y m\u00e1s de 21 a\u00f1os desde que el transporte supers\u00f3nico comercial termin\u00f3 con el \u00faltimo vuelo del avi\u00f3n anglofranc\u00e9s en noviembre de 2003.<\/p>\n<p>Ha habido varios aspirantes en el espacio supers\u00f3nico mientras los Concorde restantes acumulan polvo en museos del Reino Unido, Estados Unidos y Francia, pero hasta ahora nadie ha tenido \u00e9xito.<\/p>\n<p>Las ambiciones de Boom Supersonic siguen siendo altas. El director ejecutivo Blake Scholl dijo a CNN el a\u00f1o pasado que espera que los aviones supers\u00f3nicos reemplacen a los aviones de pasajeros convencionales durante nuestra vida.<\/p>\n<p>\u201cCreo firmemente en el regreso de los viajes a\u00e9reos supers\u00f3nicos y, en \u00faltima instancia, en llevarlos a todos los pasajeros en todas las rutas. Y eso no es algo que se haga de la noche a la ma\u00f1ana\u201d, dijo en marzo de 2024.<\/p>\n<p>El plan de Boom es que el Overture est\u00e9 en funcionamiento antes de que termine la d\u00e9cada, transportando de 64 a 80 pasajeros a Mach 1,7, aproximadamente el doble de la velocidad de los aviones subs\u00f3nicos actuales.<\/p>\n<p>Cuando CNN Travel habl\u00f3 con Scholl en mayo de 2021, nos dijo que su sue\u00f1o era que la gente pudiera alg\u00fan d\u00eda \u201cvolar a cualquier parte del mundo en cuatro horas por US$ 100\u201d. En 2024, confirm\u00f3 que esa segu\u00eda siendo su guia.<\/p>\n<p>El plan de la empresa es que Overture opere alg\u00fan d\u00eda en m\u00e1s de 600 rutas en todo el mundo.<\/p>\n<p>\u201cUn avi\u00f3n m\u00e1s r\u00e1pido es mucho m\u00e1s eficiente en t\u00e9rminos humanos y mucho m\u00e1s eficiente en t\u00e9rminos de capital. Se pueden hacer m\u00e1s vuelos con el mismo avi\u00f3n y la misma tripulaci\u00f3n\u201d, dijo Scholl.<\/p>\n<p>\u201cPodemos reducir significativamente todos los costes y el impacto de los aviones haci\u00e9ndolos m\u00e1s r\u00e1pidos. Si tenemos aviones m\u00e1s r\u00e1pidos, no necesitamos tantos\u201d.<\/p>\n<p>La aeronave de prueba XB-1 se ha utilizado para probar las nuevas tecnolog\u00edas desarrolladas por Boom Supersonic.<\/p>\n<p>Al igual que el Concorde, el XB-1 y el Overture tienen un morro largo y un \u00e1ngulo de ataque alto para el despegue y el aterrizaje, lo que interrumpe la visi\u00f3n de la pista por parte de los pilotos.<\/p>\n<p>Mientras que el Concorde solucion\u00f3 este problema con un morro m\u00f3vil, el sistema de visi\u00f3n de realidad aumentada del Boom permite una excelente visibilidad de la pista para los pilotos sin ese peso y complejidad adicionales.<\/p>\n<p>\u201cLa llegada de la ingenier\u00eda digital es un gran facilitador de la vuelta del vuelo supers\u00f3nico\u201d, dijo Scholl a CNN en 2024. \u201cAerodin\u00e1mica, materiales, propulsi\u00f3n: esas son las tres grandes \u00e1reas en las que hemos hecho grandes progresos en comparaci\u00f3n con el Concorde\u201d.<\/p>\n<p>En la d\u00e9cada de 1960, el Concorde se desarroll\u00f3 en t\u00faneles de viento, lo que implicaba construir costosos modelos f\u00edsicos, realizar pruebas y luego repetirlas.<\/p>\n<p>\u201cNo se pueden probar muchos dise\u00f1os, cuando cada iteraci\u00f3n cuesta millones y lleva meses\u201d, explica Scholl. Pero Boom ha perfeccionado el dise\u00f1o eficiente y aerodin\u00e1mico de su avi\u00f3n utilizando la din\u00e1mica de fluidos computacional, que \u201ces b\u00e1sicamente un t\u00fanel de viento digital. Podemos realizar el equivalente a cientos de pruebas en t\u00fanel de viento durante la noche en simulaci\u00f3n por una fracci\u00f3n del coste de una prueba real en t\u00fanel de viento\u201d.<\/p>\n<p>El XB-1 est\u00e1 fabricado casi en su totalidad con compuestos de fibra de carbono, seleccionados por su resistencia y ligereza.<\/p>\n<p>El Overture est\u00e1 dise\u00f1ado para ser propulsado por motores a reacci\u00f3n convencionales y funcionar con hasta un 100 % de combustible de aviaci\u00f3n sostenible (SAF).<\/p>\n<p>CNN Travel ya ha mencionado la hasta ahora <a href=\"https:\/\/cnn.com\/travel\/article\/saf-jet-fuel-green\/index.html\">lenta adopci\u00f3n del SAF<\/a>, y Scholl dijo a CNN el a\u00f1o pasado que era muy consciente de sus problemas actuales.<\/p>\n<p>\u201cNo hay suficiente y cuesta demasiado, pero est\u00e1 aumentando\u201d, dijo, pero calcul\u00f3 que alg\u00fan d\u00eda se utilizar\u00e1 para todos los viajes a\u00e9reos de larga distancia. Es el \u201cfuturo de la aviaci\u00f3n\u201d, declar\u00f3.<\/p>\n<p>La construcci\u00f3n de la superf\u00e1brica Overture de Boom en Greensboro, Carolina del Norte, se complet\u00f3 el a\u00f1o pasado. Ha sido dise\u00f1ada para producir 66 aviones Overture al a\u00f1o.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El regreso de los viajes supers\u00f3nicos ha sido notablemente lento para una nave m\u00e1s r\u00e1pida que la velocidad del sonido, pero el 28 de enero se logr\u00f3 un hito importante. Boom Supersonic, la empresa estadounidense que est\u00e1 construyendo el que promete ser el avi\u00f3n de pasajeros m\u00e1s r\u00e1pido del mundo, rompi\u00f3 la barrera del sonido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457964","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias\" \/>\n<meta property=\"og:description\" content=\"El regreso de los viajes supers\u00f3nicos ha sido notablemente lento para una nave m\u00e1s r\u00e1pida que la velocidad del sonido, pero el 28 de enero se logr\u00f3 un hito importante. Boom Supersonic, la empresa estadounidense que est\u00e1 construyendo el que promete ser el avi\u00f3n de pasajeros m\u00e1s r\u00e1pido del mundo, rompi\u00f3 la barrera del sonido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T19:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico\",\"datePublished\":\"2025-01-28T19:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\"},\"wordCount\":1092,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\",\"name\":\"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-28T19:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias","og_description":"El regreso de los viajes supers\u00f3nicos ha sido notablemente lento para una nave m\u00e1s r\u00e1pida que la velocidad del sonido, pero el 28 de enero se logr\u00f3 un hito importante. Boom Supersonic, la empresa estadounidense que est\u00e1 construyendo el que promete ser el avi\u00f3n de pasajeros m\u00e1s r\u00e1pido del mundo, rompi\u00f3 la barrera del sonido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-28T19:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/"},"author":{"name":"","@id":""},"headline":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico","datePublished":"2025-01-28T19:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/"},"wordCount":1092,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","name":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-28T19:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Boom Supersonic, la respuesta estadounidense al Concorde, complet\u00f3 su primer vuelo supers\u00f3nico","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/boom-supersonic-primer-vuelo-supersonico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-28T19:03:52Z","datePublished":"2025-01-28T19:03:52Z","dateModified":"2025-01-28T19:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Boom Supersonic, la respuesta estadounidense al Concorde, complet\\u00f3 su primer vuelo supers\\u00f3nico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/28\\\/boom-supersonic-primer-vuelo-supersonico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/28\\\/boom-supersonic-primer-vuelo-supersonico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-28T19:03:52Z\",\"datePublished\":\"2025-01-28T19:03:52Z\",\"dateModified\":\"2025-01-28T19:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459462,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/03\/03\/fotografia-nasa-ruptura-barrera-sonido-trax\/","url_meta":{"origin":1457964,"position":0},"title":"Incre\u00edble fotograf\u00eda de la NASA capta la ruptura de la barrera del sonido","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Aqu\u00ed hay una fotograf\u00eda para la repisa de la chimenea.Una imagen reci\u00e9n publicada muestra la barrera del sonido rompi\u00e9ndose el 10 de febrero cuando el primer avi\u00f3n supers\u00f3nico civil de Estados Unidos complet\u00f3 su segundo vuelo a velocidades superiores a Mach 1.Los equipos de la NASA en Tierra utilizaron la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447560,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/03\/30\/aviones-supersonicos-sustituiran-convencionales-ceo-aviacion-trax\/","url_meta":{"origin":1457964,"position":1},"title":"Los aviones supers\u00f3nicos sustituir\u00e1n a los aviones convencionales en nuestra era, afirma un CEO de aviaci\u00f3n","author":"","date":"marzo 30, 2024","format":false,"excerpt":"(CNN) \u2014 A principios de marzo despeg\u00f3 un avi\u00f3n de demostraci\u00f3n de lo que podr\u00eda ser el nuevo avi\u00f3n supers\u00f3nico civil, el primero lanzado desde la d\u00e9cada de 1960. Es un momento hist\u00f3rico en la tan esperada nueva era de los viajes supers\u00f3nicos.El XB-1, un avi\u00f3n de demostraci\u00f3n de tecnolog\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447079,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/03\/18\/avion-supersonico-xb70-supero-concorde-trax\/","url_meta":{"origin":1457964,"position":2},"title":"Este es el avi\u00f3n de transporte supers\u00f3nico que super\u00f3 en velocidad incluso al Concorde","author":"","date":"marzo 18, 2024","format":false,"excerpt":"(CNN) -- Cinco a\u00f1os antes del primer vuelo del Concorde, otro majestuoso avi\u00f3n supers\u00f3nico surc\u00f3 los cielos y estuvo a punto de convertirse en la inspiraci\u00f3n de un avi\u00f3n de pasajeros a\u00fan m\u00e1s r\u00e1pido.Se trataba del XB-70 Valkyrie, un avi\u00f3n experimental desarrollado para las Fuerzas A\u00e9reas de Estados Unidos. Su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463236,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/06\/05\/avion-supersonico-viajes-cielos-estadounidenses-trax\/","url_meta":{"origin":1457964,"position":3},"title":"Los cielos estadounidenses pronto podr\u00edan abrirse a los viajes supers\u00f3nicos, pero a\u00fan existe un gran problema","author":"","date":"junio 5, 2025","format":false,"excerpt":"Los cielos de Estados Unidos podr\u00edan estar completamente abiertos para viajes a\u00e9reos mucho m\u00e1s r\u00e1pidos en un futuro pr\u00f3ximo. No solo porque se est\u00e1n desarrollando aviones de pasajeros capaces de romper la barrera del sonido, sino que, por primera vez, podr\u00edan viajar sobre suelo estadounidense.Incluso durante la \u00e9poca del Concorde,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458285,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/05\/aviones-supersonicos-regreso-significa-pasajeros-aereos-trax\/","url_meta":{"origin":1457964,"position":4},"title":"Vuelven los aviones supers\u00f3nicos. Esto es lo que eso significa para los pasajeros","author":"","date":"febrero 5, 2025","format":false,"excerpt":"La semana pasada, la compa\u00f1\u00eda estadounidense Boom Supersonic vol\u00f3 m\u00e1s r\u00e1pido que la velocidad del sonido con su avi\u00f3n de demostraci\u00f3n supers\u00f3nico XB-1. Se trata del primer avi\u00f3n no militar pilotado que rompe la barrera del sonido desde que el Concorde fuera retirado del servicio en 2003.Es el primer paso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457990,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/5-cosas-29-enero-deportados-colombia-deepseek-soldados-norcoreanos-boom-supersonic-orix\/","url_meta":{"origin":1457964,"position":5},"title":"Las 5 cosas que debes saber este 29 de enero: deportados a Colombia, DeepSeek, soldados norcoreanos y Boom Supersonic","author":"","date":"enero 29, 2025","format":false,"excerpt":"Tras la llegada de dos vuelos con colombianos deportados, se espera que EE.UU. reactive esta semana la emisi\u00f3n de visas en su embajada en Bogot\u00e1. DeepSeek hace estallar la narrativa del dinero de la IA. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457964"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457964\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}