{"id":1457992,"date":"2025-01-29T04:04:00","date_gmt":"2025-01-29T12:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/"},"modified":"2025-01-29T04:04:00","modified_gmt":"2025-01-29T12:04:00","slug":"deepseek-punto-inflexion-silicon-valley-ia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","title":{"rendered":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA"},"content":{"rendered":"<p>Silicon Valley se est\u00e1 dando cuenta esta semana de que crear un modelo de inteligencia artificial avanzado puede que ya no sea una tarea tan especializada como se cre\u00eda antes.<\/p>\n<p>La llamada de atenci\u00f3n lleg\u00f3 en forma de DeepSeek, una <a href=\"https:\/\/www.cnn.com\/2025\/01\/27\/tech\/deepseek-ai-explainer\/index.html\">start-up china de un a\u00f1o de antig\u00fcedad<\/a> cuyo modelo de inteligencia artificial gratuito y de c\u00f3digo abierto, R1, est\u00e1 m\u00e1s o menos a la par con los modelos avanzados de los gigantes tecnol\u00f3gicos estadounidenses, y fue construido por una fracci\u00f3n del costo, aparentemente con chips menos avanzados y requiere mucha menos energ\u00eda del centro de datos para funcionar.<em><\/em><\/p>\n<p>Hasta ahora, la opini\u00f3n generalizada en el mundo tecnol\u00f3gico estadounidense era que los gigantes tecnol\u00f3gicos estadounidenses pod\u00edan mantenerse a la vanguardia si gastaban miles de millones de d\u00f3lares, acumulaban chips avanzados y constru\u00edan enormes centros de datos (a pesar del <a href=\"https:\/\/www.cnn.com\/2024\/10\/01\/business\/ai-nuclear-energy-nightcap\/index.html\">costo ambiental<\/a>). B\u00e1sicamente, como se encuentran entre las empresas m\u00e1s ricas del mundo, cre\u00edan que pod\u00edan destinar m\u00e1s recursos que cualquier otra persona al problema y salir airosos.<\/p>\n<p>Ahora, todo eso fue <a href=\"https:\/\/www.cnn.com\/2025\/01\/28\/business\/deepseek-ai-nvidia-nightcap\/index.html\">puesto en tela de juicio<\/a> y los gigantes tecnol\u00f3gicos se enfrentan <a href=\"https:\/\/www.cnn.com\/2025\/01\/27\/tech\/deepseek-stocks-ai-china\/index.html\">a preguntas dif\u00edciles<\/a> por parte de Wall Street.<\/p>\n<p>Es posible que el nombre del juego de la IA ya no gane con los modelos m\u00e1s caros y cada vez m\u00e1s potentes.<\/p>\n<p>\u201cEl paradigma est\u00e1 cambiando\u201d, afirm\u00f3 Zack Kass, consultor de inteligencia artificial y ex responsable de comercializaci\u00f3n de OpenAI.<\/p>\n<p>\u201cResulta muy dif\u00edcil apropiarse de un avance cient\u00edfico\u201d, como un avance en el modelo de IA, afirm\u00f3 Kass, y evitar que los competidores se pongan al d\u00eda. En cambio, las empresas tecnol\u00f3gicas pueden encontrarse ahora compitiendo para reducir los costos y crear aplicaciones m\u00e1s \u00fatiles para los consumidores y los clientes corporativos, y tambi\u00e9n para consumir menos energ\u00eda y recursos naturales en el proceso.<em><\/em><\/p>\n<p>Al menos un l\u00edder tecnol\u00f3gico estadounidense ya prometi\u00f3 responder a DeepSeek acelerando el lanzamiento de modelos m\u00e1s potentes.<\/p>\n<p>El CEO de OpenAI, Sam Altman, calific\u00f3 el modelo R1 de DeepSeek como \u201cimpresionante\u201d en una <a href=\"https:\/\/x.com\/sama\/status\/1884066337103962416\">publicaci\u00f3n en X<\/a> este lunes y agreg\u00f3 que \u201clanzaremos algunos nuevos modelos\u201d como respuesta. El director de productos de OpenAI, Kevin Weil, tambi\u00e9n dijo que el pr\u00f3ximo modelo o3 de la compa\u00f1\u00eda, que se lanzar\u00e1 en las pr\u00f3ximas semanas, \u201cser\u00eda otro gran paso adelante\u201d.<\/p>\n<p>\u201cEs una industria supercompetitiva, \u00bfno? Y esto demuestra que es competitiva a nivel mundial, no solo dentro de EE. UU.\u201d, dijo Weil en una llamada con periodistas sobre la nueva oferta ChatGPT de OpenAI para agencias gubernamentales, en respuesta a una pregunta de CNN. \u201cEstamos comprometidos a avanzar muy r\u00e1pido en este aspecto. Queremos mantenernos a la vanguardia\u201d.<\/p>\n<p>Pero los analistas tambi\u00e9n esperan que las grandes empresas tecnol\u00f3gicas reduzcan sus planes de gasto en centros de datos y posiblemente reconsideren cu\u00e1nto cobran a los consumidores. DeepSeek ha demostrado que es posible proporcionar la tecnolog\u00eda a un menor costo, aunque algunos expertos de la industria han sorprendido ante las afirmaciones de la startup sobre gastar poco menos de US$ 6.000 millones para construir su modelo.<\/p>\n<p>\u201cTodos esos otros laboratorios de modelos de vanguardia (OpenAI, Anthropic, Google) van a construir modelos mucho m\u00e1s eficientes basados \u200b\u200ben lo que est\u00e1n aprendiendo de DeepSeek\u201d, dijo Gil Luria, jefe de investigaci\u00f3n tecnol\u00f3gica de la firma de inversiones DA Davidson. \u201cY podr\u00e1n usarlos a una fracci\u00f3n del precio actual, porque ejecutar esos modelos costar\u00e1 una fracci\u00f3n del costo\u201d.<\/p>\n<p>Sin duda, era casi seguro que la industria acabar\u00eda cambiando su foco hacia la \u201ceficiencia\u201d: trabajar para a\u00f1adir capacidades de IA utilizando una cantidad determinada de potencia inform\u00e1tica en lugar de a\u00f1adir m\u00e1s servidores para potenciar la tecnolog\u00eda. Solo se puede construir una cierta cantidad de ordenadores y solo hay una cierta cantidad de electricidad disponible para darles servicio. Y una herramienta de IA solo puede llegar a ser tan competente, por ejemplo, en la redacci\u00f3n de correos electr\u00f3nicos o la planificaci\u00f3n de viajes, antes de que ya no valga la pena hacerla un poco m\u00e1s potente.<\/p>\n<p>Pero DeepSeek parece haber acelerado ese cronograma y, en Silicon Valley, deshacer el gasto en centros de datos podr\u00eda ser complicado.<\/p>\n<p>La semana pasada, OpenAI, Oracle y SoftBank <a href=\"https:\/\/www.cnn.com\/2025\/01\/21\/tech\/openai-oracle-softbank-trump-ai-investment\/index.html\">visitaron la Casa Blanca<\/a> para anunciar la creaci\u00f3n de una nueva empresa y una inversi\u00f3n de US$ 500 millones en infraestructura de inteligencia artificial en Estados Unidos; el CEO de Microsoft, Sundar Pichai, afirm\u00f3 que estaba \u201cbien\u201d por la inversi\u00f3n planificada de US$ 80.000 millones de d\u00f3lares de su empresa en desarrollo e infraestructura de inteligencia artificial este a\u00f1o; y el CEO de Meta, Mark Zuckerberg, dijo que el gasto en inteligencia artificial de su empresa podr\u00eda alcanzar los US$ 65.000 millones este a\u00f1o.<\/p>\n<p>\u201c\u00bfEse disparatado proyecto de construcci\u00f3n de centros de datos de inteligencia artificial del que hemos estado hablando durante los \u00faltimos a\u00f1os? Ya no necesitan hacerlo. Pueden construir mucho menos porque pueden proporcionar muchos m\u00e1s servicios a un precio mucho m\u00e1s bajo\u201d, dijo Luria. Agreg\u00f3 que los inversores probablemente esperen escuchar acerca de esos planes en las conferencias de resultados de las empresas tecnol\u00f3gicas estadounidenses durante las pr\u00f3ximas dos semanas.<\/p>\n<p>Por supuesto, si los gigantes tecnol\u00f3gicos reducen los costos de los centros de datos para <em>entrenar<\/em> modelos de IA (y, por lo tanto, cobran menos a los clientes), sus herramientas se usar\u00e1n m\u00e1s, lo que generar\u00e1 m\u00e1s presi\u00f3n <em>para la inferencia<\/em> (o para que la gente haga preguntas) en los centros de datos, escribieron el martes los analistas de Bloomberg Intelligence. Por lo tanto, a\u00fan est\u00e1 por verse cu\u00e1n dr\u00e1stica podr\u00eda ser esa reducci\u00f3n del gasto en centros de datos.<em><\/em><\/p>\n<p>Algunos l\u00edderes tecnol\u00f3gicos dicen que ven a DeepSeek como una validaci\u00f3n, m\u00e1s que como una amenaza.<\/p>\n<p>Los defensores de la IA de c\u00f3digo abierto (en la que la arquitectura subyacente del modelo se pone a disposici\u00f3n del p\u00fablico en lugar de cobrar por ella) dicen que el modelo chino es una prueba de que las empresas estadounidenses deber\u00edan compartir sus innovaciones en lugar de restringirlas. <strong><\/strong>De esa manera, todo el campo estadounidense podr\u00eda avanzar m\u00e1s r\u00e1pidamente y seguir siendo el est\u00e1ndar tecnol\u00f3gico en todo el mundo.<\/p>\n<p>\u201cEstados Unidos ya cuenta con los mejores modelos cerrados del mundo. Para seguir siendo competitivos, tambi\u00e9n debemos apoyar el desarrollo de un ecosistema din\u00e1mico de c\u00f3digo abierto\u201d, escribi\u00f3 el exCEO de Google, Eric Schmidt, en un art\u00edculo <a href=\"https:\/\/www.washingtonpost.com\/opinions\/2025\/01\/28\/china-deekseek-ai-us-supremacy\/\">de opini\u00f3n publicado<\/a> el martes en el Washington Post.<\/p>\n<p>Meta, que ha impulsado la IA de c\u00f3digo abierto con su modelo Llama, tambi\u00e9n dijo que dichos modelos est\u00e1n \u201cfomentando un cambio significativo en la industria, y eso traer\u00e1 los beneficios de la IA a todos m\u00e1s r\u00e1pidamente\u201d.<\/p>\n<p>E incluso si DeepSeek obliga a repensar a corto plazo el modelo de negocios que Silicon Valley hab\u00eda imaginado para la IA, las personas que creen que la tecnolog\u00eda cambiar\u00e1 el mundo deber\u00edan estar contentas por el avance, dijo Kass.<\/p>\n<p>\u201cSupongo que estamos bastante asustados porque pens\u00e1bamos que ten\u00edamos la supremac\u00eda global de la IA, cuando en realidad deber\u00edamos estar celebrando\u201d, dijo Kass. \u201cPorque esta es una prueba m\u00e1s de que la revoluci\u00f3n de la IA va a democratizar la tecnolog\u00eda y se distribuir\u00e1 de manera justa\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Silicon Valley se est\u00e1 dando cuenta esta semana de que crear un modelo de inteligencia artificial avanzado puede que ya no sea una tarea tan especializada como se cre\u00eda antes. La llamada de atenci\u00f3n lleg\u00f3 en forma de DeepSeek, una start-up china de un a\u00f1o de antig\u00fcedad cuyo modelo de inteligencia artificial gratuito y de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457992","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias\" \/>\n<meta property=\"og:description\" content=\"Silicon Valley se est\u00e1 dando cuenta esta semana de que crear un modelo de inteligencia artificial avanzado puede que ya no sea una tarea tan especializada como se cre\u00eda antes. La llamada de atenci\u00f3n lleg\u00f3 en forma de DeepSeek, una start-up china de un a\u00f1o de antig\u00fcedad cuyo modelo de inteligencia artificial gratuito y de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T12:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA\",\"datePublished\":\"2025-01-29T12:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\"},\"wordCount\":1319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\",\"name\":\"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-29T12:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias","og_description":"Silicon Valley se est\u00e1 dando cuenta esta semana de que crear un modelo de inteligencia artificial avanzado puede que ya no sea una tarea tan especializada como se cre\u00eda antes. La llamada de atenci\u00f3n lleg\u00f3 en forma de DeepSeek, una start-up china de un a\u00f1o de antig\u00fcedad cuyo modelo de inteligencia artificial gratuito y de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-29T12:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA","datePublished":"2025-01-29T12:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/"},"wordCount":1319,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","name":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-29T12:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 DeepSeek podr\u00eda marcar un punto de inflexi\u00f3n para Silicon Valley en materia de IA","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/deepseek-punto-inflexion-silicon-valley-ia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-29T12:04:00Z","datePublished":"2025-01-29T12:04:00Z","dateModified":"2025-01-29T12:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 DeepSeek podr\\u00eda marcar un punto de inflexi\\u00f3n para Silicon Valley en materia de IA\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/deepseek-punto-inflexion-silicon-valley-ia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/deepseek-punto-inflexion-silicon-valley-ia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-29T12:04:00Z\",\"datePublished\":\"2025-01-29T12:04:00Z\",\"dateModified\":\"2025-01-29T12:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458889,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/18\/musk-grok-3-modelo-inteligencia-artificial-trax\/","url_meta":{"origin":1457992,"position":0},"title":"Elon Musk presenta Grok 3, un modelo de IA que, seg\u00fan \u00e9l, supera a ChatGPT y DeepSeek","author":"","date":"febrero 18, 2025","format":false,"excerpt":"xAI present\u00f3 el lunes su modelo de inteligencia artificial (IA) actualizado Grok 3, mientras la startup liderada por Elon Musk busca mantenerse al nivel de las capacidades avanzadas de razonamiento y b\u00fasqueda de los modelos de la competencia.En un evento transmitido en vivo en X de Musk, los l\u00edderes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457917,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/china-inteligencia-artificial-deepseek-acciones-trax\/","url_meta":{"origin":1457992,"position":1},"title":"Los avances de una inteligencia artificial china hace caer las acciones estadounidenses","author":"","date":"enero 27, 2025","format":false,"excerpt":"Las acciones estadounidenses se encaminaban a una fuerte liquidaci\u00f3n este lunes por la ma\u00f1ana despu\u00e9s de que un avance sorpresivo de una empresa china de inteligencia artificial, DeepSeek, amenazara el aura de invencibilidad que rodea a la industria tecnol\u00f3gica de Estados Unidos.DeepSeek, una startup que existe hace un a\u00f1o, revel\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458549,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/10\/china-deepseek-ai-disrupcion-trax\/","url_meta":{"origin":1457992,"position":2},"title":"DeepSeek no solo trastorn\u00f3 OpenAI. Los gigantes tecnol\u00f3gicos chinos tambi\u00e9n se vieron afectados","author":"","date":"febrero 10, 2025","format":false,"excerpt":"Los avances de DeepSeek conmocionaron los mercados burs\u00e1tiles mundiales y a los actores de la IA. Ahora, su influencia se est\u00e1 extendiendo r\u00e1pidamente en China, donde algunas de las mayores empresas tecnol\u00f3gicas, muchas de las cuales hab\u00edan estado desarrollando sus propios chatbots, se apresuran a incorporar el modelo de c\u00f3digo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457929,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/27\/que-es-deepseek-china-inteligencia-artificial-trax\/","url_meta":{"origin":1457992,"position":3},"title":"\u00bfQu\u00e9 es DeepSeek, la iniciativa china de inteligencia artificial que conmocion\u00f3 al mundo tecnol\u00f3gico?","author":"","date":"enero 27, 2025","format":false,"excerpt":"Un modelo chino de inteligencia artificial sorprendentemente eficiente y poderoso ha irrumpido en el sector tecnol\u00f3gico. Se llama DeepSeek R1 y est\u00e1 inquietando a Wall Street.El nuevo modelo de IA fue desarrollado por DeepSeek, una empresa emergente que naci\u00f3 hace apenas un a\u00f1o y que de alguna manera ha logrado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458364,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/06\/legisladores-estadounidenses-prohibir-deepseek-dispositivos-gubernamentales-trax\/","url_meta":{"origin":1457992,"position":4},"title":"Legisladores estadounidenses quieren prohibir DeepSeek en los dispositivos gubernamentales","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Un par de legisladores estadounidenses quieren prohibir a los funcionarios p\u00fablicos el uso del chatbot de inteligencia artificial de la startup china DeepSeek en dispositivos oficiales.Los representantes Darin LaHood, republicano de Illinois, y Josh Gottheimer, dem\u00f3crata de Nueva Jersey, propondr\u00e1n el viernes una ley que prohibir\u00eda el uso de DeepSeek\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458010,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/como-utilizar-deepseek-ia-origen-chino-guia-orix\/","url_meta":{"origin":1457992,"position":5},"title":"\u00bfC\u00f3mo utilizar DeepSeek, la IA de origen chino? Aqu\u00ed una gu\u00eda paso a paso","author":"","date":"enero 29, 2025","format":false,"excerpt":"La empresa china DeepSeek conmocion\u00f3 el mundo de la inteligencia artificial (IA) recientemente.DeepSeek surgi\u00f3 hace un a\u00f1o y el pasado 20 de enero lanz\u00f3 su modelo de IA m\u00e1s poderoso hasta la fecha, llamado R1.R1 casi puede igualar las capacidades de sus rivales estadounidenses lanzados con anterioridad, como GPT-4, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1457992"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1457992\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1457992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1457992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1457992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}