{"id":1458001,"date":"2025-01-29T09:03:38","date_gmt":"2025-01-29T17:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/"},"modified":"2025-01-29T09:03:38","modified_gmt":"2025-01-29T17:03:38","slug":"hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","title":{"rendered":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves"},"content":{"rendered":"<p>La oficina del primer ministro de Israel divulg\u00f3 los nombres de los rehenes israel\u00edes que ser\u00e1n liberados en Gaza el jueves, y tambi\u00e9n confirm\u00f3 que cinco ciudadanos tailandeses ser\u00e1n liberados.<\/p>\n<p>\u201cLa lista de nombres recibida hoy de Hamas por los mediadores Qatar y Egipto incluye a: Arbel Yehud (29 a\u00f1os), Agam Berger (19) y Gadi Moses (80)\u201d, dijo la oficina del primer ministro.<\/p>\n<p>Adem\u00e1s, cinco ciudadanos tailandeses ser\u00e1n liberados. Sus nombres no se hicieron p\u00fablicos.<\/p>\n<p>Un total de 33 rehenes israel\u00edes tomados cautivos por Hamas y otros grupos armados en los ataques del 7 de octubre iban a ser liberados en la primera fase del acuerdo de alto el fuego y liberaci\u00f3n de rehenes entre Israel y Ham\u00e1s. Ya se han llevado a cabo dos rondas de liberaciones.<\/p>\n<p>Ocho de los rehenes israel\u00edes restantes que iban a ser liberados est\u00e1n muertos, dijo el portavoz del Gobierno de Israel David Mencer el lunes.<\/p>\n<p>Israel tambi\u00e9n liberar\u00e1 a casi 2.000 prisioneros palestinos en la primera parte del acuerdo.<\/p>\n<p>El alto el fuego supuso un respiro para la poblaci\u00f3n de Gaza, despu\u00e9s de m\u00e1s de 15 meses de bombardeos israel\u00edes tras los ataques del 7 de octubre.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La oficina del primer ministro de Israel divulg\u00f3 los nombres de los rehenes israel\u00edes que ser\u00e1n liberados en Gaza el jueves, y tambi\u00e9n confirm\u00f3 que cinco ciudadanos tailandeses ser\u00e1n liberados. \u201cLa lista de nombres recibida hoy de Hamas por los mediadores Qatar y Egipto incluye a: Arbel Yehud (29 a\u00f1os), Agam Berger (19) y Gadi [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458001","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias\" \/>\n<meta property=\"og:description\" content=\"La oficina del primer ministro de Israel divulg\u00f3 los nombres de los rehenes israel\u00edes que ser\u00e1n liberados en Gaza el jueves, y tambi\u00e9n confirm\u00f3 que cinco ciudadanos tailandeses ser\u00e1n liberados. \u201cLa lista de nombres recibida hoy de Hamas por los mediadores Qatar y Egipto incluye a: Arbel Yehud (29 a\u00f1os), Agam Berger (19) y Gadi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T17:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves\",\"datePublished\":\"2025-01-29T17:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\",\"name\":\"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-29T17:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias","og_description":"La oficina del primer ministro de Israel divulg\u00f3 los nombres de los rehenes israel\u00edes que ser\u00e1n liberados en Gaza el jueves, y tambi\u00e9n confirm\u00f3 que cinco ciudadanos tailandeses ser\u00e1n liberados. \u201cLa lista de nombres recibida hoy de Hamas por los mediadores Qatar y Egipto incluye a: Arbel Yehud (29 a\u00f1os), Agam Berger (19) y Gadi [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-29T17:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/"},"author":{"name":"","@id":""},"headline":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves","datePublished":"2025-01-29T17:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","name":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-29T17:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel dice que tres rehenes israel\u00edes y cinco tailandeses ser\u00e1n liberados en Gaza el jueves","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-29T17:03:38Z","datePublished":"2025-01-29T17:03:38Z","dateModified":"2025-01-29T17:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel dice que tres rehenes israel\\u00edes y cinco tailandeses ser\\u00e1n liberados en Gaza el jueves\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/hamas-liberara-8-rehenes-gaza-israel-tailandeses-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-29T17:03:38Z\",\"datePublished\":\"2025-01-29T17:03:38Z\",\"dateModified\":\"2025-01-29T17:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458435,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/08\/hamas-liberara-tres-hombres-israelies-trax\/","url_meta":{"origin":1458001,"position":0},"title":"Hamas liberar\u00e1 a tres hombres israel\u00edes este s\u00e1bado en la \u00faltima ronda de intercambios bajo el acuerdo de cese del fuego","author":"","date":"febrero 8, 2025","format":false,"excerpt":"Hamas hizo p\u00fablicos los nombres de los tres israel\u00edes que prev\u00e9 liberar en Gaza este s\u00e1bado, en lo que ser\u00e1 la quinta ronda de intercambios en el marco del acuerdo de alto el fuego en curso.Se espera que Ohad Ben Ami, Eli Sharabi y Or Levy sean liberados en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458732,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/14\/rehenes-gaza-hamas-sabado-horn-trax\/","url_meta":{"origin":1458001,"position":1},"title":"Israel anuncia los nombres de los tres rehenes de Gaza que ser\u00e1n liberados el s\u00e1bado, incluido el argentino Iair Horn","author":"","date":"febrero 14, 2025","format":false,"excerpt":"Israel anunci\u00f3 los nombres de los tres rehenes que ser\u00e1n liberados el s\u00e1bado, en lo que ser\u00eda el sexto intercambio de rehenes y prisioneros palestinos en virtud del acuerdo de alto el fuego que entr\u00f3 en vigor el mes pasado.Israel dijo el viernes que los militantes palestinos liberar\u00e1n al estadounidense-israel\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458411,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/07\/hamas-liberara-tres-hombres-trax\/","url_meta":{"origin":1458001,"position":2},"title":"Hamas liberar\u00e1 a tres hombres israel\u00edes el s\u00e1bado en la \u00faltima ronda de intercambios bajo el acuerdo de alto el fuego","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Hamas hizo p\u00fablicos los nombres de los tres israel\u00edes que prev\u00e9 liberar en Gaza el s\u00e1bado, en lo que ser\u00e1 la quinta ronda de intercambios en el marco del alto el fuego en curso.Se espera que Ohad Ben Ami, Eli Sharabi y Or Levy sean liberados en el d\u00eda n\u00famero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457542,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/15\/israel-hamas-acuerdo-alto-el-fuego-rehenes-trax\/","url_meta":{"origin":1458001,"position":3},"title":"Israel y Hamas logran acuerdo de alto el fuego y liberaci\u00f3n de rehenes","author":"","date":"enero 15, 2025","format":false,"excerpt":"El Gobierno de Israel y el grupo Hamas llegaron a un acuerdo este mi\u00e9rcoles para detener los combates en Gaza y liberar gradualmente tanto a rehenes como a prisioneros palestinos, inform\u00f3 a CNN una fuente al tanto de las conversaciones.Seg\u00fan el acuerdo, que a\u00fan no se anuncia formalmente, Hamas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467245,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/09\/lo-que-sabemos-acuerdo-trump-guerra-gaza-trax\/","url_meta":{"origin":1458001,"position":4},"title":"Lo que sabemos y lo que no sobre el acuerdo de Trump para terminar la guerra en Gaza","author":"","date":"octubre 9, 2025","format":false,"excerpt":"Tras meses de retrasos y decepciones, el presidente de Estados Unidos, Donald Trump, anunci\u00f3 que Israel y Hamas han acordado la primera fase de su plan de alto el fuego en Gaza.Aunque la breve publicaci\u00f3n de Trump en Truth Social represent\u00f3 un importante avance diplom\u00e1tico, resta mucho a\u00fan por definir.Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459364,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/03\/01\/alto-el-fuego-gaza-israel-hamas-acuerdo-trax\/","url_meta":{"origin":1458001,"position":5},"title":"El alto el fuego en Gaza se acerca a su fin, pero Israel y Hamas no se ponen de acuerdo sobre c\u00f3mo seguir","author":"","date":"marzo 1, 2025","format":false,"excerpt":"La primera fase del alto el fuego en Gaza \u2014que inlicluy\u00f3 la liberaci\u00f3n de docenas de rehenes israel\u00edes y cientos de prisioneros palestinos\u2014 est\u00e1 llegando a su fin, pero Israel y Hamas est\u00e1n divididos sobre la pr\u00f3xima etapa.En esencia, los israel\u00edes quieren que contin\u00fae la primera fase: el intercambio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1458001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1458001"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1458001\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1458001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1458001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1458001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}