{"id":1458002,"date":"2025-01-29T09:03:38","date_gmt":"2025-01-29T17:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/"},"modified":"2025-01-29T09:03:38","modified_gmt":"2025-01-29T17:03:38","slug":"autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","title":{"rendered":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;"},"content":{"rendered":"<p>La Autoridad del canal de Panam\u00e1 reiter\u00f3 este martes que el organismo es paname\u00f1o en una carta dirigida a sus m\u00e1s de 8.500 trabajadores.<\/p>\n<p>\u201cEn momentos como este, debemos recordar qui\u00e9nes somos y lo que representamos: una instituci\u00f3n 100% paname\u00f1a que opera con excelencia gracias a su talento humano\u201d, indica la misiva firmada por Ricaurte V\u00e1squez Morales, administrador del canal. \u201cSigamos trabajando juntos con la misma dedicaci\u00f3n que nos caracteriza, demostrando al mundo nuestro compromiso con Panam\u00e1 y con el comercio global\u201d.<\/p>\n<p>El presidente Donald Trump sugiri\u00f3 que Estados Unidos retome el control del canal de Panam\u00e1, cuya gesti\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/08\/historia-canal-panama-trump-trax\">fue transferida al gobierno paname\u00f1o en 1999<\/a> despu\u00e9s de la firma de un acuerdo entre los dos pa\u00edses suscrito en 1977.<\/p>\n<p>Trump, incluso, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/07\/estados-unidos\/trump-fuerzas-armadas-canal-panama-groenlandia-trax\">no ha descartado el uso de Fuerzas Armadas<\/a> con tal de retomar el control de la v\u00eda mar\u00edtima, y ha sugerido que existe una \u201cinjerencia china\u201d sobre el Canal de Panam\u00e1, una afirmaci\u00f3n que ha sido rechazada tanto <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/26\/latinoamerica\/mulino-niega-injerencia-china-canal-panama-trump-orix\">por el presidente paname\u00f1o Jos\u00e9 Ra\u00fal Mulino<\/a>, como por <a href=\"https:\/\/www.fmprc.gov.cn\/eng\/xw\/fyrbt\/202501\/t20250122_11543056.html\">el ministerio de Exteriores chino<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Autoridad del canal de Panam\u00e1 reiter\u00f3 este martes que el organismo es paname\u00f1o en una carta dirigida a sus m\u00e1s de 8.500 trabajadores. \u201cEn momentos como este, debemos recordar qui\u00e9nes somos y lo que representamos: una instituci\u00f3n 100% paname\u00f1a que opera con excelencia gracias a su talento humano\u201d, indica la misiva firmada por Ricaurte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458002","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &quot;una instituci\u00f3n 100% paname\u00f1a&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &quot;una instituci\u00f3n 100% paname\u00f1a&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Autoridad del canal de Panam\u00e1 reiter\u00f3 este martes que el organismo es paname\u00f1o en una carta dirigida a sus m\u00e1s de 8.500 trabajadores. \u201cEn momentos como este, debemos recordar qui\u00e9nes somos y lo que representamos: una instituci\u00f3n 100% paname\u00f1a que opera con excelencia gracias a su talento humano\u201d, indica la misiva firmada por Ricaurte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T17:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;\",\"datePublished\":\"2025-01-29T17:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\",\"name\":\"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es \\\"una instituci\u00f3n 100% paname\u00f1a\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-29T17:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es \"una instituci\u00f3n 100% paname\u00f1a\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es \"una instituci\u00f3n 100% paname\u00f1a\" - Noticias","og_description":"La Autoridad del canal de Panam\u00e1 reiter\u00f3 este martes que el organismo es paname\u00f1o en una carta dirigida a sus m\u00e1s de 8.500 trabajadores. \u201cEn momentos como este, debemos recordar qui\u00e9nes somos y lo que representamos: una instituci\u00f3n 100% paname\u00f1a que opera con excelencia gracias a su talento humano\u201d, indica la misiva firmada por Ricaurte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","og_site_name":"Noticias","article_published_time":"2025-01-29T17:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/"},"author":{"name":"","@id":""},"headline":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;","datePublished":"2025-01-29T17:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","url":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","name":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es \"una instituci\u00f3n 100% paname\u00f1a\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-29T17:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Autoridades del canal de Panam\u00e1 reiteran en una misiva que es &#171;una instituci\u00f3n 100% paname\u00f1a&#187;","url":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/01\/29\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-29T17:03:38Z","datePublished":"2025-01-29T17:03:38Z","dateModified":"2025-01-29T17:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Autoridades del canal de Panam\\u00e1 reiteran en una misiva que es &#171;una instituci\\u00f3n 100% paname\\u00f1a&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/01\\\/29\\\/autoridades-canal-panama-reiteran-misiva-es-institucion-100-panamena-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-29T17:03:38Z\",\"datePublished\":\"2025-01-29T17:03:38Z\",\"dateModified\":\"2025-01-29T17:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472624,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/27\/puertos-canal-panama-eeuu-china-represalias-orix\/","url_meta":{"origin":1458002,"position":0},"title":"EE.UU. dice que China est\u00e1 deteniendo buques de Panam\u00e1 en &#171;represalia&#187; por p\u00e9rdida de puertos en el Canal","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Estados Unidos denunci\u00f3 el jueves que China est\u00e1 ejerciendo \u201crepresalias\u201d contra Panam\u00e1 que afectan al transporte mar\u00edtimo mundial, mientras crecen las tensiones en torno a dos puertos sobre el Canal de Panam\u00e1 que eran operados por una empresa de capitales chinos cuyo contrato fue anulado recientemente.La Comisi\u00f3n Mar\u00edtima Federal de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461043,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/04\/10\/rivalidad-ee-uu-china-canal-panama-tensiones-guerra-palabras-trax\/","url_meta":{"origin":1458002,"position":1},"title":"La rivalidad entre EE.UU. y China por el canal de Panam\u00e1 desata tensiones y deja a Panam\u00e1 atrapada en una guerra de palabras","author":"","date":"abril 10, 2025","format":false,"excerpt":"Panam\u00e1 se promociona como \u201cel puente del mundo, coraz\u00f3n del universo\u201d, pero \u00faltimamente el estrecho istmo centroamericano y el canal que lleva su nombre, que une el Atl\u00e1ntico con el Pac\u00edfico, se han convertido en el escenario de un amargo enfrentamiento entre las dos superpotencias econ\u00f3micas m\u00e1s importantes del mundo.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472810,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/02\/eeuu-china-canal-panama-respaldo-orix\/","url_meta":{"origin":1458002,"position":2},"title":"EE.UU. respalda &#171;firmemente&#187; la soberan\u00eda de Panam\u00e1 mientras critica a China por &#171;socavar&#187; el comercio global","author":"","date":"abril 2, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos insisti\u00f3 este jueves en criticar las acciones de China, a quien acusa de detener buques con bandera paname\u00f1a en el canal de Panam\u00e1 como parte de una serie de \u201crepresalias\u201d tras la suspensi\u00f3n de contratos en dos puertos del Canal que hasta enero operaban con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459013,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/21\/panama-canal-sequia-represa-trump-trax\/","url_meta":{"origin":1458002,"position":3},"title":"Trump quiere recuperar el canal de Panam\u00e1. Se enfrentar\u00eda a una v\u00eda navegable en crisis","author":"","date":"febrero 21, 2025","format":false,"excerpt":"El canal de Panam\u00e1 es una extraordinaria obra de ingenier\u00eda. Esta v\u00eda navegable, que atraviesa 80 kil\u00f3metros a trav\u00e9s del istmo de Panam\u00e1 para conectar los oc\u00e9anos Atl\u00e1ntico y Pac\u00edfico, es una arteria del comercio mundial y una fuente clave de orgullo paname\u00f1o. Pero tiene problemas.Las sequ\u00edas, cada vez m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472837,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/03\/china-responde-eeuu-canal-panama-intento-tomar-control-orix\/","url_meta":{"origin":1458002,"position":4},"title":"Fuerte respuesta de China a Rubio por Panam\u00e1: &#171;Las alegaciones revelan el intento de EE.UU. de tomar el control del canal&#187;","author":"","date":"abril 3, 2026","format":false,"excerpt":"Luego de que el Gobierno de Estados Unidos acusara a China de detener buques con bandera paname\u00f1a en sus puertos, el Gobierno chino respondi\u00f3 este viernes que los se\u00f1alamientos \u201ccarecen de fundamento\u201d y que \u201crevelan su intento\u201d de controlar el canal de Panam\u00e1, una v\u00eda mar\u00edtima clave para el comercio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456899,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","url_meta":{"origin":1458002,"position":5},"title":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el Canal de Panam\u00e1, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas.En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1458002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1458002"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1458002\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1458002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1458002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1458002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}