{"id":1467955,"date":"2025-11-02T06:03:39","date_gmt":"2025-11-02T14:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/"},"modified":"2025-11-02T06:03:39","modified_gmt":"2025-11-02T14:03:39","slug":"protestas-ice-chicago-arrestos-illinois-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","title":{"rendered":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s"},"content":{"rendered":"<p>A medida que en los \u00faltimos meses se han intensificado las manifestaciones frente a un centro de detenci\u00f3n de inmigraci\u00f3n cerca de Chicago, tambi\u00e9n ha aumentado el n\u00famero de manifestantes conducidos esposados y con fecha para comparecer ante la justicia.<\/p>\n<p>Desde septiembre, los manifestantes se han movilizado cada semana frente a la oficina del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Broadview para protestar contra la campa\u00f1a reforzada del Gobierno del presidente Donald Trump de aplicaci\u00f3n de las leyes de inmigraci\u00f3n en Chicago. Al comienzo, los agentes federales que custodiaban el edificio usaron gas lacrim\u00f3geno y dispararon proyectiles de pimienta en choques con los manifestantes y arrestaron a algunos de ellos, incluidos varios acusados de delitos graves por sospecha de agredir o bloquear a agentes.<\/p>\n<p>Pero a inicios de octubre, agentes estatales, del condado y locales asumieron un papel m\u00e1s destacado en el control de las protestas en el lugar. Estas agencias han realizado 68 arrestos vinculados a las protestas en Broadview desde el 3 de octubre, inform\u00f3 la Oficina del Sheriff del condado de Cook el 28 de octubre.<\/p>\n<p>Los arrestos en ocasiones ponen en evidencia la tensi\u00f3n entre el deseo de los manifestantes de ejercer su derecho constitucional a la libertad de expresi\u00f3n y la intenci\u00f3n de las autoridades \u2014que dicen que algunos protestantes se resistieron a sus intentos de mantener despejados los accesos al edificio\u2014 de permitir que los agentes de ICE y otras personas transiten de manera segura hacia y desde la instalaci\u00f3n.<\/p>\n<p>CNN habl\u00f3 con algunos manifestantes detenidos o, en un caso, con el representante de un protestante, para preguntarles por sus experiencias al ser arrestados por acusaciones que van desde faltas menores hasta delitos graves. Estas son sus historias.<\/p>\n<p>A\u2019Keisha Lee estaba de pie coreando consignas con un grupo de manifestantes cerca de la oficina de ICE en Broadview el 17 de octubre cuando vio salir de varias camionetas a un enjambre de agentes con cascos y porras, dijo.<\/p>\n<p>\u201cMe dio n\u00e1useas\u201d, record\u00f3 la residente de Chicago de 30 a\u00f1os. \u201cY recuerdo haber sentido mucho miedo\u201d.<\/p>\n<p>Los agentes caminaron hacia ella y hacia los dem\u00e1s manifestantes de una manera \u201cmilitarizada\u201d y comenzaron a empujarlos hacia atr\u00e1s, dijo. Un video del encuentro muestra a Lee al frente de la multitud cuando agentes con parches de la Polic\u00eda Estatal de Illinois en las mangas avanzan en un aparente intento por despejarlos de una zona pavimentada, y algunos manifestantes intentan mantenerse firmes.<\/p>\n<p>Se desat\u00f3 el caos. Hubo gritos, gente que cay\u00f3 al suelo y algunos que, al parecer, resultaron heridos en el forcejeo, cont\u00f3 Lee.<\/p>\n<p>La golpearon en la cara con una porra y no estaba segura de si el golpe fue intencional, relat\u00f3. M\u00e1s tarde descubrir\u00eda un moret\u00f3n en el rostro.<\/p>\n<p>Lee cay\u00f3 al suelo y los agentes la ayudaron a levantarse, seg\u00fan ella y el video, que fue distribuido por Reuters. Luego un agente la detuvo coloc\u00e1ndole bridas pl\u00e1sticas en las mu\u00f1ecas, dijo; ese momento no aparece en el video de Reuters. Lee no entend\u00eda por qu\u00e9 la estaban arrestando.<\/p>\n<p>\u201cLes ped\u00eda que me soltaran\u201d, dijo Lee, \u201cy les recalcaba que no hab\u00eda hecho nada que no tuviera permitido hacer\u201d.<\/p>\n<p>La llevaron a sentarse a una acera y, momentos despu\u00e9s, la subieron a un veh\u00edculo policial que la traslad\u00f3 al Departamento de Polic\u00eda de Broadview. La mente de Lee iba a mil mientras iba en el auto. Le preocupaba ir a la c\u00e1rcel y si las condiciones ser\u00edan limpias y seguras. Tambi\u00e9n le preocupaba que la trataran de forma distinta en el sistema judicial por ser una mujer negra.<\/p>\n<p>En la estaci\u00f3n de polic\u00eda, la ficharon, le tomaron huellas, la fotografiaron y la colocaron en una celda con otras manifestantes durante unas cinco horas antes de dejarla en libertad.<\/p>\n<p>La Polic\u00eda Estatal de Illinois la arrest\u00f3 por dos cargos de delito menor de clase A por resistirse a un agente \u2014delito castigado con hasta un a\u00f1o de c\u00e1rcel y una multa de hasta US$ 2.500\u2014, seg\u00fan los registros judiciales del condado de Cook. Tambi\u00e9n recibi\u00f3 una citaci\u00f3n por sospecha de desobedecer a un agente, una falta que conlleva una multa. Su comparecencia en el tribunal est\u00e1 programada para el 25 de noviembre.<\/p>\n<p>Los documentos judiciales no ofrecen detalles sobre qu\u00e9 motiv\u00f3 el arresto, pero Lee niega haberse resistido y dice que nunca le dejaron claro en qu\u00e9 desobedec\u00eda a la polic\u00eda.<\/p>\n<p>\u201cSeg\u00fan entiendo, yo ten\u00eda derecho a estar all\u00ed\u201d, dijo.<\/p>\n<p>La Polic\u00eda Estatal de Illinois no respondi\u00f3 directamente las preguntas de CNN sobre este incidente espec\u00edfico, incluida la afirmaci\u00f3n de Lee de que no hizo nada malo o por qu\u00e9 los agentes empujaron a ese grupo. Sin embargo, emiti\u00f3 un comunicado en t\u00e9rminos generales sobre el enfoque de los agentes estatales, del condado y locales que han estado a cargo del operativo desde principios de octubre, grupo al que llaman \u201cMando Unificado\u201d.<\/p>\n<p>Estos agentes en Broadview \u201cdan instrucciones y \u00f3rdenes a las multitudes que son altas, claras, coherentes y reiteradas, y brindan a las personas numerosas oportunidades para cumplir la ley\u201d, dijo la polic\u00eda estatal.<\/p>\n<p>\u201cEs importante se\u00f1alar que, desde la instauraci\u00f3n del Mando Unificado, no ha habido enfrentamientos violentos entre ICE y manifestantes en Broadview que implicaran el uso de agentes qu\u00edmicos, lo que supone un cambio significativo respecto de las operaciones anteriores a su presencia\u201d, dice el comunicado.<\/p>\n<p>Lee ha protestado varios viernes recientes en la instalaci\u00f3n de ICE en Broadview, en desacuerdo con la forma en que ICE detiene a presuntos inmigrantes indocumentados en el \u00e1rea de Chicago y con el uso de gas lacrim\u00f3geno por parte de agentes federales durante protestas en barrios.<\/p>\n<p>\u201cCreo que la manera en que este pa\u00eds ha tratado a los inmigrantes es una de nuestras transgresiones originales\u201d, dijo Lee. \u201cY esto es la primera prueba de lo que permitiremos como pueblo\u201d.<\/p>\n<p>Lee, que trabaja en una organizaci\u00f3n sin fines de lucro local, est\u00e1 preocupada por el destino de su caso; sin embargo, reafirma su decisi\u00f3n de protestar.<\/p>\n<p>\u201cSiempre existe el miedo de que te usen como ejemplo cuando estas cosas suceden\u201d, dijo Lee. \u201cPero creo que no viol\u00e9 la ley\u201d.<\/p>\n<p>Sean Mills dice que no est\u00e1 conforme con c\u00f3mo se ha tratado a los inmigrantes desde que el Gobierno de Trump empez\u00f3 a reprimir con mayor agresividad la inmigraci\u00f3n ilegal a principios de este a\u00f1o.<\/p>\n<p>Para expresar su frustraci\u00f3n, Mills, de 37 a\u00f1os y residente de Chicago, se ha convertido en un manifestante semanal en la instalaci\u00f3n de ICE en Broadview. Va todos los viernes y s\u00e1bados \u2014a veces con una bandera de Estados Unidos sobre los hombros\u2014 y se une a otros protestantes frente al lugar.<\/p>\n<p>Pero el 17 de octubre, Mills fue arrestado por primera vez en su vida, cont\u00f3, despu\u00e9s de intentar entrar al edificio. Cada vez le preocupaban m\u00e1s las denuncias de activistas locales sobre condiciones inhumanas en la instalaci\u00f3n. Por eso quiso ver el interior con sus propios ojos.<\/p>\n<p>\u201cTuve el impulso de caminar hasta all\u00ed y probar suerte\u201d, dijo Mills. \u201cMe acerqu\u00e9 para ver si pod\u00eda investigar como ciudadano y entrar a la instalaci\u00f3n para hacer preguntas y documentar\u201d.<\/p>\n<p>Los agentes rodearon a Mills cerca de la entrada y uno le dijo que no pod\u00eda ingresar, relat\u00f3. Ese mismo agente le orden\u00f3 \u201cretroceder de inmediato\u201d o ser\u00eda arrestado, seg\u00fan Mills.<\/p>\n<p>\u201cIntent\u00e9 explicarme un poco m\u00e1s\u201d, dijo Mills, y agreg\u00f3 que les dijo a los agentes que era un ciudadano preocupado que quer\u00eda entrar. \u201cY creo que unos cinco o diez segundos despu\u00e9s, \u00e9l (el agente) dijo: \u2018OK, est\u00e1s arrestado\u2019\u201d.<\/p>\n<p>Mills se sorprendi\u00f3 porque no cre\u00eda haber hecho nada malo. Tambi\u00e9n sinti\u00f3 que no le hab\u00edan dado suficiente tiempo para explicarse antes de inmovilizarle las manos con lo que cree que eran bridas pl\u00e1sticas.<\/p>\n<p>Record\u00f3 que arrestaron a otros tres manifestantes que tambi\u00e9n intentaron entrar al edificio.<\/p>\n<p>\u201cCreo que es un ejemplo de actuaci\u00f3n policial desmedida, porque me acerqu\u00e9 con las manos a los lados, me identifiqu\u00e9 abiertamente y dije que quer\u00eda entrar a la instalaci\u00f3n\u201d, dijo Mills. \u201cFue 100 % para ponernos de ejemplo\u201d.<\/p>\n<p>Llevaron a Mills hasta una acera cercana, donde esper\u00f3 unos diez minutos a que llegara una furgoneta policial que lo traslad\u00f3 a la estaci\u00f3n de polic\u00eda de Broadview, donde lo procesaron y le entregaron una citaci\u00f3n, relat\u00f3.<\/p>\n<p>La Polic\u00eda Estatal de Illinois le impuso una citaci\u00f3n por sospecha de desobedecer a un agente \u2014una falta sancionable con multa\u2014, seg\u00fan los registros del tribunal del condado de Cook, y debe comparecer ante el juez el 25 de noviembre.<\/p>\n<p>Los documentos judiciales no incluyen el relato del arresto. La polic\u00eda estatal no respondi\u00f3 directamente a las preguntas de CNN sobre este incidente espec\u00edfico, incluidas las afirmaciones de Mills de que no hizo nada malo. En su lugar, proporcion\u00f3 el mismo comunicado general que dio por el caso de Lee.<\/p>\n<p>Mills no se arrepiente de haber protestado ni de haber sido arrestado, porque est\u00e1 defendiendo sus convicciones.<\/p>\n<p>\u201cEs una verg\u00fcenza que nosotros, manifestantes pac\u00edficos, seamos objeto de persecuci\u00f3n en lugar de alentarnos a ejercer nuestros derechos de la Primera Enmienda\u201d, dijo Mills.<\/p>\n<p>Mills rechaza que los agentes del orden puedan detener y preguntar a las personas por su estatus migratorio con base, al menos en parte, en su apariencia \u00e9tnica. Un <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/08\/eeuu\/corte-suprema-trump-patrullas-ice-california-trax\">fallo de la Corte Suprema<\/a> de EE.UU. en un caso de California el mes pasado pareci\u00f3 abrir la puerta a que la etnia de una persona sea un factor en las detenciones migratorias por parte de las fuerzas del orden.<\/p>\n<p>Mills tampoco respalda las redadas de ICE en todo Chicago contra personas acusadas de estar en el pa\u00eds ilegalmente.<\/p>\n<p>\u201cEstamos haciendo lo m\u00ednimo que podemos para mantener a salvo a nuestros vecinos, y eso es muy importante para nosotros ahora mismo\u201d, dijo.<\/p>\n<p>Paul Ivery es un hombre del \u00e1rea de Chicago con una discapacidad intelectual que trabaja en la cafeter\u00eda de una escuela secundaria y que admira y respeta a la polic\u00eda y a los primeros respondedores de su comunidad \u2014incluso saluda a los agentes cuando se los cruza\u2014, seg\u00fan quienes lo conocen.<\/p>\n<p>Por eso a algunos conocidos pudo sorprenderles que durante dos semanas enfrentara un cargo federal por delito grave de agresi\u00f3n contra un agente federal durante una protesta en la instalaci\u00f3n de ICE en Broadview.<\/p>\n<p>El caso convocar\u00eda a numerosos simpatizantes \u2014incluida su propia alcaldesa\u2014 a una de las audiencias para intentar convencer al juez de que no representaba una amenaza. Ivery declin\u00f3 ser entrevistado para esta historia, pero un representante de la familia, documentos judiciales y un video de un transe\u00fante ayudan a reconstruir un proceso que el Gobierno quiso impulsar en un momento y desestimar al siguiente.<\/p>\n<p>Ivery camin\u00f3 desde su casa en Oak Park hasta la instalaci\u00f3n de ICE en Broadview el 27 de septiembre para unirse a las protestas, dijo el portavoz de la familia, Scott Sakiwama.<\/p>\n<p>M\u00e1s tarde, Ivery dir\u00eda a los investigadores que estaba all\u00ed para \u201cprotestar contra ICE\u201d porque cre\u00eda que \u201clos agentes de ICE estaban siendo irrespetuosos con el Departamento de Polic\u00eda de Broadview y con los veteranos\u201d, seg\u00fan una denuncia penal presentada contra Ivery en un tribunal federal, sin m\u00e1s detalles sobre su motivaci\u00f3n.<\/p>\n<p>Ivery tambi\u00e9n estaba molesto porque los agentes federales hab\u00edan lanzado gas lacrim\u00f3geno y disparado proyectiles de pimienta contra manifestantes en Broadview, seg\u00fan Sakiwama.<\/p>\n<p>En un momento de la protesta, Ivery se acerc\u00f3 a un agente de la Patrulla Fronteriza de EE.UU. y le grit\u00f3 algo, de acuerdo con la denuncia. Aunque el agente no recordaba qu\u00e9 se dijo, Ivery admitir\u00eda despu\u00e9s a los investigadores que dijo: \u201cTe voy a (improperio) matar ahora mismo\u201d y \u201chaz algo\u201d, seg\u00fan el documento.<\/p>\n<p>Despu\u00e9s del grito, Ivery corri\u00f3 y salt\u00f3 sobre un veh\u00edculo ocupado mientras los agentes lo persegu\u00edan, dice la denuncia.<\/p>\n<p>El video de un transe\u00fante muestra a Ivery saltar del veh\u00edculo y a un agente derribarlo cuando cae al pavimento. Ivery grita mientras varios agentes lo inmovilizan. Cerca, otros agentes disparan irritantes qu\u00edmicos al suelo para mantener a los curiosos alejados, lo que aparentemente provoca tos en algunas personas, seg\u00fan se ve en el video.<\/p>\n<p>Un testigo le pregunta a Ivery su nombre. Ivery lo grita y dice: \u201c\u00a1Ay\u00fadenme!\u201d. Minutos despu\u00e9s, tras atarle las manos a la espalda y sentarlo, un agente ayuda a Ivery a beber de una botella de agua. Finalmente, Ivery es puesto de pie y llevado a la parte trasera de un veh\u00edculo sin identificaci\u00f3n.<\/p>\n<p>La denuncia afirma que, mientras los agentes lo inmovilizaban, Ivery agarr\u00f3 el casco de un agente y lo tir\u00f3 hacia abajo, lastim\u00e1ndole la barbilla y exponi\u00e9ndolo al gas pimienta.<\/p>\n<p>Ivery fue arrestado y acusado en un tribunal federal de agresi\u00f3n con delito grave contra un agente federal, seg\u00fan los documentos judiciales.<\/p>\n<p>Ivery estuvo retenido temporalmente en la instalaci\u00f3n de ICE en Broadview el d\u00eda del arresto y esa noche fue trasladado al Centro Correccional Metropolitano federal de Chicago, dijo Sakiwama.<\/p>\n<p>Permaneci\u00f3 detenido varios d\u00edas. Pero para el 1 de octubre, los fiscales solicitaron su liberaci\u00f3n de la c\u00e1rcel y que quedara bajo arresto domiciliario en espera de juicio, en reconocimiento de su discapacidad, inform\u00f3 la afiliada de CNN WLS-TV.<\/p>\n<p>En una audiencia ese d\u00eda, un juez dej\u00f3 a Ivery en libertad bajo palabra. Muchos de sus simpatizantes, incluida la alcaldesa de Oak Park, Vicki Scaman, estuvieron all\u00ed para apoyarlo, seg\u00fan WLS.<\/p>\n<p>En una carta al juez, Scaman dijo que Ivery es un \u201cmiembro valioso de nuestra comunidad\u201d que se detiene y saluda a la polic\u00eda cuando los ve en la calle. Escribi\u00f3 que Ivery no representa una amenaza para la comunidad y que esperaba que el juez considerara su \u201cdiagn\u00f3stico de necesidades especiales\u201d.<\/p>\n<p>El 9 de octubre, los fiscales solicitaron desestimar el cargo por completo, y el juez as\u00ed lo orden\u00f3 al d\u00eda siguiente. Los registros judiciales no indicaron por qu\u00e9 se desestim\u00f3 el caso.<\/p>\n<p>La Fiscal\u00eda de EE.UU. para el distrito norte de Illinois no respondi\u00f3 a la solicitud de informaci\u00f3n de CNN sobre la desestimaci\u00f3n. El abogado designado por el tribunal para Ivery declin\u00f3 ser entrevistado sobre los detalles del caso.<\/p>\n<p>\u201cMe alegra por el se\u00f1or Ivery y por la resoluci\u00f3n justa de su caso, y espero que otros cuyas libertades de la Primera Enmienda tambi\u00e9n est\u00e9n siendo vulneradas por el Gobierno reciban justicia\u201d, dijo en un correo a CNN el defensor p\u00fablico federal Johanathan Brooks.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que en los \u00faltimos meses se han intensificado las manifestaciones frente a un centro de detenci\u00f3n de inmigraci\u00f3n cerca de Chicago, tambi\u00e9n ha aumentado el n\u00famero de manifestantes conducidos esposados y con fecha para comparecer ante la justicia. Desde septiembre, los manifestantes se han movilizado cada semana frente a la oficina del Servicio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467955","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias\" \/>\n<meta property=\"og:description\" content=\"A medida que en los \u00faltimos meses se han intensificado las manifestaciones frente a un centro de detenci\u00f3n de inmigraci\u00f3n cerca de Chicago, tambi\u00e9n ha aumentado el n\u00famero de manifestantes conducidos esposados y con fecha para comparecer ante la justicia. Desde septiembre, los manifestantes se han movilizado cada semana frente a la oficina del Servicio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-02T14:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s\",\"datePublished\":\"2025-11-02T14:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\"},\"wordCount\":2560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\",\"name\":\"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-02T14:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias","og_description":"A medida que en los \u00faltimos meses se han intensificado las manifestaciones frente a un centro de detenci\u00f3n de inmigraci\u00f3n cerca de Chicago, tambi\u00e9n ha aumentado el n\u00famero de manifestantes conducidos esposados y con fecha para comparecer ante la justicia. Desde septiembre, los manifestantes se han movilizado cada semana frente a la oficina del Servicio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-02T14:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/"},"author":{"name":"","@id":""},"headline":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s","datePublished":"2025-11-02T14:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/"},"wordCount":2560,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","name":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-02T14:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\u00f3 despu\u00e9s","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/02\/protestas-ice-chicago-arrestos-illinois-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-02T14:03:39Z","datePublished":"2025-11-02T14:03:39Z","dateModified":"2025-11-02T14:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los arrestaron en una protesta contra ICE a las afueras de Chicago. Esto fue lo que les pas\\u00f3 despu\\u00e9s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/02\\\/protestas-ice-chicago-arrestos-illinois-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/02\\\/protestas-ice-chicago-arrestos-illinois-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-02T14:03:39Z\",\"datePublished\":\"2025-11-02T14:03:39Z\",\"dateModified\":\"2025-11-02T14:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468351,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/14\/detienen-manifestantes-ice-chicago-trax\/","url_meta":{"origin":1467955,"position":0},"title":"Detienen a manifestantes frente a un edificio de ICE cerca de Chicago","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Una protesta mayormente pac\u00edfica frente al edificio del controvertido Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en un suburbio al oeste de Chicago se torn\u00f3 ca\u00f3tica este viernes, cuando la Polic\u00eda local detuvo a varias personas despu\u00e9s de que, presuntamente, derribaran las barreras frente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467462,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/17\/chicago-epicentro-contra-inmigracion-trax\/","url_meta":{"origin":1467955,"position":1},"title":"Chicago se consolida como el epicentro de la ofensiva contra la inmigraci\u00f3n tras una serie de acontecimientos vertiginosos","author":"","date":"octubre 17, 2025","format":false,"excerpt":"Mientras los abogados se enfrentan en los tribunales y los agentes federales en el terreno chocan con los manifestantes, Chicago se est\u00e1 consolidando como el epicentro de la ofensiva migratoria de la administraci\u00f3n Trump despu\u00e9s de una serie de acontecimientos en las \u00faltimas 24 horas.Ahora, cuando la ciudad se dirige\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467089,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/03\/manifestacion-illinois-ice-noem-trax\/","url_meta":{"origin":1467955,"position":2},"title":"Manifestantes protestan ante las instalaciones de ICE en Illinois durante visita de Kristi Noem","author":"","date":"octubre 3, 2025","format":false,"excerpt":"Varias agencias del orden p\u00fablico se encuentran, aparentemente, en un enfrentamiento con decenas de manifestantes este viernes frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) cerca de Chicago, donde este viernes estuvo la secretaria de Seguridad Nacional, Kristi Noem.Al menos una persona ha sido arrestada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470682,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/30\/paro-nacional-protestas-ice-represion-inmigratoria-orix\/","url_meta":{"origin":1467955,"position":3},"title":"Manifestantes realizan paro nacional en EE.UU. en rechazo a la ofensiva inmigratoria del Gobierno de Trump","author":"","date":"enero 30, 2026","format":false,"excerpt":"El paro nacional de este viernes en Estados Unidos para protestar contra acciones de agentes federales en Minneapolis y la represi\u00f3n inmigratoria del Gobierno de Trump result\u00f3 en el cierre de negocios y estudiantes y personas saliendo a las calles de todo el pa\u00eds, con grupos que llamaron a \u201cno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466634,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","url_meta":{"origin":1467955,"position":4},"title":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Un alcalde dem\u00f3crata que se postulaba al Congreso por Illinois fue rociado con gas lacrim\u00f3geno la ma\u00f1ana de este viernes durante una peque\u00f1a protesta frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en las afueras de Chicago, seg\u00fan declar\u00f3 \u00e9l\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467524,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/20\/testifican-funcionarios-federales-acciones-chicago-claves-trax\/","url_meta":{"origin":1467955,"position":5},"title":"Llaman a testificar a funcionarios federales ante un juez por acciones en Chicago. Estas son las claves del caso","author":"","date":"octubre 20, 2025","format":false,"excerpt":"D\u00edas antes de que se le ordenara comparecer ante una jueza federal para responder preguntas urgentes sobre la ofensiva migratoria en Chicago, el director local de Inmigraci\u00f3n y Control de Aduanas (ICE) de la ciudad se va de la ciudad y otros dos funcionarios testificar\u00e1n este lunes en su lugar.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1467955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1467955"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1467955\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1467955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1467955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1467955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}