{"id":1467996,"date":"2025-11-03T14:03:39","date_gmt":"2025-11-03T22:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/"},"modified":"2025-11-03T14:03:39","modified_gmt":"2025-11-03T22:03:39","slug":"posponen-audiencias-abrego-garcia-diciembre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","title":{"rendered":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda"},"content":{"rendered":"<p>Dos d\u00edas de audiencias sobre si el procesamiento de Kilmar \u00c1brego Garc\u00eda por parte del Gobierno en Tennessee se dio de manera ilegal se han trasladado a principios de diciembre despu\u00e9s de que los abogados de \u00c1brego Garc\u00eda argumentaran que los fiscales no hab\u00edan entregado las comunicaciones entre altos funcionarios del Departamento de Justicia y los fiscales encargados del caso.<\/p>\n<p>Las audiencias, originalmente programadas para el 4 y 5 de noviembre, se pospusieron para el 8 y 9 de diciembre, poco m\u00e1s de un mes antes de que comience el juicio de \u00c1brego Garc\u00eda en el caso de trata de personas a finales de enero.<\/p>\n<p>Los abogados de \u00c1brego Garc\u00eda han argumentado que el vicesecretario de Justicia Todd Blanche y otros quer\u00edan que su cliente fuera procesado despu\u00e9s de que el Gobierno de EE.UU. admitiera haberlo deportado err\u00f3neamente \u2014siendo \u00e9l un no ciudadano estadounidense\u2014 de regreso a El Salvador, a pesar de una orden judicial destinada a evitar tal acci\u00f3n.<\/p>\n<p> Los fiscales dicen que el fiscal federal para el Distrito Medio de Tennessee tom\u00f3 solo la decisi\u00f3n de procesar a \u00c1brego Garc\u00eda y han luchado contra los intentos de que Blanche y otros testifiquen.<\/p>\n<p>Se desconoce c\u00f3mo se desarrollar\u00e1n las disputas sobre qu\u00e9 informaci\u00f3n deben entregar los fiscales y qui\u00e9nes estar\u00e1n obligados a testificar. Al permitir las audiencias, el juez que preside el caso les dijo a ambas partes que hab\u00eda suficiente evidencia de procesamiento selectivo y vengativo en el caso como para justificar un mayor escrutinio, a pesar de su raro \u00e9xito en casos federales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos d\u00edas de audiencias sobre si el procesamiento de Kilmar \u00c1brego Garc\u00eda por parte del Gobierno en Tennessee se dio de manera ilegal se han trasladado a principios de diciembre despu\u00e9s de que los abogados de \u00c1brego Garc\u00eda argumentaran que los fiscales no hab\u00edan entregado las comunicaciones entre altos funcionarios del Departamento de Justicia y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467996","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos d\u00edas de audiencias sobre si el procesamiento de Kilmar \u00c1brego Garc\u00eda por parte del Gobierno en Tennessee se dio de manera ilegal se han trasladado a principios de diciembre despu\u00e9s de que los abogados de \u00c1brego Garc\u00eda argumentaran que los fiscales no hab\u00edan entregado las comunicaciones entre altos funcionarios del Departamento de Justicia y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-03T22:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda\",\"datePublished\":\"2025-11-03T22:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\",\"name\":\"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-03T22:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias","og_description":"Dos d\u00edas de audiencias sobre si el procesamiento de Kilmar \u00c1brego Garc\u00eda por parte del Gobierno en Tennessee se dio de manera ilegal se han trasladado a principios de diciembre despu\u00e9s de que los abogados de \u00c1brego Garc\u00eda argumentaran que los fiscales no hab\u00edan entregado las comunicaciones entre altos funcionarios del Departamento de Justicia y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-03T22:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/"},"author":{"name":"","@id":""},"headline":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda","datePublished":"2025-11-03T22:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","name":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-03T22:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Posponen para diciembre las audiencias de Kilmar \u00c1brego Garc\u00eda","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/posponen-audiencias-abrego-garcia-diciembre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-03T22:03:39Z","datePublished":"2025-11-03T22:03:39Z","dateModified":"2025-11-03T22:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Posponen para diciembre las audiencias de Kilmar \\u00c1brego Garc\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/03\\\/posponen-audiencias-abrego-garcia-diciembre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/03\\\/posponen-audiencias-abrego-garcia-diciembre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-03T22:03:39Z\",\"datePublished\":\"2025-11-03T22:03:39Z\",\"dateModified\":\"2025-11-03T22:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464006,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/06\/27\/abogados-kilmar-abrego-garcia-retrase-liberacion-trax\/","url_meta":{"origin":1467996,"position":0},"title":"Los abogados de Kilmar \u00c1brego Garc\u00eda solicitan a un juez federal que retrase su liberaci\u00f3n","author":"","date":"junio 27, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda solicitaron a un juez federal que retrase la liberaci\u00f3n de su cliente que estaba prevista para este viernes, despu\u00e9s de que fiscales federales declararan durante una audiencia el jueves que buscar\u00edan deportarlo a un \u201ctercer pa\u00eds\u201d, distinto a su natal El Salvador.El Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465011,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/31\/juez-abrego-garcia-gobierno-modere-comentarios-trax\/","url_meta":{"origin":1467996,"position":1},"title":"Juez en el caso de \u00c1brego Garc\u00eda pide al Gobierno de Trump que modere comentarios p\u00fablicos para asegurar un juicio justo","author":"","date":"julio 31, 2025","format":false,"excerpt":"El juez federal en Tennessee que supervisa el caso penal de Kilmar \u00c1brego Garc\u00eda le dijo este jueves al Gobierno Trump que los funcionarios deben moderar sus comentarios p\u00fablicos sobre \u00e9l para asegurar que reciba un juicio justo.La orden del juez de distrito de EE.UU. Waverly Crenshaw llega una semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467282,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/10\/abrego-garcia-mocion-suprimir-declaraciones-arresto-trax\/","url_meta":{"origin":1467996,"position":2},"title":"Kilmar \u00c1brego Garc\u00eda presentar\u00e1 una moci\u00f3n para suprimir declaraciones de su arresto en marzo","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda afirman que es posible que los agentes federales no le hayan le\u00eddo correctamente sus derechos Miranda tras su arresto en marzo. En una audiencia ante un juez federal en Tennessee, indicaron que planean presentar varias mociones \u2013incluida una sobre posible coacci\u00f3n por parte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464170,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/03\/abogados-kilmar-abrego-el-salvador-trax\/","url_meta":{"origin":1467996,"position":3},"title":"Abogados de Kilmar \u00c1brego Garc\u00eda detallan torturas y malos tratos en la megac\u00e1rcel de El Salvador","author":"","date":"julio 3, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda continuaron el mi\u00e9rcoles su esfuerzo para mantener vivo su caso civil contra la administraci\u00f3n Trump, solicitando enmendar la demanda para incluir lo que describen como la \u201ctortura y maltrato\u201d que experiment\u00f3 en la notoria megaprisi\u00f3n de El Salvador, adonde fue deportado injustamente y retenido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464203,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/03\/bukele-rechaza-acusaciones-tortura-kilmar-abrego-salvador-orix\/","url_meta":{"origin":1467996,"position":4},"title":"Bukele rechaza las acusaciones de tortura durante la detenci\u00f3n de Kilmar \u00c1brego Garc\u00eda en El Salvador","author":"","date":"julio 3, 2025","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, rechaz\u00f3 el jueves las acusaciones de que Kilmar \u00c1brego Garc\u00eda fue torturado o maltratado durante el tiempo que estuvo detenido en el pa\u00eds centroamericano, entre el 15 de marzo y el 6 de junio, donde fue enviado tras haber sido deportado debido a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469674,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/12\/30\/funcionarios-presionando-cargos-penales-abrego-garcia-trax\/","url_meta":{"origin":1467996,"position":5},"title":"Funcionarios del Departamento de Justicia habr\u00edan presionando para presentar cargos penales contra \u00c1brego Garc\u00eda, dice juez","author":"","date":"diciembre 30, 2025","format":false,"excerpt":"Archivos internos del Departamento de Justicia \u201csugieren\u201d que altos funcionarios en Washington trabajaron con fiscales federales en Nashville para procesar a Kilmar \u00c1brego Garc\u00eda despu\u00e9s de que \u00e9l luchara contra su deportaci\u00f3n injusta a El Salvador, dijo un juez federal en una reciente decisi\u00f3n desclasificada.La opini\u00f3n del 3 de diciembre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1467996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1467996"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1467996\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1467996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1467996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1467996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}