{"id":1468034,"date":"2025-11-04T17:03:40","date_gmt":"2025-11-05T01:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/"},"modified":"2025-11-04T17:03:40","modified_gmt":"2025-11-05T01:03:40","slug":"elecciones-gobernador-virginia-resultados-2025-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","title":{"rendered":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo"},"content":{"rendered":"<p>Cuatro a\u00f1os despu\u00e9s de que el gobernador republicano Glenn Youngkin lograra una gran sorpresa al aprovechar la ira de los padres contra las juntas escolares locales, su vicegobernadora, Winsome Earle-Sears, busca reemplazarlo con una campa\u00f1a enfocada en las pol\u00edticas transg\u00e9nero, particularmente en las escuelas.<\/p>\n<p>Pero las encuestas sugieren que su oponente dem\u00f3crata, la exrepresentante Abigail Spanberger, tiene una clara ventaja de cara al D\u00eda de las Elecciones en un estado que vot\u00f3 tres veces contra Trump. Los dem\u00f3cratas han vinculado incansablemente a Earle-Sears con Trump, y ella no ha intentado distanciarse del presidente.<\/p>\n<p>Fuente: Datos de resultados v\u00eda Associated Press; Proyecciones de CNN<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro a\u00f1os despu\u00e9s de que el gobernador republicano Glenn Youngkin lograra una gran sorpresa al aprovechar la ira de los padres contra las juntas escolares locales, su vicegobernadora, Winsome Earle-Sears, busca reemplazarlo con una campa\u00f1a enfocada en las pol\u00edticas transg\u00e9nero, particularmente en las escuelas. Pero las encuestas sugieren que su oponente dem\u00f3crata, la exrepresentante Abigail [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468034","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuatro a\u00f1os despu\u00e9s de que el gobernador republicano Glenn Youngkin lograra una gran sorpresa al aprovechar la ira de los padres contra las juntas escolares locales, su vicegobernadora, Winsome Earle-Sears, busca reemplazarlo con una campa\u00f1a enfocada en las pol\u00edticas transg\u00e9nero, particularmente en las escuelas. Pero las encuestas sugieren que su oponente dem\u00f3crata, la exrepresentante Abigail [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T01:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo\",\"datePublished\":\"2025-11-05T01:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\",\"name\":\"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-05T01:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias","og_description":"Cuatro a\u00f1os despu\u00e9s de que el gobernador republicano Glenn Youngkin lograra una gran sorpresa al aprovechar la ira de los padres contra las juntas escolares locales, su vicegobernadora, Winsome Earle-Sears, busca reemplazarlo con una campa\u00f1a enfocada en las pol\u00edticas transg\u00e9nero, particularmente en las escuelas. Pero las encuestas sugieren que su oponente dem\u00f3crata, la exrepresentante Abigail [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-05T01:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/"},"author":{"name":"","@id":""},"headline":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo","datePublished":"2025-11-05T01:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","name":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-05T01:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/04\/elecciones-gobernador-virginia-resultados-2025-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-05T01:03:40Z","datePublished":"2025-11-05T01:03:40Z","dateModified":"2025-11-05T01:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Resultados de las elecciones a Gobernador de Virginia 2025, en vivo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/04\\\/elecciones-gobernador-virginia-resultados-2025-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/04\\\/elecciones-gobernador-virginia-resultados-2025-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-05T01:03:40Z\",\"datePublished\":\"2025-11-05T01:03:40Z\",\"dateModified\":\"2025-11-05T01:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468002,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/a-que-hora-cierran-urnas-elecciones-resultados-trax\/","url_meta":{"origin":1468034,"position":0},"title":"A qu\u00e9 hora cierran las urnas de las elecciones de Estados Unidos y cu\u00e1ndo habr\u00e1 resultados","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"El martes se llevar\u00e1n a cabo las primeras elecciones importantes durante el segundo mandato del presidente Donald Trump, una serie de pruebas tanto para Trump como para los dem\u00f3cratas que intentan decidir c\u00f3mo oponerse a \u00e9l.Te presentamos a qu\u00e9 hora cerrar\u00e1n las \u00faltimas urnas en las cuatro principales contiendas la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467987,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/03\/trump-elecciones-mitad-de-periodo-2026-trax\/","url_meta":{"origin":1468034,"position":1},"title":"Trump espera un veredicto temprano con las elecciones del martes, pero ya piensa en las de mitad de per\u00edodo del pr\u00f3ximo a\u00f1o","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"Incluso mientras las elecciones del martes mantienen en vilo el panorama pol\u00edtico, el presidente de EE.UU., Donald Trump, ha dejado claro que ya mira con preocupaci\u00f3n hacia las elecciones de mitad de per\u00edodo de 2026.\u201cHemos tenido un \u00e9xito como nadie, pero por alguna raz\u00f3n se pierden las elecciones de mitad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467965,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/02\/carreras-claves-elecciones-virginia-nueva-jersey-nueva-york-trax\/","url_meta":{"origin":1468034,"position":2},"title":"Las carreras claves de las elecciones del 4 de noviembre en EE.UU.","author":"","date":"noviembre 2, 2025","format":false,"excerpt":"Las elecciones en varios estados este martes buscan medir c\u00f3mo se sienten los votantes en el primer a\u00f1o del segundo mandato de Donald Trump, y si los dem\u00f3cratas han mejorado su posici\u00f3n con las elecciones de medio t\u00e9rmino a solo un a\u00f1o de distancia.Los votantes elegir\u00e1n nuevos gobernadores en Virginia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468041,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/04\/conclusiones-elecciones-democratas-ganan-votantes-rechazan-trump-trax\/","url_meta":{"origin":1468034,"position":3},"title":"Conclusiones de las elecciones de EE.UU. 2025: dem\u00f3cratas ganan en todo el espectro pol\u00edtico y los votantes rechazan a Trump","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Los votantes de toda la costa este otorgaron este martes una victoria arrolladora a los dem\u00f3cratas, eligiendo candidatos de todo el espectro ideol\u00f3gico del partido en una clara muestra de descontento con el presidente Donald Trump casi un a\u00f1o despu\u00e9s del comienzo de su segundo mandato.En Virginia, la exrepresentante moderada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467899,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/31\/favoritos-elecciones-noviembre-eeuu-trax\/","url_meta":{"origin":1468034,"position":4},"title":"\u00bfQui\u00e9nes son favoritos en las carreras clave de las elecciones de EE.UU. del 4 de noviembre de 2025? Esto dicen las encuestas","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Estamos a pocos d\u00edas de las elecciones especiales de 2025. M\u00e1s all\u00e1 de los resultados de las contiendas, estas ser\u00e1n una valiosa fuente de datos para analizar \u2014y quiz\u00e1s sobreanalizar\u2014 de cara a las elecciones de mitad de mandato del pr\u00f3ximo a\u00f1o.Aqu\u00ed les presentamos un resumen de lo que sugieren\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468068,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/05\/elecciones-martes-republicanos-democratas-intermedias-trax\/","url_meta":{"origin":1468034,"position":5},"title":"Advertencia para los republicanos y lecciones para los dem\u00f3cratas: c\u00f3mo las elecciones del martes influir\u00e1n en las de 2026","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El dominio dem\u00f3crata en las elecciones del martes restableci\u00f3 las expectativas de cara a la batalla del pr\u00f3ximo a\u00f1o por el control de la C\u00e1mara de Representantes y el Senado, revitalizando a un partido que hab\u00eda estado en el desierto pol\u00edtico y dejando a los republicanos lament\u00e1ndose de que las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468034"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468034\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}