{"id":1468078,"date":"2025-11-06T01:03:56","date_gmt":"2025-11-06T09:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/"},"modified":"2025-11-06T01:03:56","modified_gmt":"2025-11-06T09:03:56","slug":"chicago-marimar-martinez-disparos-audiencia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","title":{"rendered":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago"},"content":{"rendered":"<p>Un agente de Aduanas y Protecci\u00f3n Fronteriza pareci\u00f3 alardear ante sus compa\u00f1eros sobre su punter\u00eda al <a href=\"https:\/\/www.cnn.com\/2025\/10\/16\/us\/chicago-car-ramming-case-ice-protests\">disparar repetidamente a una mujer de Chicago<\/a> tras una colisi\u00f3n entre sus veh\u00edculos, seg\u00fan revelaron mensajes de texto mostrados en el tribunal.<\/p>\n<p>La mujer, Marimar Mart\u00ednez, est\u00e1 acusada de perseguir al agente y chocar contra su auto. Sin embargo, su abogado defensor alega lo contrario, afirmando que fue el funcionario quien la embisti\u00f3 lateralmente.<\/p>\n<p>El mi\u00e9rcoles se mostraron en el tribunal mensajes de texto del agente Charles Exum, mientras el abogado defensor de Mart\u00ednez intentaba probar su afirmaci\u00f3n de que <a href=\"https:\/\/www.cnn.com\/2025\/10\/21\/us\/chicago-suv-ramming-case-update\">el Gobierno potencialmente destruy\u00f3 evidencia<\/a> que podr\u00eda haber respaldado a la defensa cuando liber\u00f3 el veh\u00edculo da\u00f1ado de Exum y permiti\u00f3 que el agente lo condujera m\u00e1s de 1.600 km<strong> <\/strong>hasta su estado natal de Maine.<\/p>\n<p>El abogado defensor penal Christopher Parente se\u00f1al\u00f3 los mensajes como una indicaci\u00f3n de que Exum comprend\u00eda el alto escrutinio p\u00fablico del caso y habr\u00eda reconocido el potencial valor probatorio de este veh\u00edculo.<\/p>\n<p>A medida que el caso acaparaba la atenci\u00f3n de los medios nacionales y del p\u00fablico, Exum envi\u00f3 un <a href=\"https:\/\/www.theguardian.com\/us-news\/2025\/oct\/07\/chicago-woman-shot-immigration-agents\">art\u00edculo de The Guardian<\/a> del 7 de octubre a un grupo de otros agentes, en el que se citaba a Parente diciendo que Mart\u00ednez ten\u00eda \u201csiete agujeros en el cuerpo por cinco disparos de este agente\u201d.<\/p>\n<p>\u201cL\u00e9elo. 5 tiros, 7 hoyos\u201d, dijo Exum en el siguiente mensaje.<\/p>\n<p>Cuando Parente le insisti\u00f3 en que aclarara a qu\u00e9 se refer\u00eda, Exum respondi\u00f3 que era instructor de armas de fuego. Dijo: \u201cMe enorgullezco de mi punter\u00eda\u201d.<\/p>\n<p>Otro mensaje al grupo dec\u00eda: \u201cTengo una modificaci\u00f3n a mi historia. Dispar\u00e9 5 veces y ella ten\u00eda 7 agujeros. Ap\u00fantenlo, muchachos\u201d.<\/p>\n<p>Exum explic\u00f3 al juez que MOF es un \u201cviejo miserable\u201d que siempre est\u00e1 tratando de superar a alguien donde sea posible.<\/p>\n<p>No est\u00e1 claro a qu\u00e9 respond\u00eda exactamente, ya que las conversaciones de texto fueron censuradas cuando se presentaron ante el tribunal.<\/p>\n<p>Al ped\u00edrsele que explicara el texto, Exum dijo: \u201cEso significa que las acciones ilegales tienen consecuencias legales\u201d.<\/p>\n<p>Exum defendi\u00f3 el uso de la fuerza contra Mart\u00ednez, diciendo que su vida corr\u00eda peligro y que \u201chice lo que ten\u00eda que hacer\u201d.<\/p>\n<p>Posteriormente, se\u00f1al\u00f3 que los agentes de la Patrulla Fronteriza consideran la \u201cintenci\u00f3n transferida\u201d al decidir si usar la fuerza; es decir, por ejemplo, cualquier da\u00f1o causado al veh\u00edculo se considera una intenci\u00f3n de hacerle lo mismo al agente. El uso de la fuerza por parte del funcionario deb\u00eda ser proporcional, afirm\u00f3.<\/p>\n<p>\u201cEste incidente no se parece en nada a lo que hemos entrenado\u201d, dijo Exum al juez. A\u00f1adi\u00f3 que era algo que uno podr\u00eda ver en zonas del mundo controladas por c\u00e1rteles, no en las calles estadounidenses.<\/p>\n<p>No dio m\u00e1s detalles. Parente, exfiscal federal, ha descrito con frecuencia el incidente que condujo al tiroteo como un simple accidente de tr\u00e1fico.<\/p>\n<p>Mart\u00ednez, una ciudadana estadounidense de 30 a\u00f1os, y su coacusado, Anthony Ruiz, quien conduc\u00eda un veh\u00edculo diferente, han sido acusados \u200b\u200bpor fiscales federales de seguir de manera \u201cagresiva e impredecible\u201d y luego embestir a Exum y a otros agentes que se encontraban dentro de su veh\u00edculo y que estaban realizando labores de seguridad en Chicago.<\/p>\n<p>Seg\u00fan una declaraci\u00f3n jurada presentada por un agente del FBI, Mart\u00ednez y Ruiz presuntamente condujeron a escasos cent\u00edmetros del coche de la Patrulla Fronteriza, salt\u00e1ndose en ocasiones sem\u00e1foros en rojo y conduciendo por el carril contrario mientras persegu\u00edan al agente.<\/p>\n<p>Mart\u00ednez y Ruiz estuvieron presentes en el tribunal el mi\u00e9rcoles y ambos se declararon inocentes de un cargo federal de agresi\u00f3n, resistencia u obstrucci\u00f3n a agentes federales.<\/p>\n<p>Cuando Parente le pregunt\u00f3 a Exum si alguna vez le hab\u00eda preocupado que su conducta pudiera haber violado la pol\u00edtica de la CBP, Exum respondi\u00f3: \u201cEn absoluto\u201d.<\/p>\n<p>Aunque cabr\u00eda esperar que las audiencias del caso se centraran en lo sucedido en los momentos previos a la colisi\u00f3n, el mi\u00e9rcoles se centraron en lo ocurrido despu\u00e9s, y en qu\u00e9 hizo exactamente el Gobierno con el coche de Exum.<\/p>\n<p>La jueza de distrito estadounidense Georgia Alexakis expres\u00f3 el mi\u00e9rcoles su escepticismo sobre por qu\u00e9 los autom\u00f3viles de los dos conductores acusados \u200b\u200ben el caso \u2014Mart\u00ednez y Ruiz\u2014 han permanecido en Chicago como evidencia, mientras que el autom\u00f3vil del agente de la Patrulla Fronteriza fue liberado y se le permiti\u00f3 viajar con normalidad.<\/p>\n<p>\u201cLo que me preocupa mucho es el hecho de que los autos hayan recibido un trato diferente\u201d, dijo Alexakis.<\/p>\n<p>Los abogados del Gobierno defendieron las decisiones de los agentes federales, afirmando que el FBI hab\u00eda preservado todas las pruebas que consideraban relevantes antes de devolver el veh\u00edculo a la calle.<\/p>\n<p>El d\u00eda del accidente, el FBI recogi\u00f3 fotograf\u00edas del exterior del coche, muestras de pintura y otras pruebas, seg\u00fan una declaraci\u00f3n jurada presentada por el Departamento de Justicia. El veh\u00edculo le fue devuelto a Exum esa misma noche, y \u00e9l afirm\u00f3 que no se le indic\u00f3 que lo conservara de ninguna manera.<\/p>\n<p>Durante los tres d\u00edas siguientes, Exum condujo el coche por Chicago mientras completaba su turno en la ciudad, seg\u00fan la declaraci\u00f3n jurada. Tambi\u00e9n se reuni\u00f3 con el FBI y la Fiscal\u00eda Federal, y se descargaron datos de su auto, afirm\u00f3.<\/p>\n<p>El 8 de octubre, cuatro d\u00edas despu\u00e9s del accidente, condujo la camioneta de regreso a Maine y la estacion\u00f3 en un garaje seguro de la Patrulla Fronteriza. All\u00ed, un mec\u00e1nico comenz\u00f3 las reparaciones, pero recibi\u00f3 la orden de detenerlas debido a los litigios en curso relacionados con el veh\u00edculo.<\/p>\n<p>Aproximadamente una semana despu\u00e9s de regresar a Maine, Exum dijo que un agente del FBI lo llam\u00f3 y le coment\u00f3 que tal vez necesitar\u00edan recuperar el auto. Aunque inicialmente Exum le dijo al FBI que no cre\u00eda que se le hubiera hecho ning\u00fan trabajo al auto, luego descubri\u00f3 que un mec\u00e1nico hab\u00eda pulido las marcas de roce.<\/p>\n<p>Exum dijo que envi\u00f3 un correo electr\u00f3nico a su cadena de mando indicando que su veh\u00edculo podr\u00eda tener valor probatorio y que no deb\u00eda repararse.<\/p>\n<p>El supervisor de Exum dijo que aprob\u00f3 el trabajo mec\u00e1nico realizado en el veh\u00edculo porque cre\u00eda que todas las pruebas hab\u00edan sido recopiladas en Chicago, testific\u00f3 el agente.<\/p>\n<p>\u201cSi lo necesitaran como prueba, no creo que lo hubieran descartado de la investigaci\u00f3n, despu\u00e9s de que usted condujera tres d\u00edas de regreso a Maine, posiblemente destruyendo parte de esa evidencia en el camino, si a\u00fan la necesitaban\u201d, escribi\u00f3 el supervisor en un correo electr\u00f3nico enviado a Exum el 17 de octubre y mostrado en la corte.<\/p>\n<p>Pero el juez Alexakis dijo que el Gobierno cre\u00eda claramente que el veh\u00edculo pod\u00eda ser una prueba exculpatoria, de lo contrario no se habr\u00eda tomado la molestia de conservar los registros del autom\u00f3vil.<\/p>\n<p>Alexakis orden\u00f3 al Gobierno el mes pasado que devolviera el todoterreno a Chicago, esta vez transportado en una plataforma. No deb\u00eda haberse realizado ninguna alteraci\u00f3n, ni siquiera un lavado, antes de que la defensa pudiera examinarlo.<\/p>\n<p>Pero Parente afirma que se le ha impedido examinar completamente el veh\u00edculo desde que fue devuelto.<\/p>\n<p>\u00c9l y su experto pudieron inspeccionar el veh\u00edculo, seg\u00fan declar\u00f3 el mi\u00e9rcoles, pero no les dejaron acercarse a menos de medio metro ni tocarlo.<\/p>\n<p>Antes de seguir adelante con la audiencia, Alexakis se\u00f1al\u00f3 que el caso del Gobierno ha incluido algunas discrepancias y omisiones que la han obligado a actuar con cautela.<\/p>\n<p>Se\u00f1al\u00f3 que el Departamento de Justicia hab\u00eda dicho previamente en la corte que el agente se llev\u00f3 la camioneta de regreso a Maine porque era su \u201cveh\u00edculo personal\u201d, y luego declar\u00f3 en una presentaci\u00f3n judicial posterior que el autom\u00f3vil forma parte de una flota oficial de la Patrulla Fronteriza.<\/p>\n<p>La jueza tambi\u00e9n se\u00f1al\u00f3 que no se le hab\u00eda informado previamente que un mec\u00e1nico hubiera trabajado en el autom\u00f3vil, y que adem\u00e1s el Gobierno ha dado al menos dos versiones diferentes sobre qui\u00e9n aprob\u00f3 el traslado del autom\u00f3vil a Maine.<\/p>\n<p>Reconoci\u00f3 que la versi\u00f3n oficial de los hechos podr\u00eda resultar cierta, \u201cpero no puedo aceptar esa posibilidad en este momento\u201d, dijo.<\/p>\n<p>\u201cEl hecho de que surjan estas discrepancias me lleva a cuestionar la versi\u00f3n que se est\u00e1 presentando\u201d, dijo el juez.<\/p>\n<p>Alexakis reconoci\u00f3 que el Gobierno estaba trabajando con plazos muy ajustados para transmitir la informaci\u00f3n al tribunal, pero afirm\u00f3: \u201cEste plazo tan ajustado es un plazo que ellos mismos se han creado\u201d.<\/p>\n<p>Entre las cuestiones que ahora tiene ante s\u00ed, indic\u00f3, est\u00e1 si el Gobierno actu\u00f3 de mala fe o si las pruebas fueron manipuladas de manera perjudicial.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un agente de Aduanas y Protecci\u00f3n Fronteriza pareci\u00f3 alardear ante sus compa\u00f1eros sobre su punter\u00eda al disparar repetidamente a una mujer de Chicago tras una colisi\u00f3n entre sus veh\u00edculos, seg\u00fan revelaron mensajes de texto mostrados en el tribunal. La mujer, Marimar Mart\u00ednez, est\u00e1 acusada de perseguir al agente y chocar contra su auto. Sin embargo, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468078","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un agente de Aduanas y Protecci\u00f3n Fronteriza pareci\u00f3 alardear ante sus compa\u00f1eros sobre su punter\u00eda al disparar repetidamente a una mujer de Chicago tras una colisi\u00f3n entre sus veh\u00edculos, seg\u00fan revelaron mensajes de texto mostrados en el tribunal. La mujer, Marimar Mart\u00ednez, est\u00e1 acusada de perseguir al agente y chocar contra su auto. Sin embargo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T09:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago\",\"datePublished\":\"2025-11-06T09:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\"},\"wordCount\":1557,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\",\"name\":\"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-06T09:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias","og_description":"Un agente de Aduanas y Protecci\u00f3n Fronteriza pareci\u00f3 alardear ante sus compa\u00f1eros sobre su punter\u00eda al disparar repetidamente a una mujer de Chicago tras una colisi\u00f3n entre sus veh\u00edculos, seg\u00fan revelaron mensajes de texto mostrados en el tribunal. La mujer, Marimar Mart\u00ednez, est\u00e1 acusada de perseguir al agente y chocar contra su auto. Sin embargo, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-06T09:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/"},"author":{"name":"","@id":""},"headline":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago","datePublished":"2025-11-06T09:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/"},"wordCount":1557,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","name":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-06T09:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Agente de Patrulla Fronteriza pareci\u00f3 alardear de su punter\u00eda tras dispararle cinco veces a una mujer de Chicago","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/chicago-marimar-martinez-disparos-audiencia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-06T09:03:56Z","datePublished":"2025-11-06T09:03:56Z","dateModified":"2025-11-06T09:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Agente de Patrulla Fronteriza pareci\\u00f3 alardear de su punter\\u00eda tras dispararle cinco veces a una mujer de Chicago\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/chicago-marimar-martinez-disparos-audiencia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/chicago-marimar-martinez-disparos-audiencia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-06T09:03:56Z\",\"datePublished\":\"2025-11-06T09:03:56Z\",\"dateModified\":\"2025-11-06T09:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468574,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/21\/marimar-martinez-patrulla-fronteriza-trax\/","url_meta":{"origin":1468078,"position":0},"title":"Ataque a Marimar Mart\u00ednez: as\u00ed se desmoron\u00f3 la defensa del agente de la Patrulla Fronteriza por parte del Gobierno","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"El jueves, Marimar Mart\u00ednez luc\u00eda una amplia sonrisa mientras agradec\u00eda a sus abogados a la salida de un tribunal de Illinois y declar\u00f3 a los reporteros: \u201cMe siento bendecida. Estoy feliz\u201d.\u201cHa sido dif\u00edcil\u201d, dijo. \u201cNo pod\u00eda dormir, pero ahora voy a dormir\u201d.Una jueza, tras una solicitud extraordinaria de la fiscal\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471122,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/11\/patrulla-fronteriza-elogio-agente-disparar-mujer-trax\/","url_meta":{"origin":1468078,"position":1},"title":"Funcionario de la Patrulla Fronteriza elogi\u00f3 el &#171;excelente servicio&#187; de un agente tras disparar a una mujer, seg\u00fan evidencia","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Nuevas pruebas gubernamentales divulgadas sobre el tiroteo del a\u00f1o pasado por parte de la Patrulla Fronteriza contra una mujer en Chicago revelaron im\u00e1genes de la c\u00e1mara corporal del incidente, mensajes de texto del agente que le dispar\u00f3 \u2014que no se hab\u00edan visto previamente\u2014 y elogios del entonces principal funcionario de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470951,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/06\/jueza-video-agente-marimar-martinez-trax\/","url_meta":{"origin":1468078,"position":2},"title":"Jueza ordena al Gobierno publicar video de agente de la Patrulla Fronteriza disparando contra una manifestante de Chicago","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Un video del gobierno que muestra a un agente de la Patrulla Fronteriza disparando contra una manifestante de Chicago en su autom\u00f3vil el pasado octubre puede hacerse p\u00fablico, seg\u00fan orden\u00f3 una jueza federal de distrito este viernes.La jueza Georgia Alexakis concedi\u00f3 la solicitud de Marimar Mart\u00ednez para modificar la orden\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469498,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/12\/22\/agentes-ice-minnesota-fuego-embestidos-camioneta-trax\/","url_meta":{"origin":1468078,"position":3},"title":"Agentes del ICE en St. Paul, Minnesota, abren fuego tras ser embestidos por una camioneta","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"La ca\u00f3tica detenci\u00f3n de un inmigrante indocumentado en St. Paul, Minnesota, termin\u00f3 de forma violenta el domingo, despu\u00e9s de que el hombre presuntamente atropellara a dos funcionarios federales con su veh\u00edculo durante una parada, lo que llev\u00f3 a que uno de los agentes disparara \u201cen defensa propia\u201d, antes de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468545,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/20\/fiscales-desestimar-cargos-mujer-chicago-baleada-trax\/","url_meta":{"origin":1468078,"position":4},"title":"Fiscales solicitan desestimar cargos contra mujer de Chicago baleada tras ser acusada de embestir un veh\u00edculo policial","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"En un giro inesperado del Gobierno estadounidense, la Fiscal\u00eda present\u00f3 este jueves una moci\u00f3n para desestimar los cargos federales contra una mujer que recibi\u00f3 un disparo de parte de un agente de la Oficina de Aduanas y Protecci\u00f3n Fronteriza en Chicago tras supuestamente chocar contra su auto, seg\u00fan muestran documentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471249,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/15\/hombre-baleado-ice-minneapolis-confesion-trax\/","url_meta":{"origin":1468078,"position":5},"title":"Acusan de agresi\u00f3n a un hombre baleado por un agente de ICE en Minneapolis. Una sorprendente confesi\u00f3n puso fin al caso","author":"","date":"febrero 15, 2026","format":false,"excerpt":"Alfredo Alejandro Aljorna estaba trabajando en Minneapolis una noche de mi\u00e9rcoles del mes pasado, haciendo entregas como conductor de DoorDash, cuando se dio cuenta de que estaba siendo seguido por agentes de ICE, seg\u00fan su abogado.Condujo hasta su casa y fue derribado por un agente, pero logr\u00f3 zafarse y corri\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468078"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468078\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}