{"id":1468098,"date":"2025-11-06T14:03:41","date_gmt":"2025-11-06T22:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/"},"modified":"2025-11-06T14:03:41","modified_gmt":"2025-11-06T22:03:41","slug":"jefe-patrulla-fronteriza-uso-fuerza-chicago-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","title":{"rendered":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza"},"content":{"rendered":"<p>Una juez federal emiti\u00f3 una orden judicial preliminar que restringe el uso de la fuerza por parte de agentes federales en Chicago, al considerar que la versi\u00f3n de los acontecimientos recientes presentada por el Gobierno de Trump no era cre\u00edble.<\/p>\n<p>Uno de los incidentes en cuesti\u00f3n fue un enfrentamiento entre agentes federales y manifestantes, donde Gregory Bovino, un<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/24\/eeuu\/gregory-bovino-patrulla-fronteriza-orden-judicial-chicago-trax\"> alto funcionario de la Patrulla Fronteriza <\/a>encargado de la ofensiva migratoria en Chicago, utiliz\u00f3 gas lacrim\u00f3geno.<\/p>\n<p>La jueza federal de distrito Sara Ellis determin\u00f3 que Bovino <a href=\"https:\/\/www.cnn.com\/2025\/10\/24\/us\/gregory-bovino-chicago-immigration-tear-gas-hnk\">no fue golpeado en la cabeza <\/a>con una piedra antes de lanzar gas lacrim\u00f3geno, a pesar de las afirmaciones del Departamento de Seguridad Nacional que justificaban el uso de la fuerza. \u201cEl acusado Bovino admiti\u00f3 que minti\u00f3\u201d, dijo ella.<\/p>\n<p>\u201cLa evidencia en video finalmente desminti\u00f3 esto\u201d, se\u00f1al\u00f3 Ellis, quien preside un caso relacionado con las t\u00e1cticas excesivas utilizadas por agentes federales en Chicago. Bovino, quien se someti\u00f3 a una declaraci\u00f3n bajo juramento que dur\u00f3 horas, dijo que fue golpeado despu\u00e9s de que se lanz\u00f3 el gas lacrim\u00f3geno, coment\u00f3 Ellis. El alto funcionario de la Patrulla Fronteriza comenz\u00f3 a usar su c\u00e1mara corporal, seg\u00fan abogados del Gobierno, luego de revelar el mes pasado en la corte que no ten\u00eda una.<\/p>\n<p>Durante la audiencia de este jueves, Ellis critic\u00f3 al Gobierno de Trump, diciendo que la versi\u00f3n que el Gobierno present\u00f3 de Chicago \u201cno es verdadera\u201d.<\/p>\n<p>\u201cNo considero cre\u00edble la evidencia del acusado\u201d, dijo Ellis. \u201cVi los videos de los acusados\u201d, continu\u00f3. \u201cEsto, y horas y horas y horas de videos de c\u00e1maras corporales y videos desde helic\u00f3pteros, fue lo mejor que pudieron aportar\u201d.<\/p>\n<p>Ellis tambi\u00e9n determin\u00f3 que los demandantes en el caso, quienes acusan a los agentes federales de comportamiento agresivo contra manifestantes pac\u00edficos, fueron \u201camenazados y perjudicados por ejercer sus derechos constitucionales\u201d.<\/p>\n<p>Al citar la preocupaci\u00f3n del Gobierno sobre la microgesti\u00f3n por parte del tribunal, la jueza Ellis dijo: \u201cNo estoy haciendo tal cosa con esta orden judicial\u201d.<\/p>\n<p>Ellis dijo que no le est\u00e1 diciendo al Gobierno c\u00f3mo manejar sus operaciones. \u201cNo les estoy diciendo a los acusados a qui\u00e9n contratar\u201d, agreg\u00f3 Ellis.<\/p>\n<p>Los agentes federales deben dar al menos dos advertencias separadas antes de usar armas para control de disturbios, brindando una \u201coportunidad razonable\u201d para que las personas cumplan, sentenci\u00f3 Ellis.<\/p>\n<p>La jueza tambi\u00e9n dijo que no suspender\u00e1 la orden judicial mientras se resuelve la apelaci\u00f3n y que emitir\u00e1 una orden escrita m\u00e1s tarde este jueves.<\/p>\n<p>Al finalizar la audiencia, el abogado de los demandantes, Steve Art, agradeci\u00f3 a la jueza diciendo: \u201cApreciamos que est\u00e9 protegiendo a esta comunidad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una juez federal emiti\u00f3 una orden judicial preliminar que restringe el uso de la fuerza por parte de agentes federales en Chicago, al considerar que la versi\u00f3n de los acontecimientos recientes presentada por el Gobierno de Trump no era cre\u00edble. Uno de los incidentes en cuesti\u00f3n fue un enfrentamiento entre agentes federales y manifestantes, donde [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468098","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una juez federal emiti\u00f3 una orden judicial preliminar que restringe el uso de la fuerza por parte de agentes federales en Chicago, al considerar que la versi\u00f3n de los acontecimientos recientes presentada por el Gobierno de Trump no era cre\u00edble. Uno de los incidentes en cuesti\u00f3n fue un enfrentamiento entre agentes federales y manifestantes, donde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T22:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza\",\"datePublished\":\"2025-11-06T22:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\",\"name\":\"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-06T22:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias","og_description":"Una juez federal emiti\u00f3 una orden judicial preliminar que restringe el uso de la fuerza por parte de agentes federales en Chicago, al considerar que la versi\u00f3n de los acontecimientos recientes presentada por el Gobierno de Trump no era cre\u00edble. Uno de los incidentes en cuesti\u00f3n fue un enfrentamiento entre agentes federales y manifestantes, donde [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-06T22:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/"},"author":{"name":"","@id":""},"headline":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza","datePublished":"2025-11-06T22:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","name":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-06T22:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jefe de la patrulla fronteriza admiti\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\u00fan jueza","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-06T22:03:41Z","datePublished":"2025-11-06T22:03:41Z","dateModified":"2025-11-06T22:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jefe de la patrulla fronteriza admiti\\u00f3 haber mentido en fallo que limita uso de la fuerza por agentes en Chicago, seg\\u00fan jueza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/jefe-patrulla-fronteriza-uso-fuerza-chicago-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-06T22:03:41Z\",\"datePublished\":\"2025-11-06T22:03:41Z\",\"dateModified\":\"2025-11-06T22:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467825,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/28\/jefe-patrulla-fronteriza-chicago-jueza-uso-fuerza-trax\/","url_meta":{"origin":1468098,"position":0},"title":"Jefe de la Patrulla Fronteriza en Chicago deber\u00e1 presentarse diario ante una jueza ante cuestionamientos sobre uso de fuerza","author":"","date":"octubre 28, 2025","format":false,"excerpt":"El jefe de la Patrulla Fronteriza, Gregory Bovino, quien supervisa la pol\u00edtica migratoria del Gobierno de Trump en el \u00e1rea de Chicago, fue citado por una jueza federal el martes tras recibir reportes de que agentes federales no estaban cumpliendo su orden de limitar t\u00e1cticas en\u00e9rgicas y advertir a manifestantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467698,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/24\/gregory-bovino-patrulla-fronteriza-orden-judicial-chicago-trax\/","url_meta":{"origin":1468098,"position":1},"title":"Acusan a alto funcionario de la Patrulla Fronteriza de violar la orden judicial sobre el uso de la fuerza en Chicago","author":"","date":"octubre 24, 2025","format":false,"excerpt":"El alto funcionario de la Patrulla Fronteriza, Gregory Bovino, est\u00e1 acusado de lanzar al menos un cartucho de gas lacrim\u00f3geno contra una multitud de manifestantes en un barrio de Chicago el jueves, en una posible violaci\u00f3n de la orden judicial que restringe a los agentes federales el uso de t\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470501,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/26\/gregory-bovino-patrulla-fronteriza-salida-minneapolis-trump-trax\/","url_meta":{"origin":1468098,"position":2},"title":"Gregory Bovino, el pol\u00e9mico comandante general de la Patrulla Fronteriza, abandonar\u00eda Minneapolis el martes, seg\u00fan fuentes","author":"","date":"enero 26, 2026","format":false,"excerpt":"Se espera que el comandante gemeral de la Patrulla Fronteriza Gregory Bovino y algunos de sus agentes salgan de Minneapolis el martes y regresen a sus respectivos sectores, seg\u00fan tres fuentes familiarizadas con las discusiones, dejando de lado a un actor clave en la ofensiva migratoria del Gobierno de Trump.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467851,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/29\/jefe-patrulla-fronteriza-comparecer-jueza-federal-chicago-trax\/","url_meta":{"origin":1468098,"position":3},"title":"Tribunal suspende la orden que obligaba al jefe de la Patrulla Fronteriza en Chicago a comparecer ante una jueza federal","author":"","date":"octubre 29, 2025","format":false,"excerpt":"El jefe de la Patrulla Fronteriza, Gregory Bovino, no tendr\u00e1 que comparecer ante una jueza federal de Chicago la noche de este mi\u00e9rcoles, despu\u00e9s de que un tribunal de apelaciones suspendiera la orden de la jueza que exig\u00eda que Bovino presentara informes diarios en la corte sobre las t\u00e1cticas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468527,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/19\/tribunal-bloquea-orden-redadas-inmigracion-chicago-trax\/","url_meta":{"origin":1468098,"position":4},"title":"Tribunal de apelaciones bloquea orden de jueza que restring\u00eda el uso de la fuerza en las redadas de inmigraci\u00f3n en Chicago","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"Un tribunal de apelaciones de EE.UU. ha bloqueado temporalmente una orden que limitaba la aplicaci\u00f3n de la ley de inmigraci\u00f3n federal en Chicago, argumentando que la jueza de primera instancia se excedi\u00f3 al imponer restricciones estrictas y de gran alcance sobre c\u00f3mo los agentes pueden interactuar con manifestantes y periodistas.Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467916,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/31\/tribunal-anula-orden-patrulla-fronteriza-trax\/","url_meta":{"origin":1468098,"position":5},"title":"Tribunal anula orden de jueza que exig\u00eda a jefe de Patrulla Fronteriza informar diario las actividades de agentes en Chicago","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones anul\u00f3 este viernes la orden de una jueza de Illinois que requer\u00eda que el comandante de la Patrulla Fronteriza, Gregory Bovino, proporcionara informes diarios al tribunal sobre las t\u00e1cticas de cumplimiento de la ley de inmigraci\u00f3n de sus agentes en el \u00e1rea de Chicago.La breve\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468098"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468098\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}