{"id":1468109,"date":"2025-11-06T19:03:51","date_gmt":"2025-11-07T03:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/"},"modified":"2025-11-06T19:03:51","modified_gmt":"2025-11-07T03:03:51","slug":"formula-uno-alpine-renovacion-franco-colapinto-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","title":{"rendered":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?"},"content":{"rendered":"<p>\u201c07. 11. 25. \u00bfYa hiciste las cuentas?\u201d. Con esa enigm\u00e1tica publicaci\u00f3n en redes sociales, la escuder\u00eda Alpine de F\u00f3rmula 1 parece haber quedado a un paso de anunciar la continuidad del argentino Franco Colapinto para 2026.<\/p>\n<p>La fotograf\u00eda que lleva los tres n\u00fameros parece referirse a una fecha, 7 de noviembre de 2025 (en Argentina y Latinoam\u00e9rica, las fechas se escriben d\u00eda, mes y a\u00f1o, a diferencia de lo que pasa en Estados Unidos), es decir, este viernes, justo cuando comienza la actividad oficial del Gran Premio de Brasil, que se correr\u00e1 el fin de semana en el circuito de Interlagos.<\/p>\n<p>Hace semanas se especula con que esta carrera ser\u00eda la elegida para hacer el anuncio, ya que, al ser la m\u00e1s cercana a Argentina, es en la cual Colapinto ser\u00e1 m\u00e1s local que en cualquier otra. De hecho, miles de argentinos viajaron el a\u00f1o pasado al GP de Brasil para verlo, cuando todav\u00eda estaba en Williams.<\/p>\n<p>Pero, m\u00e1s all\u00e1 de la fecha, lo importante es el mensaje escrito. \u201c\u00bfYa hiciste las cuentas?\u201d.<br \/>Ah\u00ed es donde los n\u00fameros que hacen a la fecha calendario cobran otro significado. Si se suma el 7, el 11 y el 25, la cuenta da 43, exactamente el n\u00famero bajo el cual Colapinto corre en la F\u00f3rmula 1. \u00bfCoincidencia? No parece\u2026<\/p>\n<p>De concretarse, ser\u00eda la primera vez que el argentino inicie una temporada como titular, con todo lo que eso significa (ensayos en la pretemporada, voz y voto en las decisiones sobre el auto, etc), ya que en 2024 y 2025 comenz\u00f3 como suplente de Logan Sargeant (en Williams) y Jack Doohan (en Alpine), respectivamente.<\/p>\n<p>Alpine es una de las pocas escuder\u00edas que a\u00fan no confirm\u00f3 oficialmente a su dupla de pilotos para el a\u00f1o que viene. La continuidad de Gasly, su n\u00famero uno, es una obviedad, pero el compa\u00f1ero del franc\u00e9s a\u00fan estaba en el aire.<\/p>\n<p>Y es que los resultados de Colapinto han sido dispares. Tuvo un comienzo dif\u00edcil, que hizo pensar a muchos que la decisi\u00f3n de bajar a Doohan quiz\u00e1s hab\u00eda sido apresurada, pero en las \u00faltimas seis o siete carreras el piloto argentino ha estado a la par de su compa\u00f1ero de equipo, igualando y hasta mejorando su ritmo de carrera. En alguna ocasi\u00f3n incluso su equipo le dio la orden de dejar pasar a Gasly porque este no pod\u00eda superarlo auto a auto y en el GP de Estados Unidos decidi\u00f3 pasar al franc\u00e9s contra toda orden de equipo al considerar que era m\u00e1s veloz.<\/p>\n<p>Lo cierto es que el auto ha estado muy lejos de los primeros planos. Alpine es la peor escuder\u00eda de la parrilla. Ni Doohan ni Colapinto han podido <a href=\"https:\/\/www.formula1.com\/en\/results\/2025\/drivers\">sumar puntos<\/a> y Gasly ha hecho milagros para conseguir 20. Todo parece apuntar al pr\u00f3ximo a\u00f1o, cuando los cambios en las reglas y las configuraciones de los monoplazas puedan provocar un movimiento importante entre las escuder\u00edas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c07. 11. 25. \u00bfYa hiciste las cuentas?\u201d. Con esa enigm\u00e1tica publicaci\u00f3n en redes sociales, la escuder\u00eda Alpine de F\u00f3rmula 1 parece haber quedado a un paso de anunciar la continuidad del argentino Franco Colapinto para 2026. La fotograf\u00eda que lleva los tres n\u00fameros parece referirse a una fecha, 7 de noviembre de 2025 (en Argentina [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468109","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u201c07. 11. 25. \u00bfYa hiciste las cuentas?\u201d. Con esa enigm\u00e1tica publicaci\u00f3n en redes sociales, la escuder\u00eda Alpine de F\u00f3rmula 1 parece haber quedado a un paso de anunciar la continuidad del argentino Franco Colapinto para 2026. La fotograf\u00eda que lleva los tres n\u00fameros parece referirse a una fecha, 7 de noviembre de 2025 (en Argentina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T03:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?\",\"datePublished\":\"2025-11-07T03:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\",\"name\":\"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-07T03:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias","og_description":"\u201c07. 11. 25. \u00bfYa hiciste las cuentas?\u201d. Con esa enigm\u00e1tica publicaci\u00f3n en redes sociales, la escuder\u00eda Alpine de F\u00f3rmula 1 parece haber quedado a un paso de anunciar la continuidad del argentino Franco Colapinto para 2026. La fotograf\u00eda que lleva los tres n\u00fameros parece referirse a una fecha, 7 de noviembre de 2025 (en Argentina [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-07T03:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/"},"author":{"name":"","@id":""},"headline":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?","datePublished":"2025-11-07T03:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","name":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-07T03:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un enigm\u00e1tico posteo de Alpine despert\u00f3 la ilusi\u00f3n en Argentina: \u00bfconfirma la renovaci\u00f3n de Colapinto en la F\u00f3rmula 1?","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/formula-uno-alpine-renovacion-franco-colapinto-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-07T03:03:51Z","datePublished":"2025-11-07T03:03:51Z","dateModified":"2025-11-07T03:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un enigm\\u00e1tico posteo de Alpine despert\\u00f3 la ilusi\\u00f3n en Argentina: \\u00bfconfirma la renovaci\\u00f3n de Colapinto en la F\\u00f3rmula 1?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/formula-uno-alpine-renovacion-franco-colapinto-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/06\\\/formula-uno-alpine-renovacion-franco-colapinto-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-07T03:03:51Z\",\"datePublished\":\"2025-11-07T03:03:51Z\",\"dateModified\":\"2025-11-07T03:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462731,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/23\/orlando-rios-desde-monaco-colapinto-es-un-piloto-muy-rapido-un-piloto-en-construccion\/","url_meta":{"origin":1468109,"position":0},"title":"Orlando R\u00edos, desde M\u00f3naco: &#171;Colapinto es un piloto muy r\u00e1pido, un proyecto en construcci\u00f3n&#187;","author":"","date":"mayo 23, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Orlando R\u00edos, enviado de la revista Campeones y del diario La Naci\u00f3n a la F\u00f3rmula 1 en M\u00f3naco, habl\u00f3 este viernes con Regreso CNN con Mariana Arias y Pepe Gil Vidal sobre la participaci\u00f3n del piloto argentino Franco Colapinto en su segunda carrera con el equipo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457400,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/09\/franco-colapinto-alpine-piloto-de-reserva-formula-uno-orix\/","url_meta":{"origin":1468109,"position":1},"title":"El argentino Franco Colapinto se une a la escuder\u00eda Alpine como piloto de reserva","author":"","date":"enero 9, 2025","format":false,"excerpt":"Con un breve y contundente \u201cVamos Franco\u201d publicado en su cuenta de X, la escuder\u00eda Alpine confirm\u00f3 la incorporaci\u00f3n del argentino Franco Colapinto como piloto de reserva para la temporada 2025 de F\u00f3rmula Uno.Colapinto llega desde Williams, equipo con el que sum\u00f3 puntos en la m\u00e1xima categor\u00eda del automovilismo, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469225,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/12\/12\/franco-colapinto-temporada-2026-formula-1-orix\/","url_meta":{"origin":1468109,"position":2},"title":"\u00bfQu\u00e9 puede esperar Franco Colapinto en la temporada 2026 de la F\u00f3rmula 1?","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Desde que era un ni\u00f1o peque\u00f1o, uno de los sue\u00f1os de Franco Colapinto era correr en la F\u00f3rmula 1 y representar a su pa\u00eds, Argentina.En septiembre de 2024, ese sue\u00f1o se volvi\u00f3 realidad tras su debut en carrera en el Gran Premio de Italia junto a la escuder\u00eda Williams. Y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455698,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/11\/09\/posibilidades-franco-colapinto-continuar-formula-1-2025-orix\/","url_meta":{"origin":1468109,"position":3},"title":"Las posibilidades de Franco Colapinto de continuar en la F\u00f3rmula 1 en 2025","author":"","date":"noviembre 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol)\u00a0 --\u00a0 Los rumores sobre la continuidad del piloto argentino Franco Colapinto en la F\u00f3rmula 1 en 2025 sonaron m\u00e1s fuerte que nunca el fin de semana pasado, durante el Gran Premio de Sao Paulo, en Brasil. La visita de Christian Horner, jefe de equipo de la escuder\u00eda Red\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450918,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/07\/06\/argentino-vuelve-participar-gran-premio-formula-1-orix\/","url_meta":{"origin":1468109,"position":4},"title":"Despu\u00e9s de 23 a\u00f1os, un argentino vuelve a participar en un Gran Premio de F\u00f3rmula 1","author":"","date":"julio 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"Disfrut\u00e9 cada vuelta, cada curva\". Esas fueron las primeras impresiones de Franco Colapinto apenas descendi\u00f3 del Williams FW46 tras su debut en una pr\u00e1ctica en la F\u00f3rmula 1, en el circuito de Silverstone en Inglaterra. El piloto se convirti\u00f3 en el primer argentino en participar de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468130,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/franco-colapinto-alpine-2026-brasil-gp-orix\/","url_meta":{"origin":1468109,"position":5},"title":"F\u00f3rmula 1: Franco Colapinto se mantiene con Alpine para 2026, mientras el t\u00edtulo de pilotos se empieza a definir en Brasil","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"El piloto argentino Franco Colapinto renov\u00f3 contrato con la escuder\u00eda Alpine y competir\u00e1 en el Campeonato Mundial de la F\u00f3rmula 1 de 2026.El anuncio se realiz\u00f3 en el Aut\u00f3dromo Jos\u00e9 Carlos Pace, conocido como Interlagos y sede del Gran Premio de Sao Paulo, la vig\u00e9sima primera carrera de la temporada.Colapinto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468109"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468109\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}