{"id":1468122,"date":"2025-11-07T07:03:40","date_gmt":"2025-11-07T15:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/"},"modified":"2025-11-07T07:03:40","modified_gmt":"2025-11-07T15:03:40","slug":"mls-gerardo-martino-atlanta-united-luis-suarez-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","title":{"rendered":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n"},"content":{"rendered":"<p>El Atlanta United de la Major League Soccer (MLS) anunci\u00f3 el regreso de Gerardo \u201cTata\u201d Martino.<\/p>\n<p>El entrenador argentino que tendr\u00e1 contrato hasta el 2027, seg\u00fan lo comunic\u00f3 el equipo de la principal liga de f\u00fatbol estadounidense, envi\u00f3 un saludo a los seguidores en las redes sociales del club y expres\u00f3 su alegr\u00eda por la vuelta.<\/p>\n<p>\u201cTata es un entrenador excepcional que marc\u00f3 la pauta de la excelencia en nuestro club y contribuy\u00f3 a consolidar nuestra identidad en la Major League Soccer (MLS)\u201d, declar\u00f3 en un comunicado el propietario del Atlanta United, Arthur M. Blank.<\/p>\n<p>Martino tom\u00f3 las riendas del Atlanta United en 2017 y gener\u00f3 una revoluci\u00f3n futbol\u00edstica con figuras latinoamericanas como el venezolano Josef Mart\u00ednez y el paraguayo Miguel Almir\u00f3n.<\/p>\n<p>Bajo su mando, el equipo gan\u00f3 el t\u00edtulo en 2018 de la MLS y el argentino fue elegido como entrenador del a\u00f1o.<\/p>\n<p>La consagraci\u00f3n del Atlanta United rompi\u00f3 con la sequ\u00eda de t\u00edtulos para la ciudad en deportes grandes desde 1995, cuando los Braves ganaron la Serie Mundial.<\/p>\n<p>Despu\u00e9s de Atlanta se march\u00f3 a dirigir a la selecci\u00f3n mexicana y regres\u00f3 a la MLS para tomar las riendas del Inter Miami con Lionel Messi a bordo.<\/p>\n<p>Su paso por el Inter fue destacado: con ese equipo conquist\u00f3 la Leagues Cup en 2023 y el Supporter\u2019s Shield en 2024.<\/p>\n<p>Sin embargo, perdi\u00f3 la final de la US Cup 2023 ante el Dynamo de Houston y no pudo avanzar en la postemporada de la MLS Cup 2024, al ser eliminado por su exequipo Atlanta United.<\/p>\n<p>El Tata tiene una amplia trayectoria como entrenador en pa\u00edses como Argentina, Paraguay y Espa\u00f1a, al igual que en selecciones, tras haber dirigido a Paraguay, Argentina y M\u00e9xico.<\/p>\n<p>La MLS decidi\u00f3 suspender de oficio al delantero del Inter Miami Luis Su\u00e1rez.<\/p>\n<p>El castigo lleg\u00f3 luego de que el comit\u00e9 disciplinario de la liga estadounidense analizara una acci\u00f3n del juego, donde Su\u00e1rez propin\u00f3 una agresi\u00f3n a un rival que fue revisada por el VAR, pero no fue sancionada por el \u00e1rbitro durante el partido.<\/p>\n<p>\u201cEl Comit\u00e9 Disciplinario de la MLS ha suspendido al delantero del Inter Miami CF Luis Su\u00e1rez por un partido y le ha impuesto una multa de cantidad no revelada (\u2026) por conducta violenta en el minuto 71 del partido del Inter Miami contra el Nashville SC el 1 de noviembre\u201d, <a href=\"https:\/\/www.mlssoccer.com\/news\/inter-miami-s-luis-suarez-fined-suspended-by-mls-disciplinary-committee\">dice el comunicado de la liga.<\/a><\/p>\n<p>En el minuto 71 del mencionado encuentro, Su\u00e1rez golpe\u00f3 con su tal\u00f3n la entrepierna del defensa hondure\u00f1o Andy Najar.<\/p>\n<p>Esta sanci\u00f3n podr\u00eda marcar el fin de la temporada para el delantero uruguayo si el Inter queda eliminado ante Nashville de la serie de postemporada que se encuentra igualada.<\/p>\n<p>El Inter, por su parte, reaccion\u00f3 y acept\u00f3 la sanci\u00f3n de su delantero, pero expres\u00f3 cierta preocupaci\u00f3n ante la decisi\u00f3n que ya en su momento hab\u00eda sido analizada por el VAR.<\/p>\n<p>\u201cEl club manifiesta su preocupaci\u00f3n por el precedente generado al rearbitrar una jugada de partido ya juzgada por el equipo arbitral y el VAR, y su confianza en que en el futuro el mismo criterio ser\u00e1 aplicado en todas las situaciones de juego que se produzcan, en cualquier partido y por parte de cualquier equipo\u201d, asegur\u00f3 el<a href=\"https:\/\/es.intermiamicf.com\/noticias\/comunicado-de-inter-miami-cf-sobre-la-suspension-de-un-partido-a-luis-suarez\"> Inter en su comunicado.<\/a><\/p>\n<p>Es la segunda vez, en menos de dos meses, que el jugador sudamericano recibe una sanci\u00f3n.<\/p>\n<p>En septiembre fue castigado con seis partidos de la Leagues Cup y tres de la MLS tras escupir a un miembro de seguridad del Seattle Sounders, al t\u00e9rmino de la final de la Leagues Cup, en la que el Inter Miami cay\u00f3 por 3-0.<\/p>\n<p>La postemporada de la MLS sigue su curso y este fin de semana se definen los clasificados a las semifinales de conferencia.<\/p>\n<p>Solo tres equipos han logrado su pase y cinco quedan por definir su clasificaci\u00f3n en igual n\u00famero de series empatadas.<\/p>\n<p> El \u00fanico duelo definido es el de Vancouver contra el LAFC, mientras Philadelphia espera el rival entre Charlotte y New York City.<\/p>\n<p><strong>Viernes: <\/strong>Chartlotte vs. New York City.<\/p>\n<p><strong>S\u00e1bado: <\/strong>Minnesota vs. Seattle, Cincinnati vs. Columbus, Inter vs. Nashville.<\/p>\n<p><strong>Domingo: <\/strong>San Diego vs. Portland.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Atlanta United de la Major League Soccer (MLS) anunci\u00f3 el regreso de Gerardo \u201cTata\u201d Martino. El entrenador argentino que tendr\u00e1 contrato hasta el 2027, seg\u00fan lo comunic\u00f3 el equipo de la principal liga de f\u00fatbol estadounidense, envi\u00f3 un saludo a los seguidores en las redes sociales del club y expres\u00f3 su alegr\u00eda por la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468122","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Atlanta United de la Major League Soccer (MLS) anunci\u00f3 el regreso de Gerardo \u201cTata\u201d Martino. El entrenador argentino que tendr\u00e1 contrato hasta el 2027, seg\u00fan lo comunic\u00f3 el equipo de la principal liga de f\u00fatbol estadounidense, envi\u00f3 un saludo a los seguidores en las redes sociales del club y expres\u00f3 su alegr\u00eda por la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T15:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n\",\"datePublished\":\"2025-11-07T15:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\"},\"wordCount\":744,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\",\"name\":\"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-07T15:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","og_locale":"es_ES","og_type":"article","og_title":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias","og_description":"El Atlanta United de la Major League Soccer (MLS) anunci\u00f3 el regreso de Gerardo \u201cTata\u201d Martino. El entrenador argentino que tendr\u00e1 contrato hasta el 2027, seg\u00fan lo comunic\u00f3 el equipo de la principal liga de f\u00fatbol estadounidense, envi\u00f3 un saludo a los seguidores en las redes sociales del club y expres\u00f3 su alegr\u00eda por la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-07T15:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/"},"author":{"name":"","@id":""},"headline":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n","datePublished":"2025-11-07T15:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/"},"wordCount":744,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","name":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-07T15:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"MLS al d\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\u00e1rez podr\u00eda despedirse de la temporada tras suspensi\u00f3n","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-07T15:03:40Z","datePublished":"2025-11-07T15:03:40Z","dateModified":"2025-11-07T15:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"MLS al d\\u00eda: Gerardo Martino regresa al Atlanta United, mientras Luis Su\\u00e1rez podr\\u00eda despedirse de la temporada tras suspensi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/07\\\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/07\\\/mls-gerardo-martino-atlanta-united-luis-suarez-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-07T15:03:40Z\",\"datePublished\":\"2025-11-07T15:03:40Z\",\"dateModified\":\"2025-11-07T15:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455930,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/11\/19\/gerardo-tata-martino-deja-el-inter-miami-orix\/","url_meta":{"origin":1468122,"position":0},"title":"Gerardo &#171;Tata&#187; Martino dejar\u00e1 el Inter Miami, seg\u00fan una fuente del club","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Argumentando razones personales, Gerardo \u201cTata\u201d Martino dejar\u00e1 de ser esta semana el entrenador del Inter Miami, dijo este martes una fuente del club de f\u00fatbol a CNN.Se espera que la renuncia se oficialice el viernes en una rueda de prensa con la presencia del propio Martino y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471498,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/20\/lionel-messi-inter-miami-camino-corona-mls-orix\/","url_meta":{"origin":1468122,"position":1},"title":"Lionel Messi est\u00e1 disponible y junto al Inter Miami comienzan su camino a una nueva corona en la MLS","author":"","date":"febrero 20, 2026","format":false,"excerpt":"La temporada 2026 de la Major League Soccer (MLS) no pudo tener un primer plato m\u00e1s atractivo para comenzar el a\u00f1o de la Copa del Mundo.El campe\u00f3n vigente, el Inter Miami, con Lionel Messi a la cabeza, realizar\u00e1 la primera de las cinco visitas que tiene pautadas para comenzar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455716,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/11\/10\/messi-inter-miami-se-despiden-mls-derrota-ante-atlanta-united-trax\/","url_meta":{"origin":1468122,"position":2},"title":"Lionel Messi y el Inter de Miami se despiden de las eliminatorias de la MLS con una sorprendente derrota ante el Atlanta United","author":"","date":"noviembre 10, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi y el Inter Miami tuvieron una temporada regular de r\u00e9cord, terminando con un r\u00e9cord de 74 puntos y llev\u00e1ndose a casa el Supporters' Shield.Sin embargo, los favoritos a la Copa se estrellaron en las eliminatorias de la Major League Soccer (MLS) tras una sorprendente derrota por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444523,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/27\/gerardo-tata-martino-y-su-tercer-ciclo-como-dt-de-messi-su-carrera-como-jugador-y-como-tecnico-y-a-que-juegan-sus-equipos\/","url_meta":{"origin":1468122,"position":3},"title":"Gerardo \u201cTata\u201d Martino y su tercer ciclo como DT de Messi: su carrera como jugador y como t\u00e9cnico y a qu\u00e9 juegan sus equipos","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"Qu\u00e9 linda sorpresa que haya sido elegido Martino\", asegur\u00f3 en 2013 Lionel Messi cuando supo que el Tata ser\u00eda su nuevo entrenador en el FC Barcelona. Diez a\u00f1os despu\u00e9s, jugador y t\u00e9cnico est\u00e1n otra vez juntos, embarcados en un nuevo desaf\u00edo: volver\u00e1n a compartir vestuario en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456104,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/11\/26\/javier-mascherano-messi-nuevo-entrenador-inter-miami-trax\/","url_meta":{"origin":1468122,"position":4},"title":"Javier Mascherano, excompa\u00f1ero de Lionel Messi, es el nuevo entrenador del Inter Miami","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN) \u2014 Javier Mascherano, excapit\u00e1n de la selecci\u00f3n de Argentina, ser\u00e1 el nuevo entrenador del Inter Miami, seg\u00fan anunci\u00f3 este martes el club.Mascherano se reencontrar\u00e1 con el legendario delantero Lionel Messi, con quien jug\u00f3 en la selecci\u00f3n nacional y pas\u00f3 casi ocho a\u00f1os en el Barcelona.Este ser\u00e1 el primer cargo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458884,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/18\/cuentas-pendientes-lionel-messi-inter-miami-orix\/","url_meta":{"origin":1468122,"position":5},"title":"Las cuentas pendientes de Lionel Messi y el Inter Miami","author":"","date":"febrero 18, 2025","format":false,"excerpt":"Antes de cada partido, el Chase Stadium de Fort Lauderdale es una fiesta. La algarab\u00eda de la gente, emocionada por ver a Lionel Messi al frente del Inter Miami, se entrelaza con la m\u00fasica a todo volumen de Pitbull y Miami Sound Machine, la banda sonora que indica que lleg\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468122"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468122\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}