{"id":1468138,"date":"2025-11-07T18:03:40","date_gmt":"2025-11-08T02:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/"},"modified":"2025-11-07T18:03:40","modified_gmt":"2025-11-08T02:03:40","slug":"acoso-sheinbaum-expone-violencia-mujeres-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","title":{"rendered":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico"},"content":{"rendered":"<p>Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/05\/mexico\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\">parece tocarle el pecho e intenta darle un beso.<\/a> Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia de g\u00e9nero a la que se ven expuestas miles de mujeres, seg\u00fan datos oficiales.<\/p>\n<p>As\u00ed lo dijo la propia Sheinbaum: \u201cSi esto le pasa a la presidenta, \u00bfqu\u00e9 les pasar\u00e1 a todas las j\u00f3venes de nuestro pa\u00eds?\u201d.<\/p>\n<p>Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/05\/mexico\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\">parece tocarle el pecho e intenta darle un beso.<\/a> Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia de g\u00e9nero a la que se ven expuestas miles de mujeres, seg\u00fan datos oficiales.<\/p>\n<p>M\u00e1s del 70 % de las mexicanas mayores de 15 a\u00f1os han vivido al menos un tipo de violencia, como sexual (49,7 %), psicol\u00f3gica (casi un 52 %) o f\u00edsica (34,7 %), seg\u00fan <a href=\"https:\/\/www.inegi.org.mx\/tablerosestadisticos\/vcmm\/\">datos<\/a> del Instituto Nacional de Estad\u00edstica y Geograf\u00eda de M\u00e9xico (Inegi).<\/p>\n<p>Un <a href=\"https:\/\/efs.efeservicios.com\/texto\/onu-condena-acoso-sheinbaum-urge-normalizar-violencia-mujeres-mexico\/55018447069\">15,5%<\/a> de las mujeres en M\u00e9xico han vivido acoso sexual, manoseo, exhibicionismo o intento de violaci\u00f3n. Esta cifra es cinco veces mayor que la de los hombres, que se sit\u00faa en 3,2 %, seg\u00fan una <a href=\"https:\/\/www.inegi.org.mx\/contenidos\/saladeprensa\/aproposito\/2024\/EAP_VCM_24.pdf\">encuesta<\/a> del Inegi basada en datos de 2021. Un 64,8 % de los casos ocurri\u00f3 en una calle o un parque, como pas\u00f3 con Sheinbaum. La presidenta incluso cont\u00f3 que a los 12 a\u00f1os padeci\u00f3 acoso en el transporte p\u00fablico, \u201ccomo lo viven muchas mujeres\u201d.<\/p>\n<p>Un dato muy relevante es que el 94 % de mujeres que fueron v\u00edctimas de acoso dijeron que no denunciaron, en respuesta a la mencionada encuesta.<\/p>\n<p>\u201cYo creo que todas cuando vemos una imagen como esa (la del acoso a Sheinbaum) recordamos experiencias de acoso que nos han sucedido\u201d, dijo a CNN Catalina Ruiz Navarro, activista feminista y periodista colombiana radicada en Ciudad de M\u00e9xico, autora de \u201cLas mujeres que luchan se encuentran: manual de feminismo pop latinoamericano\u201d.<\/p>\n<p>\u201cDefinitivamente hay un problema muy grande de violencia en M\u00e9xico, exacerbado por una cultura muy machista y por una situaci\u00f3n de narcotr\u00e1fico, bandas criminales, crimen organizado, que una cosa alimenta a la otra. Pero yo creo que mujeres de todo el mundo han vivido una circunstancia como esa, en la calle, en una fiesta, y es muy impresionante verlo en una mujer con tanto poder como Claudia\u201d, a\u00f1ade Ruiz Navarro.<\/p>\n<p>Sobre la reacci\u00f3n de Sheinbaum, la especialista sostiene que Sheinbaum hizo \u201clo que hacemos todas, que es paralizarnos, sonre\u00edr, tratar de tener una reacci\u00f3n que no agrande el problema. Porque sentimos el miedo\u201d.<\/p>\n<p>Sheinbaum dijo el mi\u00e9rcoles que present\u00f3 una denuncia por acoso, y las autoridades indicaron que un hombre fue detenido vinculado al hecho. CNN contact\u00f3 a la Fiscal\u00eda de la Ciudad de M\u00e9xico para preguntar si el hombre ya tiene representaci\u00f3n jur\u00eddica y c\u00f3mo se declara. Hasta ahora no obtuvo respuesta.<\/p>\n<p>En este contexto, este jueves, el Gobierno de M\u00e9xico <a href=\"https:\/\/efs.efeservicios.com\/texto\/mexico-plan-abuso-sexual-caso-acoso-sheinbaum\/55018456150\">anunci\u00f3 un plan integral<\/a> contra el abuso sexual con el objetivo de agilizar las denuncias, mejorar la atenci\u00f3n a las v\u00edctimas y promover un cambio cultural. Este delito no est\u00e1 homologado en los c\u00f3digos penales de las 32 entidades del pa\u00eds.<\/p>\n<p>\u201cQueremos decirle a todas las mujeres mexicanas, ni\u00f1as, j\u00f3venes, mujeres en general que no est\u00e1n solas, que cuando vivan alg\u00fan tipo de violencia es importante denunciarlo y que sepan que hoy hay una presidenta que les cuida y una secretar\u00eda que trabaja todos los d\u00edas para ello\u201d, dijo la secretaria de las Mujeres, Citlalli Hern\u00e1ndez, al presentar la estrategia desde Palacio Nacional.<\/p>\n<p>El objetivo del plan es que el abuso sexual sea considerado delito grave en todos los estados y \u201cfortalecer toda la respuesta institucional, sobre todo en la atenci\u00f3n y procuraci\u00f3n de justicia hacia las mujeres\u201d, adem\u00e1s de lograr que \u201clas mujeres se sientan m\u00e1s seguras, que denuncien de manera mucho m\u00e1s \u00e1gil\u201d, seg\u00fan detall\u00f3 Hern\u00e1ndez.<\/p>\n<p>Entre otras medidas, adem\u00e1s de la tipificaci\u00f3n del delito, el plan incluye la \u201cpromoci\u00f3n de la denuncia\u201d, al reforzar la l\u00ednea de atenci\u00f3n 079 opci\u00f3n 1 e impulsar la capacitaci\u00f3n de ministerios p\u00fablicos, fiscal\u00edas y jueces para que act\u00faen con perspectiva de g\u00e9nero.<\/p>\n<p>Tambi\u00e9n incluye la Capacitaci\u00f3n del personal y conductores de transporte p\u00fablico para saber c\u00f3mo actuar ante denuncias y prevenir situaciones de riesgo. Adem\u00e1s de la promoci\u00f3n de campa\u00f1as de concientizaci\u00f3n.<\/p>\n<p>En su presentaci\u00f3n, Hern\u00e1ndez resalt\u00f3 la importancia de que los hombres revisen \u201ctodas esas conductas, actitudes, acciones que se han normalizado\u201d, pero que \u201cen realidad son parte de expresiones machistas o que incomodan o que violentan a una mujer\u201d.<\/p>\n<p>La especialista Ruiz Navarro considera que lo m\u00e1s importante es promover el cambio cultural. \u201cEntiendo que las medidas penales sirven para poner en el tema en conversaci\u00f3n, sirve para que toque capacitar jueces, polic\u00edas y eso puede ser algo positivo. Pero no creo que sea la manera necesariamente de resolverlo\u201d, sostiene.<\/p>\n<p>Lo ocurrido es un hecho \u201creprobable\u201d que debe ser nombrado y denunciado, <a href=\"https:\/\/www.reuters.com\/world\/americas\/groping-mexicos-president-highlights-violence-against-women-2025-11-05\/#:~:text=HARASSMENTAna%20Yeli%20Perez,day%2C%22%20she%20said.\">dijo a Reuters<\/a> Ana Yeli P\u00e9rez, del Observatorio Ciudadano Nacional sobre Feminicidio, y agreg\u00f3 es tambi\u00e9n \u201csignificativo y simb\u00f3lico de lo que las mujeres experimentan a diario\u201d.<\/p>\n<p>El acoso sexual a Sheinbaum vuelve a poner el tema de la violencia contra las mujeres en la agenda nacional, consider\u00f3 la analista.<\/p>\n<p>En tanto la Organizaci\u00f3n de las Naciones Unidas (ONU) en M\u00e9xico <a href=\"https:\/\/x.com\/ONUMujeresMX\/status\/1986078783707734332\">conden\u00f3 el episodio<\/a> e hizo un llamado a \u201cno normalizar ni minimizar\u201d la violencia contra las mujeres en el pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, parece tocarle el pecho e intenta darle un beso. Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia de g\u00e9nero a la que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468138","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, parece tocarle el pecho e intenta darle un beso. Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia de g\u00e9nero a la que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-08T02:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico\",\"datePublished\":\"2025-11-08T02:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\"},\"wordCount\":1037,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\",\"name\":\"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-08T02:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias","og_description":"Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, parece tocarle el pecho e intenta darle un beso. Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia de g\u00e9nero a la que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-08T02:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/"},"author":{"name":"","@id":""},"headline":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico","datePublished":"2025-11-08T02:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/"},"wordCount":1037,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","name":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-08T02:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-08T02:03:40Z","datePublished":"2025-11-08T02:03:40Z","dateModified":"2025-11-08T02:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El acoso que denunci\\u00f3 Sheinbaum saca a la luz la violencia a la que est\\u00e1n expuestas muchas mujeres en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/07\\\/acoso-sheinbaum-expone-violencia-mujeres-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/07\\\/acoso-sheinbaum-expone-violencia-mujeres-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-08T02:03:40Z\",\"datePublished\":\"2025-11-08T02:03:40Z\",\"dateModified\":\"2025-11-08T02:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468058,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","url_meta":{"origin":1468138,"position":0},"title":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, habl\u00f3 este mi\u00e9rcoles sobre el acoso sexual que sufri\u00f3 cuando se dirig\u00eda a una reuni\u00f3n a pie desde su residencia en Palacio Nacional el martes, cuando un hombre se le acerc\u00f3 al tiempo que la mandataria saludaba a otras personas.\u201cDecidimos irnos caminando (de Palacio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472769,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/01\/mexico-deja-atras-ee-uu-presidenta-mujer-meryl-streep-claudia-sheinbaum-orix\/","url_meta":{"origin":1468138,"position":1},"title":"Meryl Streep elogi\u00f3 a Sheinbaum y la presidenta de M\u00e9xico respondi\u00f3: &#171;Es la mejor actriz del mundo&#187;","author":"","date":"abril 1, 2026","format":false,"excerpt":"La actriz estadounidense Meryl Streep reconoci\u00f3 el rol de la presidenta de M\u00e9xico, Claudia Sheinbaum, y consider\u00f3 que el pa\u00eds \u201cha dejado atr\u00e1s\u201d a Estados Unidos al tener una presidenta mujer, la primera en m\u00e1s de 200 a\u00f1os de historia.\u201cClaro que M\u00e9xico ha dejado atr\u00e1s a los Estados Unidos teniendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468584,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/21\/claudia-sheinbaum-fatima-bosch-miss-universo-mexico-orix\/","url_meta":{"origin":1468138,"position":2},"title":"Sheinbaum sobre Bosch, ganadora de Miss Universo: &#171;Me gust\u00f3 de ella que levanta la voz cuando siente que hay una injusticia&#187;","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, elogi\u00f3 a la ganadora de Miss Universo, la mexicana F\u00e1tima Bosch.\u201cA m\u00ed me gust\u00f3 de ella que levanta la voz cuando siente que hay una injusticia\u201d, dijo Sheinbaum en su conferencia de prensa matutina.\u201cEso es un ejemplo para todas y todos los mexicanos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457872,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/25\/sheinbaum-solidaridad-violencia-sinaloa-protestas-orix\/","url_meta":{"origin":1468138,"position":3},"title":"Sheinbaum expresa solidaridad a familia de ni\u00f1os muertos por violencia en Sinaloa tras protestas frente a Congreso local","author":"","date":"enero 25, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, expres\u00f3 este viernes su \u201csolidaridad\u201d con los familiares de un hombre y sus dos hijos, quienes murieron en medio de un ataque ocurrido en Sinaloa, en el noroeste del pa\u00eds, y dijo que pedir\u00eda a la secretaria de Gobernaci\u00f3n, Rosa Icela Rodr\u00edguez, que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450879,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/07\/04\/quien-es-ariadna-montiel-reyes-secretaria-bienestar-mexico-orix\/","url_meta":{"origin":1468138,"position":4},"title":"\u00bfQui\u00e9n es Ariadna Montiel Reyes, quien se mantiene como secretaria de Bienestar de M\u00e9xico?","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Ariadna Montiel Reyes permanecer\u00e1 como titular de la Secretar\u00eda de Bienestar de M\u00e9xico, dependencia que gestiona los programas sociales de la administraci\u00f3n, en el Gobierno de Claudia Sheinbaum, quien asumir\u00e1 como presidenta el pr\u00f3ximo 1 de octubre y confirm\u00f3 este jueves su continuidad en el cargo.\"No solamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464317,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/08\/mexicano-murio-desaparecido-inundaciones-texas-orix\/","url_meta":{"origin":1468138,"position":5},"title":"Un ciudadano mexicano muri\u00f3 y otro est\u00e1 desaparecido tras las inundaciones en Texas, confirm\u00f3 Sheinbaum","author":"","date":"julio 8, 2025","format":false,"excerpt":"Este martes, la presidenta de M\u00e9xico, Claudia Sheinbaum, inform\u00f3 durante su conferencia de prensa matutina que un ciudadano mexicano muri\u00f3 y otro est\u00e1 desaparecido en las inundaciones en Texas, Estados Unidos, donde se han registrado m\u00e1s de 100 muertes.La presidenta tambi\u00e9n aprovech\u00f3 la oportunidad para felicitar a Protecci\u00f3n Civil y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468138"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468138\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}