{"id":1468158,"date":"2025-11-08T16:03:55","date_gmt":"2025-11-09T00:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/"},"modified":"2025-11-08T16:03:55","modified_gmt":"2025-11-09T00:03:55","slug":"vuelos-cancelados-retrasados-cierre-gobierno-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","title":{"rendered":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno"},"content":{"rendered":"<p>Viajeros descontentos en todo Estados Unidos enfrentar\u00e1n m\u00e1s interrupciones en sus planes este fin de semana, ya que las aerol\u00edneas cancelan cientos de vuelos adicionales y los retrasos contin\u00faan acumul\u00e1ndose debido a la escasez de personal de controladores de tr\u00e1fico a\u00e9reo en medio de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/06\/eeuu\/recorte-vuelos-pasajeros-precios-trax\">un cierre del Gobierno sin final a la vista.<\/a><\/p>\n<p>M\u00e1s de 1.700 vuelos han sido cancelados desde el viernes hasta el domingo, seg\u00fan datos de Cirium, ya que las aerol\u00edneas comienzan a implementar una reducci\u00f3n del 4 % en los vuelos nacionales en 40 de los aeropuertos m\u00e1s concurridos, seg\u00fan lo ordenado por la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s).<\/p>\n<p>Sin embargo, los recortes \u2014que seg\u00fan las autoridades est\u00e1n destinados a mantener la seguridad en los viajes a\u00e9reos mientras algunos de los controladores de tr\u00e1fico a\u00e9reo y revisores de seguridad federales que no reciben sus cheques de pago no se presentan a trabajar\u2014 no han evitado miles de retrasos de varias horas que han dejado a los pasajeros luchando por encontrar la forma de llegar a sus destinos.<\/p>\n<p>\u201cNo quiero quedarme varada en el aeropuerto durmiendo en un banco\u201d, dijo Michele Cuthbert, de Columbus, Ohio, a <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fapnews.com%2Farticle%2Fflight-cancellations-government-shutdown-what-to-know-dea56ba97690b43397a96289f5f949e8&#038;data=05%7C02%7Candrea.saintmartin%40cnn.com%7C52c57f9341174b461a9208de1f10c345%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638982354198537495%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=0s94wunGE19Jw%2FQv6H6ZxJEJQ%2F%2FBt92COzsKIZHWffE%3D&#038;reserved=0\">Associated Press<\/a>, expresando su preocupaci\u00f3n por posibles cancelaciones de vuelos antes de su viaje a Dallas.<\/p>\n<p>Durante la pr\u00f3xima semana, las aerol\u00edneas aumentar\u00e1n las cancelaciones de vuelos hasta un 10 % para el pr\u00f3ximo viernes si el cierre del Gobierno no se resuelve. Sin embargo, los viajeros pueden seguir viendo recortes en vuelos incluso si el Gobierno reabre la pr\u00f3xima semana, ya que la orden de la FAA requiere que las aerol\u00edneas cancelen los vuelos con varios d\u00edas de anticipaci\u00f3n.<\/p>\n<p>Esto es lo que debe saber si planea viajar por aire en los pr\u00f3ximos d\u00edas:<\/p>\n<p>Una orden de emergencia de la FAA emitida el jueves exige a las aerol\u00edneas reducir el tr\u00e1fico en un 4 %, lo que result\u00f3 en unas 800 cancelaciones el viernes, cifra que super\u00f3 las 1.000 durante el d\u00eda, de acuerdo con FlightAware.<\/p>\n<p>Este s\u00e1bado hubo m\u00e1s de 1.000 cancelaciones y al menos 5.000 retrasos, seg\u00fan el sitio de seguimiento de vuelos. Para el domingo ya se hab\u00edan cancelado m\u00e1s de 840 vuelos.<\/p>\n<p>Las interrupciones se deben principalmente a la falta de personal de controladores y a la orden de la FAA, aunque tambi\u00e9n hay recortes no relacionados.<\/p>\n<p>La FAA indica que las aerol\u00edneas deber\u00e1n recortar un 6 % de sus vuelos a esos 40 aeropuertos el martes, un 8 % el jueves y un 10 % el viernes siguiente si el cierre persiste.<\/p>\n<p>El porcentaje podr\u00eda aumentar hasta un 15-20 % si el estancamiento en el Congreso no termina pronto, advirti\u00f3 el secretario de Transporte, Sean Duffy.<\/p>\n<p>Los efectos de las interrupciones podr\u00edan continuar incluso si el Congreso llega a un acuerdo, ya que los controladores podr\u00edan no regresar de inmediato.<\/p>\n<p>La FAA report\u00f3 35 casos de falta de personal en instalaciones de control a\u00e9reo este s\u00e1bado. Los problemas persisten a pesar de las cancelaciones, que buscan aliviar la carga de los controladores.<\/p>\n<p>Aaron Barker, empleado de la Administraci\u00f3n de Seguridad en el Transporte y l\u00edder sindical, dijo que ni \u00e9l ni sus colegas pueden cubrir sus gastos durante el cierre, ya que los controladores han perdido su segundo salario consecutivo.<\/p>\n<p>\u201cHoy habr\u00eda sido d\u00eda de pago para los agentes\u201d, dijo a CNN. \u201cAhora tengo miembros que est\u00e1n siendo desalojados. Algunos ya lo fueron. Una familia incluso duerme en su auto con ni\u00f1os\u201d.<\/p>\n<p>Las principales aerol\u00edneas han anunciado m\u00e1s cancelaciones para cientos de vuelos programados durante el fin de semana, tras m\u00e1s de 1.000 cancelaciones el viernes.<\/p>\n<p>American Airlines eliminar\u00e1 220 vuelos de su programaci\u00f3n del s\u00e1bado, inform\u00f3 un portavoz.<\/p>\n<p>United Airlines anunci\u00f3 cientos de cancelaciones hasta principios de la pr\u00f3xima semana: 168 el s\u00e1bado, 158 el domingo, 190 el lunes y 269 el martes.<\/p>\n<p>Southwest Airlines cancelar\u00e1 unos 100 vuelos este s\u00e1bado y 150 el domingo para cumplir con la orden de la FAA, y ya ha reducido su programaci\u00f3n en un 4 % hasta el lunes en 34 de los 117 aeropuertos que atiende.<\/p>\n<p>La mayor\u00eda de los vuelos de Southwest no se ver\u00e1n afectados, y la aerol\u00ednea est\u00e1 contactando directamente a los clientes afectados.<\/p>\n<p>Aerol\u00edneas como American, Delta, Southwest, United y Frontier est\u00e1n eximiendo de cargos a los pasajeros que deseen cambiar sus boletos.<\/p>\n<p>Algunos directivos, como el de Frontier, recomiendan reservar un boleto alternativo en otra aerol\u00ednea para evitar quedar varados.<\/p>\n<p>Para reducir molestias, evita vuelos con escalas y reserva directamente con la aerol\u00ednea. Revisa el estado de tu vuelo, considera un seguro de viaje y recuerda que tienes derecho a un reembolso completo si tu vuelo nacional es cancelado o se retrasa m\u00e1s de tres horas.<\/p>\n<p>Los aeropuertos m\u00e1s transitados del pa\u00eds han sido los m\u00e1s afectados por el cierre, con retrasos y cancelaciones que contin\u00faan durante el fin de semana.<\/p>\n<p>Los tres principales aeropuertos del \u00e1rea de Nueva York presentan retrasos de varias horas este s\u00e1bado por falta de personal, de acuerdo con la FAA.<\/p>\n<p>Se emiti\u00f3 una restricci\u00f3n temporal para vuelos a Newark Liberty este s\u00e1bado, tras retrasos promedio de m\u00e1s de cuatro horas.<\/p>\n<p>En LaGuardia, los vuelos de llegada se retrasaron casi una hora y las salidas, 75 minutos en promedio. En John F. Kennedy, los retrasos de llegada superan las 2.5 horas y las salidas, 105 minutos.<\/p>\n<p>En Atlanta, los vuelos de llegada tienen un retraso promedio de cinco horas y media.<\/p>\n<p>El viernes, el aeropuerto Reagan de Washington fue el m\u00e1s afectado, con casi 80 vuelos cancelados y la mitad de las llegadas retrasadas.<\/p>\n<p>Chicago O\u2019Hare, Hartsfield-Jackson de Atlanta, Denver y Dallas-Fort Worth tambi\u00e9n registraron decenas de cancelaciones y cientos de retrasos. En la costa oeste, Los \u00c1ngeles y San Francisco reportaron problemas similares.<\/p>\n<p>Otros aeropuertos afectados incluyen Boston Logan, Phoenix Sky Harbor, Seattle-Tacoma y Orlando International.<\/p>\n<p>A nivel internacional, \u00c1msterdam Schiphol, Toronto Pearson y Tokio Haneda tambi\u00e9n reportaron cancelaciones de dos d\u00edgitos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viajeros descontentos en todo Estados Unidos enfrentar\u00e1n m\u00e1s interrupciones en sus planes este fin de semana, ya que las aerol\u00edneas cancelan cientos de vuelos adicionales y los retrasos contin\u00faan acumul\u00e1ndose debido a la escasez de personal de controladores de tr\u00e1fico a\u00e9reo en medio de un cierre del Gobierno sin final a la vista. M\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468158","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias\" \/>\n<meta property=\"og:description\" content=\"Viajeros descontentos en todo Estados Unidos enfrentar\u00e1n m\u00e1s interrupciones en sus planes este fin de semana, ya que las aerol\u00edneas cancelan cientos de vuelos adicionales y los retrasos contin\u00faan acumul\u00e1ndose debido a la escasez de personal de controladores de tr\u00e1fico a\u00e9reo en medio de un cierre del Gobierno sin final a la vista. M\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T00:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno\",\"datePublished\":\"2025-11-09T00:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\",\"name\":\"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-09T00:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias","og_description":"Viajeros descontentos en todo Estados Unidos enfrentar\u00e1n m\u00e1s interrupciones en sus planes este fin de semana, ya que las aerol\u00edneas cancelan cientos de vuelos adicionales y los retrasos contin\u00faan acumul\u00e1ndose debido a la escasez de personal de controladores de tr\u00e1fico a\u00e9reo en medio de un cierre del Gobierno sin final a la vista. M\u00e1s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-09T00:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/"},"author":{"name":"","@id":""},"headline":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno","datePublished":"2025-11-09T00:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","name":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-09T00:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Viajeros enfrentan retrasos este fin de semana mientras las aerol\u00edneas reducen cientos de vuelos por el cierre del Gobierno","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/vuelos-cancelados-retrasados-cierre-gobierno-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-09T00:03:55Z","datePublished":"2025-11-09T00:03:55Z","dateModified":"2025-11-09T00:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Viajeros enfrentan retrasos este fin de semana mientras las aerol\\u00edneas reducen cientos de vuelos por el cierre del Gobierno\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/08\\\/vuelos-cancelados-retrasados-cierre-gobierno-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/08\\\/vuelos-cancelados-retrasados-cierre-gobierno-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-09T00:03:55Z\",\"datePublished\":\"2025-11-09T00:03:55Z\",\"dateModified\":\"2025-11-09T00:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468142,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/viajeros-ee-uu-retrasos-cancelaciones-vuelos-trax\/","url_meta":{"origin":1468158,"position":0},"title":"Viajeros en EE.UU. enfrentan retrasos cada vez mayores por las cancelaciones de cientos de vuelos. Esto es lo que debes saber","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Viajeros descontentos en Estados Unidos enfrentar\u00e1n m\u00e1s alteraciones en sus planes este fin de semana, ya que las aerol\u00edneas han cancelado cientos de vuelos adicionales y las demoras siguen aumentando debido a la escasez de controladores de tr\u00e1fico a\u00e9reo como consecuencia de un cierre del Gobierno sin final aparente.M\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472378,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/20\/viajeros-ee-uu-enfrentan-espera-aeropuertos-tsa-trax\/","url_meta":{"origin":1468158,"position":1},"title":"Viajeros en EE.UU. enfrentan tiempos de espera impredecibles en aeropuertos debido a que agentes de la TSA no reciben sueldo","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Largas colas que duraban dos horas recibieron en la madrugada de este viernes a los viajeros en el control principal de seguridad de la TSA (Administraci\u00f3n de Seguridad del Transporte) en el Aeropuerto Internacional Hartsfield-Jackson de Atlanta.Las autoridades de la terminal informaron tiempos de espera de 120 minutos antes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443663,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/14\/aerolineas-cancelan-miles-de-vuelos-en-estados-unidos-por-el-clima-invernal\/","url_meta":{"origin":1468158,"position":2},"title":"Aerol\u00edneas cancelan miles de vuelos en Estados Unidos por el clima invernal","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) --\u00a0 Las aerol\u00edneas todav\u00eda se est\u00e1n recuperando de un intenso d\u00eda de tormentas que azot\u00f3 la mitad este de los Estados Unidos el viernes y vio a todos los estados bajo alg\u00fan tipo de alerta relacionada con el clima.Hasta las primeras horas de la tarde del s\u00e1bado, m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1410568,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/07\/04\/record-de-viajeros-retrasos-y-cancelaciones-provocan-caos-en-aeropuertos\/","url_meta":{"origin":1468158,"position":3},"title":"R\u00e9cord de viajeros, retrasos y cancelaciones provocan caos en aeropuertos","author":"agomez","date":"julio 4, 2022","format":false,"excerpt":"El fin de semana largo por las festividades del D\u00eda de la Independencia generaron una gran movilidad de viajeros.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443664,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/01\/14\/aerolineas-cancelan-miles-de-vuelos-en-estados-unidos-por-el-clima-invernal-2\/","url_meta":{"origin":1468158,"position":4},"title":"Aerol\u00edneas cancelan miles de vuelos en Estados Unidos por el clima invernal","author":"agomez","date":"enero 14, 2024","format":false,"excerpt":"(CNN) --\u00a0 Las aerol\u00edneas todav\u00eda se est\u00e1n recuperando de un intenso d\u00eda de tormentas que azot\u00f3 la mitad este de los Estados Unidos el viernes y vio a todos los estados bajo alg\u00fan tipo de alerta relacionada con el clima.Hasta las primeras horas de la tarde del s\u00e1bado, m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468105,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/06\/recorte-vuelos-pasajeros-precios-trax\/","url_meta":{"origin":1468158,"position":5},"title":"Recortar los vuelos en Estados Unidos tendr\u00e1 enormes repercusiones entre los pasajeros y en los precios de los boletos","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Los pasajeros de aerol\u00edneas ya estaban enfrentando tarifas m\u00e1s altas y aviones llenos esta temporada navide\u00f1a. Pero los dolores de cabeza podr\u00edan empeorar mucho m\u00e1s a medida que el cierre del Gobierno provoque reducciones de vuelos en los principales aeropuertos.El Gobierno de Trump reducir\u00e1 el tr\u00e1fico en 40 aeropuertos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468158"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468158\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}