{"id":1468161,"date":"2025-11-08T19:03:42","date_gmt":"2025-11-09T03:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/"},"modified":"2025-11-08T19:03:42","modified_gmt":"2025-11-09T03:03:42","slug":"conductor-disparos-patrulla-fronteriza-chicago-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","title":{"rendered":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos"},"content":{"rendered":"<p>Un conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza de Estados Unidos que realizaban una operaci\u00f3n migratoria en Chicago este s\u00e1bado antes de huir, dijo el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) a CNN en un comunicado.<\/p>\n<p>La agencia dijo que los agentes de la Patrulla Fronteriza realizaban \u201coperaciones de control migratorio cerca de la Calle 26 y la Avenida Kedzie en Chicago, Illinois, cuando un hombre desconocido que conduc\u00eda un Jeep negro dispar\u00f3 contra los agentes y huy\u00f3 del lugar\u201d.<\/p>\n<p>\u201cEl atacante y el veh\u00edculo siguen pr\u00f3fugos\u201d, dijo el DHS.<\/p>\n<p> \u201cUn n\u00famero desconocido de agitadores tambi\u00e9n arroj\u00f3 una lata de pintura y ladrillos a los veh\u00edculos de la Patrulla Fronteriza\u201d, indica el comunicado.<\/p>\n<p>El Departamento de Polic\u00eda de Chicago dijo que no hubo reportes de personas heridas por disparos tras el incidente.<\/p>\n<p>\u201cNo se reportaron heridos de bala\u201d, declar\u00f3 el Departamento de Polic\u00eda de Chicago, que respondi\u00f3 al incidente y ayud\u00f3 a asegurar la zona, en un comunicado emitido la tarde de este s\u00e1bado.<\/p>\n<p>\u201cEl incidente no es aislado y refleja una tendencia creciente y peligrosa de violencia y obstrucci\u00f3n\u201d, afirm\u00f3 el DHS.<\/p>\n<p>CNN se ha puesto en contacto con el DHS para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza de Estados Unidos que realizaban una operaci\u00f3n migratoria en Chicago este s\u00e1bado antes de huir, dijo el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) a CNN en un comunicado. La agencia dijo que los agentes de la Patrulla Fronteriza realizaban \u201coperaciones de control [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468161","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza de Estados Unidos que realizaban una operaci\u00f3n migratoria en Chicago este s\u00e1bado antes de huir, dijo el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) a CNN en un comunicado. La agencia dijo que los agentes de la Patrulla Fronteriza realizaban \u201coperaciones de control [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T03:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos\",\"datePublished\":\"2025-11-09T03:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\"},\"wordCount\":248,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\",\"name\":\"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-09T03:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias","og_description":"Un conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza de Estados Unidos que realizaban una operaci\u00f3n migratoria en Chicago este s\u00e1bado antes de huir, dijo el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) a CNN en un comunicado. La agencia dijo que los agentes de la Patrulla Fronteriza realizaban \u201coperaciones de control [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-09T03:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/"},"author":{"name":"","@id":""},"headline":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos","datePublished":"2025-11-09T03:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/"},"wordCount":248,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","name":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-09T03:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conductor dispar\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/08\/conductor-disparos-patrulla-fronteriza-chicago-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-09T03:03:42Z","datePublished":"2025-11-09T03:03:42Z","dateModified":"2025-11-09T03:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conductor dispar\\u00f3 contra agentes de la Patrulla Fronteriza durante operativo migratorio en Chicago; no se reportaron heridos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/08\\\/conductor-disparos-patrulla-fronteriza-chicago-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/08\\\/conductor-disparos-patrulla-fronteriza-chicago-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-09T03:03:42Z\",\"datePublished\":\"2025-11-09T03:03:42Z\",\"dateModified\":\"2025-11-09T03:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471876,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/04\/tiroteo-patrulla-fronteriza-el-paso-texas-trax\/","url_meta":{"origin":1468161,"position":0},"title":"Muere un conductor que huy\u00f3 de un control de la Patrulla Fronteriza en Texas y dispar\u00f3 a los agentes, seg\u00fan las autoridades","author":"","date":"marzo 4, 2026","format":false,"excerpt":"Un hombre muri\u00f3 el mi\u00e9rcoles despu\u00e9s de huir de un control de la Patrulla Fronteriza de EE.UU. cerca de El Paso, Texas, y disparar a las fuerzas del orden, inform\u00f3 una portavoz de la oficina del sheriff local.El hombre comenz\u00f3 a disparar primero contra los agentes que realizaban inspecciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467198,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/08\/residentes-chicago-intervienen-patrulla-fronteriza-detengan-hombre-trax\/","url_meta":{"origin":1468161,"position":1},"title":"Residentes de Chicago intervienen para impedir que agentes de la Patrulla Fronteriza detengan a un hombre","author":"","date":"octubre 8, 2025","format":false,"excerpt":"Agentes de la Patrulla Fronteriza no pudieron detener a un hombre en Chicago el s\u00e1bado despu\u00e9s de que intervinieron testigos, seg\u00fan muestra una grabaci\u00f3n del hecho.En el video, compartido con CNN, se ve a dos agentes enmascarados de la Patrulla Fronteriza de Estados Unidos tirando de un hombre no identificado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470532,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/27\/tiroteo-patrulla-fronteriza-arizona-trax\/","url_meta":{"origin":1468161,"position":2},"title":"Una persona est\u00e1 en estado cr\u00edtico tras intercambiar disparos con agentes de la Patrulla Fronteriza en Arizona, seg\u00fan fuente","author":"","date":"enero 27, 2026","format":false,"excerpt":"Un sospechoso se encuentra en condici\u00f3n cr\u00edtica despu\u00e9s de intercambiar disparos con agentes de la Patrulla Fronteriza de EE.UU. y disparar a un helic\u00f3ptero federal durante una persecuci\u00f3n en Arizona, cerca de la frontera entre EE.UU. y M\u00e9xico, la madrugada del martes, seg\u00fan una fuente federal de las fuerzas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464285,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/07\/hombre-abre-fuego-patrulla-fronteriza-en-texas-trax\/","url_meta":{"origin":1468161,"position":3},"title":"Un hombre abre fuego contra un puesto de la Patrulla Fronteriza en Texas y muere en intercambio de disparos","author":"","date":"julio 7, 2025","format":false,"excerpt":"Un hombre con un rifle y equipo t\u00e1ctico abri\u00f3 fuego contra agentes de la ley este lunes por la ma\u00f1ana en un puesto de la Patrulla Fronteriza en McAllen, Texas, y fue abatido durante un intercambio de disparos con la Patrulla Fronteriza y la polic\u00eda local, dijo el Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470032,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/13\/acusan-hombre-herido-portland-agresion-agravada-trax\/","url_meta":{"origin":1468161,"position":4},"title":"Acusan a hombre herido por la Patrulla Fronteriza en Portland de agresi\u00f3n agravada por presunto ataque con veh\u00edculo a agente","author":"","date":"enero 13, 2026","format":false,"excerpt":"Un agente de la Patrulla Fronteriza dispar\u00f3 a dos personas en Portland, Oregon, durante una parada de tr\u00e1fico porque, seg\u00fan las autoridades, estaban asociadas con una pandilla venezolana.El enfrentamiento fue uno m\u00e1s de una serie de incidentes similares que involucran a funcionarios federales y que han dejado a los estadounidenses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469918,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/08\/dos-personas-recibieron-disparos-portland-agentes-trax\/","url_meta":{"origin":1468161,"position":5},"title":"Dos personas recibieron disparos de agentes federales en Portland, Oregon, seg\u00fan la polic\u00eda local","author":"","date":"enero 8, 2026","format":false,"excerpt":"Dos personas est\u00e1n hospitalizadas tras ser baleadas por agentes federales, inform\u00f3 la Polic\u00eda de Portland en un comunicado.El tiroteo involucr\u00f3 a agentes de la Patrulla Fronteriza que realizaban una detenci\u00f3n vehicular a una pareja casada, de acuerdo con una fuente policial. El esposo fue herido en el brazo y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468161"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468161\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}