{"id":1468217,"date":"2025-11-11T03:03:39","date_gmt":"2025-11-11T11:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/"},"modified":"2025-11-11T03:03:39","modified_gmt":"2025-11-11T11:03:39","slug":"mueren-12-explosion-tribunal-islamabad-pakistan-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","title":{"rendered":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n"},"content":{"rendered":"<p>Una inusual explosi\u00f3n en la capital de Pakist\u00e1n, Islamabad, dej\u00f3 12 muertos y 20 heridos este martes, seg\u00fan inform\u00f3 a la prensa el Instituto de Ciencias M\u00e9dicas del pa\u00eds.<\/p>\n<p>Una fuente de seguridad en Pakist\u00e1n declar\u00f3 a CNN que la explosi\u00f3n cerca del Tribunal Superior de la ciudad se est\u00e1 investigando como un ataque suicida.<\/p>\n<p>Islamabad requiere un alto nivel de seguridad para entrar y salir de la ciudad, con zonas de seguridad espec\u00edficas en toda la capital.<\/p>\n<p>La explosi\u00f3n tuvo lugar en el estacionamiento del concurrido complejo judicial de la ciudad, en un distrito lleno de oficinas gubernamentales de alto rango.<\/p>\n<p>Nadie se ha atribuido la responsabilidad del ataque todav\u00eda, pero una declaraci\u00f3n emitida por una fuente de seguridad a CNN afirma que personas asociadas con los talibanes afganos e India habr\u00edan sido los responsables.<\/p>\n<p>El atentado se produce menos de un d\u00eda despu\u00e9s de que un grupo de militantes asaltara un colegio militar en el noroeste de Pakist\u00e1n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una inusual explosi\u00f3n en la capital de Pakist\u00e1n, Islamabad, dej\u00f3 12 muertos y 20 heridos este martes, seg\u00fan inform\u00f3 a la prensa el Instituto de Ciencias M\u00e9dicas del pa\u00eds. Una fuente de seguridad en Pakist\u00e1n declar\u00f3 a CNN que la explosi\u00f3n cerca del Tribunal Superior de la ciudad se est\u00e1 investigando como un ataque suicida. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468217","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una inusual explosi\u00f3n en la capital de Pakist\u00e1n, Islamabad, dej\u00f3 12 muertos y 20 heridos este martes, seg\u00fan inform\u00f3 a la prensa el Instituto de Ciencias M\u00e9dicas del pa\u00eds. Una fuente de seguridad en Pakist\u00e1n declar\u00f3 a CNN que la explosi\u00f3n cerca del Tribunal Superior de la ciudad se est\u00e1 investigando como un ataque suicida. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T11:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n\",\"datePublished\":\"2025-11-11T11:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\"},\"wordCount\":205,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\",\"name\":\"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T11:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias","og_description":"Una inusual explosi\u00f3n en la capital de Pakist\u00e1n, Islamabad, dej\u00f3 12 muertos y 20 heridos este martes, seg\u00fan inform\u00f3 a la prensa el Instituto de Ciencias M\u00e9dicas del pa\u00eds. Una fuente de seguridad en Pakist\u00e1n declar\u00f3 a CNN que la explosi\u00f3n cerca del Tribunal Superior de la ciudad se est\u00e1 investigando como un ataque suicida. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-11T11:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/"},"author":{"name":"","@id":""},"headline":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n","datePublished":"2025-11-11T11:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/"},"wordCount":205,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","name":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T11:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mueren al menos 12 personas en una explosi\u00f3n frente a un tribunal en Islamabad, Pakist\u00e1n","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T11:03:39Z","datePublished":"2025-11-11T11:03:39Z","dateModified":"2025-11-11T11:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mueren al menos 12 personas en una explosi\\u00f3n frente a un tribunal en Islamabad, Pakist\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/11\\\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/11\\\/mueren-12-explosion-tribunal-islamabad-pakistan-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T11:03:39Z\",\"datePublished\":\"2025-11-11T11:03:39Z\",\"dateModified\":\"2025-11-11T11:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455696,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/11\/08\/pakistan-estacion-trenes-ataque-bomba-trax\/","url_meta":{"origin":1468217,"position":0},"title":"M\u00e1s de veinte muertos en explosi\u00f3n en estaci\u00f3n de tren en Pakist\u00e1n; militantes de Baluchist\u00e1n reclaman responsabilidad","author":"","date":"noviembre 8, 2024","format":false,"excerpt":"(CNN) -- Al menos 24 personas han muerto y otras 53 resultaron heridas tras una poderosa explosi\u00f3n en una estaci\u00f3n de tren en el suroeste de Pakist\u00e1n el viernes, inform\u00f3 la polic\u00eda.La explosi\u00f3n ocurri\u00f3 en una plataforma de la estaci\u00f3n en la ciudad de Quetta alrededor de las 9 a.m.,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462622,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/21\/tres-ninos-dos-adultos-mueren-ataque-suicida-atobus-escolar-pakistan-trax\/","url_meta":{"origin":1468217,"position":1},"title":"Tres ni\u00f1os y dos adultos mueren en un ataque suicida contra un autob\u00fas escolar en Pakist\u00e1n","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Un ataque suicida en un autob\u00fas escolar en el suroeste de Pakist\u00e1n mat\u00f3 el mi\u00e9rcoles a tres estudiantes de una escuela dirigida por militares, dijeron las autoridades. El incidente pone en relieve el deterioro de la situaci\u00f3n de seguridad en la regi\u00f3n.La explosi\u00f3n ocurri\u00f3 en la ciudad de Khuzdar, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470931,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/06\/pakistan-explosion-mezquita-muertes-trax\/","url_meta":{"origin":1468217,"position":2},"title":"Explosi\u00f3n causa varias muertes en una mezquita de Pakist\u00e1n, seg\u00fan la polic\u00eda","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Una explosi\u00f3n arras\u00f3 este viernes una mezquita musulmana chiita en la capital de Pakist\u00e1n, Islamabad, provocando la muerte de varios fieles, inform\u00f3 la polic\u00eda.La explosi\u00f3n sacudi\u00f3 la mezquita durante la oraci\u00f3n del viernes, seg\u00fan el agente de polic\u00eda Zafar Iqbal. \u201cHemos trasladado a varias personas a hospitales. No puedo decir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472275,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/17\/afganistan-denuncia-ataque-hospital-pakistan-reux\/","url_meta":{"origin":1468217,"position":3},"title":"Afganist\u00e1n dice que m\u00e1s de 400 personas murieron en ataque paquistan\u00ed contra un hospital en Kabul; Islamabad niega acusaci\u00f3n","author":"","date":"marzo 17, 2026","format":false,"excerpt":"M\u00e1s de 400 personas murieron y 265 resultaron heridas en un ataque a\u00e9reo perpetrado por Pakist\u00e1n contra un hospital de rehabilitaci\u00f3n para usuarios de drogas en Kabul, declar\u00f3 este martes un portavoz del gobierno talib\u00e1n afgano, lo que representa una marcada escalada en el conflicto entre ambos pa\u00edses vecinos.Pakist\u00e1n rechaz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461923,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/03\/india-prohibe-importacion-productos-pakistan-trax\/","url_meta":{"origin":1468217,"position":4},"title":"India proh\u00edbe la importaci\u00f3n de todos los productos de Pakist\u00e1n en medio de crecientes tensiones","author":"","date":"mayo 3, 2025","format":false,"excerpt":"India prohibi\u00f3 la importaci\u00f3n de todos los productos de Pakist\u00e1n en medio de la creciente tensi\u00f3n entre ambos pa\u00edses, seg\u00fan inform\u00f3 este viernes el Ministerio de Comercio e Industria de India.La importaci\u00f3n de todos los productos, directos o indirectos, originarios de Pakist\u00e1n ha sido \u201cprohibida con efecto inmediato\u201d en \u201cinter\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461766,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/04\/29\/pakistan-afirma-informacion-india-atacara-36-horas-trax\/","url_meta":{"origin":1468217,"position":5},"title":"Pakist\u00e1n afirma tener &#171;informaci\u00f3n cre\u00edble&#187; de que India atacar\u00e1 en 36 horas","author":"","date":"abril 29, 2025","format":false,"excerpt":"Las tensiones entre India y Pakist\u00e1n han aumentado a\u00fan m\u00e1s despu\u00e9s de que un alto cargo paquistan\u00ed afirmara a primera hora del mi\u00e9rcoles que dispone de \u201cinformaci\u00f3n cre\u00edble\u201d de que Nueva Delhi llevar\u00e1 a cabo una acci\u00f3n militar contra Islamabad en los pr\u00f3ximos dos d\u00edas.\u201cPakist\u00e1n tiene informaci\u00f3n cre\u00edble de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468217"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468217\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}