{"id":1468242,"date":"2025-11-11T16:03:48","date_gmt":"2025-11-12T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/"},"modified":"2025-11-11T16:03:48","modified_gmt":"2025-11-12T00:03:48","slug":"trump-amenaza-demanda-bbc-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","title":{"rendered":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?"},"content":{"rendered":"<p>El ataque de Donald Trump contra los medios de comunicaci\u00f3n se internacionaliz\u00f3 esta semana, ya que amenaz\u00f3 con demandar a la BBC por US$ 1.000 millones debido a un documental en el que, seg\u00fan su abogado, hay ediciones \u201cfalsas, difamatorias, maliciosas, denigrantes e incendiarias\u201d de un discurso que el presidente de EE.UU. pronunci\u00f3 antes del asalto al Capitolio el 6 de enero de 2021.<\/p>\n<p>La amenaza podr\u00eda llevar a la BBC a un abismo financiero y ha profundizado la peor crisis de la radiodifusora p\u00fablica brit\u00e1nica en la historia reciente, generando dudas sobre su futuro en un panorama medi\u00e1tico y pol\u00edtico polarizado.<\/p>\n<p>Esto es lo que necesitas saber.<\/p>\n<p>En octubre de 2024, d\u00edas antes de las elecciones presidenciales de EE.UU., la BBC emiti\u00f3 un documental titulado \u201cTrump: \u00bfuna segunda oportunidad?\u201d<\/p>\n<p>En ese momento, la pel\u00edcula recibi\u00f3 cr\u00edticas positivas en el Reino Unido \u2013 The Guardian la elogi\u00f3 por tomarse en serio a Trump y el fen\u00f3meno MAGA \u2013 pero atrajo poca atenci\u00f3n en Estados Unidos.<\/p>\n<p>Y as\u00ed podr\u00eda haberse quedado, de no haber sido por un ahora notorio memorando filtrado, que \u2013 entre una letan\u00eda de otras quejas sobre la programaci\u00f3n de la BBC \u2013 revel\u00f3 c\u00f3mo, en una peque\u00f1a secci\u00f3n, el documental hab\u00eda empalmado comentarios hechos con casi una hora de diferencia por Trump durante su infame discurso del 6 de enero.<\/p>\n<p>\u201cVamos a caminar hacia el Capitolio y yo estar\u00e9 all\u00ed con ustedes y lucharemos. Lucharemos con todas nuestras fuerzas y si no luchan con todas sus fuerzas, ya no tendr\u00e1n pa\u00eds\u201d aparece diciendo Trump.<\/p>\n<p>En realidad, Trump dijo: \u201cvamos a caminar hacia el Capitolio y vamos a animar a nuestros valientes senadores y congresistas y congresistas mujeres\u201d. Cincuenta y cuatro minutos despu\u00e9s, les dijo a sus seguidores que lucharan \u201ccon todas sus fuerzas\u201d<\/p>\n<p>En una carta dirigida a un comit\u00e9 parlamentario el lunes, el presidente de la BBC, Samir Shah, se disculp\u00f3 por lo que calific\u00f3 de \u201cerror de juicio\u201d respecto a c\u00f3mo se edit\u00f3 el discurso de Trump, lo que admiti\u00f3 que \u201cs\u00ed dio la impresi\u00f3n de un llamado directo a la acci\u00f3n violenta\u201d.<\/p>\n<p>La semana pasada, un memorando filtrado a la junta directiva de la BBC de Michael Prescott, exasesor externo del comit\u00e9 de est\u00e1ndares editoriales de la radiodifusora, fue publicado por The Telegraph \u2013 un peri\u00f3dico brit\u00e1nico, con una l\u00ednea editorial de derecha, que ha sido hostil a la BBC durante mucho tiempo.<\/p>\n<p>En su memorando, elaborado este verano, Prescott expuso una larga lista de supuestas deficiencias en la cobertura informativa de la BBC, desde un presunto sesgo antiisrael\u00ed en su servicio en \u00e1rabe hasta una inclinaci\u00f3n excesivamente progresista en su cobertura de las personas transg\u00e9nero y sus derechos.<\/p>\n<p>Tambi\u00e9n critic\u00f3 la edici\u00f3n \u201ccompletamente enga\u00f1osa\u201d del discurso de Trump en la pel\u00edcula, que se emiti\u00f3 como parte de la serie documental de la BBC \u201cPanorama\u201d. \u201cSi se permite a los periodistas de la BBC editar videos para hacer que la gente \u2018diga\u2019 cosas que en realidad nunca dijeron, \u00bfde qu\u00e9 sirven las directrices de la corporaci\u00f3n, por qu\u00e9 se deber\u00eda confiar en la BBC y ad\u00f3nde llevar\u00e1 todo esto?\u201d escribi\u00f3.<\/p>\n<p>Experiodistas de la BBC han criticado a la radiodifusora por no enfrentar los cuestionamientos al documental que Shah, el presidente, dijo que hab\u00edan sido planteados por Prescott y otros en una reuni\u00f3n del comit\u00e9 de est\u00e1ndares editoriales en enero.<\/p>\n<p>\u201cConoc\u00edan el problema desde hac\u00eda 10 meses antes de que los peri\u00f3dicos publicaran el informe de Prescott\u201d, escribi\u00f3 Mark Urban, editor diplom\u00e1tico del programa \u201cNewsnight\u201d de BBC Two hasta el a\u00f1o pasado, en Substack. \u201cEs un error grave, \u00bfpor qu\u00e9 no lo abordaron antes?\u201d<\/p>\n<p>Incluso cuando se public\u00f3 el art\u00edculo de The Telegraph, la BBC tard\u00f3 en actuar. Katie Razzall, editora de medios de la BBC, inform\u00f3 el domingo que una declaraci\u00f3n sobre el documental hab\u00eda estado \u201clista para publicarse durante d\u00edas\u201d. En cambio, la junta directiva de la BBC decidi\u00f3 disculparse en la carta de Shah al comit\u00e9 parlamentario el lunes. Esa vacilaci\u00f3n parece haber sido perjudicial. Solo unas horas despu\u00e9s de que se publicara la carta de Shah, la BBC inform\u00f3 sobre la amenaza de demanda de Trump.<\/p>\n<p>S\u00ed. El director general de la BBC, Tim Davie, y la directora ejecutiva de BBC News, Deborah Turness, renunciaron el domingo, en medio de una tormenta creciente por los problemas de parcialidad y sesgo planteados en el memorando Prescott.<\/p>\n<p>En una declaraci\u00f3n, Davie admiti\u00f3 que \u201cha habido algunos errores\u201d por los cuales ten\u00eda que asumir la \u201cresponsabilidad \u00faltima\u201d, pero no lleg\u00f3 a mencionar el documental \u201cPanorama\u201d. En un discurso al personal de la BBC el lunes, Davie sugiri\u00f3 que su decisi\u00f3n ten\u00eda tanto que ver con la presi\u00f3n acumulada de cinco a\u00f1os en el puesto m\u00e1s alto como con el manejo del memorando Prescott en s\u00ed.<\/p>\n<p>Turness, quien supervisaba la divisi\u00f3n de noticias, dijo que la controversia en torno a la pel\u00edcula hab\u00eda \u201calcanzado un punto en el que est\u00e1 causando da\u00f1o a la BBC\u201d.<\/p>\n<p>\u201cLa responsabilidad recae en m\u00ed\u201d, dijo en su declaraci\u00f3n de renuncia.<\/p>\n<p>A pesar de admitir errores, Turness respondi\u00f3 a las acusaciones de sesgo deliberado. \u201cQuiero dejar absolutamente claro que las recientes acusaciones de que BBC News es institucionalmente parcial son incorrectas\u201d, afirm\u00f3.<\/p>\n<p>La emisora recibe financiamiento p\u00fablico pero no es propiedad del Estado. Una \u201ccarta real\u201d, que estableci\u00f3 la BBC como una corporaci\u00f3n p\u00fablica en 1927, garantiza su libertad editorial e independencia del Gobierno.<\/p>\n<p>Se financia mediante una \u201ctasa de licencia\u201d, un pago anual de \u00a3 174.50 (US$ 299) que se cobra a cualquier hogar que vea televisi\u00f3n en vivo, grabe programas o use BBC iPlayer, el servicio de streaming de la emisora. Es un delito penal no pagar la tasa.<\/p>\n<p>Desde su fundaci\u00f3n, la misi\u00f3n de la BBC ha sido \u201cactuar en inter\u00e9s p\u00fablico\u201d y proporcionar \u201ccontenido imparcial, de alta calidad y distintivo\u201d para \u201cinformar, educar y entretener\u201d a su audiencia.<\/p>\n<p>De manera m\u00e1s profunda, la BBC funciona como una especie de pegamento nacional, situ\u00e1ndose junto a instituciones como la monarqu\u00eda, que supuestamente deben estar por encima de la pol\u00edtica y proporcionar un punto de referencia com\u00fan para todo el pa\u00eds.<\/p>\n<p>Nominalmente, s\u00ed. La tasa de licencia se supone que libera a la BBC de las restricciones comerciales que enfrentan otros medios, lo que lleva a muchos a adaptar su contenido a la inclinaci\u00f3n pol\u00edtica de su audiencia.<\/p>\n<p>Pero la postura de imparcialidad se ha vuelto dif\u00edcil de mantener. En los \u00faltimos a\u00f1os, la BBC ha enfrentado acusaciones de sesgo tanto de la izquierda como de la derecha, y un panorama pol\u00edtico polarizado y un ecosistema medi\u00e1tico fragmentado han hecho m\u00e1s dif\u00edcil alcanzar la ambici\u00f3n cada vez m\u00e1s legendaria de representar una voz singular y no partidista a trav\u00e9s de los televisores y radios del pa\u00eds.<\/p>\n<p>La BBC ha sido criticada durante mucho tiempo por sus rivales medi\u00e1ticos comerciales, que le reprochan su estatus protegido y financiado p\u00fablicamente; y por pol\u00edticos, mayormente de derecha, que se oponen a la tasa de licencia obligatoria y piensan que la BBC deber\u00eda competir por su audiencia en el libre mercado como sus competidores.<\/p>\n<p>\u201cLa BBC ha sido institucionalmente parcial durante d\u00e9cadas\u201d, dijo el lunes Nigel Farage, l\u00edder del incipiente partido antiinmigraci\u00f3n Reform UK, pidiendo \u201cuna BBC mucho m\u00e1s reducida\u201d.<\/p>\n<p>Farage dijo que habl\u00f3 con Trump sobre el informe \u201cPanorama\u201d la semana pasada. \u201c\u00c9l solo me dijo: \u2018\u00bfas\u00ed es como tratan a su mejor aliado?\u2019\u201d<\/p>\n<p>En una carta a la BBC, un abogado de Trump dijo que la emisora difam\u00f3 al presidente al editar \u201cintencionada y enga\u00f1osamente\u201d la pel\u00edcula \u201cPanorama\u201d para mostrarlo interfiriendo en las elecciones presidenciales. Aunque el equipo de Trump no se\u00f1al\u00f3 el error en ese momento, el abogado dijo que esto caus\u00f3 al entonces candidato \u201cun da\u00f1o financiero y reputacional abrumador\u201d.<\/p>\n<p>Trump quiere que la BBC retire el documental, emita una disculpa y lo \u201ccompense adecuadamente\u201d por el supuesto da\u00f1o causado. Se le ha dado a la BBC hasta el viernes a las 5 p.m., hora de Miami, para responder.<\/p>\n<p>La carta dice que si no se cumplen esas demandas, \u201cel presidente Trump no tendr\u00e1 otra alternativa que hacer valer sus derechos legales y equitativos, todos los cuales se reservan expresamente y son irrenunciables, incluso mediante la presentaci\u00f3n de una acci\u00f3n legal por no menos de US$ 1.000 millones en da\u00f1os\u201d.<\/p>\n<p>Probablemente no. La BBC recaud\u00f3 \u00a3 5.9 mil millones (US$ 7.8 mil millones) en ingresos en el \u00faltimo a\u00f1o fiscal, principalmente de los pagos de la licencia (\u00a3 3.8 mil millones), el resto proviene de actividades comerciales.<\/p>\n<p>Cerr\u00f3 el a\u00f1o con reservas de efectivo de \u00a3 477 millones (US$ 627 millones), un poco m\u00e1s de la mitad de la cantidad por la que Trump amenaz\u00f3 con demandar.<\/p>\n<p>Cualquier pago a Trump, incluso uno significativamente menor que su extravagante demanda, aumentar\u00eda las presiones financieras que enfrenta la BBC. Con la carta real expirando en 2027, su administraci\u00f3n podr\u00eda haber sido optimista de que el Gobierno laborista favorable a la BBC de Keir Starmer la renovar\u00eda felizmente por otra d\u00e9cada. La m\u00e1s reciente crisis podr\u00eda hacer que el Gobierno sea cauteloso a la hora de pedir al p\u00fablico brit\u00e1nico que siga pagando por un servicio que muchos han llegado a resentir en una era de alternativas de streaming m\u00e1s baratas.<\/p>\n<p>En el Reino Unido y en muchos estados de EE.UU., un caso de difamaci\u00f3n debe iniciarse dentro de los 12 meses posteriores a la supuesta difamaci\u00f3n. En Florida, una v\u00edctima tiene 24 meses para presentar una queja.<\/p>\n<p>Aun as\u00ed, presentar el caso en Florida complicar\u00e1 el argumento de Trump, seg\u00fan Mark Stephens, un abogado de medios del Reino Unido en Howard Kennedy, una firma en Londresd<\/p>\n<p>\u201cLa pregunta clave es: \u00bfda\u00f1a esto su reputaci\u00f3n?\u201d dijo Stephens a CNN. \u201cTendr\u00e1 que demostrar que alguien en Florida vio este \u2018Panorama\u2019 y pens\u00f3 peor de \u00e9l. (\u2026) \u00bfEso lo rebaj\u00f3 en la estima de personas sensatas?\u201d<\/p>\n<p>S\u00ed, varias veces. El a\u00f1o pasado, ABC acord\u00f3 pagar US$ 15 millones en un acuerdo con Trump en su demanda por difamaci\u00f3n contra la cadena y el presentador George Stephanopoulos.<\/p>\n<p>En  julio, Paramount, la empresa matriz de CBS News, tambi\u00e9n acord\u00f3 pagar US$ 16 millones para resolver una demanda presentada por Trump sobre una entrevista de \u201c60 Minutes\u201d con la entonces vicepresidenta Kamala Harris el oto\u00f1o pasado. Al igual que con la BBC, la queja de Trump fue sobre la edici\u00f3n del programa; afirm\u00f3 que el intercambio con Harris fue editado deliberadamente para beneficiarla a ella y perjudicarlo a \u00e9l.<\/p>\n<p>Analistas dijeron que probablemente Paramount acord\u00f3 resolver ese caso para completar una lucrativa fusi\u00f3n con Skydance Media, que el Gobierno de Trump aprob\u00f3 formalmente en julio.<\/p>\n<p>Stephens, el abogado, dijo que Trump podr\u00eda encontrar m\u00e1s dif\u00edcil lograr que la BBC acepte un acuerdo, ya que \u201cno tiene el tipo de influencia\u201d sobre la emisora que ten\u00eda sobre Paramount.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ataque de Donald Trump contra los medios de comunicaci\u00f3n se internacionaliz\u00f3 esta semana, ya que amenaz\u00f3 con demandar a la BBC por US$ 1.000 millones debido a un documental en el que, seg\u00fan su abogado, hay ediciones \u201cfalsas, difamatorias, maliciosas, denigrantes e incendiarias\u201d de un discurso que el presidente de EE.UU. pronunci\u00f3 antes del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468242","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ataque de Donald Trump contra los medios de comunicaci\u00f3n se internacionaliz\u00f3 esta semana, ya que amenaz\u00f3 con demandar a la BBC por US$ 1.000 millones debido a un documental en el que, seg\u00fan su abogado, hay ediciones \u201cfalsas, difamatorias, maliciosas, denigrantes e incendiarias\u201d de un discurso que el presidente de EE.UU. pronunci\u00f3 antes del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?\",\"datePublished\":\"2025-11-12T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\"},\"wordCount\":1925,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\",\"name\":\"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias","og_description":"El ataque de Donald Trump contra los medios de comunicaci\u00f3n se internacionaliz\u00f3 esta semana, ya que amenaz\u00f3 con demandar a la BBC por US$ 1.000 millones debido a un documental en el que, seg\u00fan su abogado, hay ediciones \u201cfalsas, difamatorias, maliciosas, denigrantes e incendiarias\u201d de un discurso que el presidente de EE.UU. pronunci\u00f3 antes del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-12T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?","datePublished":"2025-11-12T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/"},"wordCount":1925,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","name":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/11\/trump-amenaza-demanda-bbc-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T00:03:48Z","datePublished":"2025-11-12T00:03:48Z","dateModified":"2025-11-12T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 Trump amenaza con demandar a la BBC por US$ 1.000 millones?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/11\\\/trump-amenaza-demanda-bbc-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/11\\\/trump-amenaza-demanda-bbc-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T00:03:48Z\",\"datePublished\":\"2025-11-12T00:03:48Z\",\"dateModified\":\"2025-11-12T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468316,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/bbc-disculpa-trump-documental-discurso-trax\/","url_meta":{"origin":1468242,"position":0},"title":"BBC se disculpa con Trump por la edici\u00f3n de un documental sobre el discurso del presidente de EE.UU.","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"La BBC se disculp\u00f3 con el presidente de Estados Unidos, Donald Trump, este jueves, por un documental que sus abogados calificaron de falso y difamatorio, en un intento por desactivar una controversia que ha sumido al medio p\u00fablico en su peor crisis en a\u00f1os.Un portavoz de la BBC inform\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468384,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/15\/trump-dice-demandara-bbc-trax\/","url_meta":{"origin":1468242,"position":1},"title":"Trump dice que demandar\u00e1 a la BBC a pesar de la disculpa de la emisora","author":"","date":"noviembre 15, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dice que tiene la intenci\u00f3n de demandar a la BBC por entre US$ 1.000 millones y US$ 5.000 millones \u201cprobablemente en alg\u00fan momento de la pr\u00f3xima semana\u201d, a pesar de la disculpa de la emisora por un documental que los abogados de Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469327,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/12\/16\/analisis-lagunas-demanda-trump-bbc-trax\/","url_meta":{"origin":1468242,"position":2},"title":"\u00bfPor qu\u00e9 los expertos legales ven &#171;lagunas&#187; en la ins\u00f3lita demanda de Trump contra la BBC por US$ 10.000 millones?","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Hasta este a\u00f1o, era inaudito que un presidente de EE.UU. en funciones demandara a un medio de comunicaci\u00f3n. En solo unos meses, el presidente Donald Trump ha logrado que parezca algo normal.Trump ha demandado a The Wall Street Journal, The New York Times y ahora a la BBC, presentando la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468177,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/09\/bbc-renuncias-polemica-discurso-trump-trax\/","url_meta":{"origin":1468242,"position":3},"title":"Directivos de la BBC renuncian en medio de un esc\u00e1ndalo por im\u00e1genes manipuladas de un discurso de Trump","author":"","date":"noviembre 9, 2025","format":false,"excerpt":"El director general de la BBC, Tim Davie, y la directora ejecutiva de Noticias, Deborah Turness, renunciaron este domingo tras las cr\u00edticas a un documental del programa \u201cPanorama\u201d, que habr\u00eda enga\u00f1ado a la audiencia al editar un discurso del presidente de Estados Unidos, Donald Trump.En un comunicado publicado en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464529,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/15\/trump-apoyo-otan-putin-trax\/","url_meta":{"origin":1468242,"position":4},"title":"Trump expresa su apoyo a la OTAN y afirma que &#171;no ha terminado&#187; con Putin, en una entrevista con la BBC","author":"","date":"julio 15, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, expres\u00f3 su apoyo a la OTAN en una llamada telef\u00f3nica con la BBC.Al ser consultado sobre si consideraba que la alianza militar estaba \u201cobsoleta\u201d, Trump respondi\u00f3: \u201cNo. Creo que la OTAN se est\u00e1 convirtiendo en lo opuesto\u201d, inform\u00f3 la cadena brit\u00e1nica. A\u00f1adi\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464834,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/24\/estreno-south-park-critica-trump-paramount-trax\/","url_meta":{"origin":1468242,"position":5},"title":"El estreno de \u2018South Park\u2019 critica a Trump y a Paramount en un regreso incendiario","author":"","date":"julio 24, 2025","format":false,"excerpt":"Los creadores de \u201cSouth Park\u201d, Trey Parker y Matt Stone, regresaron con fuerza el mi\u00e9rcoles, en un episodio que lanz\u00f3 cr\u00edticas tanto a la empresa matriz de la cadena que transmite su popular serie animada como al presidente de EE.UU. Donald Trump.El retrasado estreno de la temporada 27 de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468242"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468242\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}