{"id":1468261,"date":"2025-11-12T07:03:41","date_gmt":"2025-11-12T15:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/"},"modified":"2025-11-12T07:03:41","modified_gmt":"2025-11-12T15:03:41","slug":"peru-caida-autobus-decenas-muertos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","title":{"rendered":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa"},"content":{"rendered":"<p>M\u00e1s de 30 personas murieron tras la ca\u00edda de un autob\u00fas a un abismo en Per\u00fa. El incidente ocurri\u00f3 en Arequipa, en la provincia de Caman\u00e1. Walter Oporto, gerente regional de Salud de Arequipa, dijo al medio RPP que adem\u00e1s hay m\u00e1s de una decena de personas heridas que est\u00e1n siendo atendidas en diferentes centros de salud de la zona.<br \/>El autob\u00fas cay\u00f3 a un barranco a la altura del kil\u00f3metro 780 de la carretera Panamericana Sur durante la madrugada de este mi\u00e9rcoles, luego de chocar con una camioneta, seg\u00fan la agencia estatal de noticias Andina.<\/p>\n<p><em>Noticia en desarrollo<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 30 personas murieron tras la ca\u00edda de un autob\u00fas a un abismo en Per\u00fa. El incidente ocurri\u00f3 en Arequipa, en la provincia de Caman\u00e1. Walter Oporto, gerente regional de Salud de Arequipa, dijo al medio RPP que adem\u00e1s hay m\u00e1s de una decena de personas heridas que est\u00e1n siendo atendidas en diferentes centros [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468261","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 30 personas murieron tras la ca\u00edda de un autob\u00fas a un abismo en Per\u00fa. El incidente ocurri\u00f3 en Arequipa, en la provincia de Caman\u00e1. Walter Oporto, gerente regional de Salud de Arequipa, dijo al medio RPP que adem\u00e1s hay m\u00e1s de una decena de personas heridas que est\u00e1n siendo atendidas en diferentes centros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T15:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa\",\"datePublished\":\"2025-11-12T15:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\",\"name\":\"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T15:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias","og_description":"M\u00e1s de 30 personas murieron tras la ca\u00edda de un autob\u00fas a un abismo en Per\u00fa. El incidente ocurri\u00f3 en Arequipa, en la provincia de Caman\u00e1. Walter Oporto, gerente regional de Salud de Arequipa, dijo al medio RPP que adem\u00e1s hay m\u00e1s de una decena de personas heridas que est\u00e1n siendo atendidas en diferentes centros [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-12T15:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa","datePublished":"2025-11-12T15:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","name":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T15:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T15:03:41Z","datePublished":"2025-11-12T15:03:41Z","dateModified":"2025-11-12T15:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e1s de 30 muertos y decenas de heridos por la ca\\u00edda de un autob\\u00fas al vac\\u00edo en Per\\u00fa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/12\\\/peru-caida-autobus-decenas-muertos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/12\\\/peru-caida-autobus-decenas-muertos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T15:03:41Z\",\"datePublished\":\"2025-11-12T15:03:41Z\",\"dateModified\":\"2025-11-12T15:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471573,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/23\/helicoptero-peru-accidente-arequipa-chala-orix\/","url_meta":{"origin":1468261,"position":0},"title":"Mueren quince personas en Per\u00fa tras ca\u00edda de un helic\u00f3ptero militar","author":"","date":"febrero 23, 2026","format":false,"excerpt":"Quince personas murieron, entre ellos siete menores de edad, luego de que un helic\u00f3ptero militar se estrellara en el sur de Per\u00fa, seg\u00fan un comunicado emitido este lunes por la Fuerza A\u00e9rea (FAP).Las patrullas de b\u00fasqueda localizaron el helic\u00f3ptero MI-17 luego de que se perdiera contacto radial la tarde del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450767,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/06\/28\/peru-alerta-tsunami-sismo-72-trax\/","url_meta":{"origin":1468261,"position":1},"title":"Gran sismo de magnitud 7,2  sacude a Arequipa, Per\u00fa.  No hay alertas de tsunami","author":"","date":"junio 28, 2024","format":false,"excerpt":"(CNN) -- Un fuerte sismo de magnitud 7,2 \u00a0sacudi\u00f3 la costa del sur de Per\u00fa durante la noche de este viernes a una profundidad de 28 kil\u00f3metros en el oc\u00e9ano y a una distancia de 8 km de Arequipa, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos (USGC).El Ministerio de Transportes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451164,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","url_meta":{"origin":1468261,"position":2},"title":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) -- Al menos 23 personas murieron en Per\u00fa despu\u00e9s de que un autob\u00fas cayera m\u00e1s de 200 metros a un barranco el martes mientras viajaba desde Lima a la ciudad de Ayacucho, dijeron las autoridades.Las autoridades realizan operaciones de b\u00fasqueda y rescate, dijo el Ministerio del Interior del pa\u00eds\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464235,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/04\/personas-muertas-y-heridas-caida-autobus-rio-mexico-orix\/","url_meta":{"origin":1468261,"position":3},"title":"Al menos 9 personas muertas y 15 heridas por ca\u00edda de un autob\u00fas a un r\u00edo en M\u00e9xico","author":"","date":"julio 4, 2025","format":false,"excerpt":"Al menos nueve personas murieron y 15 m\u00e1s resultaron heridas despu\u00e9s de que un autob\u00fas, procedente de Cuernavaca y con destino a Tlapa de Comonfort, en el estado mexicano de Guerrero, cay\u00f3 este jueves al cauce de un r\u00edo, informaron las autoridades municipales a trav\u00e9s de su cuenta de Facebook.\u201cNos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448045,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/04\/12\/fuerza-aerea-peru-encuentra-restos-avion-arequipa-orix\/","url_meta":{"origin":1468261,"position":4},"title":"La Fuerza A\u00e9rea de Per\u00fa encuentra los restos de su avi\u00f3n que se cay\u00f3 en Arequipa y donde un piloto muri\u00f3","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fuerza A\u00e9rea de Per\u00fa inform\u00f3 que sus equipos de b\u00fasqueda y rescate localizaron este viernes los restos de su avi\u00f3n tipo Mirage 2000 que el jueves se extravi\u00f3 durante labores de entrenamiento en la zona de Arequipa.En su cuenta de X, la instituci\u00f3n militar indic\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460001,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/03\/16\/muere-cantante-grupo-musical-armonia-10-peru-orix\/","url_meta":{"origin":1468261,"position":5},"title":"Muere cantante del grupo musical Armon\u00eda 10 en un atentado al autob\u00fas de la banda en Lima, Per\u00fa","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Paul Hambert Flores Garc\u00eda, tambi\u00e9n conocido como el Russo y cantante del grupo musical de cumbia Armon\u00eda 10, muri\u00f3 la madrugada de este domingo como consecuencia de los disparos efectuados por desconocidos al autob\u00fas de la banda, inform\u00f3 el Ministerio del Interior de Per\u00fa en un comunicado en sus redes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468261"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468261\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}