{"id":1468270,"date":"2025-11-12T12:03:44","date_gmt":"2025-11-12T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/"},"modified":"2025-11-12T12:03:44","modified_gmt":"2025-11-12T20:03:44","slug":"ultimo-centavo-acunado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","title":{"rendered":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia"},"content":{"rendered":"<p>El centavo estadounidense desaparecer\u00e1 este mi\u00e9rcoles tras una larga enfermedad. Ten\u00eda 238 a\u00f1os.<\/p>\n<p>El \u00faltimo centavo se acu\u00f1\u00f3 el mi\u00e9rcoles por la tarde en la Casa de la Moneda de Estados Unidos en Filadelfia, bajo la supervisi\u00f3n del tesorero estadounidense, Brandon Beach. El presidente Donald Trump anunci\u00f3 en febrero a trav\u00e9s de las redes sociales que hab\u00eda ordenado a la Casa de la Moneda que <a href=\"https:\/\/www.cnn.com\/2025\/02\/09\/business\/trump-treasury-penny-production-halt\/index.html\">dejara de producir<\/a> la moneda, que alguna vez fue muy popular, debido al alto costo de producci\u00f3n.<\/p>\n<p>Acu\u00f1ar el centavo <a href=\"https:\/\/www.cnn.com\/2025\/02\/10\/business\/costs-of-pennies-and-nickels\">cuesta casi cuatro centavos<\/a>, m\u00e1s de lo que vale la moneda. Alguna vez fue lo suficientemente valioso como para comprar \u201cdulces de centavo\u201d como chicles y alimentar parqu\u00edmetros o casetas de peaje; hoy, el centavo vive principalmente en frascos de monedas, cajones de objetos varios o bandejas de \u201cdeja un centavo\/toma un centavo\u201d.<\/p>\n<p>El centavo sobrevivi\u00f3 a su hermano, el medio centavo, por 168 a\u00f1os. Le sobreviven el n\u00edquel, la moneda de diez centavos, el cuarto de d\u00f3lar y las raramente vistas monedas de medio d\u00f3lar y un d\u00f3lar.<\/p>\n<p>A pesar de su desaparici\u00f3n, el centavo seguir\u00e1 siendo de <a href=\"https:\/\/www.cnn.com\/2025\/05\/25\/business\/penny-what-happens-to-them\">curso legal<\/a>.<\/p>\n<p>Para una moneda que parece obsoleta, su eliminaci\u00f3n de la circulaci\u00f3n est\u00e1 causando m\u00e1s problemas de lo esperado, especialmente para los minoristas.<\/p>\n<p>Algunos comerciantes planean redondear los precios al n\u00edquel m\u00e1s cercano, a menudo uno o dos centavos m\u00e1s. Otros est\u00e1n pidiendo a los clientes que paguen con centavos para ayudar con el suministro. Pero en algunos estados, los comerciantes podr\u00edan enfrentar problemas legales por redondear hacia arriba o hacia abajo.<\/p>\n<p>Adem\u00e1s, cualquier ahorro por la discontinuaci\u00f3n de la moneda de un centavo podr\u00eda verse compensado por la necesidad de acu\u00f1ar m\u00e1s n\u00edqueles, lo cual <a href=\"https:\/\/www.cnn.com\/2025\/02\/10\/business\/cost-to-make-penny-nickel-dg\">cuesta m\u00e1s dinero<\/a> a la Casa de la Moneda de EE.UU. que el centavo.<\/p>\n<p>La eliminaci\u00f3n progresiva del centavo por parte del gobierno ha sido \u201cun poco ca\u00f3tica\u201d, dijo Mark Weller, director ejecutivo de Americans for Common Cents.<br \/>El grupo a favor del centavo es financiado principalmente por Artazn, la empresa que provee los discos met\u00e1licos usados para fabricar los centavos.<br \/>\u201cPara cuando llegue la Navidad, los problemas ser\u00e1n m\u00e1s evidentes con los minoristas que no tendr\u00e1n centavos\u201d.<\/p>\n<p>Weller dijo que otros pa\u00edses que eliminaron monedas de baja denominaci\u00f3n, como Canad\u00e1, Australia y Suiza, tuvieron directrices para despu\u00e9s. Eso no ocurre en Estados Unidos.<\/p>\n<p>\u201cTuvimos una publicaci\u00f3n en redes sociales (de Trump) durante el Super Bowl, pero ning\u00fan plan real sobre lo que los minoristas tendr\u00edan que hacer\u201d, dijo, refiri\u00e9ndose al anuncio del presidente en febrero.<\/p>\n<p>Kwik Trip, una cadena de tiendas de conveniencia de propiedad familiar que opera en el Medio Oeste, decidi\u00f3 redondear a la baja las compras en efectivo en las tiendas donde no han podido conseguir centavos.<\/p>\n<p>\u201cNo hab\u00eda manera de que quisi\u00e9ramos cobrarles (a los clientes) 2 centavos extra porque simplemente no nos parec\u00eda justo\u201d, afirm\u00f3 John McHugh, portavoz de la empresa.<br \/>\u201cQuiero decir, no es culpa de ellos que haya escasez de centavos\u201d.<\/p>\n<p>Pero con 20 millones de clientes al a\u00f1o, y el 17 % de ellos pagando en efectivo, la pol\u00edtica eventualmente le costar\u00e1 a Kwik Trip un par de millones de d\u00f3lares al a\u00f1o, dijo McHugh.<\/p>\n<p>No solo las empresas enfrentan costos m\u00e1s altos. Redondear al n\u00edquel m\u00e1s cercano costar\u00e1 a los consumidores unos US$ 6 millones al a\u00f1o, seg\u00fan un estudio de julio del Banco de la Reserva Federal de Richmond. Es una cifra bastante modesta, que equivale a unos cinco centavos por hogar en 133 millones de hogares estadounidenses.<\/p>\n<p>Y el redondeo no es una soluci\u00f3n nacional.<\/p>\n<p>Cuatro estados \u2013Delaware, Connecticut, Michigan y Oreg\u00f3n\u2013 as\u00ed como numerosas ciudades, incluidas Nueva York, Filadelfia, Miami y Washington, requieren que los comerciantes entreguen el cambio exacto, seg\u00fan la Asociaci\u00f3n Nacional de Tiendas de Conveniencia (NACS).<\/p>\n<p>Adem\u00e1s, la ley que regula el programa federal de asistencia alimentaria conocido como SNAP exige que a los beneficiarios no se les cobre m\u00e1s que a otros clientes. Dado que los beneficiarios de SNAP usan una tarjeta de d\u00e9bito que se carga con el monto exacto, si los comerciantes redondean los precios a la baja para compras en efectivo, podr\u00edan exponerse a problemas legales y multas, dijo Jeff Lenard, portavoz de NACS.<\/p>\n<p>\u201cEl redondeo a la baja en todas las transacciones presenta varios desaf\u00edos m\u00e1s all\u00e1 de la p\u00e9rdida promedio de 2 centavos por transacci\u00f3n\u201d, coment\u00f3 Lenard.<br \/>\u201cNecesitamos desesperadamente una legislaci\u00f3n que permita el redondeo para que los minoristas puedan dar cambio a estos clientes\u201d.<\/p>\n<p>Por esa raz\u00f3n, NACS y otros grupos minoristas escribieron recientemente al Congreso para solicitar una legislaci\u00f3n que aborde las preguntas surgidas por el fin de la producci\u00f3n de centavos.<\/p>\n<p>El centavo fue una de las primeras monedas del pa\u00eds, acu\u00f1ada por primera vez en 1787, seis a\u00f1os antes de que se estableciera la propia Casa de la Moneda.<\/p>\n<p>Se le atribuye ampliamente a Benjamin Franklin el dise\u00f1o del primer centavo, conocido como el centavo Fugio. Su forma actual lleg\u00f3 en 1909, en el centenario del nacimiento de Abraham Lincoln, cuando se convirti\u00f3 en la primera moneda estadounidense en presentar a un presidente.<\/p>\n<p>Pero desde entonces ha disminuido tanto en uso como en popularidad. El Departamento del Tesoro afirma ahora que se estima que <a href=\"https:\/\/www.cnn.com\/2025\/05\/25\/business\/penny-what-happens-to-them\">hay 300.000 millones de centavos en circulaci\u00f3n<\/a>. Eso equivale a poco menos de US$ 9 por cada estadounidense. Pero la mayor\u00eda de esas monedas est\u00e1n \u201cgravemente subutilizadas\u201d. Por eso, la protesta p\u00fablica por su desaparici\u00f3n ha sido moderada.<\/p>\n<p>Joe Ditler, un escritor e historiador de 74 a\u00f1os de Colorado, dijo que todav\u00eda tiene una vieja caja de cigarros llena en su mayor\u00eda de centavos que le regal\u00f3 su abuelo.<br \/>Recuerda haber aplanado centavos en las v\u00edas del tren o en m\u00e1quinas de recuerdos en los parques de diversiones.<\/p>\n<p>Sin embargo, solo ocasionalmente usa centavos para hacer una compra en efectivo. Y a menudo arroja la moneda de un centavo en el frasco de propinas.<\/p>\n<p>\u201cMe traen recuerdos que me han acompa\u00f1ado toda la vida\u201d, coment\u00f3. \u201cEl centavo ha tenido una vida maravillosa. Pero probablemente ya es hora de que desaparezca\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El centavo estadounidense desaparecer\u00e1 este mi\u00e9rcoles tras una larga enfermedad. Ten\u00eda 238 a\u00f1os. El \u00faltimo centavo se acu\u00f1\u00f3 el mi\u00e9rcoles por la tarde en la Casa de la Moneda de Estados Unidos en Filadelfia, bajo la supervisi\u00f3n del tesorero estadounidense, Brandon Beach. El presidente Donald Trump anunci\u00f3 en febrero a trav\u00e9s de las redes sociales [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468270","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias\" \/>\n<meta property=\"og:description\" content=\"El centavo estadounidense desaparecer\u00e1 este mi\u00e9rcoles tras una larga enfermedad. Ten\u00eda 238 a\u00f1os. El \u00faltimo centavo se acu\u00f1\u00f3 el mi\u00e9rcoles por la tarde en la Casa de la Moneda de Estados Unidos en Filadelfia, bajo la supervisi\u00f3n del tesorero estadounidense, Brandon Beach. El presidente Donald Trump anunci\u00f3 en febrero a trav\u00e9s de las redes sociales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia\",\"datePublished\":\"2025-11-12T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\"},\"wordCount\":1107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\",\"name\":\"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias","og_description":"El centavo estadounidense desaparecer\u00e1 este mi\u00e9rcoles tras una larga enfermedad. Ten\u00eda 238 a\u00f1os. El \u00faltimo centavo se acu\u00f1\u00f3 el mi\u00e9rcoles por la tarde en la Casa de la Moneda de Estados Unidos en Filadelfia, bajo la supervisi\u00f3n del tesorero estadounidense, Brandon Beach. El presidente Donald Trump anunci\u00f3 en febrero a trav\u00e9s de las redes sociales [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-12T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/"},"author":{"name":"","@id":""},"headline":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia","datePublished":"2025-11-12T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/"},"wordCount":1107,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","name":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/ultimo-centavo-acunado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La \u00faltima moneda de un centavo de la historia se acu\u00f1\u00f3 hoy en Filadelfia","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/ultimo-centavo-acunado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/12\/ultimo-centavo-acunado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T20:03:44Z","datePublished":"2025-11-12T20:03:44Z","dateModified":"2025-11-12T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La \\u00faltima moneda de un centavo de la historia se acu\\u00f1\\u00f3 hoy en Filadelfia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/12\\\/ultimo-centavo-acunado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/12\\\/ultimo-centavo-acunado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T20:03:44Z\",\"datePublished\":\"2025-11-12T20:03:44Z\",\"dateModified\":\"2025-11-12T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457856,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/24\/eficiencia-gubernamental-musk-eliminar-centavo-trax\/","url_meta":{"origin":1468270,"position":0},"title":"El Departamento de Eficiencia Gubernamental de Musk busca eliminar el centavo en EE.UU.","author":"","date":"enero 24, 2025","format":false,"excerpt":"El Departamento de Eficiencia Gubernamental de Elon Musk tiene un nuevo objetivo para reducir costos: el centavo estadounidense.El Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s) inform\u00f3 en X que la fabricaci\u00f3n del centavo cuesta m\u00e1s de 3 centavos y cost\u00f3 a los contribuyentes estadounidenses m\u00e1s de US$\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458506,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/02\/10\/trump-detencion-centavos-trax\/","url_meta":{"origin":1468270,"position":1},"title":"Trump ordena al Tesoro que detenga la producci\u00f3n de monedas de un centavo","author":"","date":"febrero 10, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 el domingo que dio instrucciones al secretario del Tesoro, Scott Bessent, para detener la producci\u00f3n de monedas de un centavo, citando el alto costo de producir los centavos.\u201cDurante demasiado tiempo, Estados Unidos ha acu\u00f1ado monedas de un centavo que literalmente nos cuestan m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469217,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/12\/12\/centavo-dolar-trump-trax\/","url_meta":{"origin":1468270,"position":2},"title":"Eliminar el centavo fue solo el comienzo: Trump est\u00e1 reescribiendo las reglas de las monedas estadounidenses","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Las pr\u00f3ximas se\u00f1ales de la divisi\u00f3n pol\u00edtica de Estados Unidos podr\u00edan sonar en tu bolsillo en 2026.El Gobierno planea emitir una moneda de 1 d\u00f3lar con la imagen del presidente Donald Trump el pr\u00f3ximo a\u00f1o, a pesar de un precedente centenario de no honrar a presidentes en ejercicio ni expresidentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462783,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/05\/25\/que-pasara-millones-centavos-produccion-trax\/","url_meta":{"origin":1468270,"position":3},"title":"\u00bfQu\u00e9 pasar\u00e1 con los 114.000 millones de centavos de Estados Unidos una vez que el pa\u00eds deje de producirlos?","author":"","date":"mayo 25, 2025","format":false,"excerpt":"El centavo estadounidense no desaparecer\u00e1 en el corto plazo.El Departamento del Tesoro de Estados Unidos anunci\u00f3 el jueves que planea comenzar a reducir la producci\u00f3n de la moneda de un centavo que ha acu\u00f1ado durante m\u00e1s de 230 a\u00f1os. Sin embargo, el centavo seguir\u00e1 siendo de curso legal y se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1407501,"url":"https:\/\/noticiasya.com\/san-diego\/2022\/06\/20\/cae-por-quinto-dia-consecutivo-precio-de-la-gasolina-en-san-diego\/","url_meta":{"origin":1468270,"position":4},"title":"Cae por quinto d\u00eda consecutivo precio de la gasolina en San Diego","author":"agomez","date":"junio 20, 2022","format":false,"excerpt":"El costo en promedio establecido registra 18 veces en 19 d\u00edas durante la ejecuci\u00f3n de aumentos, incluido un r\u00e9cord de $ 6.373 el 15 de junio.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472756,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/04\/01\/aumento-precio-gasolina-guerra-trax\/","url_meta":{"origin":1468270,"position":5},"title":"El precio de la gasolina en EE.UU. sube 5 centavos, hasta los US$ 4,06 por gal\u00f3n","author":"agomez","date":"abril 1, 2026","format":false,"excerpt":"El precio promedio del gal\u00f3n (3,78 litros) de gasolina regular en EE.UU. aument\u00f3 casi 5 centavos, hasta los US$ 4,06, seg\u00fan la \u00faltima lectura de la AAA. Este es el mayor aumento diario en los precios de la gasolina en m\u00e1s de dos semanas.El alza se produjo un d\u00eda despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468270"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468270\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}