{"id":1468292,"date":"2025-11-13T04:04:03","date_gmt":"2025-11-13T12:04:03","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/"},"modified":"2025-11-13T04:04:03","modified_gmt":"2025-11-13T12:04:03","slug":"precios-cafe-eeuu-no-bajaran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","title":{"rendered":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1"},"content":{"rendered":"<p>Tras la aplastante derrota del Partido Republicano en las elecciones de mitad de mandato de la semana pasada, el gobierno de Trump ha recuperado el \u00edmpetu por la palabra <a href=\"https:\/\/www.cnn.com\/2025\/11\/12\/economy\/affordability-crisis-mortgage-debt-bnpl\">\u201caccesibilidad\u201d<\/a> y se esfuerza por demostrar que est\u00e1 haciendo algo, lo que sea, para bajar los precios.<\/p>\n<p>Una de las soluciones que se ofrecen: revertir su propia pol\u00edtica de gravar las importaciones de caf\u00e9.<\/p>\n<p>\u201cEn los pr\u00f3ximos d\u00edas se anunciar\u00e1n medidas importantes relacionadas con productos que no cultivamos en Estados Unidos, como el caf\u00e9, los pl\u00e1tanos y otras frutas\u201d, declar\u00f3 el secretario del Tesoro, Scott Bessent, a Fox News el mi\u00e9rcoles. \u201cEsto provocar\u00e1 una r\u00e1pida bajada de precios\u201d.<\/p>\n<p>Esto resulta interesante por un par de razones:<\/p>\n<ol>\n<li>Bessent reconoce impl\u00edcitamente que los aranceles <em>s\u00ed<\/em> aumentan los precios para los consumidores estadounidenses, un hecho que la administraci\u00f3n Trump ha negado reiteradamente. Bessent no ofreci\u00f3 detalles sobre c\u00f3mo ser\u00edan las reducciones arancelarias ni qu\u00e9 pa\u00edses se incluir\u00edan, pero afirm\u00f3 \u2014aparentemente reconociendo la presi\u00f3n financiera que contribuy\u00f3 a la victoria dem\u00f3crata la semana pasada\u2014 que \u201cel pueblo estadounidense empezar\u00e1 a sentirse mejor\u201d. (La Casa Blanca, al ser consultada sobre m\u00e1s detalles del plan, remiti\u00f3 a CNN a <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/09\/modifying-the-scope-of-reciprocal-tariffs-and-establishing-procedures-for-implementing-trade-and-security-agreements\/\">un decreto<\/a> de septiembre que detalla posibles ajustes arancelarios basados \u200b\u200ben objetivos de seguridad nacional y econ\u00f3micos).<\/li>\n<li>Aunque Trump y Bessent hicieran una gran excepci\u00f3n para el caf\u00e9, es muy improbable que los precios bajen significativamente. Y eso se debe a que los estadounidenses, como pueblo, adoran el caf\u00e9.<\/li>\n<\/ol>\n<p>Como es obvio: el caf\u00e9 se ha vuelto <a href=\"https:\/\/www.cnn.com\/2025\/09\/12\/food\/coffee-prices\">prohibitivo por su elevado precio<\/a>. Los precios al por menor han subido alrededor de un 20 % interanual.<\/p>\n<p>Hay dos causas principales para esa inflaci\u00f3n de precios: las condiciones clim\u00e1ticas extremadamente variables han mermado la cosecha de un cultivo que ya de por s\u00ed requiere mucha mano de obra y es dif\u00edcil de cultivar. Esto viene ocurriendo desde hace algunos a\u00f1os. Adem\u00e1s, los aranceles impuestos por Trump a Brasil (50 %), Colombia (10 %) y Vietnam (20 %), los tres mayores exportadores de caf\u00e9, est\u00e1n incrementando a\u00fan m\u00e1s los costos. Y dado que el caf\u00e9 solo crece en unos pocos lugares del planeta, no podemos simplemente arrasar con unos cuantos campos de ma\u00edz en el interior del pa\u00eds y comenzar nuestra propia producci\u00f3n nacional.<\/p>\n<p>A pesar de todo, los estadounidenses no han abandonado su estimulante preferido.<\/p>\n<p>Seg\u00fan la Asociaci\u00f3n Nacional del Caf\u00e9, el consumo se ha mantenido estable a pesar de las subidas de precios, porque el caf\u00e9 se percibe como algo esencial y, a la vez, un capricho que merece la pena. Probablemente no exista otro producto de consumo al que los estadounidenses sean tan fieles, independientemente de su nivel de ingresos, ideolog\u00eda pol\u00edtica, lugar de residencia, edad, raza, g\u00e9nero, etc.<\/p>\n<p>Y las empresas lo saben. Los vendedores de caf\u00e9 han subido los precios para seguir en el negocio, y seguimos comprando. Entonces, \u00bfpor qu\u00e9 no seguir cobr\u00e1ndonos US$ 7 por caf\u00e9 si pueden?<\/p>\n<p>Eso es exactamente lo que deber\u00edamos esperar, especialmente cuando se trata de comprar caf\u00e9 en una cafeter\u00eda, seg\u00fan Alex Susskind, profesor de educaci\u00f3n y gesti\u00f3n del vino en Cornell.<\/p>\n<p>\u201cEs un principio que se aplica a la mayor\u00eda de las empresas: una vez que se suben los precios, se tiende a no bajarlos\u201d, dijo a CNN.<\/p>\n<p>Seg\u00fan \u00e9l, es probable que las grandes cadenas como Starbucks o Peet\u2019s mantengan precios altos incluso si desaparecen los aranceles, porque sus clientes principales no se han visto disuadidos por los precios m\u00e1s altos.<\/p>\n<p>Pero es posible que se produzca cierto alivio en los precios de los supermercados, entre los productores de caf\u00e9 de gran consumo cuyos clientes son m\u00e1s sensibles a las fluctuaciones de precios.<\/p>\n<p><strong>En resumen:<\/strong> Tras m\u00e1s de nueve meses de su segundo mandato, Trump est\u00e1 perdiendo terreno en el debate sobre la asequibilidad de la vivienda, el tema que, seg\u00fan \u00e9l mismo afirma, le vali\u00f3 la reelecci\u00f3n. <a href=\"https:\/\/www.cnn.com\/2025\/11\/11\/politics\/trump-economy-biden-analysis\">Una encuesta de CNN realizada la semana pasada<\/a> revel\u00f3 que el 61 % de los estadounidenses opina que sus pol\u00edticas \u201cempeoraron la situaci\u00f3n econ\u00f3mica del pa\u00eds\u201d. Ese porcentaje alcanz\u00f3 un m\u00e1ximo del 58 % durante la presidencia de Biden, seg\u00fan las encuestas de CNN, y se mantuvo generalmente entre el 50 % y el 55 % durante su mandato.<\/p>\n<p>Si Trump reduce los aranceles al caf\u00e9 pensando que as\u00ed aliviar\u00e1 la situaci\u00f3n de los estadounidenses, se equivoc\u00f3 de producto. Puede que no nos guste pagar m\u00e1s por el caf\u00e9, pero lo hacemos igual. Y, en definitiva, el dinero extra que gastamos en caf\u00e9 es insignificante comparado con los <a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/business\/democrats-trump-economy-affordability-nightcap\">temas cruciales<\/a> \u2014como la vivienda, la energ\u00eda y la sanidad\u2014 que contribuyeron a las victorias dem\u00f3cratas la semana pasada.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la aplastante derrota del Partido Republicano en las elecciones de mitad de mandato de la semana pasada, el gobierno de Trump ha recuperado el \u00edmpetu por la palabra \u201caccesibilidad\u201d y se esfuerza por demostrar que est\u00e1 haciendo algo, lo que sea, para bajar los precios. Una de las soluciones que se ofrecen: revertir su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468292","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras la aplastante derrota del Partido Republicano en las elecciones de mitad de mandato de la semana pasada, el gobierno de Trump ha recuperado el \u00edmpetu por la palabra \u201caccesibilidad\u201d y se esfuerza por demostrar que est\u00e1 haciendo algo, lo que sea, para bajar los precios. Una de las soluciones que se ofrecen: revertir su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T12:04:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1\",\"datePublished\":\"2025-11-13T12:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\"},\"wordCount\":836,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\",\"name\":\"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-13T12:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias","og_description":"Tras la aplastante derrota del Partido Republicano en las elecciones de mitad de mandato de la semana pasada, el gobierno de Trump ha recuperado el \u00edmpetu por la palabra \u201caccesibilidad\u201d y se esfuerza por demostrar que est\u00e1 haciendo algo, lo que sea, para bajar los precios. Una de las soluciones que se ofrecen: revertir su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-13T12:04:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/"},"author":{"name":"","@id":""},"headline":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1","datePublished":"2025-11-13T12:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/"},"wordCount":836,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","name":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-13T12:04:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lo siento, Estados Unidos. Probablemente el precio del caf\u00e9 no bajar\u00e1","url":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/precios-cafe-eeuu-no-bajaran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-13T12:04:03Z","datePublished":"2025-11-13T12:04:03Z","dateModified":"2025-11-13T12:04:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lo siento, Estados Unidos. Probablemente el precio del caf\\u00e9 no bajar\\u00e1\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/13\\\/precios-cafe-eeuu-no-bajaran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2025\\\/11\\\/13\\\/precios-cafe-eeuu-no-bajaran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-13T12:04:03Z\",\"datePublished\":\"2025-11-13T12:04:03Z\",\"dateModified\":\"2025-11-13T12:04:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468306,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/13\/trump-costo-aranceles-inflacion-analisis-trax\/","url_meta":{"origin":1468292,"position":0},"title":"Trump se contradice y admite que los estadounidenses s\u00ed pagan m\u00e1s por los aranceles","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"Cuando la presentadora de Fox News, Laura Ingraham, le record\u00f3 al presidente Donald Trump en una entrevista esta semana que los precios del caf\u00e9 son altos, Trump respondi\u00f3: \u201cCaf\u00e9: vamos a bajar algunos aranceles, vamos a tener m\u00e1s caf\u00e9. Vamos a solucionar todo esto muy r\u00e1pido y muy f\u00e1cil\u201d.Dejando de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468360,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/14\/trump-reduce-aranceles-cafe-carne-de-res-frutas-trax\/","url_meta":{"origin":1468292,"position":1},"title":"Trump reduce aranceles al caf\u00e9, la carne de res y las frutas, mientras crecen preocupaciones por asequibilidad en EE.UU.","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"El presidente Donald Trump firm\u00f3 este viernes un decreto que reduce retroactivamente los aranceles sobre la carne de res, tomates, caf\u00e9 y pl\u00e1tanos, entre otras importaciones agr\u00edcolas, con efecto retroactivo al jueves.El decreto que firm\u00f3 Trump excluye estos productos de las tasas de aranceles \u201crec\u00edprocos\u201d, que comienzan en un 10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466393,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/09\/12\/precios-cafe-aumento-trax\/","url_meta":{"origin":1468292,"position":2},"title":"Los precios del caf\u00e9 en EE.UU. experimentaron el mayor aumento en d\u00e9cadas","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"Los amantes del caf\u00e9 recibir\u00e1n una sacudida antes de beber su primer sorbo.En agosto, los precios minoristas del caf\u00e9 en Estados Unidos aumentaron casi un 21 % en comparaci\u00f3n con el mismo mes del a\u00f1o pasado, en el mayor salto anual desde octubre de 1997, seg\u00fan el \u00faltimo \u00cdndice de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468400,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/16\/cheques-us-2000-aranceles-trump-trax\/","url_meta":{"origin":1468292,"position":3},"title":"Secretario del Tesoro dice &#171;ya veremos&#187; sobre cheques de US$ 2.000 mientras la Corte Suprema eval\u00faa los aranceles de Trump","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El secretario del Tesoro, Scott Bessent, dijo este domingo que la propuesta del presidente Donald Trump de emitir cheques de reembolso por aranceles de US$ 2.000 para la mayor\u00eda de los estadounidenses requerir\u00eda la aprobaci\u00f3n del Congreso.\u201cYa veremos. Necesitamos una ley para eso\u201d, dijo Bessent en \u201cSunday Morning Futures\u201d de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457969,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/28\/precios-cafe-suben-cancelacion-arancel-colombia-trax\/","url_meta":{"origin":1468292,"position":4},"title":"Precios del caf\u00e9 suben pese a cancelaci\u00f3n de arancel de Trump a Colombia","author":"","date":"enero 28, 2025","format":false,"excerpt":"Los precios del caf\u00e9 alcanzaron un nuevo m\u00e1ximo el lunes, un d\u00eda despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, amenazara (y luego diera marcha atr\u00e1s) con aplicar un arancel del 25% a Colombia durante una disputa sobre los vuelos de deportaci\u00f3n desde EE.UU. Y el precio sigue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468357,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/14\/crisis-asequibilidad-plan-economico-trump-analisis-trax\/","url_meta":{"origin":1468292,"position":5},"title":"La crisis de asequibilidad est\u00e1 obligando a Trump a remodelar radicalmente su plan econ\u00f3mico","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"El presidente Donald Trump lleg\u00f3 al cargo con un plan audaz para rehacer la econom\u00eda de Estados Unidos. Pero las realidades de una crisis de asequibilidad persistente, bajos \u00edndices de favorabilidad y dolorosas derrotas electorales para su Partido Republicano lo est\u00e1n obligando a rehacer su plan sobre la marcha.Aunque a\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1468292"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1468292\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1468292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1468292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1468292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}