{"id":1470631,"date":"2026-01-29T16:03:43","date_gmt":"2026-01-30T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/"},"modified":"2026-01-29T16:03:43","modified_gmt":"2026-01-30T00:03:43","slug":"trump-fdecreto-combatir-adiccion-drogas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","title":{"rendered":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, firm\u00f3 un decreto este jueves que lanza una iniciativa gubernamental para combatir la adicci\u00f3n a las drogas.<\/p>\n<p>\u201cLa Gran Iniciativa de Recuperaci\u00f3n Estadounidense reunir\u00e1 recursos federales, estatales, locales y del sector privado para apoyar la recuperaci\u00f3n, el tratamiento y la prevenci\u00f3n de adicciones, y ayudar\u00e1 a movilizar todos los recursos y la autoridad del Gobierno federal para ayudar a detener esta grave problem\u00e1tica\u201d, dijo el presidente en la Oficina Oval, acompa\u00f1ado por su secretario de Salud y Servicios Humanos, Robert F. Kennedy Jr.<\/p>\n<p>Las muertes por sobredosis de drogas en Estados Unidos aumentaron a niveles r\u00e9cord durante la pandemia de covid-19, impulsadas por el fentanilo. Sin embargo, datos de los Centros para el Control y Prevenci\u00f3n de Enfermedades (CDC) muestran que las tasas han disminuido desde 2022, regresando recientemente a niveles previos a la pandemia. Aun as\u00ed, los<a href=\"https:\/\/www.cdc.gov\/nchs\/nvss\/vsrr\/drug-overdose-data.htm\"> datos <\/a>m\u00e1s recientes muestran que m\u00e1s de 70.000 personas en Estados Unidos murieron por sobredosis de drogas en el \u00faltimo a\u00f1o.<\/p>\n<p>En 2024, alrededor del 17 % de las personas de 12 a\u00f1os o m\u00e1s \u2014m\u00e1s de 48 millones\u2014 ten\u00eda un trastorno por consumo de sustancias, de acuerdo con los <a href=\"https:\/\/www.samhsa.gov\/data\/sites\/default\/files\/reports\/rpt56462\/2024-nsduh-companion-report.pdf\">datos <\/a>de la Administraci\u00f3n de Servicios de Salud Mental y Abuso de Sustancias. Este porcentaje se ha mantenido relativamente estable en los \u00faltimos a\u00f1os.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, firm\u00f3 un decreto este jueves que lanza una iniciativa gubernamental para combatir la adicci\u00f3n a las drogas. \u201cLa Gran Iniciativa de Recuperaci\u00f3n Estadounidense reunir\u00e1 recursos federales, estatales, locales y del sector privado para apoyar la recuperaci\u00f3n, el tratamiento y la prevenci\u00f3n de adicciones, y ayudar\u00e1 a movilizar todos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470631","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, firm\u00f3 un decreto este jueves que lanza una iniciativa gubernamental para combatir la adicci\u00f3n a las drogas. \u201cLa Gran Iniciativa de Recuperaci\u00f3n Estadounidense reunir\u00e1 recursos federales, estatales, locales y del sector privado para apoyar la recuperaci\u00f3n, el tratamiento y la prevenci\u00f3n de adicciones, y ayudar\u00e1 a movilizar todos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas\",\"datePublished\":\"2026-01-30T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\",\"name\":\"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-30T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, firm\u00f3 un decreto este jueves que lanza una iniciativa gubernamental para combatir la adicci\u00f3n a las drogas. \u201cLa Gran Iniciativa de Recuperaci\u00f3n Estadounidense reunir\u00e1 recursos federales, estatales, locales y del sector privado para apoyar la recuperaci\u00f3n, el tratamiento y la prevenci\u00f3n de adicciones, y ayudar\u00e1 a movilizar todos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-30T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/"},"author":{"name":"","@id":""},"headline":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas","datePublished":"2026-01-30T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","name":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-30T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\u00f3n a las drogas","url":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/29\/trump-fdecreto-combatir-adiccion-drogas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-30T00:03:43Z","datePublished":"2026-01-30T00:03:43Z","dateModified":"2026-01-30T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump firma decreto que lanza iniciativa gubernamental para combatir la adicci\\u00f3n a las drogas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/29\\\/trump-fdecreto-combatir-adiccion-drogas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/29\\\/trump-fdecreto-combatir-adiccion-drogas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-30T00:03:43Z\",\"datePublished\":\"2026-01-30T00:03:43Z\",\"dateModified\":\"2026-01-30T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464620,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/17\/sheinbaum-responde-medidas-trump-drogas-fentanilo-orix\/","url_meta":{"origin":1470631,"position":0},"title":"Sheinbaum responde a cr\u00edticas de Trump sobre narcotr\u00e1fico en M\u00e9xico: &#171;EE.UU. debe reconocer su problema de consumo de drogas&#187;","author":"","date":"julio 17, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este jueves que Trump necesita \u201cestar bien informado\u201d sobre las accciones de M\u00e9xico contra el tr\u00e1fico de drogas, luego de que el presidente de EE.UU. afirmara que los c\u00e1rteles tienen un \u201cfuerte control\u201d sobre M\u00e9xico.En una declaraci\u00f3n durante su conferencia matutina, la mandataria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465909,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/27\/disputa-trump-maduro-paises-posicion-orix\/","url_meta":{"origin":1470631,"position":1},"title":"En la disputa entre Trump y Maduro, estos pa\u00edses de Am\u00e9rica latina ya tomaron posici\u00f3n","author":"","date":"agosto 27, 2025","format":false,"excerpt":"El enfrentamiento entre los gobiernos de Estados Unidos y Venezuela crece tanto en acusaciones como en movilizaci\u00f3n de recursos, personal y buques militares, y fuerza a los pa\u00edses de Am\u00e9rica Latina a tomar gradualmente posici\u00f3n ante la tensi\u00f3n entre dos de los actores centrales de la regi\u00f3n.A trav\u00e9s del secretario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465913,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/27\/disputa-trump-maduro-paises-toman-posicion-orix\/","url_meta":{"origin":1470631,"position":2},"title":"En la disputa entre Trump y Maduro, estos pa\u00edses de Am\u00e9rica Latina ya tomaron posici\u00f3n","author":"","date":"agosto 27, 2025","format":false,"excerpt":"El enfrentamiento entre los gobiernos de Estados Unidos y Venezuela crece tanto en acusaciones como en movilizaci\u00f3n de recursos, personal y buques militares, y fuerza a los pa\u00edses de Am\u00e9rica Latina a tomar gradualmente posici\u00f3n ante la tensi\u00f3n entre dos de los actores centrales de la regi\u00f3n.A trav\u00e9s del secretario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466501,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/09\/16\/que-pierde-colombia-descertificacion-millones-usd-orix\/","url_meta":{"origin":1470631,"position":3},"title":"\u00bfQu\u00e9 pone en juego Colombia con la descertificaci\u00f3n? Varios cientos de millones de d\u00f3lares y algo m\u00e1s","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Estados Unidos y Colombia tienen desde hace d\u00e9cadas una relaci\u00f3n de dependencia mutua. Por un lado, Estados Unidos es el principal socio comercial de Colombia y, por el otro, Bogot\u00e1 es uno de los mayores aliados estrat\u00e9gicos de Washington en la lucha contra las drogas y el terrorismo, uno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473814,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/05\/05\/estrategia-drogas-trump-colombia-mexico-orix\/","url_meta":{"origin":1470631,"position":4},"title":"Detenciones, extradiciones y frenar cultivos de coca: qu\u00e9 pide EE.UU. a M\u00e9xico y Colombia en su estrategia antidrogas","author":"","date":"mayo 5, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos quiere que los pa\u00edses de Am\u00e9rica Latina, Colombia y M\u00e9xico en particular, hagan m\u00e1s para combatir el tr\u00e1fico de drogas que, seg\u00fan la Casa Blanca, representa \u201cuna de las m\u00e1s graves amenazas\u201d para sus ciudadanos.La nueva Estrategia Nacional de Control de Drogas de Estados Unidos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466957,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/09\/29\/decreto-maduro-intervencion-extranjera-estados-unidos-orix\/","url_meta":{"origin":1470631,"position":5},"title":"Maduro firma decreto que le otorga poderes especiales ante posible &#171;agresi\u00f3n externa&#187; de EE.UU.","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"La vicepresidenta de Venezuela, Delcy Rodr\u00edguez, inform\u00f3 este lunes que el presidente Nicol\u00e1s Maduro firm\u00f3 un decreto que le otorga poderes especiales en caso de una incursi\u00f3n militar extranjera.\u201cCualquier tipo de agresi\u00f3n externa\u2026 si se atreviesen las Fuerzas Armadas militares de los Estados Unidos se considera una agresi\u00f3n externa y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470631"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470631\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}