{"id":1470646,"date":"2026-01-30T02:03:45","date_gmt":"2026-01-30T10:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/"},"modified":"2026-01-30T02:03:45","modified_gmt":"2026-01-30T10:03:45","slug":"solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","title":{"rendered":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n"},"content":{"rendered":"<p>Dos d\u00edas despu\u00e9s de que agentes de Inmigraci\u00f3n y Control de Aduanas en Minnesota supuestamente derribaron a una cuidadora a domicilio procedente del \u00c1frica subsahariana al pavimento nevado y se la llevaron en una camioneta, una amiga cercana hizo el viaje de 2.200 km hasta un controvertido <a href=\"https:\/\/www.cnn.com\/2026\/01\/21\/us\/lunas-campos-ice-detainee-texas-death\">centro de detenci\u00f3n de Texas<\/a> donde se encuentra detenida.<\/p>\n<p>\u201cSe sorprendi\u00f3 much\u00edsimo al verme\u201d, dijo su amigo Justin, un cuidador a domicilio de 40 a\u00f1os que pidi\u00f3 no revelar su nombre completo por temor a represalias. \u201cNunca crey\u00f3 que alguien supiera d\u00f3nde estaba\u201d.<\/p>\n<p>Ella no est\u00e1 sola.<\/p>\n<p>Decenas de solicitantes de asilo como ella, as\u00ed como refugiados que pasaron un riguroso proceso de selecci\u00f3n que dur\u00f3 a\u00f1os antes de ser admitidos en Estados Unidos, han sido arrestados en Minnesota en las \u00faltimas semanas, dicen abogados y defensores de inmigraci\u00f3n.<\/p>\n<p>Los inmigrantes son encadenados y trasladados en vuelos a centros de detenci\u00f3n en Texas, donde se les obliga a relatar sus dolorosas solicitudes de asilo con poco o ning\u00fan contacto con familiares o abogados, seg\u00fan abogados y defensores. Algunos, tras d\u00edas de entrevistas con agentes, han sido liberados en Texas sin dinero, identificaci\u00f3n ni tel\u00e9fono. Otros permanecen detenidos sin informaci\u00f3n sobre el motivo de su detenci\u00f3n.<\/p>\n<p>\u201cEs realmente una campa\u00f1a de terror. Est\u00e1 dise\u00f1ada para asustar a la gente\u201d, dijo Laurie Ball Cooper, vicepresidenta de programas legales estadounidenses del Proyecto Internacional de Asistencia a Refugiados. \u201cS\u00e9 que ha habido muchas historias de desorganizaci\u00f3n. No estoy segura de que esta sea una de ellas\u201d.<\/p>\n<p>Tom Homan, el zar fronterizo del presidente Donald Trump, reconoci\u00f3 el jueves que el esfuerzo de control de inmigraci\u00f3n en Minnesota necesitaba ser \u201carreglado\u201d y dijo que su equipo estaba trabajando en un plan de reducci\u00f3n mientras agudizaba el enfoque de las operaciones en inmigrantes indocumentados con antecedentes penales.<\/p>\n<p>Homan, enviado por la administraci\u00f3n a Minneapolis para gestionar las operaciones de ICE tras el <a href=\"https:\/\/www.cnn.com\/2026\/01\/28\/us\/cbp-pretti-investigation-evidence-fbi-dhs\">tiroteo fatal de Alex Pretti,<\/a> dijo que no \u201ctodo lo que se ha hecho aqu\u00ed ha sido perfecto\u201d y que \u201cse pueden y se deben hacer ciertas mejoras\u201d.<\/p>\n<p>Los refugiados <strong><\/strong>provienen de pa\u00edses como Somalia, Etiop\u00eda, Afganist\u00e1n, Siria, El Salvador, Venezuela y Rusia, afirm\u00f3 Ball Cooper. Entraron a Estados Unidos legalmente, pero no pueden solicitar la permanencia hasta un a\u00f1o despu\u00e9s de su admisi\u00f3n, como lo exige la ley estadounidense. Ball Cooper y otros defensores han estado en contacto con algunos de estos refugiados, quienes, seg\u00fan afirman, no han sido acusados \u200b\u200bde delitos o infracciones migratorias que los expongan a un proceso de deportaci\u00f3n.<\/p>\n<p>\u201cConozco casos en los que la persona fue arrestada, detenida en Minnesota y subida a un avi\u00f3n (a Texas) en 90 minutos o menos\u201d, dijo Ball Cooper a CNN, y agreg\u00f3 que los abogados y defensores en Minnesota y Texas se han visto obligados a luchar para conectarse con muchos de los refugiados.<\/p>\n<p>El mi\u00e9rcoles por la noche, un juez federal emiti\u00f3 una orden de restricci\u00f3n temporal que impide al gobierno de Trump arrestar o detener a refugiados reasentados en Minnesota mientras se tramita una demanda colectiva que impugna esta pr\u00e1ctica. El juez tambi\u00e9n orden\u00f3 la liberaci\u00f3n inmediata de todos los refugiados detenidos en Minnesota, as\u00ed como la liberaci\u00f3n de aquellos que fueron sacados del estado en un plazo de cinco d\u00edas, y dio al gobierno 48 horas para proporcionar una lista de los refugiados detenidos.<\/p>\n<p>Algunos refugiados en el caso est\u00e1n representados por el Proyecto Internacional de Asistencia a Refugiados y otras organizaciones legales y de defensa. La demanda y los abogados de los demandantes acusan a los agentes federales de perseguir puerta a puerta a los refugiados reasentados y trasladarlos a instalaciones en Texas.<\/p>\n<p>\u201cEs una expedici\u00f3n de pesca\u201d, dijo Ball Cooper sobre la persecuci\u00f3n del gobierno contra los refugiados, incluyendo ni\u00f1os y ancianos. \u201cEl enfoque del gobierno aqu\u00ed es primero arrestar, luego investigar\u201d.<\/p>\n<p>CNN contact\u00f3 al Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos, al Departamento de Seguridad Nacional y al ICE para solicitar comentarios, pero no recibi\u00f3 respuesta.<\/p>\n<p>\u201cHu\u00ed de mi pa\u00eds natal porque me enfrentaba a la represi\u00f3n del gobierno\u201d, declar\u00f3 un demandante identificado como D. Doe, se\u00f1alando que lo hab\u00edan trasladado a Texas con grilletes y esposas tras ser arrestado en su casa a principios de este mes. \u201cNo puedo creer que est\u00e9 sucediendo de nuevo aqu\u00ed. Es escalofriante y tengo miedo\u201d.<\/p>\n<p>El demandante, quien, seg\u00fan la demanda, ha vivido en Estados Unidos con su esposa e hijo desde que fue admitido como refugiado en 2024, fue detenido abruptamente el 11 de enero. Su esposa, con su hijo de 3 a\u00f1os en brazos, sali\u00f3 corriendo con sus documentos mientras los agentes se lo llevaban, seg\u00fan la demanda. Una vez en Texas, lo mantuvieron encadenado durante 16 horas y lo interrogaron sobre su solicitud de refugio antes de ser liberado sin documentos de un centro de detenci\u00f3n en Houston, seg\u00fan la demanda.<\/p>\n<p>Jocelyn Wyatt, CEO de Alight, una organizaci\u00f3n humanitaria con sede en Minneapolis, afirm\u00f3 que los defensores de los refugiados han tenido conocimiento de al menos 100 personas detenidas en Minnesota y trasladadas a Texas \u2014incluyendo El Paso, Houston y San Antonio\u2014 para ser interrogadas y reprocesadas. En algunos casos, han sido liberadas sin documentaci\u00f3n, pr\u00e1cticamente varadas en Texas, y algunas han logrado contactar con trabajadores de agencias de reasentamiento que las hab\u00edan ayudado anteriormente, explic\u00f3 Wyatt.<\/p>\n<p>\u201cEs dif\u00edcil obtener un recuento preciso de esto\u201d, dijo. \u201cEl ciclo completo est\u00e1 sucediendo muy r\u00e1pido\u201d.<\/p>\n<p>El p\u00e1nico se est\u00e1 extendiendo en las comunidades inmigrantes.<\/p>\n<p>\u201cHay miles de personas que est\u00e1n pr\u00e1cticamente cautivas o viviendo como prisioneras en sus propias casas ahora mismo, sin poder salir por miedo a ser arrestadas y detenidas\u201d, dijo Wyatt. \u201cNo van a las citas m\u00e9dicas\u2026 los ni\u00f1os no van a la escuela ahora mismo. Padres y adultos no trabajan. No pueden salir a comprar comida\u201d<\/p>\n<p>La tensi\u00f3n y el miedo en las calles de Minneapolis s\u00f3lo han aumentado desde que agentes de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos dispararon fatalmente a Pretti, el segundo asesinato de un <a href=\"https:\/\/www.cnn.com\/2026\/01\/24\/us\/invs-videos-show-federal-officer-recovered-gun\">ciudadano estadounidense<\/a> por parte de agentes de inmigraci\u00f3n este mes, despu\u00e9s de <a href=\"https:\/\/www.cnn.com\/2026\/01\/08\/us\/renee-nicole-good-minneapolis-ice-shooting-hnk\">Renee Good<\/a> .<\/p>\n<p>Durante la investigaci\u00f3n del Departamento de Estado y el Departamento de Seguridad Nacional, los refugiados deben demostrar que fueron perseguidos o enfrentan persecuci\u00f3n en sus pa\u00edses de origen y, una vez en los EE.UU., deben solicitar tarjetas verdes un a\u00f1o despu\u00e9s de la admisi\u00f3n.<\/p>\n<p>\u201cHay un elemento \u00fanico en que esto le suceda a un refugiado\u201d, dijo Ball Cooper. \u201cSe trata de una persona o familia que ya ha sufrido persecuci\u00f3n\u201d.<\/p>\n<p>Los funcionarios de Trump han criticado y analizado minuciosamente durante mucho tiempo el programa de admisi\u00f3n de refugiados, que hist\u00f3ricamente ha contado con apoyo bipartidista, y argumentaron que la administraci\u00f3n anterior no investig\u00f3 adecuadamente a las personas que ingresaban a Estados Unidos. Trump ha suspendido en gran medida la admisi\u00f3n de refugiados, con la estrecha excepci\u00f3n de los sudafricanos blancos. A finales del a\u00f1o pasado, la administraci\u00f3n <a href=\"https:\/\/www.cnn.com\/2025\/11\/24\/politics\/trump-refugee-program-interviews-biden\">decidi\u00f3 volver a entrevistar<\/a> a ciertos refugiados admitidos en Estados Unidos durante el mandato del expresidente Joe Biden como parte de una revisi\u00f3n exhaustiva.<\/p>\n<p>El n\u00famero de arrestos comenz\u00f3 a aumentar en Minnesota a principios de este mes, cuando la administraci\u00f3n inici\u00f3 una  \u201c<a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/dhs-launches-landmark-uscis-fraud-investigation-in-minnesota\">amplia iniciativa<\/a> \u201d para reexaminar a los refugiados en Minnesota, con un enfoque inicial de 5.600 personas, desatando bandas de agentes en las calles para golpear puertas, seguir autos y presentarse en lugares de trabajo y escuelas, enviando una ola de p\u00e1nico entre los refugiados y otros inmigrantes en todo el estado, dijeron los defensores.<\/p>\n<p>Amiin Harun, abogado de Minneapolis, afirm\u00f3 conocer al menos siete casos de solicitantes de asilo o refugiados arrestados en Minneapolis-Saint Paul en las \u00faltimas semanas y trasladados r\u00e1pidamente a Texas. Un caso que maneja su oficina involucra a un refugiado que fue detenido en una situaci\u00f3n de tr\u00e1fico por agentes de ICE poco despu\u00e9s de salir de su hogar. El arresto ocurri\u00f3 hace unas dos semanas a las 9:20 a. m., seg\u00fan Harun. A la 1 p. m., el hombre, casado y con dos hijos peque\u00f1os, ya estaba en un vuelo a Texas.<\/p>\n<p>Al d\u00eda siguiente, dijo Harun, recibi\u00f3 una llamada de un oficial de inmigraci\u00f3n diciendo que quer\u00edan interrogar a su cliente durante aproximadamente cuatro horas, a pesar de que no ten\u00eda solicitudes pendientes con el gobierno.<\/p>\n<p>\u201cNo he tenido noticias de mi cliente desde entonces, pero le ped\u00ed que tuviera cuidado\u201d, dijo Harun. \u201cNo tiene ninguna obligaci\u00f3n legal de responder a sus preguntas. As\u00ed que, que guarde silencio\u201d.<\/p>\n<p>Ninguno de los refugiados detenidos representados en la demanda ha sido acusado de ning\u00fan delito ni violaci\u00f3n de las leyes migratorias, seg\u00fan la demanda y sus defensores. Las \u201cdetenciones infundadas y las entrevistas coercitivas\u201d ten\u00edan como objetivo \u201cprovocar la cancelaci\u00f3n masiva de la condici\u00f3n de refugiado\u201d y dejar a los refugiados vulnerables a la deportaci\u00f3n, seg\u00fan la demanda.<\/p>\n<p>Sara Nelson, directora de programas del Centro para V\u00edctimas de Tortura, una organizaci\u00f3n sin fines de lucro que brinda atenci\u00f3n de salud mental y servicios de trabajo social en Minnesota, inform\u00f3 que cinco clientes \u2014solicitantes de asilo con permisos de trabajo\u2014 fueron detenidos por el ICE y enviados a Texas. Uno fue devuelto a Minnesota, pero a\u00fan se encuentra bajo custodia.<\/p>\n<p>\u201cLos clientes expresaron temor y dijeron que nadie parece poder ayudarlos\u201d, dijo Nelson. \u201cUna de ellas tiene una afecci\u00f3n m\u00e9dica grave y requiere medicaci\u00f3n diaria y una cirug\u00eda pr\u00f3xima. Informa que no le han dado su medicaci\u00f3n, y hemos intentado presentar un certificado m\u00e9dico sobre sus necesidades m\u00e9dicas varias veces, sin respuesta\u2026 Es realmente aterrador ver cu\u00e1ntas personas se consumen en estas instalaciones, solas y asustadas\u201d.<\/p>\n<p>\u201cEl temor es que los casos simplemente se cancelen administrativamente y los deporten sin tener su d\u00eda en la corte o sin el debido proceso\u201d, agreg\u00f3.<\/p>\n<p>Si son deportados, los refugiados probablemente se convertir\u00e1n en un blanco a\u00fan m\u00e1s dif\u00edcil para quienes huyen en primer lugar, dijo Nelson.<\/p>\n<p>\u201cLa gente va a morir, para ser totalmente franca\u201d, dijo.<\/p>\n<p>Justin, un ciudadano estadounidense naturalizado del \u00c1frica subsahariana, dijo que vol\u00f3 a Texas dos veces desde Minnesota en la semana despu\u00e9s de que su amiga fuera detenida el 9 de enero y transferido al Campamento East Montana en El Paso, donde al menos tres detenidos murieron mientras estaban bajo custodia de ICE en las \u00faltimas semanas, incluido uno mientras recib\u00eda tratamiento en un hospital cercano.<\/p>\n<p>Tras suplicar a los oficiales del centro de detenci\u00f3n, Justin dijo que le permitieron ver a su amiga. Estuvieron separados por una mampara durante una reuni\u00f3n de una hora.<\/p>\n<p>\u201cNo se ve\u00eda bien\u201d, dijo. \u201cEstaba p\u00e1lida. Dijo que no hab\u00eda dormido. Estaba agotada. Apenas hablaba. Tuve que acercarme a la pantalla para o\u00edrla. Lo \u00fanico que pudo decirme fue: \u2018Por favor, s\u00e1came de aqu\u00ed\u2019\u201d.<\/p>\n<p>Justin record\u00f3 el miedo que sent\u00eda cada vez que se acercaba a la entrada del centro de detenci\u00f3n.<\/p>\n<p>\u201cTen\u00eda miedo de m\u00ed mismo al ir all\u00ed. El coraz\u00f3n me lat\u00eda con fuerza como si tuviera la presi\u00f3n alta\u201d, dijo. \u201cPorque me dijo que hab\u00eda ciudadanos estadounidenses dentro. Llevaba mi pasaporte estadounidense conmigo. Incre\u00edble. Era la primera vez que llevaba mi pasaporte en Estados Unidos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos d\u00edas despu\u00e9s de que agentes de Inmigraci\u00f3n y Control de Aduanas en Minnesota supuestamente derribaron a una cuidadora a domicilio procedente del \u00c1frica subsahariana al pavimento nevado y se la llevaron en una camioneta, una amiga cercana hizo el viaje de 2.200 km hasta un controvertido centro de detenci\u00f3n de Texas donde se encuentra [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470646","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos d\u00edas despu\u00e9s de que agentes de Inmigraci\u00f3n y Control de Aduanas en Minnesota supuestamente derribaron a una cuidadora a domicilio procedente del \u00c1frica subsahariana al pavimento nevado y se la llevaron en una camioneta, una amiga cercana hizo el viaje de 2.200 km hasta un controvertido centro de detenci\u00f3n de Texas donde se encuentra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T10:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n\",\"datePublished\":\"2026-01-30T10:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\"},\"wordCount\":2007,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\",\"name\":\"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-30T10:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias","og_description":"Dos d\u00edas despu\u00e9s de que agentes de Inmigraci\u00f3n y Control de Aduanas en Minnesota supuestamente derribaron a una cuidadora a domicilio procedente del \u00c1frica subsahariana al pavimento nevado y se la llevaron en una camioneta, una amiga cercana hizo el viaje de 2.200 km hasta un controvertido centro de detenci\u00f3n de Texas donde se encuentra [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-30T10:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/"},"author":{"name":"","@id":""},"headline":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n","datePublished":"2026-01-30T10:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/"},"wordCount":2007,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","name":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-30T10:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\u00f3 a Texas para enfrentar la deportaci\u00f3n","url":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/30\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-30T10:03:45Z","datePublished":"2026-01-30T10:03:45Z","dateModified":"2026-01-30T10:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Eran solicitantes de asilo y refugiados en Minnesota. ICE los detuvo y los traslad\\u00f3 a Texas para enfrentar la deportaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/30\\\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/30\\\/solicitantes-asilo-refugiados-minnesota-ice-deportacion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-30T10:03:45Z\",\"datePublished\":\"2026-01-30T10:03:45Z\",\"dateModified\":\"2026-01-30T10:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468425,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/17\/gran-bretana-cambio-normas-asilo-trax\/","url_meta":{"origin":1470646,"position":0},"title":"Gran Breta\u00f1a anuncia el cambio m\u00e1s radical en las normas de asilo en a\u00f1os, alargando la ruta para la residencia permanente","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"Gran Breta\u00f1a planea llevar a cabo la reforma m\u00e1s significativa de su pol\u00edtica de asilo en la era moderna, convirtiendo el estatus de refugiado en temporal y cuadruplicando a 20 a\u00f1os el tiempo de espera para la residencia permanente. El Gobierno laborista se enfrenta a un sistema de asilo deficiente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466828,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/09\/25\/gobierno-de-trump-sistema-global-de-asilo-trax\/","url_meta":{"origin":1470646,"position":1},"title":"Gobierno de Trump dice que el sistema global de asilo permite que &#171;la inmigraci\u00f3n ilegal masiva sea legal&#187; y pide cambiarlo","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Un alto funcionario del Gobierno de Trump pidi\u00f3 este jueves cambios en las pol\u00edticas internacionales de asilo de larga data, una medida que se produce en medio de un cambio radical en Estados Unidos que ha trastocado y restringido las pol\u00edticas migratorias en el pa\u00eds.En declaraciones al margen de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467881,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/10\/30\/jueza-suspende-tarifa-solicitudes-asilo-trax\/","url_meta":{"origin":1470646,"position":2},"title":"Un jueza federal suspende el cobro de una tarifa para tramitar las solicitudes de asilo","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Una jueza federal de Maryland suspendi\u00f3 temporalmente la implementaci\u00f3n por parte del Gobierno de una nueva tarifa anual para la solicitud de asilo. Aleg\u00f3 que hubo confusi\u00f3n e inconsistencias en las pol\u00edticas entre las agencias federales.La jueza Stephanie Gallagher afirm\u00f3 que dos agencias, el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457715,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","url_meta":{"origin":1470646,"position":3},"title":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo","author":"","date":"enero 21, 2025","format":false,"excerpt":"La frontera entre Estados Unidos y M\u00e9xico se cerr\u00f3 efectivamente a los migrantes que buscan asilo en Estados Unidos pocas horas despu\u00e9s de que el presidente Donald Trump asumiera el cargo, una desviaci\u00f3n extraordinaria de los protocolos anteriores que ha dejado en el limbo a muchos migrantes preocupados.Se trata de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468427,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/11\/17\/corte-suprema-revisara-politica-trump-asilo-frontera-trax\/","url_meta":{"origin":1470646,"position":4},"title":"La Corte Suprema revisar\u00e1 una pol\u00edtica revocada de Trump que permit\u00eda rechazar a los solicitantes de asilo en la frontera","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"La Corte Suprema de EE.UU. anunci\u00f3 el lunes que revisar\u00e1 una pol\u00e9mica pol\u00edtica inmigratoria adoptada durante el primer mandato de Trump, que consist\u00eda en rechazar a potenciales solicitantes de asilo antes de que pisaran suelo estadounidense, dando inicio al primer caso importante sobre pol\u00edtica inmigratoria de este per\u00edodo.La ley federal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472503,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/24\/corte-suprema-examinara-politica-asilo-frontera-sur-trax\/","url_meta":{"origin":1470646,"position":5},"title":"La Corte Suprema examinar\u00e1 una antigua pol\u00edtica que permit\u00eda rechazar a los solicitantes de asilo en la frontera sur","author":"","date":"marzo 24, 2026","format":false,"excerpt":"La Corte Suprema examinar\u00e1 este martes la legalidad de una pol\u00edtica impulsada por el presidente Donald Trump durante su primer mandato que impidi\u00f3 que un gran n\u00famero de migrantes que llegaban a la frontera sur iniciaran el proceso de solicitud de asilo.La pol\u00edtica fue originalmente presentada bajo la presidencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470646"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470646\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}