{"id":1470708,"date":"2026-01-31T12:03:38","date_gmt":"2026-01-31T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/"},"modified":"2026-01-31T12:03:38","modified_gmt":"2026-01-31T20:03:38","slug":"liam-conejo-ramos-liberan-ice-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","title":{"rendered":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente"},"content":{"rendered":"<p>Un juez federal ha ordenado la liberaci\u00f3n de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/23\/latinoamerica\/exclusivo-entrevista-familia-liam-ice-minnesota-orix\">Liam Conejo Ramos<\/a>, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado.<\/p>\n<p>CNN no logr\u00f3 hasta el momento obtener una copia del fallo del juez.<\/p>\n<p>Conejo Ramos y su padre fueron detenidos por agentes de inmigraci\u00f3n en la entrada de su casa en un suburbio de Minneapolis, cubierta de nieve, y trasladados a m\u00e1s de 2.000 kil\u00f3metros de distancia, a un centro de detenci\u00f3n en Texas dise\u00f1ado para familias. Han estado detenidos durante m\u00e1s de una semana.<\/p>\n<p>La orden especifica que el ni\u00f1o en edad preescolar y su padre deben ser liberados a m\u00e1s tardar el martes, mientras su caso de inmigraci\u00f3n avanza en el sistema judicial, seg\u00fan <a href=\"https:\/\/www.expressnews.com\/news\/article\/judge-5-year-old-migrant-released-texas-ice-21320852.php?utm_source=marketing&#038;utm_medium=copy-url-link&#038;utm_campaign=article-share&#038;hash=aHR0cHM6Ly93d3cuZXhwcmVzc25ld3MuY29tL25ld3MvYXJ0aWNsZS9qdWRnZS01LXllYXItb2xkLW1pZ3JhbnQtcmVsZWFzZWQtdGV4YXMtaWNlLTIxMzIwODUyLnBocA%3D%3D&#038;time=MTc2OTg4NTA5NTg4Mg%3D%3D&#038;rid=NzJjM2I3M2UtNWVhOS00Yjk5LWI0NDgtYTc4NzUyODY3MGQy&#038;sharecount=MQ%3D%3D\">San Antonio Express-News<\/a>, que fue el primer medio en informar sobre el fallo.<\/p>\n<p>La detenci\u00f3n de Liam, y la impactante fotograf\u00eda de un agente sosteniendo la mochila de Spiderman del ni\u00f1o mientras \u00e9l miraba con un gorro de conejo de dibujos animados, avivaron la creciente indignaci\u00f3n por la masiva represi\u00f3n migratoria del Gobierno de Trump en Minneapolis y reavivaron la pregunta: \u00bfQu\u00e9 sucede con los ni\u00f1os cuando sus padres son detenidos repentinamente por el ICE?<\/p>\n<p>Aunque las detenciones a nivel nacional han afectado a algunos delincuentes indocumentados, a quienes el Gobierno de Trump afirma estar persiguiendo, tambi\u00e9n han afectado a residentes legales, familias y ni\u00f1os peque\u00f1os. Liam es el cuarto ni\u00f1o de su distrito escolar en ser detenido por agentes de inmigraci\u00f3n en un per\u00edodo de dos semanas, seg\u00fan las Escuelas P\u00fablicas de Columbia Heights. Y el pasado fin de semana, una ni\u00f1a peque\u00f1a fue devuelta a su madre en Minneapolis despu\u00e9s de haber sido detenida de manera similar y enviada a Texas con su padre.<\/p>\n<p>El representante dem\u00f3crata Joaqu\u00edn Castro, quien visit\u00f3 al ni\u00f1o y a su padre en el centro de detenci\u00f3n a principios de esta semana, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/28\/eeuu\/deprimido-sin-comer-liam-conejo-ice-texas-trax\">hab\u00eda declarado<\/a> anteriormente que el ni\u00f1o estaba \u201cmuy deprimido\u201d.<\/p>\n<p>El padre de Liam le cont\u00f3 a Castro que su hijo no ha estado comiendo bien, duerme mucho y pregunta por su madre y sus compa\u00f1eros de clase, inform\u00f3 el congresista el mi\u00e9rcoles.<\/p>\n<p>Mientras que los familiares y los administradores escolares han acusado a ICE de usar a Liam como \u201ccebo\u201d para capturar a sus padres, los funcionarios de inmigraci\u00f3n dicen que su madre estaba a pocos pasos de distancia, pero se neg\u00f3 a llev\u00e1rselo.<\/p>\n<p>La madre de Liam, que est\u00e1 embarazada y tambi\u00e9n tiene un hijo adolescente, estaba \u201caterrorizada\u201d por los agentes que estaban afuera de su casa, dijo el pastor Sergio Amezcua, quien ha estado ayudando a la madre.<\/p>\n<p>\u201cLos agentes de ICE intentaban usar al ni\u00f1o para que ella saliera de su casa\u201d, dijo Amezcua. Pero los vecinos le aconsejaron que no saliera, por temor a que tambi\u00e9n fuera detenida.<\/p>\n<p>Un agente \u201clo llev\u00f3 a la puerta y le indic\u00f3 que tocara, pidiendo que lo dejaran entrar, para ver si hab\u00eda alguien m\u00e1s en la casa; b\u00e1sicamente, usando a un ni\u00f1o de 5 a\u00f1os como cebo\u201d, dijo Zena Stenvik, superintendente del distrito escolar local.<\/p>\n<p>Mary Granlund, presidenta de la junta escolar de las Escuelas P\u00fablicas de Columbia Heights, pasaba en su auto y presenci\u00f3 la escena. Le dijo a CNN que la madre de Liam miraba por una ventana, mientras que el padre de Liam gritaba: \u201c\u00a1Por favor, no abran la puerta! \u00a1No abran la puerta!\u201d.<\/p>\n<p>\u201cHab\u00eda otro adulto que viv\u00eda en la casa y que estaba all\u00ed diciendo: \u2018Yo me llevo al ni\u00f1o. Yo me llevo al ni\u00f1o\u2019\u201d, dijo Granlund.<\/p>\n<p>Sin embargo, el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) ha ofrecido una versi\u00f3n diferente, diciendo que el padre de Liam huy\u00f3 cuando los agentes intentaron detenerlo, dejando al ni\u00f1o solo.<\/p>\n<p>El DHS dijo en una publicaci\u00f3n en redes sociales que la \u201csupuesta madre de Liam se NEG\u00d3 a hacerse cargo de su propio hijo\u201d a pesar de \u201cm\u00faltiples intentos de que la madre entrara a la casa para hacerse cargo de su hijo\u201d.<\/p>\n<p>\u201cSe les pregunta a los padres si desean ser deportados con sus hijos, o ICE colocar\u00e1 a los ni\u00f1os con una persona segura designada por el padre\u201d, dec\u00eda la publicaci\u00f3n.<\/p>\n<p>El DHS dijo en otra publicaci\u00f3n que los agentes \u201crespetaron los deseos del padre de que el ni\u00f1o permaneciera con \u00e9l\u201d.<\/p>\n<p>Un funcionario de ICE dijo que la agencia nunca ha \u201cusado a un ni\u00f1o como cebo\u201d.<\/p>\n<p>\u201cMis oficiales hicieron todo lo posible para reunirlo con su familia\u201d, dijo Marcos Charles, director asociado ejecutivo interino de Operaciones de Control y Remoci\u00f3n de ICE. Dijo que los agentes cuidaron de Liam y lo llevaron a McDonald\u2019s para que comiera.<\/p>\n<p>El Departamento de Seguridad Nacional ha calificado al padre de Liam como un \u201cinmigrante indocumentado\u201d, pero su abogado afirma que la familia entr\u00f3 legalmente a Estados Unidos y estaba solicitando asilo.<\/p>\n<p>Liam y su familia son de Ecuador y se presentaron ante los agentes fronterizos en Texas en diciembre de 2024 para solicitar asilo, seg\u00fan el abogado de la familia, Marc Prokosch.<\/p>\n<p>El padre y su esposa llegaron a Estados Unidos buscando \u201cuna vida mejor\u201d, lejos de la inestabilidad econ\u00f3mica y la precariedad laboral en Ecuador, seg\u00fan declar\u00f3 su hermano, Luis Conejo, a CNN.<\/p>\n<p>El padre de Liam no parece tener antecedentes penales en Minnesota, dijo Prokosch. Los funcionarios del DHS a\u00fan no han compartido ning\u00fan historial criminal de Conejo Arias, y una fuente familiarizada con el caso le dijo a CNN que no parece tener antecedentes penales.<\/p>\n<p>Cuando se le pregunt\u00f3 sobre posibles antecedentes penales, la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin, dijo: \u201cLa ley exige que quienes se encuentran ilegalmente en el pa\u00eds y alegan temor a ser detenidos permanezcan bajo custodia en espera de su deportaci\u00f3n. Pueden consultar la ley\u201d.<\/p>\n<p>CNN no ha podido encontrar ning\u00fan antecedente penal de Arias en fuentes p\u00fablicas. No ten\u00eda antecedentes penales en Ecuador, seg\u00fan el Ministerio del Interior de ese pa\u00eds.<\/p>\n<p><em>Esta es una noticia ha sido actualizada con m\u00e1s informaci\u00f3n.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez federal ha ordenado la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado. CNN no logr\u00f3 hasta el momento obtener una copia del fallo del juez. Conejo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470708","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un juez federal ha ordenado la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado. CNN no logr\u00f3 hasta el momento obtener una copia del fallo del juez. Conejo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente\",\"datePublished\":\"2026-01-31T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\"},\"wordCount\":1119,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\",\"name\":\"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-31T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias","og_description":"Un juez federal ha ordenado la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado. CNN no logr\u00f3 hasta el momento obtener una copia del fallo del juez. Conejo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-31T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/"},"author":{"name":"","@id":""},"headline":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente","datePublished":"2026-01-31T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/"},"wordCount":1119,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","name":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-31T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente","url":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-31T20:03:38Z","datePublished":"2026-01-31T20:03:38Z","dateModified":"2026-01-31T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un juez ordena la liberaci\\u00f3n de Liam Conejo Ramos, de 5 a\\u00f1os, y su padre, seg\\u00fan una fuente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/31\\\/liam-conejo-ramos-liberan-ice-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/01\\\/31\\\/liam-conejo-ramos-liberan-ice-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-31T20:03:38Z\",\"datePublished\":\"2026-01-31T20:03:38Z\",\"dateModified\":\"2026-01-31T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470750,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/liam-ramos-5-anos-custodia-federal-trax\/","url_meta":{"origin":1470708,"position":0},"title":"\u00bfQu\u00e9 sigue para Liam Ramos, de 5 a\u00f1os, y su padre tras su liberaci\u00f3n de la custodia federal?","author":"","date":"febrero 2, 2026","format":false,"excerpt":"De regreso a casa en Minneapolis despu\u00e9s de m\u00e1s de una semana en un centro de inmigraci\u00f3n en Texas, el ni\u00f1o ecuatoriano en edad preescolar Liam Conejo Ramos y su padre est\u00e1n tratando de recuperar una sensaci\u00f3n de normalidad en medio de casos judiciales en curso y una tormenta nacional,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470709,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/31\/que-paso-liam-conejo-ramos-trax\/","url_meta":{"origin":1470708,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 con el ni\u00f1o de 5 a\u00f1os Liam Conejo Ramos?","author":"","date":"enero 31, 2026","format":false,"excerpt":"El martes 20 de enero, Liam Conejo Ramos, de 5 a\u00f1os, fue llevado por funcionarios del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) despu\u00e9s de regresar a casa del preescolar en el suburbio de Columbia Heights, Minneapolis.Envuelto en su peque\u00f1o abrigo de cuadros y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470976,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/07\/juez-aplazo-asilo-liam-conejo-familia-trax\/","url_meta":{"origin":1470708,"position":2},"title":"Juez concede aplazo en el caso de asilo de Liam Conejo Ramos y su familia en EE.UU., pero su futuro sigue en vilo","author":"","date":"febrero 7, 2026","format":false,"excerpt":"Liam Conejo Ramos, de cinco a\u00f1os, y su familia tendr\u00e1n m\u00e1s tiempo para presentar su caso de asilo.En una audiencia judicial llevada a cabo el viernes por el caso de asilo de la familia, un juez concedi\u00f3 un aplazo, lo que pospone el caso para una fecha posterior, dijo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470533,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/27\/liam-cornejo-juez-bloquea-deportacion-padre-hijo-cinco-anos-trax\/","url_meta":{"origin":1470708,"position":3},"title":"Un juez federal bloquea, por ahora, la posible deportaci\u00f3n del ni\u00f1o de 5 a\u00f1os Liam Conejo Ramos y su padre","author":"","date":"enero 27, 2026","format":false,"excerpt":"Un ni\u00f1o de preescolar de Minnesota detenido en Texas con su padre no puede ser deportado de manera inminente, dictamin\u00f3 un juez federal el lunes.Liam Conejo Ramos, de 5 a\u00f1os, fue separado de la entrada de la casa de su familia en los suburbios de Minneapolis la semana pasada despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470586,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/28\/deprimido-sin-comer-liam-conejo-ice-texas-trax\/","url_meta":{"origin":1470708,"position":4},"title":"Deprimido y extra\u00f1ando a su madre: legislador describe la situaci\u00f3n del ni\u00f1o de 5 a\u00f1os Liam Conejo en centro de ICE en Texas","author":"","date":"enero 28, 2026","format":false,"excerpt":"El legislador estadounidense Joaquin Castro se reuni\u00f3 este mi\u00e9rcoles con Liam Conejo Ramos, el ni\u00f1o de cinco a\u00f1os de Minnesota que fue separado de su familia en la entrada de su casa en un suburbio de Minneapolis la semana pasada, luego de que agentes federales detuvieran a su padre, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470765,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/liam-conejo-ramos-liberacion-reaccion-familia-orix\/","url_meta":{"origin":1470708,"position":5},"title":"La emotiva reacci\u00f3n de la familia de Liam Conejo Ramos ante la noticia de su regreso a casa: &#171;Es lo que rog\u00e1bamos al cielo&#187;","author":"","date":"febrero 2, 2026","format":false,"excerpt":"Liam Conejo Ramos y su padre est\u00e1n de regreso en su casa en Minneapolis, despu\u00e9s de m\u00e1s de una semana en un centro de inmigraci\u00f3n en Texas. La salida de ambos gener\u00f3 alivio entre sus familiares, aunque a\u00fan hay incertidumbre sobre c\u00f3mo seguir\u00e1 el caso.\u201cEstoy s\u00faper contenta de que mi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470708"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470708\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}