{"id":1470779,"date":"2026-02-02T18:03:41","date_gmt":"2026-02-03T02:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/"},"modified":"2026-02-02T18:03:41","modified_gmt":"2026-02-03T02:03:41","slug":"fichajes-mercado-europa-mas-destacados-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","title":{"rendered":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados"},"content":{"rendered":"<p>Europa cerr\u00f3 este lunes un mercado de fichajes de mitad de temporada marcado nuevamente por el desembolso de billetes desde la Premier League. El Liverpool, que se gast\u00f3 m\u00e1s de US$ 500 millones en el verano boreal, volvi\u00f3 a romper la ventana de transferencias con un jugador que ni siquiera jugar\u00e1 de inmediato en Anfield Road. Y el Manchester City se hizo con el pase m\u00e1s caro de todo el mercado.<\/p>\n<p>En Espa\u00f1a, en tanto, rein\u00f3 por su ausencia la participaci\u00f3n del Real Madrid y el FC Barcelona, que, a contramano, terminaron cediendo jugadores al extranjero. El del Merengue es el caso m\u00e1s llamativo, porque est\u00e1 sumergido en una profunda crisis futbol\u00edstica y porque para colmo todav\u00eda est\u00e1 digiriendo la lesi\u00f3n de Jude Bellingham, que se perder\u00e1 un mes de competencia. Para colmo, la repesca ante el Benfica por la Champions League ya est\u00e1 casi tocando a la puerta.<\/p>\n<p>El club espa\u00f1ol que s\u00ed se destac\u00f3 este lunes fue el Atl\u00e9tico de Madrid, quien cerr\u00f3 al estadounidense nacionalizado mexicano Obed Vargas y al veloz delantero Ademola Lookman, con la esperanza de enderezar el rumbo de una campa\u00f1a donde est\u00e1 claramente en el debe.<\/p>\n<p>La temporada del Manchester City dista de ser la ideal, y por eso, los Citizens de Pep Guardiola volvieron a salir al mercado en busca de un jugador desequilibrante que acompa\u00f1e al ariete Erling Haaland.<\/p>\n<p>La respuesta a esa b\u00fasqueda fue el delantero Antoine Semenyo, por quien pag\u00f3 casi US$ 85 millones m\u00e1s variables al Bournemouth, tambi\u00e9n de la Premier League. El extremo derecho tuvo un impacto inmediato, con cuatro goles en cinco partidos jugados en todas las competencias.<\/p>\n<p>El atacante ghan\u00e9s es una fija de su selecci\u00f3n para el Mundial de 2026.<\/p>\n<p>Si alguno pensaba que el Liverpool se hab\u00eda quedado sin chequera tras un verano donde compr\u00f3 jugadores por m\u00e1s de US$ 500 millones, estaba muy equivocado. Es m\u00e1s, los Reds ya est\u00e1n gastando para la pr\u00f3xima temporada.<\/p>\n<p>El \u00faltimo refuerzo de los ingleses es el joven defensor J\u00e9r\u00e9my Jacquet, quien firmar\u00e1 por cinco a\u00f1os con el Liverpool, aunque permanecer\u00e1 en su actual club, el Rennes de la Ligue 1 de Francia, hasta mitad de 2026.<\/p>\n<p>Con esto, los Reds, que estar\u00edan pagando unos US$ 70 millones por la contrataci\u00f3n, demuestran que empiezan a pensar en el recambio de una defensa que no se ha visto bien en lo que va de la presente campa\u00f1a.<\/p>\n<p>El pase que gener\u00f3 la furia de Cristiano Ronaldo cost\u00f3 cero centavos. S\u00ed, como leen. El delantero franc\u00e9s rescindi\u00f3 su contrato con el Al-Ittihad, en medio de rumores de que el club de Yeda le hab\u00eda ofrecido una renovaci\u00f3n para jugar \u201cgratis\u201d.<\/p>\n<p>El ganador de cinco Champions League con el Real Madrid encontr\u00f3 equipo muy r\u00e1pido: el Al-Hilal, el actual l\u00edder del campeonato de Arabia Saudita, con el que firm\u00f3 por una temporada y media, seg\u00fan confirm\u00f3 el propio club.<\/p>\n<p>M\u00e1s all\u00e1 de que la transferencia se hizo sin costo, su llegada al Al-Hilal puede ser trascendental, y as\u00ed lo marca la postura que tom\u00f3 Cristiano Ronaldo, quien se neg\u00f3 a jugar este lunes con el Al-Nassr (segundo en la tabla) como protesta por la poca inversi\u00f3n en fichajes de los due\u00f1os de su club.<\/p>\n<p>LaLiga no estuvo muy activa en la ventana de enero, pero el Atl\u00e9tico de Madrid rompi\u00f3 ese molde, al desembolsar casi US$ 65 millones en total. La mayor\u00eda (m\u00e1s de US$ 41 millones) fueron para costear el traspaso del delantero nigeriano Ademola Lookman, la figura del Atalanta de Italia.<\/p>\n<p>La anemia ofensiva es una de las principales cr\u00edticas que se le han hecho al Colchonero de Diego el Cholo Simeone, en medio de un baj\u00f3n del rendimiento de Juli\u00e1n \u00c1lvarez y los problemas sin soluci\u00f3n que arrastra Alexander Sorloth.<\/p>\n<p>Lookman tendr\u00e1 que acoplarse r\u00e1pido al equipo, que en un par de semanas se juega su continuidad en la Champions League.<\/p>\n<p>A pesar de todo el dinero que han gastado en incorporaciones los clubes europeos, es una salida la que ha terminado por reconfigurar el mercado de fichajes. La venta del brasile\u00f1o Lucas Paquet\u00e1, que dej\u00f3 el West Ham de la Premier League para volver al Flamengo de Brasil por unos US$ 50 millones, acab\u00f3 por situar al Brasileirao a la altura del Viejo Continente.<\/p>\n<p>No es la primera vez que un jugador pasa del f\u00fatbol europeo al sudamericano por una cifra onerosa. Basta recordar los casos de Vitor Roque (del FC Barcelona al Palmeiras) o el de Samuel Lino (del Atl\u00e9tico de Madrid al propio Flamengo). Pero la cifra pagada por Paquet\u00e1 tiene el potencial de abrir una puerta para la llegada de m\u00e1s jugadores de calibre mundial.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa cerr\u00f3 este lunes un mercado de fichajes de mitad de temporada marcado nuevamente por el desembolso de billetes desde la Premier League. El Liverpool, que se gast\u00f3 m\u00e1s de US$ 500 millones en el verano boreal, volvi\u00f3 a romper la ventana de transferencias con un jugador que ni siquiera jugar\u00e1 de inmediato en Anfield [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470779","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias\" \/>\n<meta property=\"og:description\" content=\"Europa cerr\u00f3 este lunes un mercado de fichajes de mitad de temporada marcado nuevamente por el desembolso de billetes desde la Premier League. El Liverpool, que se gast\u00f3 m\u00e1s de US$ 500 millones en el verano boreal, volvi\u00f3 a romper la ventana de transferencias con un jugador que ni siquiera jugar\u00e1 de inmediato en Anfield [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T02:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados\",\"datePublished\":\"2026-02-03T02:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\"},\"wordCount\":841,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\",\"name\":\"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T02:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias","og_description":"Europa cerr\u00f3 este lunes un mercado de fichajes de mitad de temporada marcado nuevamente por el desembolso de billetes desde la Premier League. El Liverpool, que se gast\u00f3 m\u00e1s de US$ 500 millones en el verano boreal, volvi\u00f3 a romper la ventana de transferencias con un jugador que ni siquiera jugar\u00e1 de inmediato en Anfield [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-03T02:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/"},"author":{"name":"","@id":""},"headline":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados","datePublished":"2026-02-03T02:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/"},"wordCount":841,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","name":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T02:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cerr\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\u00e1s destacados","url":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/fichajes-mercado-europa-mas-destacados-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T02:03:41Z","datePublished":"2026-02-03T02:03:41Z","dateModified":"2026-02-03T02:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cerr\\u00f3 el mercado de fichajes en Europa: los cinco movimientos m\\u00e1s destacados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/02\\\/fichajes-mercado-europa-mas-destacados-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/02\\\/fichajes-mercado-europa-mas-destacados-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T02:03:41Z\",\"datePublished\":\"2026-02-03T02:03:41Z\",\"dateModified\":\"2026-02-03T02:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465508,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/14\/mercado-fichajes-ultimos-movimientos-orix\/","url_meta":{"origin":1470779,"position":0},"title":"Mercado de fichajes: rumores, \u00faltimos movimientos y los equipos y ligas que m\u00e1s gastaron","author":"","date":"agosto 14, 2025","format":false,"excerpt":"A muy poco para que cierre el mercado de fichajes de verano de 2025, es interesante repasar los movimientos m\u00e1s importantes, teniendo en cuenta lo que representan para los equipos de las ligas m\u00e1s importantes de Europa.El movimiento m\u00e1s notable en las \u00faltimas horas ha sido el del portero italiano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464886,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/26\/fichajes-cambios-real-madrid-temporada-2025-2026-orix\/","url_meta":{"origin":1470779,"position":1},"title":"Los fichajes y cambios del Real Madrid para la temporada 2025\/2026: qui\u00e9n lleg\u00f3 y qui\u00e9n se fue","author":"","date":"julio 26, 2025","format":false,"excerpt":"Queda todav\u00eda poco m\u00e1s de un mes para el cierre del mercado de fichajes de verano y uno de los equipos de f\u00fatbol del mundo que m\u00e1s expectativa genera en su preparaci\u00f3n de cara a la siguiente campa\u00f1a, el Real Madrid, ya cuenta con nuevos refuerzos.Cada temporada, los movimientos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465402,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/11\/cruces-copa-libertadores-octavos-candidatos-orix\/","url_meta":{"origin":1470779,"position":2},"title":"Copa Libertadores 2025, octavos de final: cruces, candidatos y m\u00e1s","author":"","date":"agosto 11, 2025","format":false,"excerpt":"Este martes comienzan los octavos de final de la principal competencia internacional de Sudam\u00e9rica, la Copa Libertadores, con tres cruces de alto vuelo.Esto es lo que debes saber:De entre los 16 clasificados, varios equipos de Brasil resaltan como candidatos a ganar la competici\u00f3n. No solo porque los conjuntos brasile\u00f1os han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464975,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/07\/30\/luis-diaz-se-va-al-bayern-munich-en-un-fichaje-millonario-plagado-de-records\/","url_meta":{"origin":1470779,"position":3},"title":"Luis D\u00edaz se va al Bayern Munich en un fichaje millonario plagado de r\u00e9cords","author":"","date":"julio 30, 2025","format":false,"excerpt":"Fue un secreto a voces durante la ventana del mercado de fichajes y finalmente este mi\u00e9rcoles el Bayern Munich oficializ\u00f3 la llegada de Luis D\u00edaz.El colombiano llega al equipo b\u00e1varo, procedente del Liverpool, con una mejora salarial y una serie de r\u00e9cords econ\u00f3micos en su traspaso.D\u00edaz, quien firm\u00f3 contrato hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465780,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/22\/lizbeth-ovalle-rompe-record-fichajes-futbol-femenino-orix\/","url_meta":{"origin":1470779,"position":4},"title":"La mexicana Lizbeth Ovalle rompe el r\u00e9cord de fichajes en el f\u00fatbol femenino","author":"","date":"agosto 22, 2025","format":false,"excerpt":"El libro de pases en esta ventana veraniega de traspasos escribi\u00f3 otro r\u00e9cord, esta vez en el f\u00fatbol femenino.El traspaso de Lizbeth Jacqueline Ovalle se ha convertido en el m\u00e1s caro en la historia de la disciplina.La mexicana se uni\u00f3 al Orlando Pride de la liga estadounidense de f\u00fatbol femenino\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465052,"url":"https:\/\/noticiasya.com\/san-diego\/2025\/08\/01\/fichajes-cambios-fc-barcelona-temporada-2025-2026-orix\/","url_meta":{"origin":1470779,"position":5},"title":"Los fichajes y cambios del FC Barcelona para la temporada 2025\/2026: qui\u00e9n lleg\u00f3 y qui\u00e9n se fue","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Desde el 15 de mayo, d\u00eda en el que el FC Barcelona se consagr\u00f3 campe\u00f3n de la liga espa\u00f1ola venciendo 2-0 al Espanyol, hasta el 30 de agosto habr\u00e1n pasado dos meses y medio, un lapso en el que la instituci\u00f3n catalana se ha focalizado en sostener lo m\u00e1s preciado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470779"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470779\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}